{"id":7844,"date":"2021-04-27T16:07:14","date_gmt":"2021-04-27T19:07:14","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=7844"},"modified":"2021-04-27T16:12:50","modified_gmt":"2021-04-27T19:12:50","slug":"maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/","title":{"rendered":"&#8220;M\u00e3os Dadas&#8221;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Belo Horizonte &#8211; A deputada estadual que preside a Comiss\u00e3o de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Assembleia Legislativa, Beatriz Cerqueira, apresentou o Projeto de Lei 2617\/2021 para que seja obrigat\u00f3rio o debate pr\u00e9vio com a comunidade escolar antes da descentraliza\u00e7\u00e3o do ensino dos anos iniciais do ensino fundamental das escolas p\u00fablicas estaduais. \u201cTamb\u00e9m vamos dialogar com vereadores e vereadoras demonstrando os erros e problemas deste projeto que, apesar de chamar \u2018M\u00e3os Dadas\u2019 est\u00e1 sendo executado pelo governo do Estado sem di\u00e1logo, sem transpar\u00eancia e desrespeitando comunidades escolares e os profissionais da educa\u00e7\u00e3o\u201d, avaliou a deputada.<\/p>\n\n\n\n<p>A parlamentar tamb\u00e9m fez um alerta importante sobre a municipaliza\u00e7\u00e3o de s\u00e9ries fundamentais: nenhum termo assinado pelos prefeitos com o governo do Estado tem valor sem a autoriza\u00e7\u00e3o formal das c\u00e2maras municipais. \u201cA Lei 12.768\/98 determina que o legislativo municipal aprove a municipaliza\u00e7\u00e3o para que o prefeito possa faz\u00ea-la\u201d, esclarece.<\/p>\n\n\n\n<p><strong>Prefeitos devem fazer as contas<\/strong><\/p>\n\n\n\n<p>A deputada alerta que, pela legisla\u00e7\u00e3o (LDB), a oferta de matr\u00edculas do Ensino Fundamental tamb\u00e9m \u00e9 atribui\u00e7\u00e3o dos&nbsp; munic\u00edpios, mas \u00e9 preciso, primeiro, que o Estado ajude as redes municipais&nbsp; a planejarem a universaliza\u00e7\u00e3o do acesso \u00e0 educa\u00e7\u00e3o infantil. \u201cMas o Estado quer ficar livre, transferindo logo o Ensino Fundamental para munic\u00edpios, de forma desrespeitosa\u201d, aponta.<\/p>\n\n\n\n<p>H\u00e1 tamb\u00e9m uma conta que est\u00e1 sendo mal apresentada, avisa: No caso de Ouro Preto, com a municipaliza\u00e7\u00e3o, haveria um aumento de 55% nas matr\u00edculas na rede municipal dos anos iniciais e um acr\u00e9scimo de apenas 18% nos recursos do Fundeb. O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas. Se a Prefeitura de Ouro Preto assumir tudo que o Estado quer, vai ter uma despesa extra de R$ 7.589 milh\u00f5es por ano, estimou.<br><br>A proposta do Governo para Ouro Preto \u00e9 municipalizar as Escolas Estaduais Mar\u00edlia de Dirceu; Dom Veloso; Hor\u00e1cio Andrade; Jos\u00e9 Leandro, em Santa Rita de Ouro Preto; Nossa Senhora Auxiliadora, em Cachoeira do Campo e a escola Daura de Carvalho Neto, em Ant\u00f4nio Pereira. No total seriam 60 turmas absorvidas pelo munic\u00edpio, sendo 1.426 alunos.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por todas essas raz\u00f5es, a deputada \u00e9 contra a municipaliza\u00e7\u00e3o sem a escuta das comunidades. \u201c\u00c9 preciso ter transpar\u00eancia e que munic\u00edpios fa\u00e7am as contas e vejam se t\u00eam condi\u00e7\u00f5es financeiras de arcar com essa despesa e se j\u00e1 cumpriram as metas do Plano Municipal de Educa\u00e7\u00e3o\u201d, recomenda. Os munic\u00edpios, destaca a deputada, s\u00f3 v\u00e3o aderir ao \u201cM\u00e3os Dadas\u201d se a prefeituras quiserem e \u00e9 fundamental, sobretudo, que os prefeitos\u00a0 fa\u00e7am\u00a0 aquilo que Estado n\u00e3o fez: escutem as suas comunidades e respeitem a opini\u00e3o de quem \u00e9 atendido pelas escolas estaduais.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria Parlamentar<br>Foto: Arquivo\/Luiz Santana\/ALMG<\/p>","protected":false},"excerpt":{"rendered":"<p>Belo Horizonte &#8211; A deputada estadual que preside a Comiss\u00e3o de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Assembleia Legislativa, Beatriz Cerqueira, apresentou o Projeto de Lei 2617\/2021 para que seja obrigat\u00f3rio o debate pr\u00e9vio com a comunidade escolar antes da descentraliza\u00e7\u00e3o do ensino dos anos iniciais do ensino fundamental das escolas<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":5276,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-7844","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;M\u00e3os Dadas&quot;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;M\u00e3os Dadas&quot;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T19:07:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T19:12:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"&#8220;M\u00e3os Dadas&#8221;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira\",\"datePublished\":\"2021-04-27T19:07:14+00:00\",\"dateModified\":\"2021-04-27T19:12:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20.10LuizSantana.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/\",\"name\":\"\\\"M\u00e3os Dadas\\\": Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20.10LuizSantana.jpg\",\"datePublished\":\"2021-04-27T19:07:14+00:00\",\"dateModified\":\"2021-04-27T19:12:50+00:00\",\"description\":\"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20.10LuizSantana.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20.10LuizSantana.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;M\u00e3os Dadas&#8221;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"M\u00e3os Dadas\": Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto","description":"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/","og_locale":"pt_PT","og_type":"article","og_title":"\"M\u00e3os Dadas\": Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto","og_description":"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2021-04-27T19:07:14+00:00","article_modified_time":"2021-04-27T19:12:50+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"&#8220;M\u00e3os Dadas&#8221;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira","datePublished":"2021-04-27T19:07:14+00:00","dateModified":"2021-04-27T19:12:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/"},"wordCount":491,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/","url":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/","name":"\"M\u00e3os Dadas\": Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","datePublished":"2021-04-27T19:07:14+00:00","dateModified":"2021-04-27T19:12:50+00:00","description":"O munic\u00edpio vai assumir mais despesas do que, proporcionalmente, receber recursos para atender as novas matr\u00edculas calcula a deputada","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/maos-dadas-municipalizacao-pode-fechar-escolas-estaduais-alerta-beatriz-cerqueira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"&#8220;M\u00e3os Dadas&#8221;: Municipaliza\u00e7\u00e3o pode fechar escolas estaduais alerta Beatriz Cerqueira"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/20.10LuizSantana.jpg","jetpack-related-posts":[{"id":7857,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/presidente-da-comissao-de-educacao-da-assembleia-visita-ouro-preto-para-analisar-a-municipalizacao-de-6-escolas-estaduais\/","url_meta":{"origin":7844,"position":0},"title":"Presidente da Comiss\u00e3o de Educa\u00e7\u00e3o da Assembleia visita  Ouro Preto para analisar a municipaliza\u00e7\u00e3o de 6 escolas estaduais","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2021","format":false,"excerpt":"Ouro Preto - A municipaliza\u00e7\u00e3o de seis escolas estaduais \u00e9 a pauta da reuni\u00e3o do prefeito Angelo Oswaldo com a deputada estadual Beatriz Cerqueira (PT), presidente da Comiss\u00e3o de Educa\u00e7\u00e3o da Assembleia e o deputado Federal Rog\u00e9rio Correia (PT), marcada para as 14 horas de hoje.A reuni\u00e3o tamb\u00e9m ter\u00e1 a\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-14.53.44-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-14.53.44-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-14.53.44-1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7911,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-descarta-projeto-maos-dadas-anuncia-secretario-de-educacao\/","url_meta":{"origin":7844,"position":1},"title":"Ouro Preto descarta projeto M\u00e3os Dadas, anuncia Secret\u00e1rio de Educa\u00e7\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"3 de Maio de 2021","format":false,"excerpt":"Ouro Preto - O Secret\u00e1rio Municipal de Educa\u00e7\u00e3o, Rog\u00e9rio Fernandes, acabou de informar, durante a audi\u00eancia P\u00fablica realizada pela C\u00e2mara, que o munic\u00edpio n\u00e3o vai aceitar o convite do Governo de Minas, para que seis escola estaduais sejam municipalizadas em Ouro Preto.A informa\u00e7\u00e3o mudou o foco d\u00e1 audi\u00eancia que buscava\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-18.09.34.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-18.09.34.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-18.09.34.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-18.09.34.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-18.09.34.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7942,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comissao-debate-projeto-que-municipaliza-ensino-fundamental\/","url_meta":{"origin":7844,"position":2},"title":"Comiss\u00e3o debate projeto que municipaliza ensino fundamental","author":"Di\u00e1rio de Ouro Preto","date":"4 de Maio de 2021","format":false,"excerpt":"A Comiss\u00e3o de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Assembleia Legislativa de Minas Gerais (ALMG) vai debater, nesta quarta-feira (5\/5\/21), o\u00a0projeto M\u00e3os Dadas, anunciado pelo governador. Solicitada pela presidenta da comiss\u00e3o, deputada Beatriz Cerqueira (PT), a audi\u00eancia p\u00fablica ter\u00e1 in\u00edcio \u00e0s 10 horas, no Audit\u00f3rio do andar SE da ALMG, com\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/imagem-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":45409,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tribunal-de-contas-do-estado-solicitou-ao-governo-zema-que-nao-faca-novas-adesoes-ao-projeto-maos-dadas\/","url_meta":{"origin":7844,"position":3},"title":"Tribunal de Contas do Estado solicitou ao Governo Zema que n\u00e3o fa\u00e7a novas ades\u00f5es ao Projeto M\u00e3os Dadas","author":"Di\u00e1rio de Ouro Preto","date":"16 de Junho de 2025","format":false,"excerpt":"Ap\u00f3s representa\u00e7\u00e3o da deputada estadual Beatriz Cerqueira (PT) sobre irregularidades no Projeto \u201cM\u00e3os Dadas\u201d, que trata da municipaliza\u00e7\u00e3o de escolas estaduais, o Tribunal de Contas de Minas Gerais (TCE\/MG) solicitou que o Governo Zema, por meio da Secretaria de Estado de Educa\u00e7\u00e3o de Minas Gerais, se abstenha-se de realizar ou\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/04\/beatriz_cerqueira_Daniel-Protzner_ALMG.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/04\/beatriz_cerqueira_Daniel-Protzner_ALMG.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/04\/beatriz_cerqueira_Daniel-Protzner_ALMG.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/04\/beatriz_cerqueira_Daniel-Protzner_ALMG.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/04\/beatriz_cerqueira_Daniel-Protzner_ALMG.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7877,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/audiencia-publica-da-camara-discute-sobre-municipalizacao-de-escolas-em-ouro-preto\/","url_meta":{"origin":7844,"position":4},"title":"Audi\u00eancia P\u00fablica da C\u00e2mara discute sobre municipaliza\u00e7\u00e3o de escolas em Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"1 de Maio de 2021","format":false,"excerpt":"Na pr\u00f3xima segunda-feira (03\/05), a C\u00e2mara Municipal de Ouro Preto realizar\u00e1 a 12\u00aa Audi\u00eancia P\u00fablica de 2021, requerida pelo vereador Matheus Pacheco (PV).\u00a0O encontro ter\u00e1 como objetivo debater sobre a municipaliza\u00e7\u00e3o das escolas estaduais em Ouro Preto.\u00a0A audi\u00eancia come\u00e7ar\u00e1 \u00e0s 17h e ser\u00e1 transmitida ao vivo pelo Facebook e Youtube\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/imagem.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/imagem.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/imagem.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/imagem.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":46915,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/pleno-do-tce-mg-confirma-suspensao-da-expansao-do-programa-das-escolas-civico-militares-em-resposta-a-representacao-da-deputada-estadual-beatriz-cerqueira\/","url_meta":{"origin":7844,"position":5},"title":"Pleno do TCE\/MG confirma suspens\u00e3o da expans\u00e3o do Programa das Escolas C\u00edvico-Militares em resposta \u00e0 representa\u00e7\u00e3o da deputada estadual Beatriz Cerqueira\u00a0","author":"Di\u00e1rio de Ouro Preto","date":"13 de Agosto de 2025","format":false,"excerpt":"Por quatro votos a um, os conselheiros do Tribunal de Contas de Minas Gerais, confirmaram na tarde desta quarta-feira, 13 de agosto, a suspens\u00e3o do Programa das Escolas C\u00edvico-Militares em Minas Gerais.\u00a0 Na \u00faltima segunda-feira, o conselheiro relator Adonias Monteiro j\u00e1 havia determinado a suspens\u00e3o em resposta a den\u00fancia de\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/2367894.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/2367894.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/2367894.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/2367894.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/2367894.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/7844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=7844"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/7844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/5276"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=7844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=7844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=7844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}