{"id":7541,"date":"2021-04-11T14:45:13","date_gmt":"2021-04-11T17:45:13","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=7541"},"modified":"2021-04-11T14:45:17","modified_gmt":"2021-04-11T17:45:17","slug":"china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","title":{"rendered":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica"},"content":{"rendered":"<p>O conselheiro de Estado e ministro das Rela\u00e7\u00f5es Exteriores da China, Wang Yi, disse neste s\u00e1bado (10) que a China quer trabalhar com o Brasil para promover sua parceria estrat\u00e9gica abrangente a fim de continuar fazendo novo progresso.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1406518&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1406518&amp;o=node\"><\/p>\n\n\n\n<p>Wang fez o coment\u00e1rio em uma conversa por telefone com Carlos Alberto Franco Fran\u00e7a, ministro das Rela\u00e7\u00f5es Exteriores do Brasil.<\/p>\n\n\n\n<p>Ao parabenizar Fran\u00e7a por sua nomea\u00e7\u00e3o como ministro das Rela\u00e7\u00f5es Exteriores, Wang disse que como grandes pa\u00edses em desenvolvimento, representantes das economias emergentes e parceiros no Brics, a China e o Brasil s\u00e3o for\u00e7as importantes impulsionando a multipolariza\u00e7\u00e3o do mundo e compartilhando interesses comuns extensivos e estreitos.<\/p>\n\n\n\n<p>A China, segundo Wang, sempre valoriza e desenvolve as rela\u00e7\u00f5es com o Brasil de uma perspectiva estrat\u00e9gica de longo prazo, colocando o Brasil em uma das dire\u00e7\u00f5es de prioridade para seus la\u00e7os estrangeiros.<\/p>\n\n\n\n<p>Ap\u00f3s o surto da pandemia da covid-19, a China e o Brasil t\u00eam combatido a pandemia com solidariedade e superado as dificuldades juntamente. Apesar da tend\u00eancia adversa, a coopera\u00e7\u00e3o pragm\u00e1tica tem crescido, com progresso est\u00e1vel em muitos projetos grandes, o que reflete completamente a forte resili\u00eancia da coopera\u00e7\u00e3o dos dois pa\u00edses, disse Wang.<\/p>\n\n\n\n<p>Ao indicar que o v\u00edrus \u00e9 o inimigo comum da humanidade, Wang disse que atualmente a pandemia no Brasil e outros pa\u00edses na Am\u00e9rica Latina est\u00e1 ainda muito severa.<\/p>\n\n\n\n<p>A China se compadece com o Brasil e apoia firmemente os esfor\u00e7os do governo brasileiro para conter a pandemia e restaurar sua economia, disse Wang, acrescentando que a China, dentro de sua capacidade, quer continuar com a coopera\u00e7\u00e3o de vacina com o Brasil para satisfazer sua necessidade urgente.<\/p>\n\n\n\n<p>Ele disse que as economias da China e do Brasil t\u00eam vantagens complementares \u00f3bvias e grande potencial de crescimento, e que a coopera\u00e7\u00e3o \u00e9 de interesse fundamental dos dois pa\u00edses e povos.<\/p>\n\n\n\n<p>Os dois lados devem promover o crescimento est\u00e1vel do com\u00e9rcio bilateral e expandir ativamente a coopera\u00e7\u00e3o em 5G, economia digital, intelig\u00eancia artificial e outras \u00e1reas. Acredita-se que o Brasil fornecer\u00e1 um ambiente de neg\u00f3cio justo e aberto para as empresas chinesas operando no pa\u00eds, disse Wang.<\/p>\n\n\n\n<p>Ao destacar que a China e o Brasil buscam pol\u00edticas estrangeiras independentes e respeitam a soberania e integridade territorial um do outro, Wang pediu que os dois pa\u00edses continuem a se entender e a se apoiar nos assuntos relacionados com seus interesses fundamentais respectivos.<\/p>\n\n\n\n<p>Mirando a nenhum terceiro lado, a coopera\u00e7\u00e3o China-Am\u00e9rica Latina se foca no desenvolvimento comum e coopera\u00e7\u00e3o pragm\u00e1tica, o que satisfaz as necessidades dos dois lados, disse Wang, indicando que o Brasil desempenhar\u00e1 um papel importante e ativo nesse respeito.<\/p>\n\n\n\n<p>Por sua parte, Fran\u00e7a, que agradeceu a Wang os parab\u00e9ns, assinalou que as rela\u00e7\u00f5es Brasil-China s\u00e3o de grande significado estrat\u00e9gico e que os dois pa\u00edses t\u00eam feito coopera\u00e7\u00e3o saud\u00e1vel em v\u00e1rias \u00e1reas.<\/p>\n\n\n\n<p>O chanceler brasileiro acredita que a conversa telef\u00f4nica injetar\u00e1 \u00edmpeto na coopera\u00e7\u00e3o bilateral.<\/p>\n\n\n\n<p>O Brasil espera desenvolver ainda mais as rela\u00e7\u00f5es harmoniosas com a China e realizar a coopera\u00e7\u00e3o a longo prazo, disse Franca, sugerindo que os dois pa\u00edses fa\u00e7am uso completo e melhorem os existentes canais de comunica\u00e7\u00e3o e mecanismos de coopera\u00e7\u00e3o bilateral, fortalecem seu di\u00e1logo estrat\u00e9gico e continuem a aprofundar suas rela\u00e7\u00f5es.<\/p>\n\n\n\n<p>Ao agradecer \u00e0 China sua ajuda generosa ao Brasil desde o surto da pandemia, Fran\u00e7a lembrou que a China \u00e9 um produtor importante de mat\u00e9rias-primas farmac\u00eauticas no mundo.<\/p>\n\n\n\n<p>Indicando que o Brasil est\u00e1 em necessidade urgente de vacinas e suprimentos m\u00e9dicos na luta contra a pandemia, Fran\u00e7a disse que seu pa\u00eds espera cont\u00ednuo suporte forte da China.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A coopera\u00e7\u00e3o cient\u00edfica e tecnol\u00f3gica \u00e9 de grande significado aos dois pa\u00edses, e o Brasil quer fortalecer a coopera\u00e7\u00e3o com a China nas \u00e1reas como a economia digital e 5G, e manter a comunica\u00e7\u00e3o estreita com a China na promo\u00e7\u00e3o da coopera\u00e7\u00e3o China-Am\u00e9rica Latina, acrescentou Fran\u00e7a.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Publicado em 11\/04\/2021 &#8211; 11:50 Por Ag\u00eancia Xinhua &#8211; BEIJING<br>Foto: Ant\u00f4nio Cruz\/ Ag\u00eancia Brasil<\/p>","protected":false},"excerpt":{"rendered":"<p>O conselheiro de Estado e ministro das Rela\u00e7\u00f5es Exteriores da China, Wang Yi, disse neste s\u00e1bado (10) que a China quer trabalhar com o Brasil para promover sua parceria estrat\u00e9gica abrangente a fim de continuar fazendo novo progresso. Wang fez o coment\u00e1rio em uma conversa por telefone com Carlos Alberto<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":7542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[70],"tags":[],"class_list":["entry","author-diario","post-7541","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-11T17:45:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-11T17:45:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica\",\"datePublished\":\"2021-04-11T17:45:13+00:00\",\"dateModified\":\"2021-04-11T17:45:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/vac_abr_0928250719df.jpg\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/\",\"name\":\"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/vac_abr_0928250719df.jpg\",\"datePublished\":\"2021-04-11T17:45:13+00:00\",\"dateModified\":\"2021-04-11T17:45:17+00:00\",\"description\":\"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/vac_abr_0928250719df.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/vac_abr_0928250719df.jpg\",\"width\":1170,\"height\":700,\"caption\":\"MRE, Coletiva, China\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto","description":"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","og_locale":"pt_PT","og_type":"article","og_title":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto","og_description":"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2021-04-11T17:45:13+00:00","article_modified_time":"2021-04-11T17:45:17+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica","datePublished":"2021-04-11T17:45:13+00:00","dateModified":"2021-04-11T17:45:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/"},"wordCount":732,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","articleSection":["Internacional"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","url":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/","name":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","datePublished":"2021-04-11T17:45:13+00:00","dateModified":"2021-04-11T17:45:17+00:00","description":"Declara\u00e7\u00e3o \u00e9 do chanceler chin\u00eas Wang Yi","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","width":1170,"height":700,"caption":"MRE, Coletiva, China"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/china-quer-trabalhar-com-o-brasil-para-promover-parceria-estrategica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"China quer trabalhar com o Brasil para promover parceria estrat\u00e9gica"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/vac_abr_0928250719df.jpg","jetpack-related-posts":[{"id":24731,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-e-china-celebram-50-anos-de-parceria\/","url_meta":{"origin":7541,"position":0},"title":"Vale e China celebram 50 anos de parceria","author":"Di\u00e1rio de Ouro Preto","date":"9 de Agosto de 2023","format":false,"excerpt":"A Vale celebra este ano cinco d\u00e9cadas de relacionamento com a China. O primeiro carregamento de min\u00e9rio de ferro para o pa\u00eds asi\u00e1tico aconteceu em julho de 1973, um ano antes do estabelecimento das rela\u00e7\u00f5es diplom\u00e1ticas formais entre Brasil e China. Desde 2006, a China \u00e9 o principal mercado para\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/08\/unnamed-64.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/08\/unnamed-64.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/08\/unnamed-64.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/08\/unnamed-64.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/08\/unnamed-64.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4596,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/lancada-frente-parlamentar-minas-china\/","url_meta":{"origin":7541,"position":1},"title":"Lan\u00e7ada Frente Parlamentar Minas China","author":"Di\u00e1rio de Ouro Preto","date":"18 de Agosto de 2020","format":false,"excerpt":"Foi lan\u00e7ada, na manh\u00e3 desta ter\u00e7a-feira (18\/8\/20), a\u00a0Frente Parlamentar Minas China. O objetivo \u00e9\u00a0fortalecer a rela\u00e7\u00e3o entre o Estado e o pa\u00eds asi\u00e1tico. O\u00a0presidente da frente \u00e9 o deputado Glaycon Franco (PV) e o vice, o deputado Thiago Cota (MDB). O lan\u00e7amento, realizado on-line, reuniu empres\u00e1rios mineiros e chineses, al\u00e9m\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/1523313.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/1523313.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/1523313.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8241,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ufop-assina-primeiro-acordo-de-cooperacao-com-universidade-chinesa\/","url_meta":{"origin":7541,"position":2},"title":"UFOP assina primeiro acordo de coopera\u00e7\u00e3o com universidade chinesa","author":"Di\u00e1rio de Ouro Preto","date":"19 de Maio de 2021","format":false,"excerpt":"Um acordo de coopera\u00e7\u00e3o entre a Universidade Federal de Ouro Preto e a Universidade de Geoci\u00eancias de Hebei (\u6cb3\u5317\u5730\u8d28\u5927\u5b66 - Hebei Geo University - HGU), o primeiro entre a UFOP e uma institui\u00e7\u00e3o chinesa, foi assinado na noite de ter\u00e7a (18) em cerim\u00f4nia virtual. O acordo possibilita a mobilidade de\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/slideshow_ufop_50_anos_-_vinho_3d-e1592430546835.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":44397,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/brasil-e-china-firmam-acordo-para-modernizar-servicos-postais-e-aprimorar-atendimento-a-populaca\/","url_meta":{"origin":7541,"position":3},"title":"Brasil e China firmam acordo para modernizar servi\u00e7os postais e aprimorar atendimento \u00e0 popula\u00e7\u00e3","author":"Di\u00e1rio de Ouro Preto","date":"13 de Maio de 2025","format":false,"excerpt":"Parceria prev\u00ea mais qualidade, inclus\u00e3o e efici\u00eancia nos servi\u00e7os prestados pelos Correios, com troca de tecnologias e boas pr\u00e1ticas com o governo chin\u00eas O Brasil e a China deram mais um passo estrat\u00e9gico rumo \u00e0 moderniza\u00e7\u00e3o dos servi\u00e7os postais. Nesta segunda-feira (12), o Minist\u00e9rio das Comunica\u00e7\u00f5es assinou um Memorando de\u2026","rel":"","context":"In &quot;Internacional&quot;","block_context":{"text":"Internacional","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/internacional\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/54516546391_429c8545ae_h.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/54516546391_429c8545ae_h.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/54516546391_429c8545ae_h.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/54516546391_429c8545ae_h.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/54516546391_429c8545ae_h.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":30418,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/reforma-da-onu-e-uma-das-prioridades-do-brasil-em-reuniao-do-g20\/","url_meta":{"origin":7541,"position":4},"title":"Reforma da ONU \u00e9 uma das prioridades do Brasil em reuni\u00e3o do G20","author":"Di\u00e1rio de Ouro Preto","date":"21 de Fevereiro de 2024","format":false,"excerpt":"Tema ser\u00e1 tratado em encontro de ministros de Rela\u00e7\u00f5es Exteriores Israel e Palestina, R\u00fassia e Ucr\u00e2nia, conflitos armados na Som\u00e1lia, no Sud\u00e3o, na Nig\u00e9ria e na S\u00edria. Diferentes partes do mundo veem crescer instabilidades pol\u00edticas, gastos militares e o n\u00famero de mortes. \u00c0s v\u00e9speras da Reuni\u00e3o de Ministros de Rela\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Internacional&quot;","block_context":{"text":"Internacional","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/internacional\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/02\/20240220150209_mg_3979.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/02\/20240220150209_mg_3979.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/02\/20240220150209_mg_3979.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/02\/20240220150209_mg_3979.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/02\/20240220150209_mg_3979.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":30609,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/lula-discute-parcerias-em-infraestrutura-com-banco-asiatico\/","url_meta":{"origin":7541,"position":5},"title":"Lula discute parcerias em infraestrutura com banco asi\u00e1tico","author":"Di\u00e1rio de Ouro Preto","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"O presidente Luiz In\u00e1cio Lula da Silva reuniu-se, nesta segunda-feira (4), com o presidente do Banco Asi\u00e1tico de Investimento em Infraestrutura (Asian Infrastructure Investment Bank \u2013 AIIB), Jin Liqun. Segundo o executivo chin\u00eas, a institui\u00e7\u00e3o n\u00e3o tem restri\u00e7\u00f5es de capital e est\u00e1 pronta para fornecer uma grande quantidade de recursos\u2026","rel":"","context":"In &quot;Internacional&quot;","block_context":{"text":"Internacional","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/internacional\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/whatsapp_image_2024-03-04_at_12.15.57.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/whatsapp_image_2024-03-04_at_12.15.57.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/whatsapp_image_2024-03-04_at_12.15.57.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/whatsapp_image_2024-03-04_at_12.15.57.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/whatsapp_image_2024-03-04_at_12.15.57.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/7541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=7541"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/7541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/7542"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=7541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=7541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=7541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}