{"id":6306,"date":"2021-01-25T22:58:43","date_gmt":"2021-01-26T01:58:43","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=6306"},"modified":"2021-01-25T23:05:43","modified_gmt":"2021-01-26T02:05:43","slug":"vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/","title":{"rendered":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021"},"content":{"rendered":"<p>Ouro Preto &#8211;\u00a0 O Secret\u00e1rio de Educa\u00e7\u00e3o, Rog\u00e9rio Fernandes anunciou nesta segunda-feira ao di\u00e1rio de Ouro Preto que abrir\u00e1 processo seletivo para o preenchimento das vagas da rede municipal. O Edital do processo seletivo contemplar\u00e1\u00a0<\/p>\n\n\n\n<p>Rog\u00e9rio Fernandes realizar\u00e1 processo seletivo para contrata\u00e7\u00e3o de pessoal para a Secretaria de Educa\u00e7\u00e3o. O Secret\u00e1rio explicou que encontrou distor\u00e7\u00f5es nos postos de trabalho, havendo \u201cuma multiplicidade de contratos, voc\u00ea tem servidores que s\u00e3o concursados, tem servidores em cargos comissionados, voc\u00ea tem funcion\u00e1rios com contrata\u00e7\u00e3o direta e funcion\u00e1rios que vem de um processo seletivo feito no ano de 2017\u201d.<\/p>\n\n\n\n<p>Ainda sem anunciar a data do lan\u00e7amento do processo seletivo, Rog\u00e9rio Fernandes explicou que est\u00e1 sendo realizado levantamento no setor de recursos humanos da secretaria e o RH central da Prefeitura para identificar o quantitativo de vagas a serem preenchidas via processo seletivo.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio o processo seletivo \u00e9 uma forma digna para ser compor os quadro da secretaria, e que \u201cmais digno que isso ainda \u00e9 o concurso p\u00fablico, este estamos mirando para o ano que vem, t\u00e3o logo passe essa pandemia, e a\u00ed sim\u00a0 as pessoas que quiserem ingressar na Educa\u00e7\u00e3o no munic\u00edpio de Ouro Preto, de ter uma forma digna, efetivamente de realizar seu seu trabalho, ela vai ingressar pelo m\u00e9rito, pelo concurso p\u00fablico\u201d, anunciou.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"800\" height=\"600\" data-attachment-id=\"6307\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/whatsapp-image-2021-01-25-at-22-23-57-1\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1.jpeg\" data-orig-size=\"1067,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp-Image-2021-01-25-at-22.23.57-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-800x600.jpeg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-800x600.jpeg\" alt=\"\" class=\"wp-image-6307\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-800x600.jpeg 800w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-528x396.jpeg 528w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-150x113.jpeg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-768x576.jpeg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1-160x120.jpeg 160w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.57-1.jpeg 1067w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>O Secret\u00e1rio fez quest\u00e3o de ser fotografado ao lado da secret\u00e1ria adjunta<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por Marcelino de Castro \u00e0s 22h15 <br>Fotos: Marcelino de Castro\/diariodeouropreto.com.br<\/p>","protected":false},"excerpt":{"rendered":"<p>Ouro Preto &#8211;\u00a0 O Secret\u00e1rio de Educa\u00e7\u00e3o, Rog\u00e9rio Fernandes anunciou nesta segunda-feira ao di\u00e1rio de Ouro Preto que abrir\u00e1 processo seletivo para o preenchimento das vagas da rede municipal. O Edital do processo seletivo contemplar\u00e1\u00a0 Rog\u00e9rio Fernandes realizar\u00e1 processo seletivo para contrata\u00e7\u00e3o de pessoal para a Secretaria de Educa\u00e7\u00e3o. O<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":6308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-6306","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T01:58:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T02:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"761\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021\",\"datePublished\":\"2021-01-26T01:58:43+00:00\",\"dateModified\":\"2021-01-26T02:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/\",\"name\":\"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg\",\"datePublished\":\"2021-01-26T01:58:43+00:00\",\"dateModified\":\"2021-01-26T02:05:43+00:00\",\"description\":\"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg\",\"width\":1200,\"height\":761},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto","description":"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto","og_description":"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2021-01-26T01:58:43+00:00","article_modified_time":"2021-01-26T02:05:43+00:00","og_image":[{"width":1200,"height":761,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021","datePublished":"2021-01-26T01:58:43+00:00","dateModified":"2021-01-26T02:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/","url":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/","name":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","datePublished":"2021-01-26T01:58:43+00:00","dateModified":"2021-01-26T02:05:43+00:00","description":"- Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021 - Ouro Preto","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","width":1200,"height":761},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/vagas-secretaria-de-educacao-lancara-processo-seletivo-para-o-ano-letivo-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Vagas: Secretaria de Educa\u00e7\u00e3o lan\u00e7ar\u00e1 processo seletivo para o ano letivo 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2021-01-25-at-22.23.56-e1611626419704.jpeg","jetpack-related-posts":[{"id":6839,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ano-letivo-angelo-oswaldo-anuncia-processo-seletivo-para-a-educacao-nesta-sexta-10-03\/","url_meta":{"origin":6306,"position":0},"title":"Ano Letivo: Angelo Oswaldo anuncia Processo Seletivo para a Educa\u00e7\u00e3o nesta sexta, 12\/03","author":"Di\u00e1rio de Ouro Preto","date":"11 de Mar\u00e7o de 2021","format":false,"excerpt":"Ouro Preto -\u00a0 O prefeito Angelo Oswaldo anuncia nesta sexta-feira, 12\/03, o processo seletivo da Educa\u00e7\u00e3o, instrumento para a contrata\u00e7\u00e3o de professores e servidores, para atender ao Ano Letivo 2021. O an\u00fancio ser\u00e1 feito durante entrevista coletiva, marcada para \u00e0s 10 horas, na prefeitura. Participar\u00e3o da Coletiva a vice-prefeita, Regina\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-11-at-20.56.59-e1615507119360.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-11-at-20.56.59-e1615507119360.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-11-at-20.56.59-e1615507119360.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-11-at-20.56.59-e1615507119360.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-11-at-20.56.59-e1615507119360.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6859,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/concurso-para-educacao-deve-ser-lancado-ate-dezembro\/","url_meta":{"origin":6306,"position":1},"title":"Concurso para Educa\u00e7\u00e3o deve ser lan\u00e7ado at\u00e9 dezembro","author":"Di\u00e1rio de Ouro Preto","date":"13 de Mar\u00e7o de 2021","format":false,"excerpt":"\u201cEduca\u00e7\u00e3o em primeiro lugar e educa\u00e7\u00e3o com for\u00e7a total na Prefeitura de Ouro Preto\u201d. Em coletiva de imprensa realizada na manh\u00e3 desta sexta-feira, 12, o prefeito Angelo Oswaldo refor\u00e7ou mais uma vez que a requalifica\u00e7\u00e3o do sistema municipal de ensino \u00e9 uma das prioridades da Administra\u00e7\u00e3o. Para isso, a Prefeitura\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Neno-Vianna-3-1-scaled-e1615686402980.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Neno-Vianna-3-1-scaled-e1615686402980.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Neno-Vianna-3-1-scaled-e1615686402980.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Neno-Vianna-3-1-scaled-e1615686402980.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Neno-Vianna-3-1-scaled-e1615686402980.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6796,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/secretario-de-educacao-participa-da-tribuna-livre-da-camara\/","url_meta":{"origin":6306,"position":2},"title":"Secret\u00e1rio de Educa\u00e7\u00e3o participa da Tribuna Livre da C\u00e2mara","author":"Di\u00e1rio de Ouro Preto","date":"9 de Mar\u00e7o de 2021","format":false,"excerpt":"Durante a 19\u00aa Reuni\u00e3o Ordin\u00e1ria de 2021, realizada nesta ter\u00e7a-feira (09), o Secret\u00e1rio Municipal de Educa\u00e7\u00e3o Rog\u00e9rio Lu\u00eds Fernandes e a Secret\u00e1ria Adjunta da pasta Deborah Etrusco, fizeram uso da Tribuna Livre em atendimento ao Requerimento N\u00ba 21\/2021, da vereadora L\u00edlian Fran\u00e7a (PDT).\u00a0 Na ocasi\u00e3o, o Secret\u00e1rio apresentou dados e\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-09-at-16.07.14-e1615317091561.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-09-at-16.07.14-e1615317091561.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-09-at-16.07.14-e1615317091561.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-09-at-16.07.14-e1615317091561.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-09-at-16.07.14-e1615317091561.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9041,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-abre-processo-seletivo-para-contratacoes-temporarias\/","url_meta":{"origin":6306,"position":3},"title":"Prefeitura abre Processo Seletivo para contrata\u00e7\u00f5es tempor\u00e1rias","author":"Di\u00e1rio de Ouro Preto","date":"3 de Julho de 2021","format":false,"excerpt":"A Prefeitura de Itabirito abre Processo Seletivo Simplificado para preenchimento de vagas de contrata\u00e7\u00e3o tempor\u00e1ria. A partir do dia 5 de julho, os interessados dever\u00e3o realizar a inscri\u00e7\u00e3o no site da Funda\u00e7\u00e3o de Desenvolvimento da Pesquisa - Fundep. O prazo ficar\u00e1 aberto at\u00e9 o dia 19 de julho. Ser\u00e3o oferecidas\u2026","rel":"","context":"In &quot;Itabirito&quot;","block_context":{"text":"Itabirito","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/itabirito\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Prefeitura.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Prefeitura.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Prefeitura.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Prefeitura.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Prefeitura.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41526,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-de-mariana-abre-inscricao-para-contratacao-temporaria-de-professores-da-rede-municipal\/","url_meta":{"origin":6306,"position":4},"title":"Prefeitura de Mariana abre inscri\u00e7\u00e3o para contrata\u00e7\u00e3o tempor\u00e1ria de professores da Rede Municipal","author":"Di\u00e1rio de Ouro Preto","date":"13 de Janeiro de 2025","format":false,"excerpt":"A Prefeitura de Mariana, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o, anunciou nesta sexta-feira (10) a abertura do Edital de Contrata\u00e7\u00e3o Tempor\u00e1ria de Professores, conforme o Edital n\u00ba 01\/2025. O processo seletivo visa preencher vagas para diversas fun\u00e7\u00f5es na rede municipal de ensino durante o ano letivo de 2025. As oportunidades abrangem\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/Designacao_site.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/Designacao_site.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/Designacao_site.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/Designacao_site.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/Designacao_site.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8257,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/itabirito-abre-novo-processo-seletivo-para-contratacao-de-estagiarios\/","url_meta":{"origin":6306,"position":5},"title":"Itabirito abre novo processo seletivo para contrata\u00e7\u00e3o de estagi\u00e1rios","author":"Di\u00e1rio de Ouro Preto","date":"19 de Maio de 2021","format":false,"excerpt":"Itabirito - A Prefeitura abrir\u00e1 na pr\u00f3xima sexta-feira, dia 21 de maio, inscri\u00e7\u00f5es para sele\u00e7\u00e3o de novos estagi\u00e1rios. Podem participar do processo seletivo estudantes maiores de 18 anos que estejam cursando Ci\u00eancias Biol\u00f3gicas, Medicina Veterin\u00e1ria, Engenharia Ambiental, Servi\u00e7o Social e cursos na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o. As inscri\u00e7\u00f5es podem\u2026","rel":"","context":"In &quot;Itabirito&quot;","block_context":{"text":"Itabirito","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/itabirito\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/Prefeitura-de-Itabirito.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/Prefeitura-de-Itabirito.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/Prefeitura-de-Itabirito.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/Prefeitura-de-Itabirito.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/6306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=6306"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/6306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/6308"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=6306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=6306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=6306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}