{"id":6083,"date":"2021-01-12T12:54:49","date_gmt":"2021-01-12T15:54:49","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=6083"},"modified":"2021-01-12T12:54:53","modified_gmt":"2021-01-12T15:54:53","slug":"canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/","title":{"rendered":"Canais de atendimento do TRE registraram 250 mil demandas em 2020"},"content":{"rendered":"<p>Ao longo de 2020, os canais oficiais de intera\u00e7\u00e3o do TRE \u2013 Disque-Eleitor, Ouvidoria e Fale Conosco \u2013 atenderam 250.019 demandas, entre atendimentos por telefone, WhatsApp e via sistema online. Em rela\u00e7\u00e3o a 2019, houve uma diminui\u00e7\u00e3o de atendimentos \u2013 naquele ano, os canais de intera\u00e7\u00e3o registraram 469.136 demandas.<\/p>\n\n\n\n<p>Entre janeiro e dezembro do ano passado, o Disque-Eleitor (telefone 148) atendeu 230.785 liga\u00e7\u00f5es. A maior parte delas \u2013 54.132 \u2013 foi sobre biometria. O segundo assunto mais demandado foi agendamento de atendimento nos cart\u00f3rios: 37.245 liga\u00e7\u00f5es. O terceiro assunto com mais procura foi alistamento eleitoral (emiss\u00e3o do 1\u00ba t\u00edtulo), com 23.341 chamadas.<\/p>\n\n\n\n<p>J\u00e1 a Ouvidoria atendeu um total de 19.234 demandas em 2020, incluindo aquelas apresentadas diretamente \u00e0 Ouvidoria e as que foram enviadas ao sistema Fale Conosco. Pelo telefone, foram 4.486 atendimentos e pelo WhatsApp 2.296. Pelo sistema online da Ouvidoria, foram 2.083 atendimentos registrados. Desse n\u00famero, 36% foram reclama\u00e7\u00f5es; 44% foram solicita\u00e7\u00f5es com pedidos de informa\u00e7\u00f5es, entre outros, sobre certid\u00f5es e convoca\u00e7\u00e3o de mes\u00e1rios; 13% foram den\u00fancias (por exemplo, relacionadas a condutas de candidatos); 2% foram elogios; 2% foram demandas com base na Lei de Acesso \u00e0 Informa\u00e7\u00e3o e 1,5% foram sugest\u00f5es.<\/p>\n\n\n\n<p>Pelo sistema Fale Conosco, gerenciado tamb\u00e9m pela Ouvidoria, foram feitos 10.369 atendimentos. Os principais assuntos foram inscri\u00e7\u00e3o em est\u00e1gio, certid\u00f5es da Justi\u00e7a Eleitoral, justificativa e regulariza\u00e7\u00e3o e convoca\u00e7\u00e3o e desconvoca\u00e7\u00e3o de mes\u00e1rios.<\/p>\n\n\n\n<p>Saiba mais sobre os&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/eleitor\/fale-com-o-tre\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">canais de intera\u00e7\u00e3o do TRE<\/a>.<\/p>\n\n\n\n<p><strong>YouTube, redes sociais e site<\/strong><\/p>\n\n\n\n<p>O&nbsp;<a href=\"https:\/\/www.youtube.com\/user\/Ascomtremg\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">canal do TRE no Youtube<\/a>&nbsp;chegou a 7.750 inscritos em 2020, um crescimento de 210% em rela\u00e7\u00e3o a 2019, quando o Tribunal fechou o ano com 2.500 inscritos. Contribu\u00edram para esse aumento o in\u00edcio da transmiss\u00e3o das sess\u00f5es de julgamento da Corte Eleitoral pelo YouTube, em maio, e a virtualiza\u00e7\u00e3o dos eventos de capacita\u00e7\u00e3o da Escola Judici\u00e1ria Eleitoral, a partir do mesmo m\u00eas. At\u00e9 o final de 2020, foram exibidas 89 sess\u00f5es de julgamento e 29&nbsp;<em>lives<\/em>&nbsp;ou v\u00eddeos da Escola Judici\u00e1ria.&nbsp;<\/p>\n\n\n\n<p>Nas redes sociais, o perfil do TRE no Instagram (@tre_minas) ganhou 9.456 seguidores e chegou a 14.500, um crescimento de 187%. A&nbsp;<a href=\"https:\/\/www.facebook.com\/tremg\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">fanpage do TRE no Facebook<\/a>&nbsp;ganhou cerca de dois mil seguidores, e o&nbsp;<a href=\"https:\/\/twitter.com\/TREMinas\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">perfil no Twitter<\/a>, 1.500. Al\u00e9m de serem p\u00e1ginas de veicula\u00e7\u00e3o de informa\u00e7\u00f5es sobre a Justi\u00e7a Eleitoral, sobretudo a mineira, as redes sociais do TRE tamb\u00e9m atuam como canais de intera\u00e7\u00e3o por meio de coment\u00e1rios e mensagens.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>O site do TRE-MG tamb\u00e9m foi bastante procurado em 2020 e bateu recordes. Foram 20.883.925 visualiza\u00e7\u00f5es, quase o triplo de 2019 (7.875.173); e 3.574.411 usu\u00e1rios, quase o dobro do ano anterior (1.814.519). As p\u00e1ginas do site mais acessadas foram a de\u00a0<a href=\"https:\/\/www.tre-mg.jus.br\/eleitor\/atendimento-eletronico-ao-eleitor\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">atendimento eletr\u00f4nico ao eleitor<\/a>, com 2.967.437 visualiza\u00e7\u00f5es; a de\u00a0<a href=\"https:\/\/www.tre-mg.jus.br\/eleitor\/agendamento\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">agendamento de atendimentos nos cart\u00f3rios<\/a>, com 1.362.573 visualiza\u00e7\u00f5es; e a p\u00e1gina\u00a0<a href=\"https:\/\/www.tre-mg.jus.br\/eleicoes\/eleicoes-2020\/eleicoes-2020\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Elei\u00e7\u00f5es 2020<\/a>, com 610.985 visualiza\u00e7\u00f5es.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: TRE-MG<\/p>","protected":false},"excerpt":{"rendered":"<p>Ao longo de 2020, os canais oficiais de intera\u00e7\u00e3o do TRE \u2013 Disque-Eleitor, Ouvidoria e Fale Conosco \u2013 atenderam 250.019 demandas, entre atendimentos por telefone, WhatsApp e via sistema online. Em rela\u00e7\u00e3o a 2019, houve uma diminui\u00e7\u00e3o de atendimentos \u2013 naquele ano, os canais de intera\u00e7\u00e3o registraram 469.136 demandas. Entre<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":5595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-6083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-12T15:54:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-12T15:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Canais de atendimento do TRE registraram 250 mil demandas em 2020\",\"datePublished\":\"2021-01-12T15:54:49+00:00\",\"dateModified\":\"2021-01-12T15:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/P1520001-e1605463178937.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/\",\"name\":\"Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/P1520001-e1605463178937.jpg\",\"datePublished\":\"2021-01-12T15:54:49+00:00\",\"dateModified\":\"2021-01-12T15:54:53+00:00\",\"description\":\"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/P1520001-e1605463178937.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/P1520001-e1605463178937.jpg\",\"width\":1200,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canais de atendimento do TRE registraram 250 mil demandas em 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto","description":"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/","og_locale":"pt_PT","og_type":"article","og_title":"Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto","og_description":"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2021-01-12T15:54:49+00:00","article_modified_time":"2021-01-12T15:54:53+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Canais de atendimento do TRE registraram 250 mil demandas em 2020","datePublished":"2021-01-12T15:54:49+00:00","dateModified":"2021-01-12T15:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/"},"wordCount":490,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/","url":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/","name":"Canais de atendimento do TRE registraram 250 mil demandas em 2020 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","datePublished":"2021-01-12T15:54:49+00:00","dateModified":"2021-01-12T15:54:53+00:00","description":"S\u00f3 o Disque-Eleitor atendeu cerca de 230 mil liga\u00e7\u00f5es entre janeiro e dezembro","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","width":1200,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/canais-de-atendimento-do-tre-registraram-250-mil-demandas-em-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Canais de atendimento do TRE registraram 250 mil demandas em 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/11\/P1520001-e1605463178937.jpg","jetpack-related-posts":[{"id":36957,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouvidoria-da-mulher-da-ufop-deve-abrir-caminho-para-canal-de-denuncias-em-universidades-estaduais\/","url_meta":{"origin":6083,"position":0},"title":"Ouvidoria da mulher da UFOP deve abrir caminho para canal de den\u00fancias em universidades estaduais","author":"Di\u00e1rio de Ouro Preto","date":"14 de Agosto de 2024","format":false,"excerpt":"Objetivo \u00e9 garantir acolhimento \u00e0s v\u00edtimas de viol\u00eancia de g\u00eanero e a devida apura\u00e7\u00e3o dos casos Baseada na experi\u00eancia da\u00a0ouvidoria da mulher da Universidade Federal de Ouro Preto (Ufop), a Comiss\u00e3o de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia da Assembleia Legislativa de Minas Gerais (ALMG) discutiu, nesta quarta-feira (14\/08), a\u00a0cria\u00e7\u00e3o de \u00f3rg\u00e3o\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/2166092.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/2166092.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/2166092.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/2166092.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/2166092.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5052,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-antecipa-atendimento-presencial-aos-partidos-politicos-para-registro-de-candidaturas\/","url_meta":{"origin":6083,"position":1},"title":"TRE antecipa atendimento presencial aos partidos pol\u00edticos para registro de candidaturas","author":"Di\u00e1rio de Ouro Preto","date":"21 de Setembro de 2020","format":false,"excerpt":"O TRE decidiu antecipar para esta segunda-feira (21) o atendimento presencial aos partidos pol\u00edticos e candidatos nos cart\u00f3rios eleitorais para os procedimentos de registro de candidaturas. A previs\u00e3o anterior era somente para o dia 26 de setembro. A decis\u00e3o ocorreu em raz\u00e3o da instabilidade do sistema CANDex, de uso obrigat\u00f3rio\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41315,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-retoma-expediente-regular-hoje\/","url_meta":{"origin":6083,"position":2},"title":"TRE retoma expediente regular hoje","author":"Di\u00e1rio de Ouro Preto","date":"7 de Janeiro de 2025","format":false,"excerpt":"Atendimento ao eleitor volta a ser das 12h \u00e0s 17h a partir de hoje 07 de Janeiro Os cart\u00f3rios eleitorais e a Secretaria do TRE-MG retornam ao expediente normal nesta ter\u00e7a-feira, ap\u00f3s o recesso forense, que foi de 20 de dezembro a 6 de janeiro. Nos cart\u00f3rios eleitorais e centrais\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2885,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/eleitores-tem-ate-06-de-maio-para-fazerem-o-primeiro-titulo-transferencia-e-regularizacao\/","url_meta":{"origin":6083,"position":3},"title":"Eleitores t\u00eam at\u00e9 06 de maio para fazerem o primeiro t\u00edtulo, transfer\u00eancia e regulariza\u00e7\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2020","format":false,"excerpt":"O dia 06 de maio marca o fechamento do cadastro eleitoral. Nessa data, termina o prazo para quem quer votar nas Elei\u00e7\u00f5es 2020 fazer a primeira via do t\u00edtulo, transfer\u00eancia de munic\u00edpio, atualiza\u00e7\u00e3o ou regulariza\u00e7\u00e3o do cadastro.\u00a0 Os atendimentos para esses servi\u00e7os podem ser solicitados no site do TRE, por\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":36922,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/sos-voto-saiba-como-funciona-o-numero-para-denunciar-mentiras-sobre-as-eleicoes-2024\/","url_meta":{"origin":6083,"position":4},"title":"SOS Voto: saiba como funciona o n\u00famero para denunciar mentiras sobre as Elei\u00e7\u00f5es 2024","author":"Di\u00e1rio de Ouro Preto","date":"12 de Agosto de 2024","format":false,"excerpt":"J\u00e1 est\u00e1 dispon\u00edvel para a popula\u00e7\u00e3o o SOS Voto, disque-den\u00fancia do Tribunal Superior Eleitoral (TSE) criado para receber relatos de mentiras e desinforma\u00e7\u00e3o sobre o processo eleitoral nas redes sociais. A ferramenta pode ser acessada gratuitamente por qualquer cidad\u00e3 ou cidad\u00e3o, em todas as regi\u00f5es do pa\u00eds, por meio do\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/59b106d7-a3c5-43f0-87eb-91ad412732ee.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/59b106d7-a3c5-43f0-87eb-91ad412732ee.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/59b106d7-a3c5-43f0-87eb-91ad412732ee.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15089,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/eleitores-que-solicitarem-atendimento-pelo-titulo-net-precisam-acompanhar-o-andamento-do-pedido-no-sistema\/","url_meta":{"origin":6083,"position":5},"title":"Eleitores que solicitarem atendimento pelo T\u00edtulo Net precisam acompanhar o andamento do pedido no sistema","author":"Di\u00e1rio de Ouro Preto","date":"18 de Abril de 2022","format":false,"excerpt":"O TRE-MG vem incentivando as eleitoras e eleitores mineiros a solicitarem atendimento pelo sistema\u00a0T\u00edtulo Net, para n\u00e3o precisarem ir at\u00e9 um cart\u00f3rio eleitoral. Mas h\u00e1 um alerta importante a ser feito: quem solicitar o atendimento virtual precisa monitorar o andamento do pedido pela\u00a0p\u00e1gina de acompanhamento do T\u00edtulo Net. \u00c9 por\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/59df213d-a834-4cbb-9992-3d86498c9d19.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/59df213d-a834-4cbb-9992-3d86498c9d19.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/59df213d-a834-4cbb-9992-3d86498c9d19.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/6083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=6083"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/6083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/5595"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=6083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=6083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=6083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}