{"id":5885,"date":"2020-12-30T18:08:57","date_gmt":"2020-12-30T21:08:57","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=5885"},"modified":"2020-12-30T18:09:01","modified_gmt":"2020-12-30T21:09:01","slug":"donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/","title":{"rendered":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021"},"content":{"rendered":"<p>Bras\u00edlia &#8211; Propriet\u00e1rios de ve\u00edculos n\u00e3o\u00a0ter\u00e3o que pagar o Seguro Obrigat\u00f3rio de Danos Pessoais Causados por Ve\u00edculos Automotores (Seguro DPVAT), em 2021.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1397623&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1397623&amp;o=node\"><\/p>\n\n\n\n<p>O Conselho Nacional de Seguros Privados (CNSP) aprovou, em reuni\u00e3o extraordin\u00e1ria realizada nessa&nbsp;ter\u00e7a-feira (29), pr\u00eamio zero para o DPVAT em 2021 e autorizou a contrata\u00e7\u00e3o de novo operador pela Superintend\u00eancia de Seguros Privados (Susep), em car\u00e1ter&nbsp;emergencial e tempor\u00e1rio. As resolu\u00e7\u00f5es do CNSP foram publicadas&nbsp;hoje&nbsp;(30) no&nbsp;<a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/resolucao-cnsp-n-398-de-29-de-dezembro-de-2020-296884187\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><em>Di\u00e1rio Oficial da Uni\u00e3o<\/em><\/a>.<\/p>\n\n\n\n<p>No final&nbsp;de novembro, foi anunciada a dissolu\u00e7\u00e3o da Cons\u00f3rcio do Seguro DPVAT a partir de 1\u00b0 de janeiro de 2021, ap\u00f3s decis\u00e3o de assembleia de seguradoras consorciadas. A partir desta data, a Seguradora L\u00edder n\u00e3o poder\u00e1 operar o Seguro DPVAT em nome das consorciadas, mas t\u00e3o somente administrar os ativos, passivos e neg\u00f3cios do Cons\u00f3rcio realizados at\u00e9&nbsp;31 de dezembro&nbsp;de 2020.<\/p>\n\n\n\n<p>No m\u00eas passado, a Susep notificou a Seguradora L\u00edder a recolher ao caixa dos recursos do Seguro DPVAT a quantia de R$ 2,257 bilh\u00f5es, referente a 2.119 despesas consideradas irregulares pela fiscaliza\u00e7\u00e3o da superintend\u00eancia, que foram executadas com recursos p\u00fablicos do seguro DPVAT entre os anos de 2008 e 2020.<\/p>\n\n\n\n<p>\u201cA Susep est\u00e1 envidando os melhores esfor\u00e7os para viabilizar a contrata\u00e7\u00e3o de pessoa jur\u00eddica, j\u00e1 na primeira semana&nbsp;de janeiro&nbsp;de 2021, com capacidade t\u00e9cnica e operacional para assumir o DPVAT, garantindo as indeniza\u00e7\u00f5es previstas em lei para a popula\u00e7\u00e3o brasileira\u201d, diz a superintend\u00eancia em nota.<\/p>\n\n\n\n<p>Nessa&nbsp;ter\u00e7a-feira, o Tribunal de Contas da Uni\u00e3o (TCU) emitiu decis\u00e3o cautelar determinando que CNSP e Susep adotem as provid\u00eancias necess\u00e1rias para assegurar a continuidade da operacionaliza\u00e7\u00e3o do seguro DPVAT.<\/p>\n\n\n\n<p>O Seguro DPVAT foi criado pela Lei n\u00b0 6.194 de 1974 e tem como finalidade o amparo \u00e0s v\u00edtimas de acidentes de tr\u00e2nsito em todo o pa\u00eds, n\u00e3o importando de quem seja a culpa dos acidentes.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Publicado em 30\/12\/2020 &#8211; 16:15 Por Kelly Oliveira \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; <\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: Bruna Saniele Foto: Marcello Casal<\/p>","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; Propriet\u00e1rios de ve\u00edculos n\u00e3o\u00a0ter\u00e3o que pagar o Seguro Obrigat\u00f3rio de Danos Pessoais Causados por Ve\u00edculos Automotores (Seguro DPVAT), em 2021. O Conselho Nacional de Seguros Privados (CNSP) aprovou, em reuni\u00e3o extraordin\u00e1ria realizada nessa&nbsp;ter\u00e7a-feira (29), pr\u00eamio zero para o DPVAT em 2021 e autorizou a contrata\u00e7\u00e3o de novo operador<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":5886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-5885","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T21:08:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-30T21:09:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021\",\"datePublished\":\"2020-12-30T21:08:57+00:00\",\"dateModified\":\"2020-12-30T21:09:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dpvat_3012203642.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/\",\"name\":\"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dpvat_3012203642.jpg\",\"datePublished\":\"2020-12-30T21:08:57+00:00\",\"dateModified\":\"2020-12-30T21:09:01+00:00\",\"description\":\"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dpvat_3012203642.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dpvat_3012203642.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Seguro DPVAT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto","description":"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto","og_description":"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-12-30T21:08:57+00:00","article_modified_time":"2020-12-30T21:09:01+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021","datePublished":"2020-12-30T21:08:57+00:00","dateModified":"2020-12-30T21:09:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/"},"wordCount":379,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/","name":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","datePublished":"2020-12-30T21:08:57+00:00","dateModified":"2020-12-30T21:09:01+00:00","description":"Decis\u00e3o \u00e9 do Conselho Nacional de Seguros Privados","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","width":1170,"height":700,"caption":"Seguro DPVAT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/donos-de-veiculos-nao-vao-pagar-seguro-dpvat-em-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Donos de ve\u00edculos n\u00e3o v\u00e3o pagar Seguro DPVAT em 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/dpvat_3012203642.jpg","jetpack-related-posts":[{"id":12266,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/motorista-nao-pagara-dpvat-pelo-segundo-ano-seguido\/","url_meta":{"origin":5885,"position":0},"title":"Motorista n\u00e3o pagar\u00e1 DPVAT pelo segundo ano seguido","author":"Di\u00e1rio de Ouro Preto","date":"2 de Janeiro de 2022","format":false,"excerpt":"Pelo segundo ano seguido, os motoristas ficar\u00e3o isentos de pagar o Seguro Obrigat\u00f3rio de Danos Pessoais Causados por Ve\u00edculos (DPVAT). A medida foi aprovada no \u00faltimo dia 17 pelo Conselho Nacional de Seguros Privados (CNSP), \u00f3rg\u00e3o vinculado ao Minist\u00e9rio da Economia. Segundo o CNSP, a isen\u00e7\u00e3o p\u00f4de ser concedida porque\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/dpvat_3012203642.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/dpvat_3012203642.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/dpvat_3012203642.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/dpvat_3012203642.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/dpvat_3012203642.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16338,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/crlv-2021-sera-obrigatorio-em-minas-a-partir-desta-quarta-feira-1-6\/","url_meta":{"origin":5885,"position":1},"title":"CRLV 2021 ser\u00e1 obrigat\u00f3rio em Minas a partir desta quarta-feira (1\/6)","author":"Di\u00e1rio de Ouro Preto","date":"1 de Junho de 2022","format":false,"excerpt":"Propriet\u00e1rios de ve\u00edculos registrados em Minas Gerais devem ficar atentos ao prazo de exig\u00eancia do Certificado de Registro e Licenciamento de Ve\u00edculo (CRLV). A partir desta quarta-feira (1\/6), o CRLV referente ao ano de 2021, ser\u00e1 o documento v\u00e1lido para comprovar a regularidade do ve\u00edculo durante as fiscaliza\u00e7\u00f5es de tr\u00e2nsito.\u00a0\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2721,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/cpf-pode-ser-obtido-nas-agencias-dos-correios\/","url_meta":{"origin":5885,"position":2},"title":"CPF pode ser obtido nas ag\u00eancias dos Correios","author":"Di\u00e1rio de Ouro Preto","date":"9 de Abril de 2020","format":false,"excerpt":"Os brasileiros que ainda n\u00e3o est\u00e3o inscritos no Cadastro de Pessoas F\u00edsicas (CPF) podem obter o documento em uma ag\u00eancia dos Correios. No local, tamb\u00e9m podem ser realizadas a regulariza\u00e7\u00e3o cadastral e a altera\u00e7\u00e3o de dados como data de nascimento, n\u00famero do t\u00edtulo eleitoral, endere\u00e7o, nome da m\u00e3e e g\u00eanero.\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22809,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/camara-aprova-mp-que-muda-codigo-de-transito-brasileiro\/","url_meta":{"origin":5885,"position":3},"title":"C\u00e2mara aprova MP que muda C\u00f3digo de Tr\u00e2nsito Brasileiro","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2023","format":false,"excerpt":"A C\u00e2mara dos Deputados aprovou nesta quinta-feira (27) a Medida Provis\u00f3ria 1153\/22, que faz v\u00e1rias mudan\u00e7as no C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB) em temas como exig\u00eancia de exame toxicol\u00f3gico de motoristas profissionais, compet\u00eancia para aplica\u00e7\u00e3o de multas e descanso de caminhoneiros. O texto que ir\u00e1 ao Senado \u00e9 um substitutivo\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/img20230427125219339-1-768x512-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/img20230427125219339-1-768x512-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/img20230427125219339-1-768x512-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/img20230427125219339-1-768x512-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5962,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/pmmg-lanca-operacao-ferias-seguras-2021-em-todo-estado\/","url_meta":{"origin":5885,"position":4},"title":"PMMG lan\u00e7a Opera\u00e7\u00e3o F\u00e9rias Seguras 2021 em todo Estado","author":"Di\u00e1rio de Ouro Preto","date":"5 de Janeiro de 2021","format":false,"excerpt":"A Pol\u00edcia Militar lan\u00e7ou dia 1\u00ba\/01, em todo o Estado a Opera\u00e7\u00e3o F\u00e9rias Seguras, com a finalidade de coibir pr\u00e1ticas criminosas, em especial, os crimes contra o patrim\u00f4nio em \u00e1reas residenciais. A Opera\u00e7\u00e3o F\u00e9rias Seguras tem a finalidade de intensificar as a\u00e7\u00f5es de pol\u00edcia ostensiva e preven\u00e7\u00e3o aos crimes contra\u2026","rel":"","context":"In &quot;Policial&quot;","block_context":{"text":"Policial","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/policial\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/52BPM-OperacaoFeriasSeguras-2021-Ouro-Preto-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/52BPM-OperacaoFeriasSeguras-2021-Ouro-Preto-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/52BPM-OperacaoFeriasSeguras-2021-Ouro-Preto-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/52BPM-OperacaoFeriasSeguras-2021-Ouro-Preto-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/52BPM-OperacaoFeriasSeguras-2021-Ouro-Preto-2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7626,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/estrada-de-ferro-vitoria-a-minas-e-a-ferrovia-mais-segura-do-pais\/","url_meta":{"origin":5885,"position":5},"title":"Estrada de Ferro Vit\u00f3ria a Minas \u00e9 a ferrovia mais segura do pa\u00eds","author":"Di\u00e1rio de Ouro Preto","date":"14 de Abril de 2021","format":false,"excerpt":"A Estrada de Ferro Vit\u00f3ria a Minas e a Estrada de Ferro Caraj\u00e1s (EFC) foram consideradas as ferrovias mais seguras no Brasil no \u00faltimo ano, de acordo com a Ag\u00eancia Nacional de Transportes Terrestres (ANTT). A EFVM atingiu o indicador de 1,16 no crit\u00e9rio estabelecido pela ag\u00eancia e divulgado no\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-6-2-scaled-e1618432026690.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-6-2-scaled-e1618432026690.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-6-2-scaled-e1618432026690.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-6-2-scaled-e1618432026690.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-6-2-scaled-e1618432026690.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=5885"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/5886"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=5885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=5885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=5885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}