{"id":5876,"date":"2020-12-29T12:11:45","date_gmt":"2020-12-29T15:11:45","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=5876"},"modified":"2020-12-29T12:11:48","modified_gmt":"2020-12-29T15:11:48","slug":"indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/","title":{"rendered":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV"},"content":{"rendered":"<p>O \u00cdndice Geral de Pre\u00e7os \u2013 Mercado (IGP-M) desacelerou em dezembro, registrando alta de 0,96%, depois de variar 3,28% em novembro. De janeiro a dezembro de 2020, o \u00edndice, que \u00e9 usado como base para o reajuste dos contratos de aluguel, acumulou alta de 23,14%. Em dezembro do ano passado, a taxa foi de 2,09% e a alta acumulada nos 12 meses de 2019 ficou em 7,30%.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1397499&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1397499&amp;o=node\"><\/p>\n\n\n\n<p>Os dados foram divulgados hoje (29) pelo Instituto Brasileiro de Economia da Funda\u00e7\u00e3o Getulio Vargas (FGV Ibre). O Coordenador dos \u00cdndices de Pre\u00e7os do instituto, Andr\u00e9 Braz, destaca que a desacelera\u00e7\u00e3o ocorreu por causa da diminui\u00e7\u00e3o da press\u00e3o inflacion\u00e1ria no \u00edndice ao produtor por est\u00e1gios de processamento, que cedeu em dezembro.<\/p>\n\n\n\n<p>\u201cAs mat\u00e9rias-primas brutas ca\u00edram 0,74% em dezembro. As principais contribui\u00e7\u00f5es para este movimento partiram das&nbsp;<em>commodities<\/em>: soja (11,91% para -8,93%), bovinos (7,40% para -0,58%) e milho (21,85% para -2,17%). Os pre\u00e7os da soja e do milho seguem em alta em bolsas internacionais e tal movimento pode limitar a magnitude das quedas nas pr\u00f3ximas apura\u00e7\u00f5es\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00cdndice de Pre\u00e7os ao Produtor Amplo<\/h2>\n\n\n\n<p>O principal componentes do IPG-M, o \u00cdndice de Pre\u00e7os ao Produtor Amplo tamb\u00e9m desacelerou, registrando varia\u00e7\u00e3o de 0,90% em dezembro, abaixo dos 4,26% de novembro. No ano, a taxa acumulou alta de 31,63%.<\/p>\n\n\n\n<p>Por est\u00e1gios de processamento, o grupo bens finais variou 2,04% em dezembro e fechou 2020 com alta de 15,78%. A taxa do grupo bens intermedi\u00e1rios passou de 4,07% em novembro para 1,86% em dezembro, fechando o ano em 21,38%. Para o est\u00e1gio das mat\u00e9rias-primas brutas, o \u00edndice caiu 0,74% em dezembro, ap\u00f3s alta de 5,60% em novembro, com acumulado em 12 meses de 59,96%.<\/p>\n\n\n\n<p>No m\u00eas, contribu\u00edram para a desacelera\u00e7\u00e3o no \u00edndice o pre\u00e7o do tomate, que caiu 30,16%, e dos su\u00ednos, com queda de 13,41%. As principais altas foram no \u00f3leo diesel (7,80%) e nas aves (4,96%).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00cdndice de Pre\u00e7os ao Consumidor<\/h2>\n\n\n\n<p>O \u00cdndice de Pre\u00e7os ao Consumidor (IPC) avan\u00e7ou 1,21% em dezembro, depois de subir 0,72% em novembro, acumulando alta de 4,81% em 2020. A maior varia\u00e7\u00e3o no m\u00eas ocorreu no grupo habita\u00e7\u00e3o, que passou de 0,23% em novembro para 2,11% em dezembro, com destaque para a taxa de eletricidade residencial, que havia ca\u00eddo 0,16% em novembro e aumentou 8,59% em dezembro.<\/p>\n\n\n\n<p>No acumulado do ano, o \u00fanico grupo do IPC que apresentou queda foi vestu\u00e1rio, que ficou 1,32% mais barato. J\u00e1 alimenta\u00e7\u00e3o aumentou 12,69% no ano. Habita\u00e7\u00e3o teve alta de 4,18% em 2020, a taxa de educa\u00e7\u00e3o, leitura e recrea\u00e7\u00e3o subiu 5,46%, sa\u00fade e cuidados pessoais cresceu 2,60% e o transporte aumentou 2,21%.<\/p>\n\n\n\n<p>As principais influ\u00eancias no \u00edndice foram o pre\u00e7o da passagem a\u00e9rea, que subiu 14,62%, e da eletricidade (8,59%). As maiores quedas foram verificadas no lim\u00e3o (22,90%), na manga (12,41%) e no tomate (11,51%).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00cdndice Nacional de Custo da Constru\u00e7\u00e3o<\/h2>\n\n\n\n<p>\u00daltimo componente do IGP-M, o \u00cdndice Nacional de Custo da Constru\u00e7\u00e3o variou 0,88% em dezembro, ante 1,29% em novembro. No acumulado do ano, o INCC fechou com alta de 8,66%.<\/p>\n\n\n\n<p>O grupo materiais, equipamentos e servi\u00e7os subiu 1,76% no m\u00eas e acumulou alta de 15,93% no ano. O \u00edndice da m\u00e3o de obra ficou em 0,06% em dezembro e 2,54% em 2020.<\/p>\n\n\n\n<p>Os principais aumentos no m\u00eas foram no grupo tubos e conex\u00f5es de ferro e a\u00e7o (6,08%), vergalh\u00f5es e arames de a\u00e7o ao carbono (4,57%) e tijolo\/telha cer\u00e2mica (3,82%).<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>ublicado em 29\/12\/2020 &#8211; 10:28 Por Akemi Nitahara \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: Val\u00e9ria Aguiar<\/p>","protected":false},"excerpt":{"rendered":"<p>O \u00cdndice Geral de Pre\u00e7os \u2013 Mercado (IGP-M) desacelerou em dezembro, registrando alta de 0,96%, depois de variar 3,28% em novembro. De janeiro a dezembro de 2020, o \u00edndice, que \u00e9 usado como base para o reajuste dos contratos de aluguel, acumulou alta de 23,14%. Em dezembro do ano passado,<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-5876","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"A alta foi puxada pelos precos ao produtor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"A alta foi puxada pelos precos ao produtor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T15:11:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T15:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"313\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV\",\"datePublished\":\"2020-12-29T15:11:45+00:00\",\"dateModified\":\"2020-12-29T15:11:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/\"},\"wordCount\":585,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/titulosite-e1569268778185.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/\",\"name\":\"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/titulosite-e1569268778185.jpg\",\"datePublished\":\"2020-12-29T15:11:45+00:00\",\"dateModified\":\"2020-12-29T15:11:48+00:00\",\"description\":\"A alta foi puxada pelos precos ao produtor\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/titulosite-e1569268778185.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/titulosite-e1569268778185.jpg\",\"width\":313,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto","description":"A alta foi puxada pelos precos ao produtor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/","og_locale":"pt_PT","og_type":"article","og_title":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto","og_description":"A alta foi puxada pelos precos ao produtor","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-12-29T15:11:45+00:00","article_modified_time":"2020-12-29T15:11:48+00:00","og_image":[{"width":313,"height":200,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV","datePublished":"2020-12-29T15:11:45+00:00","dateModified":"2020-12-29T15:11:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/"},"wordCount":585,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/","url":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/","name":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","datePublished":"2020-12-29T15:11:45+00:00","dateModified":"2020-12-29T15:11:48+00:00","description":"A alta foi puxada pelos precos ao produtor","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","width":313,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/indice-que-reajusta-alugueis-fecha-o-ano-com-alta-de-2314-diz-fgv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"\u00cdndice que reajusta alugu\u00e9is fecha o ano com alta de 23,14%, diz FGV"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite-e1569268778185.jpg","jetpack-related-posts":[{"id":6321,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/igp-m-acumula-inflacao-de-2571-em-12-meses-revela-pesquisa-da-fgv\/","url_meta":{"origin":5876,"position":0},"title":"IGP-M acumula infla\u00e7\u00e3o de 25,71% em 12 meses, revela pesquisa da FGV","author":"Di\u00e1rio de Ouro Preto","date":"28 de Janeiro de 2021","format":false,"excerpt":"O \u00cdndice Geral de Pre\u00e7os-Mercado (IGP-M), usado no reajuste de contratos de aluguel em todo o pa\u00eds, registrou infla\u00e7\u00e3o de 2,58% em janeiro deste ano. A taxa \u00e9 maior que a de dezembro do ano passado (0,96%). Segundo a Funda\u00e7\u00e3o Getulio Vargas (FGV) informou hoje (28), o IGP-M acumula infla\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27345,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/preco-de-alimentos-e-juros-contribuiram-para-frear-inflacao-em-2023\/","url_meta":{"origin":5876,"position":1},"title":"Pre\u00e7o de alimentos e juros contribu\u00edram para frear infla\u00e7\u00e3o em 2023","author":"Di\u00e1rio de Ouro Preto","date":"28 de Dezembro de 2023","format":false,"excerpt":"O comportamento dos pre\u00e7os dos alimentos e a pol\u00edtica monet\u00e1ria, que imp\u00f4s juros altos na economia em 2023, foram fatores que ajudaram a infla\u00e7\u00e3o ficar controlada neste ano que termina. A avalia\u00e7\u00e3o \u00e9 de especialistas ouvidos pela\u00a0Ag\u00eancia Brasil, nesta quinta-feira (28), quando foram divulgados dois \u00edndices de infla\u00e7\u00e3o.\u00a0 O \u00cdndice\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/1064929-edit_04214.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/1064929-edit_04214.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/1064929-edit_04214.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/1064929-edit_04214.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/1064929-edit_04214.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13494,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inflacao-e-de-054-em-janeiro-maior-resultado-para-o-mes-desde-2016\/","url_meta":{"origin":5876,"position":2},"title":"Infla\u00e7\u00e3o \u00e9 de 0,54% em janeiro, maior resultado para o m\u00eas desde 2016","author":"Di\u00e1rio de Ouro Preto","date":"9 de Fevereiro de 2022","format":false,"excerpt":"A infla\u00e7\u00e3o caiu para 0,54% em janeiro. No m\u00eas anterior, tinha ficado em 0,73%. Segundo o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), que divulgou hoje (9), no Rio de Janeiro, os dados do \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA), esse foi o maior resultado para o m\u00eas\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/real_moeda_50_reais020120a84t47165203.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/real_moeda_50_reais020120a84t47165203.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/real_moeda_50_reais020120a84t47165203.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/real_moeda_50_reais020120a84t47165203.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/real_moeda_50_reais020120a84t47165203.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":42396,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inflacao-oficial-de-janeiro-e-de-016-a-menor-para-o-mes-desde-1994\/","url_meta":{"origin":5876,"position":3},"title":"Infla\u00e7\u00e3o oficial de janeiro \u00e9 de 0,16%, a menor para o m\u00eas desde 1994","author":"Di\u00e1rio de Ouro Preto","date":"11 de Fevereiro de 2025","format":false,"excerpt":"B\u00f4nus na conta de luz ajuda a desacelerar o IPCA A infla\u00e7\u00e3o oficial de janeiro perdeu for\u00e7a e ficou em 0,16%. Este \u00e9 o menor resultado para um m\u00eas de janeiro desde 1994, ou seja, desde antes do Plano Real, iniciado em julho daquele ano. A explica\u00e7\u00e3o para a desacelera\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/realdinheiro_moeda_1310202266.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/realdinheiro_moeda_1310202266.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/realdinheiro_moeda_1310202266.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/realdinheiro_moeda_1310202266.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/realdinheiro_moeda_1310202266.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12052,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/construir-ficou-1403-mais-caro-em-2021\/","url_meta":{"origin":5876,"position":4},"title":"Construir ficou 14,03% mais caro em 2021","author":"Di\u00e1rio de Ouro Preto","date":"23 de Dezembro de 2021","format":false,"excerpt":"O \u00cdndice Nacional de Custo da Constru\u00e7\u00e3o \u2013 Mercado (INCC-M) subiu 0,30% em dezembro, desacelerando em rela\u00e7\u00e3o a novembro, quando o indicador aumentou 0,71%. Os dados foram divulgados\u00a0hoje\u00a0(23) pelo Instituto Brasileiro de Economia (Ibre) da Funda\u00e7\u00e3o Getulio Vargas (FGV). Com isso, o acumulado do ano e de 12 meses ficou\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/construcao_civil_2306219892.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/construcao_civil_2306219892.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/construcao_civil_2306219892.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/construcao_civil_2306219892.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/construcao_civil_2306219892.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":42531,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/economia-do-pais-cresce-35-em-2024-diz-fgv\/","url_meta":{"origin":5876,"position":5},"title":"Economia do pa\u00eds cresce 3,5% em 2024, diz FGV","author":"Di\u00e1rio de Ouro Preto","date":"17 de Fevereiro de 2025","format":false,"excerpt":"PIB alcan\u00e7a R$ 11,655 trilh\u00f5es A economia brasileira cresceu 3,5% em 2024, de acordo com estimativa da Funda\u00e7\u00e3o Getulio Vargas (FGV). O dado foi divulgado nesta segunda-feira (17) pelo Monitor do PIB, estudo que traz a pr\u00e9via do comportamento do PIB, conjunto de todos os bens e servi\u00e7os produzidos no\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/02\/dinnheiro-MArcello-Casa.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/02\/dinnheiro-MArcello-Casa.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/02\/dinnheiro-MArcello-Casa.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/02\/dinnheiro-MArcello-Casa.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/02\/dinnheiro-MArcello-Casa.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=5876"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=5876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=5876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=5876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}