{"id":5870,"date":"2020-12-29T05:32:18","date_gmt":"2020-12-29T08:32:18","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=5870"},"modified":"2020-12-29T05:32:22","modified_gmt":"2020-12-29T08:32:22","slug":"detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/","title":{"rendered":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia"},"content":{"rendered":"<p>O&nbsp;<a href=\"http:\/\/www.detran.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Departamento de Tr\u00e2nsito de Minas Gerais (Detran-MG)<\/a>&nbsp;suspender\u00e1, de&nbsp;30\/12 a 6\/1, a emiss\u00e3o de documentos para os servi\u00e7os de registro de ve\u00edculo zero, transfer\u00eancia de propriedade e altera\u00e7\u00e3o de dados de ve\u00edculo. O motivo, conforme a&nbsp;<a href=\"http:\/\/www.policiacivil.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Pol\u00edcia Civil de Minas Gerais (PCMG)<\/a>, \u00e9 a transi\u00e7\u00e3o para o modelo eletr\u00f4nico do Certificado de Registro de Ve\u00edculo (CRV-e) e da Autoriza\u00e7\u00e3o para Transfer\u00eancia de Propriedade do Ve\u00edculo eletr\u00f4nica (ATPV-e);<\/p>\n\n\n\n<p>A medida, que segue a&nbsp;<a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/resolucao-contran-n-809-de-15-de-dezembro-de-2020-296178226\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Resolu\u00e7\u00e3o n\u00ba 809 do Conselho Nacional de Tr\u00e2nsito (Contran)<\/a>, vale para a Divis\u00e3o de Registro de Ve\u00edculos (DRV), em Belo Horizonte, e para as Circunscri\u00e7\u00f5es Regionais de Tr\u00e2nsito (Ciretran), no interior.<\/p>\n\n\n\n<p>A previs\u00e3o \u00e9 de que os servi\u00e7os voltem a ser oferecidos normalmente em 7\/1.<\/p>\n\n\n\n<p><strong>Sistema<\/strong><\/p>\n\n\n\n<p>Durante o per\u00edodo de suspens\u00e3o, o sistema de inform\u00e1tica do Detran-MG passar\u00e1 por adequa\u00e7\u00e3o para que seja feito o gerenciamento das informa\u00e7\u00f5es da frota de ve\u00edculos do estado, impossibilitando, temporariamente, a conclus\u00e3o dos processos e emiss\u00e3o do documento ap\u00f3s as vistorias.<\/p>\n\n\n\n<p>Os prazos para servi\u00e7os de ve\u00edculos que, porventura, vencerem durante a suspens\u00e3o ser\u00e3o automaticamente prorrogados, sem qualquer preju\u00edzo para os cidad\u00e3os.<\/p>\n\n\n\n<p><strong>Mais moderno<\/strong><\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>O objetivo da nova Autoriza\u00e7\u00e3o para Transfer\u00eancia de Propriedade do Ve\u00edculo eletr\u00f4nica (ATPV-e) \u00e9 simplificar o processo na compra e venda dos automotores, por meio de itens de seguran\u00e7a mais modernos, como o QR-Code. A ATPV-e substitui a vers\u00e3o em papel moeda do antigo Certificado de Registro de Ve\u00edculo (CRV), documento no qual o comprador e o vendedor declaram estar de acordo com a transfer\u00eancia da propriedade.<br><br>A ATPV-e poder\u00e1 ser utilizada na vers\u00e3o eletr\u00f4nica ou impressa em papel comum. Quando o propriet\u00e1rio vendedor e o comprador possu\u00edrem os requisitos necess\u00e1rios para assinatura eletr\u00f4nica da ATPV-e, o preenchimento e a assinatura poder\u00e3o ocorrer nos sistemas do Departamento Nacional de Tr\u00e2nsito (Denatran), \u00f3rg\u00e3o da Uni\u00e3o, ou dos Detrans, nos estados. Caso contr\u00e1rio, a op\u00e7\u00e3o ser\u00e1 a vers\u00e3o impressa, devendo a ATPV-e ser assinada e conter o reconhecimento de firma do vendedor e do comprador por autentica\u00e7\u00e3o.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>CRVs at\u00e9 ent\u00e3o emitidos em papel moeda continuar\u00e3o sendo v\u00e1lidos por tempo indeterminado. Portanto, quem possuir a antiga vers\u00e3o do documento n\u00e3o precisar\u00e1 realizar a solicita\u00e7\u00e3o de um novo Certificado de Registro de Ve\u00edculo.<br>Fonte: Ag\u00eancia Minas<\/p>","protected":false},"excerpt":{"rendered":"<p>O&nbsp;Departamento de Tr\u00e2nsito de Minas Gerais (Detran-MG)&nbsp;suspender\u00e1, de&nbsp;30\/12 a 6\/1, a emiss\u00e3o de documentos para os servi\u00e7os de registro de ve\u00edculo zero, transfer\u00eancia de propriedade e altera\u00e7\u00e3o de dados de ve\u00edculo. O motivo, conforme a&nbsp;Pol\u00edcia Civil de Minas Gerais (PCMG), \u00e9 a transi\u00e7\u00e3o para o modelo eletr\u00f4nico do Certificado de<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-5870","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\/12); nova ferramenta vai simplificar processo de compra e venda de automotores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\/12); nova ferramenta vai simplificar processo de compra e venda de automotores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T08:32:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T08:32:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia\",\"datePublished\":\"2020-12-29T08:32:18+00:00\",\"dateModified\":\"2020-12-29T08:32:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/\",\"name\":\"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"datePublished\":\"2020-12-29T08:32:18+00:00\",\"dateModified\":\"2020-12-29T08:32:22+00:00\",\"description\":\"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\\\/12); nova ferramenta vai simplificar processo de compra e venda de automotores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"width\":535,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto","description":"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\/12); nova ferramenta vai simplificar processo de compra e venda de automotores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/","og_locale":"pt_PT","og_type":"article","og_title":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto","og_description":"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\/12); nova ferramenta vai simplificar processo de compra e venda de automotores","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-12-29T08:32:18+00:00","article_modified_time":"2020-12-29T08:32:22+00:00","og_image":[{"width":535,"height":427,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia","datePublished":"2020-12-29T08:32:18+00:00","dateModified":"2020-12-29T08:32:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/"},"wordCount":450,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/","url":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/","name":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","datePublished":"2020-12-29T08:32:18+00:00","dateModified":"2020-12-29T08:32:22+00:00","description":"Plataforma do \u00f3rg\u00e3o passar\u00e1 por adequa\u00e7\u00e3o a partir de quarta-feira (30\/12); nova ferramenta vai simplificar processo de compra e venda de automotores","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","width":535,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/detran-mg-suspende-emissao-de-documentos-de-veiculos-para-implantacao-de-novo-sistema-de-transferencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Detran-MG suspende emiss\u00e3o de documentos de ve\u00edculos para implanta\u00e7\u00e3o de novo sistema de transfer\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","jetpack-related-posts":[{"id":4499,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/proprietarios-de-veiculos-registrados-em-minas-ja-podem-imprimir-o-crlv-em-casa\/","url_meta":{"origin":5870,"position":0},"title":"Propriet\u00e1rios de ve\u00edculos registrados em Minas j\u00e1 podem imprimir o CRLV em casa","author":"Di\u00e1rio de Ouro Preto","date":"13 de Agosto de 2020","format":false,"excerpt":"Os propriet\u00e1rios de ve\u00edculos registrados em Minas Gerais agora podem imprimir o Certificado de Registro e Licenciamento de Ve\u00edculo (CRLV) em casa. A novidade ser\u00e1 disponibilizada pela\u00a0Pol\u00edcia Civil de Minas Gerais (PCMG)\u00a0a partir desta quarta-feira (12\/8), no site do\u00a0Departamento de Tr\u00e2nsito de Minas Gerais (Detran-MG). Para acessar e imprimir o\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/proprietarios-de-veiculos-registrados-em-minas-podem-imprimir-o-crlv-em-casa.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/proprietarios-de-veiculos-registrados-em-minas-podem-imprimir-o-crlv-em-casa.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/proprietarios-de-veiculos-registrados-em-minas-podem-imprimir-o-crlv-em-casa.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/proprietarios-de-veiculos-registrados-em-minas-podem-imprimir-o-crlv-em-casa.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/proprietarios-de-veiculos-registrados-em-minas-podem-imprimir-o-crlv-em-casa.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":37155,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-de-minas-define-calendario-de-exigencia-do-crlv-para-2024\/","url_meta":{"origin":5870,"position":1},"title":"Governo de Minas define calend\u00e1rio de exig\u00eancia do CRLV para 2024","author":"Di\u00e1rio de Ouro Preto","date":"19 de Agosto de 2024","format":false,"excerpt":"A Secretaria de Estado de Planejamento e Gest\u00e3o (Seplag-MG), por meio da Coordenadoria Estadual de Gest\u00e3o de Tr\u00e2nsito (CET-MG), definiu o calend\u00e1rio anual de exig\u00eancia do Certificado de Registro e Licenciamento do Ve\u00edculo (CRLV). As datas foram divulgadas no Di\u00e1rio Oficial do Estado em julho. Neste ano, os ve\u00edculos com\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/10\/content_marcianomenezes_transito_9.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/10\/content_marcianomenezes_transito_9.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/10\/content_marcianomenezes_transito_9.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/10\/content_marcianomenezes_transito_9.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5958,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/contran-autoriza-digitalizacao-de-documentos-de-registro\/","url_meta":{"origin":5870,"position":2},"title":"Contran autoriza digitaliza\u00e7\u00e3o de documentos de registro","author":"Di\u00e1rio de Ouro Preto","date":"5 de Janeiro de 2021","format":false,"excerpt":"Bras\u00edlia - Est\u00e1 em em vigor a resolu\u00e7\u00e3o emitida pelo Conselho Nacional de Tr\u00e2nsito (Contran) que autoriza a digitaliza\u00e7\u00e3o dos documentos de registro e de transfer\u00eancia de ve\u00edculos \u2013 no caso, o Certificado de Registro do Ve\u00edculo (CRV), o Certificado de Licenciamento Anual (CLA) e o comprovante de transfer\u00eancia de\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/dpvat_0401213644.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/dpvat_0401213644.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/dpvat_0401213644.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/dpvat_0401213644.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/dpvat_0401213644.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16338,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/crlv-2021-sera-obrigatorio-em-minas-a-partir-desta-quarta-feira-1-6\/","url_meta":{"origin":5870,"position":3},"title":"CRLV 2021 ser\u00e1 obrigat\u00f3rio em Minas a partir desta quarta-feira (1\/6)","author":"Di\u00e1rio de Ouro Preto","date":"1 de Junho de 2022","format":false,"excerpt":"Propriet\u00e1rios de ve\u00edculos registrados em Minas Gerais devem ficar atentos ao prazo de exig\u00eancia do Certificado de Registro e Licenciamento de Ve\u00edculo (CRLV). A partir desta quarta-feira (1\/6), o CRLV referente ao ano de 2021, ser\u00e1 o documento v\u00e1lido para comprovar a regularidade do ve\u00edculo durante as fiscaliza\u00e7\u00f5es de tr\u00e2nsito.\u00a0\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/CRLV-2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18988,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/definida-data-para-que-licenciamento-do-veiculo-seja-exigido-dos-motoristas\/","url_meta":{"origin":5870,"position":4},"title":"Definida data para que licenciamento do ve\u00edculo seja exigido dos motoristas","author":"Di\u00e1rio de Ouro Preto","date":"24 de Outubro de 2022","format":false,"excerpt":"Regularidade do registro de circula\u00e7\u00e3o ser\u00e1 cobrada a partir de novembro. CRLV 2022 poder\u00e1 ser apresentado no formato digital ou impresso Propriet\u00e1rios de ve\u00edculos registrados em Minas Gerais devem ficar atentos para o prazo de exig\u00eancia do Certificado de Registro e Licenciamento de Ve\u00edculo (CRLV). A partir de 21\/11, o\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/carro_ipva_estacionamento_garagem_vaga_veiculo__transito_semaforo_engarrafamento_automovel_caminhao_moto_placa_-_GIL_LEONARDI_812.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/carro_ipva_estacionamento_garagem_vaga_veiculo__transito_semaforo_engarrafamento_automovel_caminhao_moto_placa_-_GIL_LEONARDI_812.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/carro_ipva_estacionamento_garagem_vaga_veiculo__transito_semaforo_engarrafamento_automovel_caminhao_moto_placa_-_GIL_LEONARDI_812.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/carro_ipva_estacionamento_garagem_vaga_veiculo__transito_semaforo_engarrafamento_automovel_caminhao_moto_placa_-_GIL_LEONARDI_812.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/carro_ipva_estacionamento_garagem_vaga_veiculo__transito_semaforo_engarrafamento_automovel_caminhao_moto_placa_-_GIL_LEONARDI_812.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46299,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-de-minas-divulga-calendario-do-licenciamento-de-veiculos-de-2025\/","url_meta":{"origin":5870,"position":5},"title":"Governo de Minas divulga calend\u00e1rio do licenciamento de ve\u00edculos de 2025","author":"Di\u00e1rio de Ouro Preto","date":"20 de Julho de 2025","format":false,"excerpt":"Prazos para regulariza\u00e7\u00e3o do CRLV variam de agosto a outubro, conforme o final da placa do ve\u00edculo; veja como emitir o documento e evitar multas O\u00a0Governo de Minas\u00a0divulgou, nesta quinta-feira (17\/7), o calend\u00e1rio anual de exig\u00eancia do Certificado de Registro e Licenciamento de Ve\u00edculo (CRLV) para o ano de 2025.\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/PAB_0553.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/PAB_0553.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/PAB_0553.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/PAB_0553.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/PAB_0553.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=5870"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=5870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=5870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=5870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}