{"id":5643,"date":"2020-11-19T00:15:39","date_gmt":"2020-11-19T03:15:39","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=5643"},"modified":"2020-11-19T00:15:42","modified_gmt":"2020-11-19T03:15:42","slug":"mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/","title":{"rendered":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado"},"content":{"rendered":"<p>Ningu\u00e9m acertou as seis dezenas do concurso 2.319 da Mega-Sena, realizado nesta quarta-feira (18) no Espa\u00e7o Loterias Caixa, em S\u00e3o Paulo.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1393927&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1393927&amp;o=node\"><\/p>\n\n\n\n<p>Os n\u00fameros sorteados s\u00e3o:&nbsp;06 &#8211;&nbsp;17 &#8211;&nbsp;25 &#8211;&nbsp;35 &#8211;&nbsp;40 &#8211;&nbsp;49.<\/p>\n\n\n\n<p>A quina&nbsp;registrou 51 apostas ganhadoras, cabendo a cada uma delas R$ 74.635,43. E a quadra&nbsp;teve 5.009 apostas ganhadoras, com R$ 1.085,59 para cada uma. &nbsp; &nbsp;<\/p>\n\n\n\n<p>A estimativa do pr\u00eamio para o pr\u00f3ximo concurso, que vai ocorrer no s\u00e1bado (24), \u00e9 estimado em R$ 75 milh\u00f5es, segundo o site da Caixa Econ\u00f4mica Federal.&nbsp;<\/p>\n\n\n\n<p>As apostas poder\u00e3o ser feitas at\u00e9 as 19h de s\u00e1bado. Cada aposta custa R$ 4,50.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mega da Virada<\/h2>\n\n\n\n<p>As apostas para a Mega da Virada come\u00e7aram nesta semana e o pr\u00eamio estimado, nesta edi\u00e7\u00e3o, \u00e9 de R$ 300 milh\u00f5es. O&nbsp;sorteio ser\u00e1 realizado no dia 31 de dezembro.<\/p>\n\n\n\n<p>Como nos demais concursos especiais das Loterias CAIXA, o pr\u00eamio principal da Mega da Virada n\u00e3o acumula. Se n\u00e3o houver ganhadores na faixa principal, com acerto de 6 n\u00fameros, o pr\u00eamio ser\u00e1 dividido entre os acertadores da 2\u00aa faixa (com o acerto de 5 n\u00fameros) e assim por diante.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Publicado em 18\/11\/2020 &#8211; 22:51 Por Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: F\u00e1bio Massalli<br>Foto: Marcelo Camargo<\/p>","protected":false},"excerpt":{"rendered":"<p>Ningu\u00e9m acertou as seis dezenas do concurso 2.319 da Mega-Sena, realizado nesta quarta-feira (18) no Espa\u00e7o Loterias Caixa, em S\u00e3o Paulo. Os n\u00fameros sorteados s\u00e3o:&nbsp;06 &#8211;&nbsp;17 &#8211;&nbsp;25 &#8211;&nbsp;35 &#8211;&nbsp;40 &#8211;&nbsp;49. A quina&nbsp;registrou 51 apostas ganhadoras, cabendo a cada uma delas R$ 74.635,43. E a quadra&nbsp;teve 5.009 apostas ganhadoras, com R$<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4651,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-5643","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T03:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T03:15:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado\",\"datePublished\":\"2020-11-19T03:15:39+00:00\",\"dateModified\":\"2020-11-19T03:15:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mcamg_abr_08052019_8683_1.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/\",\"name\":\"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mcamg_abr_08052019_8683_1.jpg\",\"datePublished\":\"2020-11-19T03:15:39+00:00\",\"dateModified\":\"2020-11-19T03:15:42+00:00\",\"description\":\"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mcamg_abr_08052019_8683_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mcamg_abr_08052019_8683_1.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Apostadores fazem fila em casa lot\u00e9rica. A Caixa Econ\u00f4mica Federal sorteia hoje (08) as seis dezenas do concurso 2.149 da Mega-Sena acumulada, que deve pagar um pr\u00eamio de R$ 170 milh\u00f5es.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto","description":"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/","og_locale":"pt_PT","og_type":"article","og_title":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto","og_description":"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-11-19T03:15:39+00:00","article_modified_time":"2020-11-19T03:15:42+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado","datePublished":"2020-11-19T03:15:39+00:00","dateModified":"2020-11-19T03:15:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/","name":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","datePublished":"2020-11-19T03:15:39+00:00","dateModified":"2020-11-19T03:15:42+00:00","description":"As apostas poder\u00e3o ser feitas at\u00e9 as 19h do dia do sorteio","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","width":1170,"height":700,"caption":"Apostadores fazem fila em casa lot\u00e9rica. A Caixa Econ\u00f4mica Federal sorteia hoje (08) as seis dezenas do concurso 2.149 da Mega-Sena acumulada, que deve pagar um pr\u00eamio de R$ 170 milh\u00f5es."},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-75-milhoes-no-sabado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Mega-Sena acumula e pagar\u00e1 R$ 75 milh\u00f5es no s\u00e1bado"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/mcamg_abr_08052019_8683_1.jpg","jetpack-related-posts":[{"id":8075,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-proximo-concurso-deve-pagar-r-27-milhoes\/","url_meta":{"origin":5643,"position":0},"title":"Mega-Sena acumula e pr\u00f3ximo concurso deve pagar R$ 27 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"9 de Maio de 2021","format":false,"excerpt":"Ningu\u00e9m acertou as seis dezenas do concurso 2370 da Mega-Sena, realizado nesse s\u00e1bado (8) \u00e0 noite no Espa\u00e7o Loterias Caixa, no Terminal Rodovi\u00e1rio do Tiet\u00ea, em S\u00e3o Paulo. Os n\u00fameros sorteados foram 07 - 31 - 37 - 42 - 44 - 56. O pr\u00f3ximo concurso, na quarta-feira (12), deve\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5027,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-36-milhoes-sabado\/","url_meta":{"origin":5643,"position":1},"title":"Mega-Sena acumula e pagar\u00e1 R$ 36 milh\u00f5es s\u00e1bado","author":"Di\u00e1rio de Ouro Preto","date":"18 de Setembro de 2020","format":false,"excerpt":"Ningu\u00e9m acertou as seis dezenas do concurso 2.300 da Mega-Sena, realizado ontem em S\u00e3o Paulo. Os n\u00fameros sorteados s\u00e3o: \u00a009 - 21 - 37 - 39 - 43 - 54. A Quina (cinco n\u00fameros acertados) registrou 76 apostas ganhadoras, cabendo a cada uma delas R$ 29.541,74. E a Quadra (quatro\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5114,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-proximo-concurso-deve-sortear-r-90-milhoes\/","url_meta":{"origin":5643,"position":2},"title":"Mega-Sena acumula e pr\u00f3ximo concurso deve sortear R$ 90 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"30 de Setembro de 2020","format":false,"excerpt":"Ningu\u00e9m acertou as seis dezenas do concurso 2.304 da Mega-Sena. O pr\u00eamio\u00a0acumulou e a estimativa para o pr\u00f3ximo concurso da Mega Semana ,\u00a0que ser\u00e1 realizado no s\u00e1bado (3), \u00e9 R$ 90 milh\u00f5es. O sorteio foi realizado nesta quarta-feira (30), no Espa\u00e7o Loterias Caixa, localizado no terminal Rodovi\u00e1rio Tiet\u00ea, na cidade\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16704,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-acumula-e-pagara-r-52-milhoes-no-dia-15\/","url_meta":{"origin":5643,"position":3},"title":"Mega-Sena acumula e pagar\u00e1 R$ 52 milh\u00f5es no dia 15","author":"Di\u00e1rio de Ouro Preto","date":"12 de Junho de 2022","format":false,"excerpt":"A Mega-Sena acumulou no concurso de n\u00famero 2490 realizado neste s\u00e1bado (11), em S\u00e3o Paulo. Os n\u00fameros sorteados foram: 11, 16, 17, 41, 46 e 59.\u00a0 A quina teve 65 apostas ganhadoras, cabendo a cada uma delas R$ 65.482,06. E a quadra, com quatro n\u00fameros acertados, registrou 5.432 apostas ganhadoras,\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22807,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/apostador-de-minas-gerais-ganha-r-61-milhoes-na-mega-sena\/","url_meta":{"origin":5643,"position":4},"title":"Apostador de Minas Gerais ganha R$ 61 milh\u00f5es na Mega-Sena","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2023","format":false,"excerpt":"O concurso 2587 da Mega-Sena premiou um apostador da cidade de Pedro Leopoldo, em Minas Gerais, com R$\u00a0 R$ 61.056.497,58. Ele acertou as seis dezenas 05, 10,11, 22, 23 e 37, sorteadas neste s\u00e1bado (29), em S\u00e3o Paulo, pela Caixa Econ\u00f4mica Federal. \u00a0 A Quina (cinco acertos) teve 328 apostas\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/mega_sena-1112203504_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/mega_sena-1112203504_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/mega_sena-1112203504_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/mega_sena-1112203504_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/mega_sena-1112203504_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5078,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ninguem-acerta-a-mega-sena-e-premio-acumulado-vai-para-r-60-milhoes\/","url_meta":{"origin":5643,"position":5},"title":"Ningu\u00e9m acerta a Mega-Sena e pr\u00eamio acumulado vai para R$ 60 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"27 de Setembro de 2020","format":false,"excerpt":"Nenhuma aposta acertou as seis dezenas do concurso 2.303 da Mega-Sena. Com o pr\u00eamio principal acumulado, a estimativa da Caixa \u00e9 que ele pague R$ 60 milh\u00f5es no sorteio da pr\u00f3xima quarta-feira (30). A seis dezenas foram sorteadas nesse s\u00e1bado (26), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o Loterias Caixa,\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=5643"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4651"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=5643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=5643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=5643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}