{"id":5119,"date":"2020-10-02T12:13:20","date_gmt":"2020-10-02T15:13:20","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=5119"},"modified":"2020-10-02T12:13:25","modified_gmt":"2020-10-02T15:13:25","slug":"contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/","title":{"rendered":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria"},"content":{"rendered":"<p>O TRE esclarece que os candidatos, partidos e coliga\u00e7\u00f5es podem abrir as contas banc\u00e1rias para a campanha eleitoral em qualquer institui\u00e7\u00e3o financeira com carteira comercial reconhecida pelo Banco Central do Brasil e que emitam extratos eletr\u00f4nicos para envio \u00e0 Justi\u00e7a Eleitoral, inclusive cooperativas de cr\u00e9dito.<\/p>\n\n\n\n<p>A abertura das contas de campanha devem ser solicitadas at\u00e9 dez dias ap\u00f3s a concess\u00e3o do CNPJ pela Secretaria da Receita Federal. As institui\u00e7\u00f5es financeiras devem realizar a abertura da conta em at\u00e9 tr\u00eas dias \u00fateis a partir do pedido, conforme o disposto no art. 22, \u00a7 1\u00ba, inciso I, da Lei n\u00ba 9.504, de 30 de setembro de 1997. A eventual recusa ou o embara\u00e7o \u00e0 abertura de conta pela institui\u00e7\u00e3o financeira, inclusive no prazo fixado em lei, sujeitar\u00e1 o respons\u00e1vel \u00e0 pena prevista no art. 347 do C\u00f3digo Eleitoral: deten\u00e7\u00e3o de tr\u00eas meses a um ano e pagamento de 10 a 20 dias-multa.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Todas as normas relativas ao tema est\u00e3o na\u00a0<a href=\"http:\/\/www.tse.jus.br\/legislacao\/compilada\/res\/2019\/resolucao-no-23-607-de-17-de-dezembro-de-2019\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Resolu\u00e7\u00e3o TSE 23.607\/2019<\/a>, que trata da presta\u00e7\u00e3o de contas nas Elei\u00e7\u00f5es 2020, e no\u00a0<a href=\"https:\/\/www.bcb.gov.br\/estabilidadefinanceira\/exibenormativo?tipo=Comunicado&amp;numero=35979\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Comunicado n\u00ba 35.979\/2020 do Banco Central do Brasil<\/a>. Para facilitar o entendimento sobre a abertura de contas banc\u00e1ria de campanha, o TRE disponibilizou um\u00a0<a href=\"http:\/\/www.tre-mg.jus.br\/eleicoes\/eleicoes-2020\/evento-cafe-com-o-contabilista-crc-mg-1\/perguntas-frequentes\/rybena_pdf?file=http:\/\/www.tre-mg.jus.br\/eleicoes\/eleicoes-2020\/evento-cafe-com-o-contabilista-crc-mg-1\/perguntas-frequentes\/at_download\/file\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">FAQ, com perguntas mais frequentes sobre o assunto<\/a>, no portal do Tribunal na internet. O documento pode ser acessado pelo caminho menu Eleitor e Elei\u00e7\u00f5es>>Elei\u00e7\u00f5es 2020>>Presta\u00e7\u00e3o de Contas Eleitorais>>Material de Apoio>>Perguntas Frequentes (contas banc\u00e1rias para campanha).\u00a0<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria de Imprensa TRE<\/p>","protected":false},"excerpt":{"rendered":"<p>O TRE esclarece que os candidatos, partidos e coliga\u00e7\u00f5es podem abrir as contas banc\u00e1rias para a campanha eleitoral em qualquer institui\u00e7\u00e3o financeira com carteira comercial reconhecida pelo Banco Central do Brasil e que emitam extratos eletr\u00f4nicos para envio \u00e0 Justi\u00e7a Eleitoral, inclusive cooperativas de cr\u00e9dito. A abertura das contas de<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":3318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[68],"tags":[],"class_list":["entry","author-diario","post-5119","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eleicoes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-02T15:13:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T15:13:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria\",\"datePublished\":\"2020-10-02T15:13:20+00:00\",\"dateModified\":\"2020-10-02T15:13:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/antcrz_abr_1909185135df.jpg\",\"articleSection\":[\"Elei\u00e7\u00f5es\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/\",\"name\":\"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/antcrz_abr_1909185135df.jpg\",\"datePublished\":\"2020-10-02T15:13:20+00:00\",\"dateModified\":\"2020-10-02T15:13:25+00:00\",\"description\":\"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/antcrz_abr_1909185135df.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/antcrz_abr_1909185135df.jpg\",\"width\":1170,\"height\":700,\"caption\":\"O Tribunal Regional Eleitoral do Distrito Federal (TRE-DF) realiza hoje (19) as cerim\u00f4nias de carga e lacra\u00e7\u00e3o das 680 urnas eletr\u00f4nicas que ir\u00e3o para o exterior para serem utilizadas na elei\u00e7\u00e3o para presidente da Rep\u00fablica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto","description":"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/","og_locale":"pt_PT","og_type":"article","og_title":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto","og_description":"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-10-02T15:13:20+00:00","article_modified_time":"2020-10-02T15:13:25+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria","datePublished":"2020-10-02T15:13:20+00:00","dateModified":"2020-10-02T15:13:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","articleSection":["Elei\u00e7\u00f5es"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/","name":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","datePublished":"2020-10-02T15:13:20+00:00","dateModified":"2020-10-02T15:13:25+00:00","description":"Candidatos e partidos precisam observar normas previstas na legisla\u00e7\u00e3o eleitoral e instru\u00e7\u00f5es do Banco Central","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","width":1170,"height":700,"caption":"O Tribunal Regional Eleitoral do Distrito Federal (TRE-DF) realiza hoje (19) as cerim\u00f4nias de carga e lacra\u00e7\u00e3o das 680 urnas eletr\u00f4nicas que ir\u00e3o para o exterior para serem utilizadas na elei\u00e7\u00e3o para presidente da Rep\u00fablica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/contas-de-campanha-podem-ser-abertas-em-qualquer-instituicao-bancaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Contas de campanha podem ser abertas em qualquer institui\u00e7\u00e3o banc\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg","jetpack-related-posts":[{"id":33216,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/financiamento-coletivo-de-campanhas-comeca-amanha-15-de-maio\/","url_meta":{"origin":5119,"position":0},"title":"Financiamento coletivo de campanhas come\u00e7a amanh\u00e3, 15 de maio","author":"Di\u00e1rio de Ouro Preto","date":"14 de Maio de 2024","format":false,"excerpt":"Saiba como funciona essa modalidade de arrecada\u00e7\u00e3o de recursos para campanhas eleitorais A partir do dia 15 de maio est\u00e1 permitida a arrecada\u00e7\u00e3o de recursos para financiamento coletivo de campanhas conhecida como \u201cvaquinha virtual\u201d. Essa modalidade de financiamento permite angariar recursos para campanhas eleitorais, por meio de empresas habilitadas perante\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/50429036346_a9271a4327_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/50429036346_a9271a4327_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/50429036346_a9271a4327_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/50429036346_a9271a4327_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/10\/50429036346_a9271a4327_o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35087,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquinho-de-politica-calendario-eleitoral-as-convencoes-partidarias-vem-ai-carta-ao-eleitor\/","url_meta":{"origin":5119,"position":1},"title":"[Coluna Tiquinho de Pol\u00edtica] Calend\u00e1rio Eleitoral: As\u00a0 conven\u00e7\u00f5es partid\u00e1rias vem a\u00ed! Carta ao Eleitor\u00a0","author":"Di\u00e1rio de Ouro Preto","date":"30 de Junho de 2024","format":false,"excerpt":"Ouro Preto - O calend\u00e1rio eleitoral tem muitas atividades neste m\u00eas de julho. A data que nos chamou a aten\u00e7\u00e3o \u00e9\u00a0 o dia 8\/07, uma segunda-feira, na qual se comemora o anivers\u00e1rio de Ouro Preto, que marca os 90 dias exatos para o domingo 6 de outubro, quando ser\u00e3o conhecidos\u2026","rel":"","context":"In &quot;Coluna&quot;","block_context":{"text":"Coluna","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/coluna\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/logo-eleicoes-2024.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/logo-eleicoes-2024.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/logo-eleicoes-2024.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/logo-eleicoes-2024.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4768,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/candidatos-a-prefeito-de-ouro-preto-poderao-gastar-ate-r-443-12279-em-suas-campanhas\/","url_meta":{"origin":5119,"position":2},"title":"Candidatos a prefeito de Ouro Preto poder\u00e3o gastar at\u00e9 R$ 504.802,71 em suas campanhas","author":"Di\u00e1rio de Ouro Preto","date":"2 de Setembro de 2020","format":false,"excerpt":"J\u00e1 est\u00e3o dispon\u00edveis, no portal do Tribunal Superior Eleitoral (TSE,) os limites de gastos que os candidatos aos cargos de prefeito e vereador dever\u00e3o respeitar, em suas respectivas campanhas, para concorrer nas Elei\u00e7\u00f5es Municipais de 2020, atendendo ao que determina a Lei das Elei\u00e7\u00f5es (Lei n\u00ba 9.504\/1997). Em Ouro Preto,\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/P1370105.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/P1370105.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/P1370105.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":45375,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bancos-passam-a-oferecer-pix-automatico-a-partir-desta-segunda\/","url_meta":{"origin":5119,"position":3},"title":"Bancos passam a oferecer Pix Autom\u00e1tico a partir desta segunda","author":"Di\u00e1rio de Ouro Preto","date":"16 de Junho de 2025","format":false,"excerpt":"Nova modalidade pretende substituir d\u00e9bito autom\u00e1tico e boletos \u00a0Com a promessa de substituir o d\u00e9bito autom\u00e1tico e os boletos, o Pix autom\u00e1tico entra em vigor nesta segunda-feira (16). Extens\u00e3o do Pix, a ferramenta permite ao usu\u00e1rio autorizar pagamentos peri\u00f3dicos a empresas e prestadores de servi\u00e7os, como microempreendedores individuais (MEI).\u00a0O cliente\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/mg_5213.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/mg_5213.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/mg_5213.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/mg_5213.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/mg_5213.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41373,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-esclarece-que-nao-cobrara-imposto-por-pix\/","url_meta":{"origin":5119,"position":4},"title":"Receita esclarece que n\u00e3o cobrar\u00e1 imposto por Pix","author":"Di\u00e1rio de Ouro Preto","date":"9 de Janeiro de 2025","format":false,"excerpt":"Opera\u00e7\u00f5es acima de R$ 5 mil devem ser informadas a partir deste m\u00eas O refor\u00e7o na fiscaliza\u00e7\u00e3o de transfer\u00eancias via Pix e cart\u00e3o de cr\u00e9dito n\u00e3o significa cria\u00e7\u00e3o de impostos, esclareceu a Receita Federal. Em comunicado, o Fisco desmentiu informa\u00e7\u00f5es falsas que circularam nas redes sociais nos \u00faltimos dias sobre\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52013,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/demonstrativo-financeiro-efi-s-a-instituicao-de-pagamentos-2025\/","url_meta":{"origin":5119,"position":5},"title":"Demonstrativo financeiro Ef\u00ed S.A. \u2013 Institui\u00e7\u00e3o de Pagamentos 2025","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2026","format":false,"excerpt":"Aviso As demonstra\u00e7\u00f5es financeiras apresentadas a seguir s\u00e3o demonstra\u00e7\u00f5es financeiras resumidas e n\u00e3o devem ser consideradas isoladamente para a tomada de decis\u00e3o. O entendimento da situa\u00e7\u00e3o financeira e patrimonial da companhia demanda a leitura das demonstra\u00e7\u00f5es financeiras completas auditadas, elaboradas na forma da legisla\u00e7\u00e3o societ\u00e1ria e da regulamenta\u00e7\u00e3o cont\u00e1bil aplic\u00e1vel.\u2026","rel":"","context":"In &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/unnamed.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/unnamed.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/unnamed.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=5119"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/5119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/3318"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=5119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=5119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=5119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}