{"id":4976,"date":"2020-09-14T16:30:23","date_gmt":"2020-09-14T19:30:23","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4976"},"modified":"2020-09-14T16:30:26","modified_gmt":"2020-09-14T19:30:26","slug":"bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/","title":{"rendered":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas"},"content":{"rendered":"<p>As micro e pequenas empresas mineiras ter\u00e3o \u00e0 disposi\u00e7\u00e3o mais R$ 68 milh\u00f5es em recursos operados pelo&nbsp;<a href=\"http:\/\/www.bdmg.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Banco de Desenvolvimento de Minas Gerais (BDMG)<\/a>, por meio do Pronampe &#8211; Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte.<\/p>\n\n\n\n<p>O limite de recursos anterior \u2013 disponibilizado ao banco pelo governo federal, nesta atual 2\u00aa fase do programa, era de R$ 203 milh\u00f5es. Com o aditivo, o novo limite passar\u00e1 para R$ 271 milh\u00f5es.&nbsp;<br><br>Na 1\u00aa fase da oferta do Pronampe, ocorrida em junho e julho, o BDMG havia liberado 100% do limite de R$ 215 milh\u00f5es que lhe foi garantido. \u201cEste novo limite demonstra que o BDMG tem alocado com efici\u00eancia seus recursos e representa mais um fluxo de liquidez para os pequenos empreendedores reestruturarem seus neg\u00f3cios e planejarem o futuro\u201d, afirma o presidente do banco, Sergio Gusm\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Cr\u00e9dito no BDMG<\/strong><\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Como diferencial na opera\u00e7\u00e3o da linha, o BDMG n\u00e3o exige a contrata\u00e7\u00e3o de outros produtos para ter acesso ao cr\u00e9dito, como ocorre em muitos bancos comerciais, nem a necessidade de abertura de conta banc\u00e1ria. A contrata\u00e7\u00e3o pode ser feita on-line,\u00a0<a href=\"http:\/\/www.bdmg.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">no site do banco<\/a>,\u00a0ou por meio de seus correspondentes banc\u00e1rios. \u00a0<br><br>O Pronampe opera com juros de apenas 1,25% ao ano + Selic, com prazo total de 36 meses para pagar, sendo oito meses de car\u00eancia. O cr\u00e9dito pode ser aplicado em capital de giro ou em investimentos. J\u00e1 o limite para solicita\u00e7\u00e3o \u00e9 de 30% da receita bruta da empresa em 2019, sendo o valor m\u00e1ximo, estabelecido pela Uni\u00e3o, de R$ 100 mil por empresa.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria de Imprensa BDMG<\/p>","protected":false},"excerpt":{"rendered":"<p>As micro e pequenas empresas mineiras ter\u00e3o \u00e0 disposi\u00e7\u00e3o mais R$ 68 milh\u00f5es em recursos operados pelo&nbsp;Banco de Desenvolvimento de Minas Gerais (BDMG), por meio do Pronampe &#8211; Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte. O limite de recursos anterior \u2013 disponibilizado ao banco pelo governo<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-4976","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T19:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-14T19:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas\",\"datePublished\":\"2020-09-14T19:30:23+00:00\",\"dateModified\":\"2020-09-14T19:30:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/\"},\"wordCount\":286,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bdmg-e1592345576846.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/\",\"name\":\"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bdmg-e1592345576846.jpg\",\"datePublished\":\"2020-09-14T19:30:23+00:00\",\"dateModified\":\"2020-09-14T19:30:26+00:00\",\"description\":\"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bdmg-e1592345576846.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bdmg-e1592345576846.jpg\",\"width\":304,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto","description":"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/","og_locale":"pt_PT","og_type":"article","og_title":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto","og_description":"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-09-14T19:30:23+00:00","article_modified_time":"2020-09-14T19:30:26+00:00","og_image":[{"width":304,"height":280,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas","datePublished":"2020-09-14T19:30:23+00:00","dateModified":"2020-09-14T19:30:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/"},"wordCount":286,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/","url":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/","name":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","datePublished":"2020-09-14T19:30:23+00:00","dateModified":"2020-09-14T19:30:26+00:00","description":"Uni\u00e3o ampliou de R$ 203 mi para R$ 271 mi o limite de recursos para o banco operar nesta 2\u00aa fase do Pronampe","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","width":304,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/bdmg-anuncia-r-68-milhoes-adicionais-em-credito-para-micro-e-pequenas-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"BDMG anuncia R$ 68 milh\u00f5es adicionais em cr\u00e9dito para micro e pequenas empresas"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg","jetpack-related-posts":[{"id":4738,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-abre-cadastro-para-2a-fase-do-pronampe-e-anuncia-nova-linha-de-credito-para-pequenas-empresas\/","url_meta":{"origin":4976,"position":0},"title":"BDMG abre cadastro para 2\u00aa fase do Pronampe e anuncia nova linha de cr\u00e9dito para pequenas empresas","author":"Di\u00e1rio de Ouro Preto","date":"31 de Agosto de 2020","format":false,"excerpt":"Com a previs\u00e3o de\u00a0o\u00a0governo\u00a0federal iniciar a opera\u00e7\u00e3o da 2\u00aa fase do Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte (Pronampe)\u00a0nesta ter\u00e7a-feira (1\/9), o\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0antecipou o cadastro para as micro e pequenas empresas de Minas Gerais interessadas em obter cr\u00e9dito. As inscri\u00e7\u00f5es podem\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9183,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-abre-credito-de-r-339-milhoes-e-anuncia-condicoes-especiais\/","url_meta":{"origin":4976,"position":1},"title":"BDMG abre cr\u00e9dito de R$ 339 milh\u00f5es e anuncia condi\u00e7\u00f5es especiais","author":"Di\u00e1rio de Ouro Preto","date":"12 de Julho de 2021","format":false,"excerpt":"O\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0abriu cadastro para micro e pequenas empresas de Minas Gerais interessadas em obter cr\u00e9dito por meio do Programa Nacional de Apoio \u00e0s Microempresas e Empresas de Pequeno Porte (Pronampe). Nesta fase do programa, est\u00e3o sendo colocados \u00e0 disposi\u00e7\u00e3o, inicialmente, R$ 339 milh\u00f5es, garantidos ao\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":22894,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-reduz-taxas-e-oferece-credito-especial-para-micro-e-pequenas-empresas\/","url_meta":{"origin":4976,"position":2},"title":"BDMG reduz taxas e oferece cr\u00e9dito especial para micro e pequenas empresas","author":"Di\u00e1rio de Ouro Preto","date":"2 de Maio de 2023","format":false,"excerpt":"Com o objetivo de ampliar o apoio \u00e0s micro e pequenas empresas (MPEs) mineiras, que geram emprego e renda, fortalecendo a economia, o\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0reduziu as taxas e oferece, a partir desta ter\u00e7a-feira (2\/5), condi\u00e7\u00f5es especiais de cr\u00e9dito. As MPE poder\u00e3o contratar financiamentos pagando 5% ao\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2705,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","url_meta":{"origin":4976,"position":3},"title":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19","author":"Di\u00e1rio de Ouro Preto","date":"8 de Abril de 2020","format":false,"excerpt":"Belo Horizonte - Diante do contexto socioecon\u00f4mico desafiador gerado pela Covid-19, o\u00a0Banco de Desenvolvimento de Minas gerais (BDMG)\u00a0estruturou um plano de a\u00e7\u00e3o que vai oferecer cr\u00e9dito e tornar as condi\u00e7\u00f5es ainda mais acess\u00edveis para as empresas, especialmente as micro e pequenas (MPEs). A meta \u00e9 disponibilizar cr\u00e9dito de at\u00e9 R$\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28130,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-reduz-as-taxas-de-financiamento-para-micro-e-pequenas-empresas-mineiras\/","url_meta":{"origin":4976,"position":4},"title":"BDMG reduz as taxas de financiamento para micro e pequenas empresas mineiras","author":"Di\u00e1rio de Ouro Preto","date":"5 de Fevereiro de 2024","format":false,"excerpt":"A partir desta segunda-feira (5\/2), o\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0vai reduzir em 0.5 p.p as taxas dos financiamentos destinados aos micro e pequenos neg\u00f3cios mineiros.\u00a0Empresas com faturamento anual de at\u00e9 R$ 4,8 milh\u00f5es pagar\u00e3o 5,35% ao ano mais a Selic, com car\u00eancia de 12 meses e prazo total\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3061,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-de-minas-destina-r-274-mi-em-credito-para-as-prefeituras\/","url_meta":{"origin":4976,"position":5},"title":"Governo de Minas destina R$ 274 mi em cr\u00e9dito para as prefeituras","author":"Di\u00e1rio de Ouro Preto","date":"12 de Maio de 2020","format":false,"excerpt":"O governador Romeu Zema anunciou nesta ter\u00e7a-feira\u00a0(12\/5), na Cidade Administrativa, que o\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0alcan\u00e7ou a marca de R$ 274 milh\u00f5es em cr\u00e9dito contratado via Edital de Munic\u00edpios do bi\u00eanio 2019\/2020, montante 37% maior que a previs\u00e3o inicial de desembolso, que era de R$ 200 milh\u00f5es. Ao\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4976"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2271"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}