{"id":4962,"date":"2020-09-13T13:58:11","date_gmt":"2020-09-13T16:58:11","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4962"},"modified":"2020-09-13T13:58:19","modified_gmt":"2020-09-13T16:58:19","slug":"lotofacil-da-independencia-premio-sai-para-50-apostadores","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/","title":{"rendered":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores"},"content":{"rendered":"<p>O pr\u00eamio da Lotof\u00e1cil da Independ\u00eancia, sorteado no s\u00e1bado (12) em S\u00e3o Paulo, ser\u00e1 distribu\u00eddo entre 50 apostadores que acertaram os 15 n\u00fameros. Cada um faturou R$ 2.499.998,20.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1387780&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1387780&amp;o=node\"><\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Os n\u00fameros sorteados foram: 03, 22, 09, 14, 15, 17, 19, 10, 06, 23, 05, 12, 25, 02.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A Caixa tamb\u00e9m informou que 8.408 apostas acertaram 14 n\u00fameros e garantiram R$ 942,83. Outras 246.828 apostas&nbsp;acertaram 13 n\u00fameros e ficaram com R$ 25,00. Outras 2.702.658 apostas acertaram 12 n\u00fameros e receber\u00e3o R$ 10,00 de pr\u00eamio. E quem acertou 11 n\u00fameros (1.3506.290 apostas) tamb\u00e9m n\u00e3o ficou no preju\u00edzo e ficou com R$ 5,00.<\/p>","protected":false},"excerpt":{"rendered":"<p>O pr\u00eamio da Lotof\u00e1cil da Independ\u00eancia, sorteado no s\u00e1bado (12) em S\u00e3o Paulo, ser\u00e1 distribu\u00eddo entre 50 apostadores que acertaram os 15 n\u00fameros. Cada um faturou R$ 2.499.998,20. Os n\u00fameros sorteados foram: 03, 22, 09, 14, 15, 17, 19, 10, 06, 23, 05, 12, 25, 02. A Caixa tamb\u00e9m informou<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-4962","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-13T16:58:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-13T16:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores\",\"datePublished\":\"2020-09-13T16:58:11+00:00\",\"dateModified\":\"2020-09-13T16:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/\"},\"wordCount\":99,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1097422-img_3347.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/\",\"name\":\"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1097422-img_3347.jpg\",\"datePublished\":\"2020-09-13T16:58:11+00:00\",\"dateModified\":\"2020-09-13T16:58:19+00:00\",\"description\":\"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1097422-img_3347.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/1097422-img_3347.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Bras\u00edlia - O Caminh\u00e3o da Sorte da CAIXA sorteia o concurso 1.986 da Mega-Sena, valendo um pr\u00eamio de R$19 milh\u00f5es, na quadra 302 de Samambaia - DF (Wilson Dias\\\/Ag\u00eancia Brasil)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/lotofacil-da-independencia-premio-sai-para-50-apostadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto","description":"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/","og_locale":"pt_PT","og_type":"article","og_title":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto","og_description":"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-09-13T16:58:11+00:00","article_modified_time":"2020-09-13T16:58:19+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores","datePublished":"2020-09-13T16:58:11+00:00","dateModified":"2020-09-13T16:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/"},"wordCount":99,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/","name":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","datePublished":"2020-09-13T16:58:11+00:00","dateModified":"2020-09-13T16:58:19+00:00","description":"- Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores - Brasil","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","width":1170,"height":700,"caption":"Bras\u00edlia - O Caminh\u00e3o da Sorte da CAIXA sorteia o concurso 1.986 da Mega-Sena, valendo um pr\u00eamio de R$19 milh\u00f5es, na quadra 302 de Samambaia - DF (Wilson Dias\/Ag\u00eancia Brasil)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/lotofacil-da-independencia-premio-sai-para-50-apostadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Lotof\u00e1cil da Independ\u00eancia: pr\u00eamio sai para 50 apostadores"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1097422-img_3347.jpg","jetpack-related-posts":[{"id":10146,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-sorteia-r-3-milhoes-nesta-quarta-feira-25-08\/","url_meta":{"origin":4962,"position":0},"title":"MEGA-SENA SORTEIA R$ 3 MILH\u00d5ES NESTA QUARTA-FEIRA (25\/08)","author":"Di\u00e1rio de Ouro Preto","date":"24 de Agosto de 2021","format":false,"excerpt":"A Mega-Sena pode pagar R$ 3 milh\u00f5es nesta quarta-feira (25\/08), pelo concurso 2.403. O sorteio ser\u00e1 realizado a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o Loterias CAIXA, localizado no Terminal Rodovi\u00e1rio do Tiet\u00ea, em S\u00e3o Paulo (SP),\u00a0com transmiss\u00e3o ao vivo pelas redes sociais das Loterias CAIXA (perfil @LoteriasCAIXAOficial no\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25212,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-sorteia-nesta-quinta-feira-premio-acumulado-em-r-42-milhoes\/","url_meta":{"origin":4962,"position":1},"title":"Mega-Sena sorteia nesta quinta-feira pr\u00eamio acumulado em R$ 42 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"31 de Agosto de 2023","format":false,"excerpt":"As seis dezenas do concurso 2.627 da Mega-Sena ser\u00e3o sorteadas a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, localizado na Avenida Paulista, n\u00ba 750, na cidade de S\u00e3o Paulo (SP), com transmiss\u00e3o ao vivo pelo canal da Caixa no YouTube e no Facebook das Loterias Caixa. O\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/mega_sena_mcajr_abr_2904223680.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/mega_sena_mcajr_abr_2904223680.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/mega_sena_mcajr_abr_2904223680.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/mega_sena_mcajr_abr_2904223680.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/mega_sena_mcajr_abr_2904223680.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4504,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mega-sena-sorteia-nesta-quinta-feira-premio-de-r-125-milhoes\/","url_meta":{"origin":4962,"position":2},"title":"Mega-Sena sorteia nesta quinta-feira pr\u00eamio de R$ 12,5 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"13 de Agosto de 2020","format":false,"excerpt":"A Mega-Sena sorteia hoje (13) um pr\u00eamio acumulado de R$ 12,5 milh\u00f5es. As seis dezenas do \u00a0concurso 2.289 ser\u00e3o sorteadas, a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o Loterias Caixa, no Terminal Rodovi\u00e1rio Tiet\u00ea, na cidade de S\u00e3o Paulo. As apostas podem ser feitas at\u00e9 as 19h (hor\u00e1rio de\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/mcamg_abr_08052019_8678_1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21040,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/nenhum-apostador-acerta-mega-sena-e-premio-acumula-em-r-10-milhoes\/","url_meta":{"origin":4962,"position":3},"title":"Nenhum apostador acerta Mega-Sena e pr\u00eamio acumula em R$ 10 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"12 de Fevereiro de 2023","format":false,"excerpt":"A quina teve 49 ganhadores e a quadra 3.714 Nenhum apostador acertou as seis dezenas do concurso 2.563 da Mega-Sena sorteadas ontem (11), no Espa\u00e7o Loterias Caixa, em S\u00e3o Paulo. O pr\u00eamio acumulado para o pr\u00f3ximo sorteio (concurso 2.564), que ocorrer\u00e1 na ter\u00e7a-feira (14), est\u00e1 estimado em R$ 10 milh\u00f5es.\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/mega_sena-111220202168.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19807,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/nenhum-apostador-acerta-mega-sena-e-premio-acumula-em-r-135-milhoes\/","url_meta":{"origin":4962,"position":4},"title":"Nenhum apostador acerta Mega-Sena e pr\u00eamio acumula em R$ 135 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"11 de Dezembro de 2022","format":false,"excerpt":"A quina teve 100 ganhadores e a quadra 8.588 Nenhum apostador acertou as seis dezenas do concurso 2.547 da Mega-Sena sorteadas ontem (10), no Espa\u00e7o Loterias Caixa, em S\u00e3o Paulo.O pr\u00eamio acumulado para o pr\u00f3ximo sorteio (concurso 2.548), que ocorrer\u00e1 na quarta-feira (14), est\u00e1 estimado em R$ 135 milh\u00f5es.Os n\u00fameros\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/12\/mega_sena_mcajr_abr_2904223676.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/12\/mega_sena_mcajr_abr_2904223676.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/12\/mega_sena_mcajr_abr_2904223676.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/12\/mega_sena_mcajr_abr_2904223676.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/12\/mega_sena_mcajr_abr_2904223676.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18477,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/nenhum-apostador-acerta-mega-sena-e-premio-acumula-em-r-150-milhoes\/","url_meta":{"origin":4962,"position":5},"title":"Nenhum apostador acerta Mega-Sena e pr\u00eamio acumula em R$ 150 milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"18 de Setembro de 2022","format":false,"excerpt":"Nenhum apostador acertou as seis dezenas do concurso 2.521 da Mega-Sena sorteadas ontem (17), no Espa\u00e7o Loterias Caixa, em S\u00e3o Paulo. O pr\u00eamio acumulado para o pr\u00f3ximo sorteio (concurso 2.522), que ocorrer\u00e1 na quarta-feira (21), est\u00e1 estimado em R$ 150 milh\u00f5es. Os n\u00fameros sorteados foram 23 \u2013 28 \u2013 33\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/megasenadsc_5258.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4962"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4963"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}