{"id":4958,"date":"2020-09-12T09:40:32","date_gmt":"2020-09-12T12:40:32","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4958"},"modified":"2020-09-12T09:40:38","modified_gmt":"2020-09-12T12:40:38","slug":"especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/","title":{"rendered":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia"},"content":{"rendered":"<p>Os dados de cont\u00e1gio por covid-19 se mantiveram constantes em um n\u00edvel ainda alto ou mesmo tenderam a aumentar com a flexibiliza\u00e7\u00e3o do isolamento social, a reabertura dos setores econ\u00f4micos e o consequente aumento da mobilidade das pessoas, a partir de junho. Estas consequ\u00eancias foram debatidas por cientistas no evento \u201cO Brasil ap\u00f3s seis meses de pandemia da Covid-19 &#8211; I Ciclo de Debates do Observat\u00f3rio Covid-19\u201d, promovido pela Funda\u00e7\u00e3o Oswaldo Cruz, que come\u00e7ou essa semana.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1387712&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1387712&amp;o=node\"><\/p>\n\n\n\n<p>Na apresenta\u00e7\u00e3o \u201cOs cen\u00e1rios epidemiol\u00f3gicos no Brasil: tend\u00eancias e impactos na sociedade\u201d, o coordenador do programa de Computa\u00e7\u00e3o Cient\u00edfica da Fiocruz, Daniel Villela, mostrou que a curva de cont\u00e1gio no pa\u00eds saiu do padr\u00e3o esperado para uma epidemia, que normalmente tem um crescimento muito r\u00e1pido e depois cai de forma constante. Os dados s\u00e3o do InfoGripe (<a href=\"http:\/\/info.gripe.fiocruz.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">http:\/\/info.gripe.fiocruz.br\/<\/a>), que monitora as interna\u00e7\u00f5es no pa\u00eds por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG).<\/p>\n\n\n\n<p>Os gr\u00e1ficos do Observat\u00f3rio Fluminense Covid-19 (<a href=\"https:\/\/www.covid19rj.org\/home\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">https:\/\/www.covid19rj.org\/home<\/a>) mostram que Amap\u00e1, Rio Grande do Norte e Sergipe est\u00e3o em verde, \u201cvencendo\u201d a pandemia na an\u00e1lise de n\u00famero de casos por semana, de acordo com a classifica\u00e7\u00e3o \u201csem\u00e1foro\u201d feita pelos pesquisadores. Ainda est\u00e3o com alerta vermelho o Distrito Federal, Goi\u00e1s, Mato Grosso, Mato Grosso do Sul, Minas Gerais, Paran\u00e1, Piau\u00ed, Rio Grande do Sul, S\u00e3o Paulo e Tocantins, al\u00e9m do Brasil como um todo. Os demais estados est\u00e3o com a curva em amarelo, a maioria fazendo esse desenho para o lado em um patamar alto de contamina\u00e7\u00e3o.<\/p>\n\n\n\n<p>Sobre as medidas iniciais de isolamento social, a partir de meados de mar\u00e7o, o pesquisador diz que os gr\u00e1ficos refletem os impactos positivos, apesar de n\u00e3o terem sido capazes de frear completamente a ascens\u00e3o da curva de cont\u00e1gio.<\/p>\n\n\n\n<p>\u201cA partir da semana epidemiol\u00f3gica 12, em meados de mar\u00e7o, quando foram tomadas as decis\u00f5es de restringir a mobilidade voc\u00ea tem esse crescimento de SRAG, mas tem uma mudan\u00e7a no padr\u00e3o bem claro e depois continua crescendo. A curva mostra um efeito dessas medidas de distanciamento social\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sistema de informa\u00e7\u00e3o<\/h2>\n\n\n\n<p>Segundo Villela, o Sistema de Informa\u00e7\u00e3o da Vigil\u00e2ncia Epidemiol\u00f3gica da Gripe (Sivep-Gripe), que gera o Boletim InfoGripe, registra que mais de 95% dos casos com confirma\u00e7\u00e3o da doen\u00e7a que levaram \u00e0 interna\u00e7\u00e3o por SRAG no ano s\u00e3o do v\u00edrus SARS-Cov-2, causador da covid-19. Os dados mostram um maior n\u00famero de casos de SRAG entre idosos em 2020, quando em anos anteriores as crian\u00e7as aparecem em maior n\u00famero.<\/p>\n\n\n\n<p>O pesquisador destacou tamb\u00e9m o trabalho do Observat\u00f3rio Covid-19 da Fiocruz que mostrou uma maior vulnerabilidade para a doen\u00e7a entre as popula\u00e7\u00f5es ind\u00edgenas e moradores de favelas; o padr\u00e3o de dispers\u00e3o do v\u00edrus no pa\u00eds por meio de sequenciamento gen\u00e9tico; e definiu crit\u00e9rios que poderiam ser seguidos para a retomada das atividades.<\/p>\n\n\n\n<p>\u201cO que n\u00f3s podemos esperar atualmente \u00e9 ver, essa quest\u00e3o da imunidade individual das pessoas e a imunidade de grupo, se h\u00e1 um n\u00famero suficiente de pessoas imunes para garantir a diminui\u00e7\u00e3o do n\u00famero de casos para lidar melhor com a pandemia. A quest\u00e3o da efic\u00e1cia das vacinas e a log\u00edstica para vacinar toda a popula\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Ele afirma que a epidemia n\u00e3o passou e que a flexibiliza\u00e7\u00e3o deve ser local, gradual e coordenada entre todos os n\u00edveis de governo e entidades.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/kSVNFCFa-PqGZMadVgIX4FULhTQ=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/17_07_2020_covid_testes_exame-2.jpg?itok=BQYY0tWe\" alt=\"Uso de m\u00e1scara para prote\u00e7\u00e3o contra o novo coronav\u00edrus.\" title=\"Ricardo Wolffenbuttel\/Governo de SC\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Uso de m\u00e1scara para prote\u00e7\u00e3o contra o novo coronav\u00edrus. &#8211;&nbsp;<strong>Ricardo Wolffenbuttel\/Governo de SC<\/strong><\/h6>\n\n\n\n<h2 class=\"wp-block-heading\">Desafio de uma gera\u00e7\u00e3o<\/h2>\n\n\n\n<p>O pesquisador Guilherme Werneck, do Instituto de Sa\u00fade Coletiva da Universidade Federal do Rio de Janeiro (UFRJ), destacou que a pandemia de covid-19 \u00e9 \u201co maior desafio da nossa gera\u00e7\u00e3o\u201d, por motivos como o r\u00e1pido espalhamento do v\u00edrus, a taxa de letalidade relativamente alta, a falta de vacina e de conhecimento sobre tratamentos eficazes, a inefici\u00eancia inicial dos testes diagn\u00f3sticos e tamb\u00e9m a falta de suprimentos m\u00e9dicos e de equipamentos de prote\u00e7\u00e3o individual.<\/p>\n\n\n\n<p>Apesar de tudo isso, ele afirma que uma pandemia desse n\u00edvel n\u00e3o foi uma surpresa para os epidemiologistas, que deram v\u00e1rios alertas nesse sentido&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2019-09\/especialistas-alertam-para-risco-de-pandemias-globais\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2019-09\/especialistas-alertam-para-risco-de-pandemias-globais<\/a>).<\/p>\n\n\n\n<p>\u201cEstava claro para todos que trabalham com doen\u00e7a infecciosa que uma pandemia por um pat\u00f3geno desconhecido era uma quest\u00e3o de tempo. Ent\u00e3o a prepara\u00e7\u00e3o para esta situa\u00e7\u00e3o era obviamente necess\u00e1ria no mundo inteiro\u201d.<\/p>\n\n\n\n<p>Para ele, o Brasil tinha condi\u00e7\u00f5es de ter se preparado melhor, ap\u00f3s o aprendizado tido com a epidemia de influenza de 2009, o desenvolvimento do Infogripe, o reconhecimento internacional pelos sistemas de informa\u00e7\u00e3o de qualidade e alta cobertura, a quantidade de pesquisa cient\u00edfica b\u00e1sica e aplicada, al\u00e9m do sistema de vigil\u00e2ncia epidemiol\u00f3gica inserido no Sistema \u00danico de Sa\u00fade, com capacidade de resposta epidemiol\u00f3gica e assistencial para uma pandemia.<\/p>\n\n\n\n<p>\u201c\u00c9 de certa forma constrangedor que n\u00f3s tenhamos chegado numa situa\u00e7\u00e3o em que existia uma ideia de como essa resposta deveria ser dada, que o pa\u00eds tenha enfrentado essa pandemia de uma forma n\u00e3o t\u00e3o ideal como poderia\u201d.<\/p>\n\n\n\n<p>De acordo com Werneck, os esfor\u00e7os deveriam ter sido tamb\u00e9m no sentido de limitar a expans\u00e3o da epidemia no territ\u00f3rio, salvar vidas, garantir prote\u00e7\u00e3o e seguran\u00e7a para os setores econ\u00f4micos e sociais mais vulner\u00e1veis, al\u00e9m de se preparar para o futuro. O pesquisador destaca tamb\u00e9m como equ\u00edvocos a \u00eanfase na aten\u00e7\u00e3o hospitalar e na necessidade de testagem. Para ele, a resposta brasileira falhou na maior parte dessas fases.<\/p>\n\n\n\n<p>\u201cAs estrat\u00e9gias de conten\u00e7\u00e3o foram insuficientes, como foram em muitos pa\u00edses. As estrat\u00e9gias de mitiga\u00e7\u00e3o, depois que a transmiss\u00e3o sustentada comunit\u00e1ria aconteceu, tamb\u00e9m foram insuficientes\u201d.<\/p>\n\n\n\n<p>Pelo lado positivo, Werneck lembra do trabalho engajado da comunidade cient\u00edfica brasileira, que articulou v\u00e1rias institui\u00e7\u00f5es nas a\u00e7\u00f5es de enfrentamento.<\/p>\n\n\n\n<p>Para o pesquisador, o n\u00famero atual de \u00f3bitos por dia no pa\u00eds por covid-19, na faixa de 800, est\u00e1 em um n\u00edvel \u201cinadmiss\u00edvel\u201d para se fazer o relaxamento das medidas n\u00e3o farmacol\u00f3gicas e que \u00e9 cedo para se falar em reabertura das escolas.<\/p>\n\n\n\n<p>O pesquisador Thomas Mellan, do Imperial College London, afirmou que os dados do Brasil, principalmente os do Sivep-Gripe, auxiliaram os cientistas estrangeiros a melhorarem a an\u00e1lise dos dados mundiais.<\/p>\n\n\n\n<p>\u201c\u00c9 uma ferramenta incr\u00edvel, vem do SUS brasileiro, e essencialmente registra os casos respirat\u00f3rios numa popula\u00e7\u00e3o de mais de 200 milh\u00f5es de pessoas. No trabalho inicial todo mundo tentava analisar os dados da China, com um n\u00famero muito pequeno de pontos de dados. Temos diferen\u00e7as entre a China a Europa e o Brasil. Utilizando os dados brasileiros, conseguimos reajustar essa distribui\u00e7\u00e3o, utilizando muito mais dados\u201d.<\/p>\n\n\n\n<p>De acordo com ele, entre as contribui\u00e7\u00f5es dos dados brasileiros est\u00e1 a mudan\u00e7a de entendimento sobre o tempo entre o surgimento dos sintomas at\u00e9 o \u00f3bito do paciente, que com os dados chineses era considerado 18 dias e passou para entre 15 a 16 dias.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/Wevaxya0WjYNvjvznXu4t3M5DfM=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?itok=VrMzxnaj\" alt=\"Fachada do Minist\u00e9rio da Sa\u00fade na Esplanada dos Minist\u00e9rios\" title=\"Marcello Casal JrAg\u00eancia Brasil\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Minist\u00e9rio da Sa\u00fade&nbsp; informou que atua \u201cpermanentemente para preven\u00e7\u00e3o de doen\u00e7as\u201d &#8211;&nbsp;<strong>Marcello Casal JrAg\u00eancia Brasil<\/strong><\/h6>\n\n\n\n<h2 class=\"wp-block-heading\">Minist\u00e9rio da Sa\u00fade<\/h2>\n\n\n\n<p>Procurado, o Minist\u00e9rio da Sa\u00fade informou que atua \u201cpermanentemente para preven\u00e7\u00e3o de doen\u00e7as\u201d no pa\u00eds, com \u201cpesquisas, medidas preventivas, campanhas de vacina\u00e7\u00e3o, tratamentos especializados\u201d para \u201cevitar a dissemina\u00e7\u00e3o ou qualquer outro efeito na sa\u00fade da popula\u00e7\u00e3o\u201d. At\u00e9 o momento, foram empenhados R$ 31,9 bilh\u00f5es para a\u00e7\u00f5es exclusivas de enfrentamento \u00e0 pandemia, al\u00e9m de R$ 83,9 bilh\u00f5es em repasses para os estados e munic\u00edpio.<\/p>\n\n\n\n<p>\u201cA pandemia da Covid-19 foi prontamente abordada pela pasta logo que surgiram os primeiros sinais do surto da doen\u00e7a no mundo. Desde o in\u00edcio, foram disponibilizados apoio irrestrito aos estados e munic\u00edpios na compra e entrega de ventiladores pulmonares, equipamentos de prote\u00e7\u00e3o individual (EPI), medicamentos, al\u00e9m da habilita\u00e7\u00e3o de leitos de UTI e o envio de profissionais de sa\u00fade para apoiar os atendimentos\u201d, informa o minist\u00e9rio.<\/p>\n\n\n\n<p>Em nota enviada \u00e0&nbsp;<strong>Ag\u00eancia Brasil<\/strong>, a pasta afirma tamb\u00e9m que implementou Centros Comunit\u00e1rios nas \u00e1reas de maior vulnerabilidade social, como comunidades e favelas.<\/p>\n\n\n\n<p>\u201cO Minist\u00e9rio tamb\u00e9m direcionou equipes multidisciplinares de sa\u00fade ind\u00edgena para intensificar a distribui\u00e7\u00e3o de suprimentos, insumos, testes r\u00e1pidos e equipamentos de prote\u00e7\u00e3o individual aos 34 Distritos Sanit\u00e1rios Especiais Ind\u00edgenas (DSEIs). Para oferecer atendimento r\u00e1pido em situa\u00e7\u00f5es de emerg\u00eancia tamb\u00e9m foi autorizado a contrata\u00e7\u00e3o de Equipes de Resposta R\u00e1pida (ERR) para atuar em cada DSEI\u201d.<\/p>\n\n\n\n<p>O Minist\u00e9rio afirma, ainda, que tem acompanhado mais de 200 estudos \u201cque buscam a identifica\u00e7\u00e3o de uma vacina eficaz, segura e em quantidade suficiente para imunizar os brasileiros\u201d.<\/p>\n\n\n\n<p>Por Akemi Nitahara &#8211; Rio de Janeiro<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: Mario Toledo<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Foto: Amanda Perobelli\/Reuters<\/p>","protected":false},"excerpt":{"rendered":"<p>Os dados de cont\u00e1gio por covid-19 se mantiveram constantes em um n\u00edvel ainda alto ou mesmo tenderam a aumentar com a flexibiliza\u00e7\u00e3o do isolamento social, a reabertura dos setores econ\u00f4micos e o consequente aumento da mobilidade das pessoas, a partir de junho. Estas consequ\u00eancias foram debatidas por cientistas no evento<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61],"tags":[],"class_list":["entry","author-diario","post-4958","post","type-post","status-publish","format-standard","has-post-thumbnail","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-12T12:40:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-12T12:40:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia\",\"datePublished\":\"2020-09-12T12:40:32+00:00\",\"dateModified\":\"2020-09-12T12:40:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/\"},\"wordCount\":1571,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/\",\"name\":\"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg\",\"datePublished\":\"2020-09-12T12:40:32+00:00\",\"dateModified\":\"2020-09-12T12:40:38+00:00\",\"description\":\"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto","description":"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/","og_locale":"pt_PT","og_type":"article","og_title":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto","og_description":"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-09-12T12:40:32+00:00","article_modified_time":"2020-09-12T12:40:38+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia","datePublished":"2020-09-12T12:40:32+00:00","dateModified":"2020-09-12T12:40:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/"},"wordCount":1571,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/","url":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/","name":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","datePublished":"2020-09-12T12:40:32+00:00","dateModified":"2020-09-12T12:40:38+00:00","description":"Flexibiliza\u00e7\u00e3o social se reflete em tend\u00eancias de alta no cont\u00e1gio","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/especialistas-avaliam-situacao-do-pais-apos-seis-meses-de-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Especialistas avaliam situa\u00e7\u00e3o do pa\u00eds ap\u00f3s seis meses de pandemia"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/2020-06-10t180831z_1128208464_rc2i6h981x45_rtrmadp_3_health-coronavirus-brazil.jpg","jetpack-related-posts":[{"id":5802,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/casos-diarios-de-covid-19-se-aproximam-do-pico-de-julho-no-brasil\/","url_meta":{"origin":4958,"position":0},"title":"Casos di\u00e1rios de covid-19  se aproximam do pico de julho no Brasil","author":"Di\u00e1rio de Ouro Preto","date":"14 de Dezembro de 2020","format":false,"excerpt":"Desde o in\u00edcio de novembro, os casos de covid-19 no Brasil voltaram a subir e est\u00e3o quase no mesmo n\u00edvel do pico de julho, em novos casos di\u00e1rios na m\u00e9dia m\u00f3vel de sete dias. Os dados s\u00e3o do Monitora Covid-19, do Instituto de Comunica\u00e7\u00e3o e Informa\u00e7\u00e3o Cient\u00edfica e Tecnol\u00f3gica em\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/17_07_2020_covid_testes_exame-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/17_07_2020_covid_testes_exame-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/17_07_2020_covid_testes_exame-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/17_07_2020_covid_testes_exame-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/17_07_2020_covid_testes_exame-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4545,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/taxa-de-contagio-em-torno-de-1-sinaliza-estabilizacao-da-covid-19-em-minas\/","url_meta":{"origin":4958,"position":1},"title":"Taxa de cont\u00e1gio em torno de 1 sinaliza estabiliza\u00e7\u00e3o da covid-19 em Minas","author":"Di\u00e1rio de Ouro Preto","date":"15 de Agosto de 2020","format":false,"excerpt":"Pela primeira vez no transcorrer da pandemia em Minas Gerais, a taxa de transmiss\u00e3o da covid-19 (Rt) no estado oscila com resultado pr\u00f3ximo de 1 durante duas semanas. Desde o in\u00edcio de agosto, o indicador varia entre 0,95 e 1,07 o que significa que uma pessoa contaminada pelo novo coronav\u00edrus\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/MG_7255-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/MG_7255-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/MG_7255-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/MG_7255-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/MG_7255-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19472,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-retoma-medidas-de-seguranca-para-evitar-novo-avanco-da-covid-19\/","url_meta":{"origin":4958,"position":2},"title":"Ouro Preto retoma medidas de seguran\u00e7a para evitar novo avan\u00e7o da Covid-19","author":"Di\u00e1rio de Ouro Preto","date":"21 de Novembro de 2022","format":false,"excerpt":"Victor Stutz, para o Di\u00e1rio de Ouro Preto A Secretaria Municipal de Sa\u00fade anunciou hoje, segunda-feira, 21\/11, a retomada de algumas medidas de seguran\u00e7a contra a Covid-19. A primeira recomenda\u00e7\u00e3o \u00e9 a atualiza\u00e7\u00e3o do cart\u00e3o de vacina\u00e7\u00e3o, todos aqueles que ainda n\u00e3o completaram o quadro vacinal devem procurar as Unidades\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/Imagem-do-WhatsApp-de-2022-11-21-as-14.06.38.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/Imagem-do-WhatsApp-de-2022-11-21-as-14.06.38.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/Imagem-do-WhatsApp-de-2022-11-21-as-14.06.38.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/Imagem-do-WhatsApp-de-2022-11-21-as-14.06.38.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12021,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/criancas-arcam-com-o-pior-da-covid-19-dizem-estudos-do-vaticano\/","url_meta":{"origin":4958,"position":3},"title":"Crian\u00e7as arcam com o pior da covid-19, dizem estudos do Vaticano","author":"Di\u00e1rio de Ouro Preto","date":"22 de Dezembro de 2021","format":false,"excerpt":"As crian\u00e7as de todo o mundo est\u00e3o arcando com o pior da pandemia de covid-19, sendo alvo de aumentos acentuados de viol\u00eancia, abuso, trabalho infantil, evas\u00e3o escolar e desnutri\u00e7\u00e3o, revelam dois estudos do Vaticano divulgados hoje (22). As pesquisas, que se baseiam em dados acad\u00eamicos e cient\u00edficos, da Organiza\u00e7\u00e3o das\u2026","rel":"","context":"In &quot;Internacional&quot;","block_context":{"text":"Internacional","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/internacional\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/2021-12-22t191016z_1_lynxmpehbl0xa_rtroptp_4_saude-covid-criancas-vaticano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/2021-12-22t191016z_1_lynxmpehbl0xa_rtroptp_4_saude-covid-criancas-vaticano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/2021-12-22t191016z_1_lynxmpehbl0xa_rtroptp_4_saude-covid-criancas-vaticano.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/2021-12-22t191016z_1_lynxmpehbl0xa_rtroptp_4_saude-covid-criancas-vaticano.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/2021-12-22t191016z_1_lynxmpehbl0xa_rtroptp_4_saude-covid-criancas-vaticano.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10427,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-brasil-tem-mais-de-200-milhoes-de-doses-de-vacinas-aplicadas\/","url_meta":{"origin":4958,"position":4},"title":"Covid-19: Brasil tem mais de 200 milh\u00f5es de doses de vacinas aplicadas","author":"Di\u00e1rio de Ouro Preto","date":"5 de Setembro de 2021","format":false,"excerpt":"O Brasil ultrapassou a marca de 200 milh\u00f5es de doses de vacinas contra a covid-19 aplicadas, informou o Minist\u00e9rio da Sa\u00fade. At\u00e9 agora, s\u00e3o 134 milh\u00f5es de pessoas com a primeira dose e mais 66,5 milh\u00f5es com a imuniza\u00e7\u00e3o completa. Estudos recentes mostram que as vacinas\u00a0reduzem significativamente o risco de\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/09\/vacinao-contra-covid-19_51331657790_o_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/09\/vacinao-contra-covid-19_51331657790_o_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/09\/vacinao-contra-covid-19_51331657790_o_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/09\/vacinao-contra-covid-19_51331657790_o_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/09\/vacinao-contra-covid-19_51331657790_o_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3082,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/pesquisa-mostra-que-casos-confirmados-sao-35-dos-sintomaticos\/","url_meta":{"origin":4958,"position":5},"title":"Pesquisa mostra que casos confirmados s\u00e3o 35% dos sintom\u00e1ticos","author":"Di\u00e1rio de Ouro Preto","date":"13 de Maio de 2020","format":false,"excerpt":"Um modelo matem\u00e1tico desenvolvido por pesquisadores do Instituto Alberto Luiz Coimbra de P\u00f3s-Gradua\u00e7\u00e3o e Pesquisa de Engenharia (Coppe\/UFRJ) e da Universidade de Bordeaux (Fran\u00e7a) aponta que os casos confirmados de covid-19 no pa\u00eds s\u00e3o cerca de 35% dos indiv\u00edduos que tiveram infec\u00e7\u00f5es sintom\u00e1ticas pelo coronav\u00edrus. O percentual representa uma melhora\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/mascaras_rj_uso_obrigatorio_0424202567-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/mascaras_rj_uso_obrigatorio_0424202567-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/mascaras_rj_uso_obrigatorio_0424202567-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/mascaras_rj_uso_obrigatorio_0424202567-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/mascaras_rj_uso_obrigatorio_0424202567-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4958"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4959"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}