{"id":4643,"date":"2020-08-22T20:34:41","date_gmt":"2020-08-22T23:34:41","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4643"},"modified":"2020-08-22T20:34:44","modified_gmt":"2020-08-22T23:34:44","slug":"artigo-inovacao-aberta-na-mineracao","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/","title":{"rendered":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o"},"content":{"rendered":"<p><em>Alessandra Prata \u2013 engenheira especialista da Samarco<\/em><\/p>\n\n\n\n<p>Os \u00faltimos anos t\u00eam sido de grandes aprendizados para a Samarco e para todo o setor de minera\u00e7\u00e3o. Um dos principais \u00e9 sobre a import\u00e2ncia de as mineradoras se unirem para aprender, buscar solu\u00e7\u00f5es conjuntas para desafios comuns e, principalmente, de se aproximarem de outros atores ligados ao ecossistema de inova\u00e7\u00e3o e empreendedorismo que tanto podem contribuir para a evolu\u00e7\u00e3o da atividade.<\/p>\n\n\n\n<p>O conceito de inova\u00e7\u00e3o aberta, criado por Henry Chesbrough e bastante difundido no mundo acad\u00eamico e no setor de tecnologia, passou a ganhar cada vez mais espa\u00e7o tamb\u00e9m na minera\u00e7\u00e3o. Enquanto na inova\u00e7\u00e3o fechada a gera\u00e7\u00e3o de novas ideias e o desenvolvimento de solu\u00e7\u00f5es contam com pouco ou nenhum conhecimento externo e se limitam ao uso ou benef\u00edcio da empresa, com controle da propriedade intelectual, na inova\u00e7\u00e3o aberta esse processo ocorre de forma mais ampla e com a colabora\u00e7\u00e3o de diversos p\u00fablicos. Ganham espa\u00e7o a coopera\u00e7\u00e3o e o estabelecimento de parcerias com v\u00e1rias \u00e1reas internas da empresa e outros atores externos. A conex\u00e3o impulsiona o desenvolvimento. Dessa forma, os ganhos s\u00e3o m\u00fatuos: mais conhecimento, oportunidades e resultado para toda a sociedade.<\/p>\n\n\n\n<p>Tenho a oportunidade de acompanhar de perto dois projetos importantes alinhados a esse conceito: o Desafio MinerALL e o Mining Hub. O primeiro \u00e9 uma iniciativa da Samarco e Neo Ventures, que visa construir uma ponte entre as inova\u00e7\u00f5es e o mercado por meio do empreendedorismo.<\/p>\n\n\n\n<p>A primeira edi\u00e7\u00e3o do Desafio MinerALL, iniciada em 2018, j\u00e1 est\u00e1 na terceira etapa e tem rela\u00e7\u00e3o direta com dois compromissos da companhia: o aproveitamento do rejeito proveniente do beneficiamento do min\u00e9rio de ferro e o apoio \u00e0 diversifica\u00e7\u00e3o econ\u00f4mica dos munic\u00edpios onde est\u00e3o suas unidades operacionais, com a atra\u00e7\u00e3o de neg\u00f3cios a partir dos rejeitos e o fortalecimento do ecossistema de gest\u00e3o e de empreendedorismo. Sua proposta, portanto, \u00e9 modelar neg\u00f3cios e escalonar solu\u00e7\u00f5es capazes de direcionar esse aproveitamento de rejeitos de maneira sustent\u00e1vel para outros mercados.<\/p>\n\n\n\n<p>O outro projeto \u00e9 o primeiro hub de inova\u00e7\u00e3o aberta do setor de minera\u00e7\u00e3o do mundo, com a participa\u00e7\u00e3o de 23 mineradoras, al\u00e9m de fornecedores, startups, pesquisadores, investidores e do Instituto Brasileiro de Minera\u00e7\u00e3o (Ibram). O objetivo \u00e9 promover conex\u00f5es entre as empresas associadas e a sociedade em geral e desenvolver, de forma colaborativa, solu\u00e7\u00f5es inovadoras relacionadas a temas de grande relev\u00e2ncia para o segmento, como gest\u00e3o de rejeitos e res\u00edduos, seguran\u00e7a e sa\u00fade ocupacional, desenvolvimento social, gest\u00e3o da \u00e1gua, fontes de energia alternativa e efici\u00eancia operacional.<\/p>\n\n\n\n<p>A Samarco \u00e9 membro do Mining Hub desde sua cria\u00e7\u00e3o, no in\u00edcio de 2019, e j\u00e1 apadrinhou tr\u00eas projetos. Um deles, inclusive, se tornou caso de sucesso do hub e nos possibilitou inovar em di\u00e1logo e engajamento social, com foco na prepara\u00e7\u00e3o das comunidades para os simulados de emerg\u00eancia previstos no Plano de A\u00e7\u00e3o de Emerg\u00eancia para Barragens de Minera\u00e7\u00e3o (PAEBM).<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Com a pandemia do novo coronav\u00edrus, a troca de experi\u00eancias continuou ocorrendo de forma virtual, inclusive sobre as a\u00e7\u00f5es de preven\u00e7\u00e3o e medidas adotadas pelas mineradoras para combate \u00e0 Covid-19. Al\u00e9m disso, todos os programas para desenvolvimento de solu\u00e7\u00f5es para desafios comuns ao setor continuam sendo realizados por meio de plataformas online.&nbsp;<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A experi\u00eancia nesses dois projetos refor\u00e7ou a vis\u00e3o de que a inova\u00e7\u00e3o aberta \u00e9 fundamental para que a minera\u00e7\u00e3o se reinvente e continue evoluindo. Entendemos que estamos no caminho certo, pensando de forma colaborativa em solu\u00e7\u00f5es n\u00e3o apenas para o setor, mas em especial para a sociedade. Afinal, fazer uma minera\u00e7\u00e3o diferente \u00e9 mais do que gerar recursos, \u00e9 compartilhar valor.<br><br>Foto: L\u00e9o Drummond<\/p>","protected":false},"excerpt":{"rendered":"<p>Alessandra Prata \u2013 engenheira especialista da Samarco Os \u00faltimos anos t\u00eam sido de grandes aprendizados para a Samarco e para todo o setor de minera\u00e7\u00e3o. Um dos principais \u00e9 sobre a import\u00e2ncia de as mineradoras se unirem para aprender, buscar solu\u00e7\u00f5es conjuntas para desafios comuns e, principalmente, de se aproximarem<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-4643","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-22T23:34:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-22T23:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o\",\"datePublished\":\"2020-08-22T23:34:41+00:00\",\"dateModified\":\"2020-08-22T23:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/\"},\"wordCount\":657,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/\",\"name\":\"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg\",\"datePublished\":\"2020-08-22T23:34:41+00:00\",\"dateModified\":\"2020-08-22T23:34:44+00:00\",\"description\":\"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/artigo-inovacao-aberta-na-mineracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto","description":"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/","og_locale":"pt_PT","og_type":"article","og_title":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto","og_description":"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-08-22T23:34:41+00:00","article_modified_time":"2020-08-22T23:34:44+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o","datePublished":"2020-08-22T23:34:41+00:00","dateModified":"2020-08-22T23:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/"},"wordCount":657,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/","name":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","datePublished":"2020-08-22T23:34:41+00:00","dateModified":"2020-08-22T23:34:44+00:00","description":"- [Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o - Minas Gerais","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/artigo-inovacao-aberta-na-mineracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"[Artigo] Inova\u00e7\u00e3o aberta na minera\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/Cr\u00e9dito-Leo-Drummond_Divulga\u00e7\u00e3o-Samarco.jpeg","jetpack-related-posts":[{"id":20714,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-assume-a-presidencia-do-mining-hub\/","url_meta":{"origin":4643,"position":0},"title":"Samarco assume a presid\u00eancia do Mining Hub","author":"Di\u00e1rio de Ouro Preto","date":"24 de Janeiro de 2023","format":false,"excerpt":"A l\u00edder de inova\u00e7\u00e3o da Samarco Alessandra Prata assumiu, nesta ter\u00e7a-feira (24), a presid\u00eancia do Mining Hub, primeiro hub de minera\u00e7\u00e3o do mundo que conta com 38 empresas associadas do setor, sendo 22 mineradoras e 16 fornecedores. Um dos programas mais conhecidos, o M-Start chega em 2023 em sua 9\u00aa\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/24.01.23-Foto-1-Mining-Hub-creditos-Samarco.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/24.01.23-Foto-1-Mining-Hub-creditos-Samarco.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/01\/24.01.23-Foto-1-Mining-Hub-creditos-Samarco.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":5839,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/pavimentacao-de-estradas-com-rejeitos-de-mineracao-melhora-vias-em-mariana\/","url_meta":{"origin":4643,"position":1},"title":"Pavimenta\u00e7\u00e3o de estradas com rejeitos de minera\u00e7\u00e3o melhora vias em Mariana","author":"Di\u00e1rio de Ouro Preto","date":"21 de Dezembro de 2020","format":false,"excerpt":"O\u00a0aproveitamento de rejeitos de minera\u00e7\u00e3o na constru\u00e7\u00e3o civil \u00e9 uma realidade. Em Mariana, ser\u00e3o realizados testes a partir da utiliza\u00e7\u00e3o de lama em 10,5 quil\u00f4metros de estradas vicinais nas localidades de Constantino, Cuiab\u00e1 e Goiabeiras, com o desenvolvimento de um pavimento de alta durabilidade e baixo custo. Esta solu\u00e7\u00e3o foi\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/Comunidade-Cuiaba_Mariana_Credito_EcoMud-2-e1608582694825.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/Comunidade-Cuiaba_Mariana_Credito_EcoMud-2-e1608582694825.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/12\/Comunidade-Cuiaba_Mariana_Credito_EcoMud-2-e1608582694825.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3673,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-e-mining-hub-lancam-edital-de-mais-de-r-2-milhoes-em-busca-de-solucoes-inovadoras\/","url_meta":{"origin":4643,"position":2},"title":"Vale e Mining Hub lan\u00e7am edital de mais de R$ 2 milh\u00f5es em busca de solu\u00e7\u00f5es inovadoras","author":"Di\u00e1rio de Ouro Preto","date":"10 de Junho de 2020","format":false,"excerpt":"A Vale e o Mining Hub lan\u00e7aram o primeiro ciclo do M-Spot, novo programa que permite \u00e0s empresas associadas ao Mining Hub apresentar desafios exclusivos em busca de solu\u00e7\u00f5es customizadas. Com aporte de R$ 2 milh\u00f5es, a Vale \u00e9 a primeira mineradora a participar do M-Spot e, mirando o mercado\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9422,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-lanca-estrategia-de-sustentabilidade-e-divulga-declaracao-de-compromisso\/","url_meta":{"origin":4643,"position":3},"title":"Samarco lan\u00e7a estrat\u00e9gia de sustentabilidade e divulga declara\u00e7\u00e3o de compromisso","author":"Di\u00e1rio de Ouro Preto","date":"21 de Julho de 2021","format":false,"excerpt":"Com o prop\u00f3sito de fazer uma minera\u00e7\u00e3o diferente, como foco na sustentabilidade para conduzir o neg\u00f3cio, a Samarco lan\u00e7ou, nesta quarta-feira (21), sua estrat\u00e9gia de sustentabilidade e divulgou sua declara\u00e7\u00e3o de compromisso. A estrat\u00e9gia foi revisitada ap\u00f3s um processo colaborativo que envolveu todas as \u00e1reas da empresa, pesquisa e entrevistas\u2026","rel":"","context":"In &quot;Caderno Verde&quot;","block_context":{"text":"Caderno Verde","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/caderno-verde\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Sistema-de-Filtragem-de-rejeitos_Foto-Otavio-Honorato1-scaled-e1626899898454.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Sistema-de-Filtragem-de-rejeitos_Foto-Otavio-Honorato1-scaled-e1626899898454.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Sistema-de-Filtragem-de-rejeitos_Foto-Otavio-Honorato1-scaled-e1626899898454.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Sistema-de-Filtragem-de-rejeitos_Foto-Otavio-Honorato1-scaled-e1626899898454.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Sistema-de-Filtragem-de-rejeitos_Foto-Otavio-Honorato1-scaled-e1626899898454.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19875,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-embrapii-e-ufop-assinam-contrato-para-projeto-sobre-utilizacao-do-rejeito-de-minerio-na-construcao-civil\/","url_meta":{"origin":4643,"position":4},"title":"Samarco, EMBRAPII e UFOP assinam contrato para projeto sobre utiliza\u00e7\u00e3o do rejeito de min\u00e9rio na constru\u00e7\u00e3o civil\u00a0","author":"Di\u00e1rio de Ouro Preto","date":"15 de Dezembro de 2022","format":false,"excerpt":"A Samarco e a Unidade EMBRAPII em Minera\u00e7\u00e3o Sustent\u00e1vel, da Universidade Federal de Ouro Preto (UFOP Escola de Minas), assinaram contrato para a realiza\u00e7\u00e3o de estudos sobre novas formas de utiliza\u00e7\u00e3o do rejeito arenoso de min\u00e9rio de ferro na cadeia produtiva da constru\u00e7\u00e3o civil. A parceria, firmada em outubro deste\u2026","rel":"","context":"In &quot;Caderno Verde&quot;","block_context":{"text":"Caderno Verde","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/caderno-verde\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8151,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-lanca-programa-de-estagio-2021\/","url_meta":{"origin":4643,"position":5},"title":"Samarco lan\u00e7a programa de est\u00e1gio 2021","author":"Di\u00e1rio de Ouro Preto","date":"12 de Maio de 2021","format":false,"excerpt":"\u201cVem fazer uma minera\u00e7\u00e3o diferente com a gente\u201d. Este \u00e9 o convite da Samarco aos estudantes, que a partir desta quarta-feira (12), podem se inscrever no Programa de Est\u00e1gio da empresa. Ser\u00e3o disponibilizadas cerca de 40 vagas de n\u00edvel superior e t\u00e9cnico para os complexos de Ubu, em Anchieta, no\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/Programa_Estagio_Samarco-e1620827222520.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/Programa_Estagio_Samarco-e1620827222520.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/Programa_Estagio_Samarco-e1620827222520.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/Programa_Estagio_Samarco-e1620827222520.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/Programa_Estagio_Samarco-e1620827222520.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4643"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4644"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}