{"id":4583,"date":"2020-08-18T17:34:27","date_gmt":"2020-08-18T20:34:27","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4583"},"modified":"2020-08-18T17:35:08","modified_gmt":"2020-08-18T20:35:08","slug":"governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/","title":{"rendered":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural"},"content":{"rendered":"<p>Bras\u00edlia &#8211; O governo federal regulamentou as a\u00e7\u00f5es emergenciais destinadas ao setor cultural durante a pandemia de covid-19, conforme previsto pela Lei Aldir Blanc,\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2020-06\/bolsonaro-sanciona-lei-de-auxilio-financeiro-para-o-setor-cultural\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">sancionada em junho<\/a>. O\u00a0<a href=\"https:\/\/pesquisa.in.gov.br\/imprensa\/jsp\/visualiza\/index.jsp?data=18\/08\/2020&amp;jornal=515&amp;pagina=5\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">decreto<\/a>\u00a0foi publicado hoje (18) no<em>\u00a0Di\u00e1rio Oficial da Uni\u00e3o<\/em>\u00a0e traz as regras para a aplica\u00e7\u00e3o dos R$ 3 bilh\u00f5es de recursos federais liberados para estados, munic\u00edpios e Distrito Federal para o pagamento de subs\u00eddios e aux\u00edlio emergencial a trabalhadores do setor.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1314053&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1314053&amp;o=node\"><\/p>\n\n\n\n<p>A Lei n\u00ba 14.017\/2020, que instituiu o aux\u00edlio financeiro, foi chamada de Lei Aldir Blanc em homenagem ao escritor e compositor de 73 anos, que morreu ap\u00f3s contrair covid-19, em maio, no Rio de Janeiro. O setor cultural &#8211; cinemas, museus, shows musicais e teatrais, entre outros &#8211; foi um dos primeiros a interromper as atividades como medida de preven\u00e7\u00e3o \u00e0 dissemina\u00e7\u00e3o do novo coronav\u00edrus no pa\u00eds.<\/p>\n\n\n\n<p>O texto da lei prev\u00ea o pagamento de tr\u00eas parcelas de um aux\u00edlio de R$ 600 mensais para os trabalhadores da \u00e1rea. Ele dever\u00e1 ser prorrogado no mesmo modelo que o aux\u00edlio emergencial concedido pelo governo federal aos trabalhadores informais, microempreendedores individuais, aut\u00f4nomos e desempregados.<\/p>\n\n\n\n<p>Para receber o benef\u00edcio, os trabalhadores da cultura dever\u00e3o comprovar, de forma documental ou autodeclarat\u00f3ria, terem atuado social ou profissionalmente nas \u00e1reas art\u00edstica e cultural nos 24 meses imediatamente anteriores \u00e0 data de publica\u00e7\u00e3o da lei. Eles n\u00e3o podem ter emprego formal ativo ou receber benef\u00edcio previdenci\u00e1rio ou assistencial, ressalvado o Bolsa Fam\u00edlia.<\/p>\n\n\n\n<p>Al\u00e9m disso, os trabalhadores devem ter renda familiar mensal&nbsp;<em>per capita<\/em>&nbsp;de at\u00e9 meio sal\u00e1rio m\u00ednimo ou renda familiar mensal total de at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos, o que for maior; e n\u00e3o ter recebido, em 2018, rendimentos tribut\u00e1veis acima de R$ 28.559,70.<\/p>\n\n\n\n<p>O recebimento dessa renda emergencial est\u00e1 limitado a dois membros da mesma unidade familiar e a mulher chefe de fam\u00edlia receber\u00e1 duas cotas. O trabalhador que j\u00e1 recebe o aux\u00edlio emergencial do governo federal n\u00e3o poder\u00e1 receber o aux\u00edlio cultural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Subs\u00eddios<\/h2>\n\n\n\n<p>Os espa\u00e7os art\u00edsticos e culturais, microempresas e pequenas empresas culturais, cooperativas e organiza\u00e7\u00f5es comunit\u00e1rias que tiveram as atividades interrompidas receber\u00e3o um subs\u00eddio entre R$ 3 mil e R$ 10 mil, de acordo com crit\u00e9rios estabelecidos pelos gestores locais. Em contrapartida, ap\u00f3s a reabertura, os espa\u00e7os beneficiados dever\u00e3o realizar atividades para alunos de escolas p\u00fablicas, prioritariamente, ou para a comunidade, de forma gratuita.<\/p>\n\n\n\n<p>Os benefici\u00e1rios dever\u00e3o prestar contas at\u00e9 120 dias ap\u00f3s o recebimento da \u00faltima parcela do subs\u00eddio mensal. N\u00e3o poder\u00e3o receber o subs\u00eddio espa\u00e7os culturais criados pela administra\u00e7\u00e3o p\u00fablica de qualquer esfera, bem como aqueles vinculados a grupos empresariais e espa\u00e7os geridos pelos servi\u00e7os sociais do Sistema S.<\/p>\n\n\n\n<p>Trabalhadores do setor cultural e microempresas e empresas de pequeno porte tamb\u00e9m ter\u00e3o acesso a linhas de cr\u00e9dito espec\u00edficas para fomento de atividades e aquisi\u00e7\u00e3o de equipamentos e a condi\u00e7\u00f5es especiais para renegocia\u00e7\u00e3o de d\u00e9bitos, oferecidas por institui\u00e7\u00f5es financeiras federais. Os empr\u00e9stimos dever\u00e3o ser pagos em at\u00e9 36 meses e ter\u00e3o car\u00eancia de 180 dias ap\u00f3s o fim do estado de calamidade p\u00fablica decretado em raz\u00e3o da pandemia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Regras de repasse<\/h2>\n\n\n\n<p>Os gestores locais poder\u00e3o ainda realizar editais, chamadas p\u00fablicas ou outros artif\u00edcios, para a manuten\u00e7\u00e3o e o desenvolvimento de atividades de economia criativa e economia solid\u00e1ria, cursos, manifesta\u00e7\u00f5es culturais, produ\u00e7\u00f5es audiovisuais, bem como atividades art\u00edsticas e culturais que possam ser transmitidas pela internet ou por meio de plataformas digitais. De acordo com o decreto, ao menos 20% dos R$ 3 bilh\u00f5es dever\u00e3o ser destinados a essas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Os valores que cada ente da federa\u00e7\u00e3o receber\u00e1 ser\u00e1 proporcional \u00e0 popula\u00e7\u00e3o e de acordo com os crit\u00e9rios de rateio dos fundos de Participa\u00e7\u00e3o dos Munic\u00edpios e dos Estados e do Distrito Federal. Os recursos ser\u00e3o transferidos por meio da Plataforma +Brasil, do Minist\u00e9rio do Turismo.<\/p>\n\n\n\n<p>O prazo para publica\u00e7\u00e3o da programa\u00e7\u00e3o ou destina\u00e7\u00e3o dos recursos ser\u00e1 de 60 dias para os munic\u00edpios e de 120 para os estados e o Distrito Federal, a partir da data de recebimento dos recursos. Caso os munic\u00edpios n\u00e3o cumpram o prazo, os valores ser\u00e3o revertidos para distribui\u00e7\u00e3o pelo governo estadual. E nesse caso, os recursos n\u00e3o utilizados em 120 dias dever\u00e3o ser devolvidos \u00e0 Uni\u00e3o no prazo de dez dias.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A aplica\u00e7\u00e3o dos recursos est\u00e1 limitada aos valores liberados pelo governo federal. Caso prefeitos e governadores queiram aumentar o valor dos benef\u00edcios repassados, dever\u00e3o fazer a complementa\u00e7\u00e3o com recursos pr\u00f3prios.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da Ag\u00eancia Brasil<br>Foto: Teatro Municipal do Rio de Janeiro Cr\u00e9ditos:T\u00e2nia R\u00eago <\/p>","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; O governo federal regulamentou as a\u00e7\u00f5es emergenciais destinadas ao setor cultural durante a pandemia de covid-19, conforme previsto pela Lei Aldir Blanc,\u00a0sancionada em junho. O\u00a0decreto\u00a0foi publicado hoje (18) no\u00a0Di\u00e1rio Oficial da Uni\u00e3o\u00a0e traz as regras para a aplica\u00e7\u00e3o dos R$ 3 bilh\u00f5es de recursos federais liberados para estados,<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["entry","author-diario","post-4583","post","type-post","status-publish","format-standard","has-post-thumbnail","category-culturaeartes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-18T20:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-18T20:35:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural\",\"datePublished\":\"2020-08-18T20:34:27+00:00\",\"dateModified\":\"2020-08-18T20:35:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/\"},\"wordCount\":840,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/tania_rego_agbr.jpg\",\"articleSection\":[\"Cultura, Artes e Patrim\u00f4nio\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/\",\"name\":\"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/tania_rego_agbr.jpg\",\"datePublished\":\"2020-08-18T20:34:27+00:00\",\"dateModified\":\"2020-08-18T20:35:08+00:00\",\"description\":\"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/tania_rego_agbr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/tania_rego_agbr.jpg\",\"width\":1170,\"height\":700,\"caption\":\"O corpo do cantor, compositor e violonista Jo\u00e3o Gilberto \u00e9 velado no Theatro Municipal do Rio de Janeiro.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto","description":"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/","og_locale":"pt_PT","og_type":"article","og_title":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto","og_description":"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-08-18T20:34:27+00:00","article_modified_time":"2020-08-18T20:35:08+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural","datePublished":"2020-08-18T20:34:27+00:00","dateModified":"2020-08-18T20:35:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/"},"wordCount":840,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","articleSection":["Cultura, Artes e Patrim\u00f4nio"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/","url":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/","name":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","datePublished":"2020-08-18T20:34:27+00:00","dateModified":"2020-08-18T20:35:08+00:00","description":"Trabalhadores da \u00e1rea v\u00e3o receber aux\u00edlio de R$ 600 em tr\u00eas parcelas","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","width":1170,"height":700,"caption":"O corpo do cantor, compositor e violonista Jo\u00e3o Gilberto \u00e9 velado no Theatro Municipal do Rio de Janeiro."},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/governo-regulamenta-liberacao-de-r-3-bilhoes-para-setor-cultural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Governo regulamenta libera\u00e7\u00e3o de R$ 3 bilh\u00f5es para setor cultural"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/tania_rego_agbr.jpg","jetpack-related-posts":[{"id":4522,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/sancionada-a-regulamentacao-de-repasses-da-lei-aldir-blanc\/","url_meta":{"origin":4583,"position":0},"title":"Sancionada a regulamenta\u00e7\u00e3o de repasses da Lei Aldir Blanc","author":"Di\u00e1rio de Ouro Preto","date":"14 de Agosto de 2020","format":false,"excerpt":"Os estados e o Distrito Federal ter\u00e3o prazo de 120 dias, contados da data do repasse, para utilizarem os recursos liberados ao setor cultural pela Lei Aldir Blanc (Lei 14.017, de 2020). De acordo com a MP 986\/2020, sancionada pelo governo Federal na \u00faltima quinta-feira (13) e transformada na Lei\u00a014.036,\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/eduardo_ortega_masp.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/eduardo_ortega_masp.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/eduardo_ortega_masp.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/eduardo_ortega_masp.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22230,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/produtores-culturais-temem-burocracia-da-lei-paulo-gustavo\/","url_meta":{"origin":4583,"position":1},"title":"Produtores culturais temem burocracia da Lei Paulo Gustavo","author":"Di\u00e1rio de Ouro Preto","date":"6 de Abril de 2023","format":false,"excerpt":"Eles receiam que a regulamenta\u00e7\u00e3o da norma possa dificultar a libera\u00e7\u00e3o de recursos federais para a cultura A burocracia para acessar os recursos da Lei Paulo Gustavo preocupa gestores p\u00fablicos municipais e produtores culturais, especialmente de cidades do interior do Estado. Eles participaram de audi\u00eancia p\u00fablica da Comiss\u00e3o de Cultura\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23113,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-regulamentara-lei-paulo-gustavo-na-proxima-quinta-feira\/","url_meta":{"origin":4583,"position":2},"title":"Governo regulamentar\u00e1 Lei Paulo Gustavo na pr\u00f3xima quinta-feira","author":"Di\u00e1rio de Ouro Preto","date":"9 de Maio de 2023","format":false,"excerpt":"O governo federal formalizar\u00e1 a regulamenta\u00e7\u00e3o da chamada Lei Paulo Gustavo (Lei Complementar n\u00ba 195, de 2022) nesta quinta-feira (11). O presidente da Rep\u00fablica, Luiz In\u00e1cio Lula da Silva, aproveitar\u00e1 sua viagem \u00e0\u00a0Bahia para, junto com a ministra da Cultura, Margareth Menezes, assinar o decreto que regulamenta a lei. Aprovada\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/05\/ministra_margareth_menezes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/05\/ministra_margareth_menezes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/05\/ministra_margareth_menezes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/05\/ministra_margareth_menezes.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/05\/ministra_margareth_menezes.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":39508,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/dia-nacional-da-cultura-em-pronunciamento-nacional-ministra-destaca-os-investimentos-historicos-feitos-no-setor\/","url_meta":{"origin":4583,"position":3},"title":"Dia Nacional da Cultura: em pronunciamento nacional, Ministra destaca os investimentos hist\u00f3ricos feitos no setor","author":"Di\u00e1rio de Ouro Preto","date":"5 de Novembro de 2024","format":false,"excerpt":"Em pronunciamento oficial em rede nacional, nesta segunda (4), a ministra da Cultura, Margareth Menezes, saudou todas as fazedoras e fazedores de cultura do pa\u00eds, por ocasi\u00e3o do Dia Nacional da Cultura, comemorado nesta ter\u00e7a-feira, 5 de novembro. A data faz refer\u00eancia ao dia de nascimento do baiano Rui Barbosa,\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/11\/margareth_menezes.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/11\/margareth_menezes.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/11\/margareth_menezes.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/11\/margareth_menezes.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22571,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-destrava-r-2-bilhoes-para-o-setor-cultural\/","url_meta":{"origin":4583,"position":4},"title":"Governo destrava R$ 2 bilh\u00f5es para o setor cultural","author":"Di\u00e1rio de Ouro Preto","date":"18 de Abril de 2023","format":false,"excerpt":"O governo federal liberou R$ 2 bilh\u00f5es para o setor cultural, nos primeiros tr\u00eas meses deste ano,\u00a0de acordo com a ministra\u00a0Margareth Menezes.\u00a0 O desbloqueio\u00a0viabiliza, por exemplo, a execu\u00e7\u00e3o de 1.946 projetos art\u00edsticos e culturais por meio da Lei Rouanet, com investimento de quase R$ 1 bilh\u00e3o. \u201cS\u00e3o projetos que estavam\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/vac_abr1804232379.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/vac_abr1804232379.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/vac_abr1804232379.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/vac_abr1804232379.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/04\/vac_abr1804232379.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":26306,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/investimentos-de-r-15-bilhoes-no-setor-cultural-tem-regras-definidas\/","url_meta":{"origin":4583,"position":5},"title":"Investimentos de R$ 15 bilh\u00f5es no setor cultural t\u00eam regras definidas","author":"Di\u00e1rio de Ouro Preto","date":"19 de Outubro de 2023","format":false,"excerpt":"A Pol\u00edtica Nacional Aldir Blanc de Fomento \u00e0 Cultura (PNAB) foi regulamentada por um decreto que define como ser\u00e1 o repasse e a execu\u00e7\u00e3o dos recursos destinados aos estados, munic\u00edpios e Distrito Federal. O documento assinado pelo presidente Luiz In\u00e1cio Lula da Silva foi publicado nesta quinta-feira (18), no\u00a0Di\u00e1rio Oficial\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4583"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4584"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}