{"id":4435,"date":"2020-08-03T18:17:48","date_gmt":"2020-08-03T21:17:48","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4435"},"modified":"2020-08-03T18:17:52","modified_gmt":"2020-08-03T21:17:52","slug":"vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/","title":{"rendered":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua"},"content":{"rendered":"<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Belo Horizonte, 3 de agosto de 2020 &#8211;\u00a0<\/strong>A Vale est\u00e1 lan\u00e7ando o Programa Partilhar, que tem como objetivo fomentar o desenvolvimento social das comunidades onde atua em parceria com sua cadeia de suprimentos. Utilizando uma metodologia inovadora, a mineradora identificar\u00e1 os fornecedores com maior contribui\u00e7\u00e3o socioecon\u00f4mica para cada regi\u00e3o e os priorizar\u00e1 nos processos de contrata\u00e7\u00e3o. Al\u00e9m disso, oferecer\u00e1 um card\u00e1pio de incentivos voltado para a capacita\u00e7\u00e3o e aumento da competitividade dessas empresas.\u00a0\u00a0<br><br>O Programa Partilhar conta com a participa\u00e7\u00e3o de diferentes \u00e1reas da empresa e ser\u00e1 implantado de forma gradativa. No primeiro ciclo, de julho a dezembro, ser\u00e3o contempladas 11 categorias de compras &#8211; como servi\u00e7os de infraestrutura, constru\u00e7\u00e3o e engenharia, pe\u00e7as para processamento mineral e frete de transporte terrestre. O volume potencial inicialmente mapeado supera R$ 730 milh\u00f5es em contrata\u00e7\u00f5es. Em 2021 o programa ser\u00e1 expandido para outras categorias.<br><br><strong>\u00cdndice de Valor na Comunidade<\/strong>Em seus processos de contrata\u00e7\u00e3o de servi\u00e7os e materiais, a Vale analisa atualmente o pre\u00e7o oferecido e a capacidade t\u00e9cnica do fornecedor. Nas categorias inclu\u00eddas no Programa Partilhar ser\u00e1 analisado tamb\u00e9m o \u00cdndice de Valor na Comunidade (IVC), um indicador criado pela empresa que reflete a contribui\u00e7\u00e3o socioecon\u00f4mica dos fornecedores para as comunidades. Uma pontua\u00e7\u00e3o alta no IVC ser\u00e1 um diferencial para o fornecedor na concorr\u00eancia.Os indicadores que comp\u00f5em o IVC foram definidos com os seguintes objetivos:<br>. Incentivar a gera\u00e7\u00e3o sustent\u00e1vel de postos de trabalho nas comunidades onde a Vale opera;<br>. Incrementar a renda de trabalhadores da regi\u00e3o, valorizando a m\u00e3o de obra na cadeia de minera\u00e7\u00e3o;<br>. Fomentar as compras locais, gerando novas oportunidades de neg\u00f3cios;<br>. Estimular o aumento da arrecada\u00e7\u00e3o de impostos na regi\u00e3o;<br>. Incentivar a aplica\u00e7\u00e3o de recursos em investimento social volunt\u00e1rio visando ao bem-estar da comunidade local.A metodologia do IVC \u00e9 baseada em crit\u00e9rios objetivos, com divulga\u00e7\u00e3o aos participantes de forma transparente. O processo de certifica\u00e7\u00e3o \u00e9 gratuito para os fornecedores, feito por uma empresa independente, com garantia da prote\u00e7\u00e3o dos dados.O IVC analisa cinco fatores relacionados a contribui\u00e7\u00e3o de cada fornecedor em cada regi\u00e3o:<br>. Emprego: n\u00famero de postos de trabalho mantidos ativos na regi\u00e3o;<br>. Renda e sal\u00e1rio: somat\u00f3rio da remunera\u00e7\u00e3o bruta anual dos colaboradores;<br>. Compras locais: total de gastos em produtos e servi\u00e7os na localidade;<br>. Impostos: valor total recolhido em ISS e ICMS;<br>. Investimento social volunt\u00e1rio: somat\u00f3rio de investimentos em iniciativas sociais visando o bem-comum da comunidade.<br><br><strong>Card\u00e1pio de incentivos<\/strong><br><br>A Vale vai oferecer aos fornecedores um card\u00e1pio de incentivos voltados para a capacita\u00e7\u00e3o e o aumento de competitividade. Mesmo os que ainda n\u00e3o tenham contratos em vigor com a empresa poder\u00e3o participar. Entre as facilidades planejadas est\u00e3o: treinamentos para funcion\u00e1rios das empresas parceiras, condi\u00e7\u00f5es financeiras diferenciadas e ferramentas facilitadoras de neg\u00f3cios.A prioridade para receber os incentivos ser\u00e1 dada aos fornecedores com base numa combina\u00e7\u00e3o do IVC mais alto com o menor faturamento anual. A ideia \u00e9 recompensar e apoiar as empresas que mais invistam na comunidade, dando foco a fornecedores de pequeno porte.Nas \u00faltimas semanas, a Vale iniciou o processo de certifica\u00e7\u00e3o com os fornecedores do primeiro ciclo, convidando para ades\u00e3o ao programa e compartilhando as informa\u00e7\u00f5es referentes ao c\u00e1lculo e aplica\u00e7\u00e3o do IVC. Os processos de contrata\u00e7\u00e3o de agosto j\u00e1 contar\u00e3o com a aplica\u00e7\u00e3o da nova metodologia.<br><br><strong>Inova\u00e7\u00e3o, parceria e desenvolvimento social<\/strong><br><br>O diretor de Suprimentos, Marco Braga, destaca a inova\u00e7\u00e3o representada pelo programa. &#8220;Criamos uma metodologia pioneira no Brasil para medir a contribui\u00e7\u00e3o da nossa cadeia de suprimentos para as comunidades, estabelecendo uma parceria em que Vale, fornecedores e comunidade ser\u00e3o beneficiados. Estamos tamb\u00e9m oferecendo incentivos que ir\u00e3o potencializar o impacto positivo do setor mineral para o desenvolvimento do pa\u00eds&#8221;.O diretor de Sustentabilidade e Investimento Social, Hugo Barreto, afirma que o programa refor\u00e7a o novo pacto que a Vale quer estabelecer com a sociedade. &#8220;Estamos indo al\u00e9m de nossas obriga\u00e7\u00f5es, como impostos e projetos sociais, para nos tornarmos um facilitador do desenvolvimento nas \u00e1reas em que atuamos, gerando um impacto positivo nos territ\u00f3rios&#8221;.<img decoding=\"async\" width=\"600\" src=\"https:\/\/ci5.googleusercontent.com\/proxy\/vnL1asj3Xr-FLNUNE-ENzn4LtiPkYjBqXnPT8NHDGYfVhgvkoxtDxyBPjoOMcgN4lHWJLsZsQnt4OmT8MMHxHqhdK2qHppO2HEM1AT9AcxYL9ac=s0-d-e1-ft#http:\/\/valeglobalcomm.com\/\/conteudo\/biblioteca\/Infogrfico002.JPG\" alt=\"\"><br><br><br><br><\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><figcaption>Fonte: Assessoria de Imprensa da Vale.<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Belo Horizonte, 3 de agosto de 2020 &#8211;\u00a0A Vale est\u00e1 lan\u00e7ando o Programa Partilhar, que tem como objetivo fomentar o desenvolvimento social das comunidades onde atua em parceria com sua cadeia de suprimentos. Utilizando uma metodologia inovadora, a mineradora identificar\u00e1 os fornecedores com maior contribui\u00e7\u00e3o socioecon\u00f4mica para cada regi\u00e3o e<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,6,1],"tags":[],"class_list":["entry","author-diario","post-4435","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mariana","category-minas-gerais","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-03T21:17:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T21:17:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua\",\"datePublished\":\"2020-08-03T21:17:48+00:00\",\"dateModified\":\"2020-08-03T21:17:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/\"},\"wordCount\":745,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"articleSection\":[\"Mariana\",\"Minas Gerais\",\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/\",\"name\":\"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"datePublished\":\"2020-08-03T21:17:48+00:00\",\"dateModified\":\"2020-08-03T21:17:52+00:00\",\"description\":\"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/titulo-site3-2-scaled-e1613680230325.jpg\",\"width\":535,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto","description":"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/","og_locale":"pt_PT","og_type":"article","og_title":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto","og_description":"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-08-03T21:17:48+00:00","article_modified_time":"2020-08-03T21:17:52+00:00","og_image":[{"width":535,"height":427,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua","datePublished":"2020-08-03T21:17:48+00:00","dateModified":"2020-08-03T21:17:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/"},"wordCount":745,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","articleSection":["Mariana","Minas Gerais","Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/","url":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/","name":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","datePublished":"2020-08-03T21:17:48+00:00","dateModified":"2020-08-03T21:17:52+00:00","description":"Novo \u00edndice guiar\u00e1 empresa na contrata\u00e7\u00e3o de parceiros com maior contribui\u00e7\u00e3o socioecon\u00f4mica; programa englobar\u00e1 de in\u00edcio cerca de R$ 730 mi em compras","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","width":535,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-lanca-programa-inovador-com-fornecedores-para-fomentar-o-desenvolvimento-social-das-comunidades-onde-atua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Vale lan\u00e7a programa inovador com fornecedores para fomentar o desenvolvimento social das comunidades onde atua"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg","jetpack-related-posts":[{"id":5698,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-reduz-em-mais-de-60-o-prazo-para-pagamento-de-pequenos-fornecedores-locais\/","url_meta":{"origin":4435,"position":0},"title":"Vale reduz em mais de 60% o prazo para pagamento de pequenos fornecedores locais","author":"Di\u00e1rio de Ouro Preto","date":"1 de Dezembro de 2020","format":false,"excerpt":"A partir do dia 1\u00ba de dezembro, a Vale reduzir\u00e1 o prazo de pagamento para 20 dias ap\u00f3s o recebimento de nota fiscal v\u00e1lida a todos os pequenos fornecedores locais. A mudan\u00e7a representa uma redu\u00e7\u00e3o de mais de 60% no prazo de pagamento. Mais de 700 empresas, nos seis estados\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/titulo-site3-2-scaled-e1613680230325.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":31159,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/programa-partilhar-mais-de-490-iniciativas-sociais-realizadas-no-estado-em-2023\/","url_meta":{"origin":4435,"position":1},"title":"Programa Partilhar: mais de 490 iniciativas sociais realizadas no estado em 2023","author":"Di\u00e1rio de Ouro Preto","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"Iniciativa da Vale, lan\u00e7ada em 2020, estimula fornecedores a contribu\u00edrem para o desenvolvimento sustent\u00e1vel das regi\u00f5es onde a empresa atua Em 2023, 50 fornecedores da mineradora Vale com atua\u00e7\u00e3o em Minas Gerais promoveram mais de 490 iniciativas sociais por meio do Programa Partilhar, o que significa um investimento de cerca\u2026","rel":"","context":"In &quot;Oportunidades&quot;","block_context":{"text":"Oportunidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/oportunidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/unnamed-82.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/unnamed-82.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/unnamed-82.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/unnamed-82.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/unnamed-82.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":11932,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/programa-da-vale-e-seus-fornecedores-contribui-para-o-desenvolvimento-social-de-comunidades-em-minas\/","url_meta":{"origin":4435,"position":2},"title":"Programa da Vale e seus fornecedores contribui para o desenvolvimento social de comunidades em Minas","author":"Di\u00e1rio de Ouro Preto","date":"19 de Dezembro de 2021","format":false,"excerpt":"Lan\u00e7ado pela Vale h\u00e1 pouco mais de um ano, o Programa Partilhar j\u00e1 colhe resultados que comprovam o engajamento de sua cadeia de suprimentos com o desenvolvimento social das comunidades onde a empresa atua. Por meio do programa, os fornecedores da Vale j\u00e1 se comprometeram a realizar 55 a\u00e7\u00f5es de\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite4-e1616373972300.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite4-e1616373972300.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite4-e1616373972300.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite4-e1616373972300.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite4-e1616373972300.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17998,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/programa-partilhar-mais-de-100-fornecedores-da-vale-firmaram-acoes-sociais-voluntarias-nos-ultimos-dois-anos\/","url_meta":{"origin":4435,"position":3},"title":"Programa Partilhar: mais de 100 fornecedores da Vale firmaram a\u00e7\u00f5es sociais volunt\u00e1rias nos \u00faltimos dois anos","author":"Di\u00e1rio de Ouro Preto","date":"15 de Agosto de 2022","format":false,"excerpt":"Em dois anos de exist\u00eancia, o Programa Partilhar alcan\u00e7ou resultados importantes que t\u00eam refor\u00e7ado o compromisso da Vale, junto com sua cadeia de suprimentos, com as comunidades onde atua. Criada pela Vale em 2020, a iniciativa gerou, por meio das empresas terceirizadas fornecedoras Vale que aderiram ao Programa, mais de\u202fseis\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/unnamed-11.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/unnamed-11.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/unnamed-11.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/unnamed-11.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/unnamed-11.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21393,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/programa-partilhar-encerra-2022-com-mais-de-400-iniciativas-sociais-realizadas\/","url_meta":{"origin":4435,"position":4},"title":"Programa Partilhar encerra 2022 com mais de 400 iniciativas sociais realizadas","author":"Di\u00e1rio de Ouro Preto","date":"28 de Fevereiro de 2023","format":false,"excerpt":"Mais de 8 mil empregos foram gerados nas localidades onde a Vale atua Em 2022, o Programa Partilhar gerou mais 8 mil\u202fempregos e novas oportunidades de neg\u00f3cios nos estados onde a Vale atua\u202f- Maranh\u00e3o, Esp\u00edrito Santo, Rio de Janeiro, Minas Gerais e Par\u00e1. Neste per\u00edodo, foram mais de 150 fornecedores\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/02\/unnamed-48.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/02\/unnamed-48.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/02\/unnamed-48.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/02\/unnamed-48.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/02\/unnamed-48.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9179,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-rodada-de-negocios-do-forca-local-fomenta-o-desenvolvimento-de-empresas-locais-mineiras\/","url_meta":{"origin":4435,"position":5},"title":"Samarco: Rodada de neg\u00f3cios do For\u00e7a Local fomenta o desenvolvimento de empresas locais mineiras","author":"Di\u00e1rio de Ouro Preto","date":"12 de Julho de 2021","format":false,"excerpt":"Cerca de 100 empresas do territ\u00f3rio de atua\u00e7\u00e3o da Samarco em Minas Gerais \u2013 Mariana, Ouro Preto, Catas Altas e Santa B\u00e1rbara participaram da 1\u00aa Rodada de Neg\u00f3cios do For\u00e7a Local, realizada no dia 8 de julho.\u00a0Fornecedores de diversos setores tiveram a oportunidade de trocar experi\u00eancias e conhecer a atua\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Forca-Local_rodada-de-negocios-MG_Samarco.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Forca-Local_rodada-de-negocios-MG_Samarco.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Forca-Local_rodada-de-negocios-MG_Samarco.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Forca-Local_rodada-de-negocios-MG_Samarco.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/Forca-Local_rodada-de-negocios-MG_Samarco.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4435"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}