{"id":4381,"date":"2020-07-24T19:09:52","date_gmt":"2020-07-24T22:09:52","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4381"},"modified":"2020-07-24T19:14:56","modified_gmt":"2020-07-24T22:14:56","slug":"nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/","title":{"rendered":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais"},"content":{"rendered":"<p>&#8220;A Prefeitura de Mariana compreende a necessidade dos comerciantes em manter o pr\u00f3prio sustento e tamb\u00e9m \u00e9 favor\u00e1vel ao retorno das atividades comerciais, fazendo com que elas ocorram de forma segura, como salientou o prefeito interino de Mariana, Newton Godoy, durante sua fala os comerciantes. \u201cTrabalhamos em conjunto com a ACIAM e estamos juntos para mostrar ao judici\u00e1rio que tudo o que puder ser feito para que o com\u00e9rcio volte a funcionar com seguran\u00e7a, n\u00f3s iremos fazer. Contem conosco\u201d, disse o prefeito.\u00a0 \u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-attachment-id=\"4382\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/foto_divulgacao-2\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o.jpg\" data-orig-size=\"600,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1595601553&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Foto_Divulga\u00e7\u00e3o\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o-450x600.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o-450x600.jpg\" alt=\"\" class=\"wp-image-4382\" width=\"411\" height=\"547\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o-450x600.jpg 450w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o-297x396.jpg 297w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o-113x150.jpg 113w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Foto_Divulga\u00e7\u00e3o.jpg 600w\" sizes=\"(max-width: 411px) 100vw, 411px\" \/><\/figure><\/div>\n\n\n\n<p>Desde o come\u00e7o da pandemia, o Executivo trabalha para que a economia local sofra o menor impacto poss\u00edvel. Sendo assim, o Comit\u00ea Gestor do COVID-19 trabalhou na cria\u00e7\u00e3o de condi\u00e7\u00f5es seguras para a reabertura dos com\u00e9rcios, a partir do Plano Estrat\u00e9gico de A\u00e7\u00e3o, realizou testagem em massa nos com\u00e9rcios e aumentou a capacidade de leitos de UTI na&nbsp;Santa Casa de Ouro.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes. Por isso, o poder p\u00fablico, al\u00e9m de se concentrar em formas para a abertura, est\u00e1 estudando projetos para amenizar o impacto \u00e0 economia local.&#8221;<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria de Imprensa<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8220;A Prefeitura de Mariana compreende a necessidade dos comerciantes em manter o pr\u00f3prio sustento e tamb\u00e9m \u00e9 favor\u00e1vel ao retorno das atividades comerciais, fazendo com que elas ocorram de forma segura, como salientou o prefeito interino de Mariana, Newton Godoy, durante sua fala os comerciantes. \u201cTrabalhamos em conjunto com a<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,61],"tags":[],"class_list":["entry","author-diario","post-4381","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mariana","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-24T22:09:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-24T22:14:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1132\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais\",\"datePublished\":\"2020-07-24T22:09:52+00:00\",\"dateModified\":\"2020-07-24T22:14:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png\",\"articleSection\":[\"Mariana\",\"Sa\u00fade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/\",\"name\":\"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png\",\"datePublished\":\"2020-07-24T22:09:52+00:00\",\"dateModified\":\"2020-07-24T22:14:56+00:00\",\"description\":\"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png\",\"width\":1132,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto","description":"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/","og_locale":"pt_PT","og_type":"article","og_title":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto","og_description":"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-07-24T22:09:52+00:00","article_modified_time":"2020-07-24T22:14:56+00:00","og_image":[{"width":1132,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","type":"image\/png"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais","datePublished":"2020-07-24T22:09:52+00:00","dateModified":"2020-07-24T22:14:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/"},"wordCount":221,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","articleSection":["Mariana","Sa\u00fade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/","url":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/","name":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","datePublished":"2020-07-24T22:09:52+00:00","dateModified":"2020-07-24T22:14:56+00:00","description":"A Prefeitura informa que seguir\u00e1 trabalhando no combate ao coronav\u00edrus, mas n\u00e3o deixar\u00e1 de olhar para os comerciantes","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","width":1132,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/nota-da-prefeitura-de-mariana-em-relacao-a-manifestacao-dos-comerciantes-locais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Nota da Prefeitura de Mariana em rela\u00e7\u00e3o \u00e0 manifesta\u00e7\u00e3o dos comerciantes locais"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/MARCA_PREF_MARIANA_VERTICAL_COR-01.png","jetpack-related-posts":[{"id":3361,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeito-de-mariana-anuncia-testagem-para-covid-19-no-comercio-local\/","url_meta":{"origin":4381,"position":0},"title":"Prefeito de Mariana anuncia testagem para COVID-19 no com\u00e9rcio local","author":"Di\u00e1rio de Ouro Preto","date":"28 de Maio de 2020","format":false,"excerpt":"Em v\u00eddeo divulgado nesta quinta-feira (28), o prefeito de Mariana, Duarte J\u00fanior, anunciou que o munic\u00edpio ir\u00e1 testar para COVID-19 os funcion\u00e1rios das empresas que tiveram a volta das atividades aprovada pelo Comit\u00ea Gestor do COVID-19. Com in\u00edcio j\u00e1 na pr\u00f3xima segunda-feira (1), a testagem \u00e9 considerada pelo gestor municipal\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/Foto_LucasMantovani-scaled-e1591137303746.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/Foto_LucasMantovani-scaled-e1591137303746.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/Foto_LucasMantovani-scaled-e1591137303746.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/Foto_LucasMantovani-scaled-e1591137303746.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49770,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-abre-chamamento-publico-para-comerciantes-de-alimentos-e-bebidas-no-carnaval-2026\/","url_meta":{"origin":4381,"position":1},"title":"Mariana abre chamamento p\u00fablico para comerciantes de alimentos e bebidas no Carnaval 2026","author":"Di\u00e1rio de Ouro Preto","date":"15 de Janeiro de 2026","format":false,"excerpt":"Est\u00e1 aberto o chamamento p\u00fablico para credenciamento de interessados em atuar com com\u00e9rcio de alimenta\u00e7\u00e3o e bebidas durante o Carnaval de 2026. O processo contempla pontos fixos (barracas), com\u00e9rcio ambulante e ve\u00edculos do tipo Towner, em espa\u00e7os p\u00fablicos do munic\u00edpio. As inscri\u00e7\u00f5es devem ser feitas exclusivamente por e-mail, no per\u00edodo\u2026","rel":"","context":"In &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/carnaval-de-mariana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/carnaval-de-mariana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/carnaval-de-mariana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/carnaval-de-mariana.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/carnaval-de-mariana.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4388,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-mg-129-e-fechada-por-comerciantes-em-mariana-e-atinge-grandes-empresas\/","url_meta":{"origin":4381,"position":2},"title":"Covid-19: MG 129 \u00e9 fechada por comerciantes em Mariana e atinge grandes empresas","author":"Di\u00e1rio de Ouro Preto","date":"27 de Julho de 2020","format":false,"excerpt":"Mariana- A Semana come\u00e7ou com protestos de comerciantes fechando a MG 129, na altura do bairro S\u00e3o Crist\u00f3v\u00e3o, rota de acesso aos grandes empreendimentos da cidade, o tr\u00e2nsito ainda se encontra fechado no local. O foco dos comerciantes s\u00e3o as mineradoras, para eles seria injusto ter que parar as atividades\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-27-at-13.03.12.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-27-at-13.03.12.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-27-at-13.03.12.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-27-at-13.03.12.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-27-at-13.03.12.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16575,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/municipio-de-mariana-trabalha-para-desenvolver-e-commerce-de-suporte-ao-comerciante-local\/","url_meta":{"origin":4381,"position":3},"title":"Munic\u00edpio de Mariana trabalha para desenvolver e-commerce de suporte ao comerciante local","author":"Di\u00e1rio de Ouro Preto","date":"6 de Junho de 2022","format":false,"excerpt":"Na busca de levar mais visibilidade aos comerciantes registrados no munic\u00edpio, que somam aproximadamente 1.390, a Prefeitura de Mariana, por meio da Secretaria de Desenvolvimento Econ\u00f4mico, se re\u00fane periodicamente com parceiros para desenvolver um programa de e-commerce, com o objetivo de trazer mais efetividade e fomento \u00e0 economia marianense. Ainda\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/Desenvolvimento-Economico-Sou-mais-Mariana-Foto-Giovanna-Pereira-17.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/Desenvolvimento-Economico-Sou-mais-Mariana-Foto-Giovanna-Pereira-17.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/Desenvolvimento-Economico-Sou-mais-Mariana-Foto-Giovanna-Pereira-17.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/Desenvolvimento-Economico-Sou-mais-Mariana-Foto-Giovanna-Pereira-17.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/06\/Desenvolvimento-Economico-Sou-mais-Mariana-Foto-Giovanna-Pereira-17.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4474,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-de-mariana-estabelece-acao-conjunta-com-aciam-e-empresarios-locais\/","url_meta":{"origin":4381,"position":4},"title":"Prefeitura de Mariana estabelece a\u00e7\u00e3o conjunta com ACIAM e empres\u00e1rios locais","author":"Di\u00e1rio de Ouro Preto","date":"10 de Agosto de 2020","format":false,"excerpt":"Pensando em novas estrat\u00e9gias para o funcionamento do com\u00e9rcio local de Mariana ap\u00f3s a inclus\u00e3o da cidade no \u201cMinas Consciente\u201d, a Prefeitura de Mariana est\u00e1 trabalhando de forma conjunta com a Associa\u00e7\u00e3o Comercial de Mariana (ACIAM) e com os empres\u00e1rios locais para retomada gradual das atividades, com seguran\u00e7a e melhor\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4455,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-de-mariana-antecipa-primeira-parcela-do-13-salario\/","url_meta":{"origin":4381,"position":5},"title":"Prefeitura de Mariana antecipa primeira parcela do 13\u00b0 sal\u00e1rio","author":"Di\u00e1rio de Ouro Preto","date":"4 de Agosto de 2020","format":false,"excerpt":"Como forma de aquecer a economia local e valorizar o servidor marianense, a Prefeitura de Mariana ir\u00e1 pagar a primeira parcela do 13\u00ba sal\u00e1rio no dia 10 de agosto, pr\u00f3xima segunda-feira. A informa\u00e7\u00e3o foi apresentada pelo vice-prefeito de Mariana, Newton Godoy, na \u00faltima segunda (3). \u201cEstamos valorizando os trabalhadores, pagando\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/curiaarquidiocesana-e1595285493542.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/curiaarquidiocesana-e1595285493542.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/curiaarquidiocesana-e1595285493542.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4381"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2316"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}