{"id":4230,"date":"2020-07-12T13:33:18","date_gmt":"2020-07-12T16:33:18","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4230"},"modified":"2020-07-12T19:39:09","modified_gmt":"2020-07-12T22:39:09","slug":"coluna-tiquin-de-politica","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/","title":{"rendered":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020"},"content":{"rendered":"<p>Agora \u00e9 em novembro, promulgado e tudo como manda o figurino, as elei\u00e7\u00f5es vem a\u00ed, nada de mandatos prorrogados, unifica\u00e7\u00e3o de elei\u00e7\u00f5es, nada disso, o velho e bom costume de ir votar mant\u00e9m sua periodicidade.<br>A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores. Mas a grande pergunta \u00e9? Tem asfalto na minha rua?<br>Em Ant\u00f4nio Pereira, os moradores das primeiras ruas asfaltadas, estiveram t\u00e3o animados que soltaram foguetes, dizem que at\u00e9 o capinzal comemorou em labaredas!<br>Mas o assunto de Ant\u00f4nio Pereira, apesar do foguet\u00f3rio, continua sendo a \u00e1rea de mancha, aquela&#8230; que pode ocorrer&#8230; caso aconte\u00e7a, o que ningu\u00e9m deseja. Agora outras fam\u00edlias ser\u00e3o realocadas, a diferen\u00e7a entre a \u00e1rea anterior e a atual, ao ser observada pelo judici\u00e1rio, rendeu o bloqueio de outros R$ 50 milh\u00f5es da Vale. Alcan\u00e7ando R$ 100 milh\u00f5es, com a rota\u00e7\u00e3o de pautas na Promotoria, os &#8220;Direitos Humanos&#8221; agora ficam a cargo do Promotor de Justi\u00e7a Dr. Domingos Ventura, que j\u00e1 acompanhava o caso de perto ao lado da Promotora de Justi\u00e7a, Dra. Aline Silva Barros. O prefeito J\u00falio Pimenta esteve acompanhado dos promotores no an\u00fancio da retiradas na Escola Estadual Daura de Carvalho. Agora volta ao distrito com o asfalto, em situa\u00e7\u00e3o bem diferente de fevereiro.<br>O cen\u00e1rio eleitoral tem personagens que ainda n\u00e3o se definiram e a mudan\u00e7a do calend\u00e1rio eleitoral esticar\u00e1 as negocia\u00e7\u00f5es por mais tempo, at\u00e9 se formarem as chapas. Enquanto isso, vamos pegando um tiquin al\u00ed, um tiquin aqui e vamos juntando esse quebra cabe\u00e7a das elei\u00e7\u00f5es 2020.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"800\" data-attachment-id=\"4234\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/angelo-oswaldo-e-ze-leandro-se-cumprimentam-no-inicio-do-debate-da-tv-unibh-levi-quaresma-01-10-2008\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS DIGITAL REBEL&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1222888815&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;39&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008-900x600.jpg\" src=\"https:\/\/i2.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008.jpg?fit=900%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-4234\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008-594x396.jpg 594w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008-900x600.jpg 900w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/Angelo-Oswaldo-e-Z\u00e9-Leandro-se-cumprimentam-no-in\u00edcio-do-debate-da-TV-UniBH-Levi-Quaresma-01-10-2008-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption>Registro Hist\u00f3rico no debate da Top Cultura, 1\/10\/2008,  ser\u00e1  que esse ano eles se cumprimentam?<br> Foto: Marcelino de Castro <\/figcaption><\/figure>\n\n\n\n<p><br>Nossos protagonistas de hoje s\u00e3o velhos conhecidos, Angelo Oswaldo e Jos\u00e9 Leandro Filho, quem conseguir\u00e1 colocar mais votos na urna? Foi o que pensei ao ver a charge do Genin Guerra, eles est\u00e3o empatados em n\u00famero de mandatos como prefeitos de Ouro Preto, s\u00e3o tricampe\u00f5es, e agora teremos um tetra? Outros jogadores est\u00e3o na \u00e1rea e buscam espa\u00e7os, quem ser\u00e1 o vencedor desse p\u00e1reo.<\/p>\n\n\n\n<p>O PT \u00e9 governo, em decis\u00e3o da executiva o partido permanece na gest\u00e3o, ter\u00e1 J\u00falio Pimenta Lula como cabo eleitoral? Gleiser Boroni com Bolsonaro? Jos\u00e9 Leandro com a Santa Casa e Angelo Oswaldo com a conquista da estrada de Santa Rita de Ouro Preto?<br><\/p>\n\n\n\n<p>O que mais se avizinha? O crescimento da presen\u00e7a do Professor Rog\u00e9rio Fernandes, que teria sido cotado para vice de Jos\u00e9 Leandro, Angelo Oswaldo, o que parece que ocorrer\u00e1 \u00e9 que ele forme chapa com Caio Bueno, tendo o apoio do PCdo B. A Vereadora Regina Braga, como havia adiantado ao di\u00e1rio de Ouro Preto, n\u00e3o candidataria para vereadora mais uma vez, busca o executivo e foi ela a primeira pr\u00e9-candidata a vice, confirmada ainda neste primeiro semestre, alguns avaliam que Angelo Oswaldo est\u00e1 andando na frente, lan\u00e7ando pr\u00e9-candidatura em dezembro e articulando o vice.<\/p>\n\n\n\n<p>E A SA\u00daDE?<\/p>\n\n\n\n<p>A sa\u00fade desde quando o di\u00e1rio de Ouro Preto foi fundado h\u00e1 16 anos, a sa\u00fade \u00e9 o foco da vida p\u00fablica, a crise da Sa\u00fade 2003\/2004, que teve at\u00e9 Santa Casa fechada e beb\u00eas que morreram por n\u00e3o conseguirem quem ajudasse sua m\u00e3e a ganh\u00e1-lo. A reabertura da Santa Casa foi o trunfo de Angelo Oswaldo contra Marisa Xavier e o seu eterno rival Jos\u00e9 Leandro.<br><\/p>\n\n\n\n<p>A disputa de hoje \u00e9 entre J\u00falio Pimenta e Jos\u00e9 Leandro. A UPA j\u00e1 recebeu os equipamentos e insumos para come\u00e7ar atender paciente a partir de hoje (8\/07\/2020). De acordo com o atual prefeito, seu antecessor, Jos\u00e9 Leandro devolveu os recursos para o Minist\u00e9rio da Sa\u00fade. Com a articula\u00e7\u00e3o pol\u00edtica entre os vereadores da base e seus deputados, foram em busca de reverter a devolu\u00e7\u00e3o dos recursos. Teriam sido informados que novas oportunidade seriam colocadas em edital pelo minist\u00e9rio da Sa\u00fade, e assim o munic\u00edpio poderia participar. Desta forma os recursos da UPA s\u00e3o recursos captados na gest\u00e3o do prefeito J\u00falio Pimenta, que preferiu entregar a obra antes do anivers\u00e1rio da cidade, cumprindo o prazo eleitoral. Na disputa pol\u00edtica J\u00falio Pimenta mostrou ao rival que sua atitude n\u00e3o o atrapalhou.<br>Segundo o vereador Wander Albuquerque suas articula\u00e7\u00f5es foram vitoriosas para conseguir a UPA. \u201cOs recursos haviam sido perdidos na gest\u00e3o passada e conseguimos atrav\u00e9s do ex Deputado Federal Toninho Pinheiro agendar a visita do ent\u00e3o Secret\u00e1rio de Sa\u00fade Francisco de Assis Figueiredo \u00e0 Upa atual.<br>Ap\u00f3s verificar que ela n\u00e3o atendia os requisitos m\u00ednimos do Minist\u00e9rio da Sa\u00fade, pleiteamos junto ao Deputado e por interm\u00e9dio do Deputado Estadual Alencar da Silveira Jr a constru\u00e7\u00e3o de uma nova UPA. Em abril de 2018 foi confirmada a verba federal de 2,2 milh\u00f5es, onde o munic\u00edpio arcaria com o restante do valor.\u201d<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>As &#8220;oposi\u00e7\u00f5es&#8221; temem que o atual governo cres\u00e7a diante do eleitorado  com a inaugura\u00e7\u00e3o da UPA. J\u00e1 estavam preocupados com a mudan\u00e7as nas pesquisas, ap\u00f3s o in\u00edcio do asfalto e a aprova\u00e7\u00e3o para realizar empr\u00e9stimo banc\u00e1rio, que possibilitar\u00e1 levar cal\u00e7amento por asfalto aos distritos, ainda em estradas de terra.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por Marcelino de Castro<br>Coluna veiculada na edi\u00e7\u00e3o 1354, do dia 8\/07\/2020, p\u00e1gina 6.<\/p>","protected":false},"excerpt":{"rendered":"<p>Agora \u00e9 em novembro, promulgado e tudo como manda o figurino, as elei\u00e7\u00f5es vem a\u00ed, nada de mandatos prorrogados, unifica\u00e7\u00e3o de elei\u00e7\u00f5es, nada disso, o velho e bom costume de ir votar mant\u00e9m sua periodicidade.A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,46],"tags":[],"class_list":["entry","author-diario","post-4230","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-12T16:33:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-12T22:39:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020\",\"datePublished\":\"2020-07-12T16:33:18+00:00\",\"dateModified\":\"2020-07-12T22:39:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/\"},\"wordCount\":939,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ouro-preto5-scaled-e1594572331169.jpg\",\"articleSection\":[\"Ouro Preto\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/\",\"name\":\"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ouro-preto5-scaled-e1594572331169.jpg\",\"datePublished\":\"2020-07-12T16:33:18+00:00\",\"dateModified\":\"2020-07-12T22:39:09+00:00\",\"description\":\"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ouro-preto5-scaled-e1594572331169.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ouro-preto5-scaled-e1594572331169.jpg\",\"width\":800,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/coluna-tiquin-de-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto","description":"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/","og_locale":"pt_PT","og_type":"article","og_title":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto","og_description":"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-tiquin-de-politica\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-07-12T16:33:18+00:00","article_modified_time":"2020-07-12T22:39:09+00:00","og_image":[{"width":800,"height":593,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020","datePublished":"2020-07-12T16:33:18+00:00","dateModified":"2020-07-12T22:39:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/"},"wordCount":939,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","articleSection":["Ouro Preto","Pol\u00edtica"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/","url":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/","name":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","datePublished":"2020-07-12T16:33:18+00:00","dateModified":"2020-07-12T22:39:09+00:00","description":"A C\u00e2mara de Vila Rica que comemora hoje seus 309 anos de atividade parlamentar, saber\u00e1 em novembro quais ser\u00e3o os pr\u00f3ximos legisladores","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","width":800,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/coluna-tiquin-de-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"[Coluna: Tiquin de Pol\u00edtica] Elei\u00e7\u00f5es 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/ouro-preto5-scaled-e1594572331169.jpg","jetpack-related-posts":[{"id":30469,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-entrega-hoje-benfeitorias-na-igreja-de-nossa-senhora-da-conceicao-de-engenheiro-correa-e-repassa-r-9-milhoes-para-estrada\/","url_meta":{"origin":4230,"position":0},"title":"Vale entrega hoje benfeitorias na Igreja de Nossa Senhora da Concei\u00e7\u00e3o de Engenheiro Corr\u00eaa e repassa R$ 9 milh\u00f5es para estrada","author":"Di\u00e1rio de Ouro Preto","date":"23 de Fevereiro de 2024","format":false,"excerpt":"Ouro Preto - O prefeito Angelo Oswaldo assinou na manh\u00e3 desta sexta-feira, 23\/02, termo de doa\u00e7\u00e3o para pavimenta\u00e7\u00e3o de trecho da estrada MG-030, que liga o distrito de Engenheiro Corr\u00eaa, em Ouro Preto, ao distrito de S\u00e3o Gon\u00e7alo do Ba\u00e7\u00e3o, em Itabirito. A Vale far\u00e1 a doa\u00e7\u00e3o volunt\u00e1ria de R$\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":36029,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/eleicoes-angelo-oswaldo-e-regina-braga-tem-candidatura-a-reeleicao-confirmada-durante-convencao-partidaria\/","url_meta":{"origin":4230,"position":1},"title":"Elei\u00e7\u00f5es: Angelo Oswaldo e Regina Braga tem candidatura a reelei\u00e7\u00e3o confirmada durante conven\u00e7\u00e3o partid\u00e1ria","author":"Di\u00e1rio de Ouro Preto","date":"21 de Julho de 2024","format":false,"excerpt":"Ouro Preto - A Federa\u00e7\u00e3o Brasil da Esperan\u00e7a do Munic\u00edpio de Ouro Preto, composta pelos Partido dos Trabalhadores(PT), Partido Verde (PV) e PCdo B confirmaram neste domingo, 21\/07, durante a conven\u00e7\u00e3o partid\u00e1ria a candidatura do prefeito Angelo Oswaldo e Regina Braga para concorrem \u00e0 prefeitura de Ouro Preto. O deputado\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/IMG_7843.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/IMG_7843.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/IMG_7843.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/IMG_7843.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/IMG_7843.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4054,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/obras-do-asfalto-do-distrito-de-santo-antonio-do-salto-ja-comecaram\/","url_meta":{"origin":4230,"position":2},"title":"Obras do asfalto do distrito de Santo Ant\u00f4nio do Salto j\u00e1 come\u00e7aram","author":"Di\u00e1rio de Ouro Preto","date":"25 de Junho de 2020","format":false,"excerpt":"Ouro Preto - Santo Ant\u00f4nio do Salto \u00e9 um distrito que impressiona pela beleza de sua paisagem. Por\u00e9m, as m\u00e1s condi\u00e7\u00f5es da estrada que liga a sede ao distrito, principalmente no per\u00edodo chuvoso, impedem que esta maravilha esteja ao alcance de todos. Esta realidade j\u00e1 est\u00e1 sendo transformada. A Prefeitura\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49393,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vereador-titao-comemora-intervencao-na-mg-129\/","url_meta":{"origin":4230,"position":3},"title":"Vereador Tit\u00e3o comemora interven\u00e7\u00e3o na MG-129","author":"Marcelino Castro","date":"19 de Dezembro de 2025","format":false,"excerpt":"O problema come\u00e7ou no dia 8 de dezembro, com interdi\u00e7\u00e3o parcial, causando a lentid\u00e3o no tr\u00e2nsito e risco constante de acidentes, devido ao tr\u00e1fego pesado de carga e trabalhadores da minera\u00e7\u00e3o.","rel":"","context":"In &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-18.47.13.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-18.47.13.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-18.47.13.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-18.47.13.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-18.47.13.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":27271,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/365-dias-por-ano-a-prefeitura-nao-para-de-cuidar-da-cidade\/","url_meta":{"origin":4230,"position":4},"title":"365 dias por ano. A Prefeitura n\u00e3o para de cuidar da cidade","author":"Di\u00e1rio de Ouro Preto","date":"20 de Dezembro de 2023","format":false,"excerpt":"No in\u00edcio do ano, o prefeito Angelo Oswaldo anunciou o pacote de obras, descrevendo 2023 como o ano da colheita, relembrando as dificuldades or\u00e7ament\u00e1rias herdadas, a pandemia e os intensos per\u00edodos chuvosos em 2021 e 2022. Apesar de todo o apelo hist\u00f3rico da cidade, que completou 312 anos, o governo\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9704,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/com-casa-em-ordem-prefeito-lanca-programa-de-obras-para-contemplar-toda-a-cidade\/","url_meta":{"origin":4230,"position":5},"title":"Com Casa em Ordem prefeito lan\u00e7a programa de obras para contemplar toda a cidade","author":"Di\u00e1rio de Ouro Preto","date":"3 de Agosto de 2021","format":false,"excerpt":"Ouro Preto - O Prefeito Angelo Oswaldo anuncia hoje, 3\/08, \u00e0s 10 horas, em entrevista coletiva seu \u201cPrograma de Obras\u201d, ele vai assinar as ordens de servi\u00e7os para o in\u00edcio imediato de algumas interven\u00e7\u00f5es. Esta etapa prev\u00ea a execu\u00e7\u00e3o de 10 obras contemplando sede e distritos. Procurado por nossa reportagem\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/cropped-titulosite-e1627950238119.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/cropped-titulosite-e1627950238119.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/cropped-titulosite-e1627950238119.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/cropped-titulosite-e1627950238119.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4230"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4232"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}