{"id":4216,"date":"2020-07-12T11:46:47","date_gmt":"2020-07-12T14:46:47","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4216"},"modified":"2020-07-12T11:46:50","modified_gmt":"2020-07-12T14:46:50","slug":"prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/","title":{"rendered":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas"},"content":{"rendered":"<p>A Secretaria de Educa\u00e7\u00e3o Superior (Sesu) informa que o Programa Universidade para Todos (Prouni) oferecer\u00e1 167.789 bolsas em 1.061 Institui\u00e7\u00f5es de Ensino Superior Privadas. Desse total, 60.551 ser\u00e3o integrais e 107.229 ser\u00e3o parciais, cobrindo 50% do valor das mensalidades.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1311351&amp;o=node\"><\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho. De acordo com a pasta, j\u00e1 \u00e9 poss\u00edvel fazer consultas sobre a oferta de bolsas no&nbsp;<a href=\"http:\/\/prouniportal.mec.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">portal do Prouni<\/a>.<\/p>\n\n\n\n<p>O programa seleciona estudantes para bolsas em institui\u00e7\u00f5es privadas de ensino superior. Essas bolsas variam de acordo com a renda dos candidatos e podem ser parciais, de 50% da mensalidade, ou integrais, de 100%.<\/p>\n\n\n\n<p>De acordo com o Minist\u00e9rio da Educa\u00e7\u00e3o, o Prouni, que foi criado em 2004, tem por objetivo aumentar a quantidade de estudantes brasileiros de baixa renda na gradua\u00e7\u00e3o.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por Pedro Peduzzi \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: F\u00e1bio Massalli<\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Educa\u00e7\u00e3o Superior (Sesu) informa que o Programa Universidade para Todos (Prouni) oferecer\u00e1 167.789 bolsas em 1.061 Institui\u00e7\u00f5es de Ensino Superior Privadas. Desse total, 60.551 ser\u00e3o integrais e 107.229 ser\u00e3o parciais, cobrindo 50% do valor das mensalidades. As inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho. De acordo<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-4216","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-12T14:46:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-12T14:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas\",\"datePublished\":\"2020-07-12T14:46:47+00:00\",\"dateModified\":\"2020-07-12T14:46:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/prouni_site.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/\",\"name\":\"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/prouni_site.jpg\",\"datePublished\":\"2020-07-12T14:46:47+00:00\",\"dateModified\":\"2020-07-12T14:46:50+00:00\",\"description\":\"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/prouni_site.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/prouni_site.jpg\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto","description":"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/","og_locale":"pt_PT","og_type":"article","og_title":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto","og_description":"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-07-12T14:46:47+00:00","article_modified_time":"2020-07-12T14:46:50+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas","datePublished":"2020-07-12T14:46:47+00:00","dateModified":"2020-07-12T14:46:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/"},"wordCount":154,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/","url":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/","name":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","datePublished":"2020-07-12T14:46:47+00:00","dateModified":"2020-07-12T14:46:50+00:00","description":"Inscri\u00e7\u00f5es ser\u00e3o entre 14 e 17 de julho","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/prouni-disponibilizara-167-789-bolsas-em-1-061-instituicoes-privadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Prouni disponibilizar\u00e1 167.789 bolsas em 1.061 institui\u00e7\u00f5es privadas"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/prouni_site.jpg","jetpack-related-posts":[{"id":10093,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comeca-matricula-para-pre-selecionados-na-lista-de-espera-do-prouni\/","url_meta":{"origin":4216,"position":0},"title":"Come\u00e7a matr\u00edcula para pr\u00e9-selecionados na lista de espera do Prouni","author":"Di\u00e1rio de Ouro Preto","date":"23 de Agosto de 2021","format":false,"excerpt":"Bras\u00edlia - Come\u00e7a\u00a0hoje\u00a0(23) o per\u00edodo para a comprova\u00e7\u00e3o de informa\u00e7\u00f5es da inscri\u00e7\u00e3o e matr\u00edcula dos candidatos pr\u00e9-selecionados na lista de espera do Programa Universidade para Todos (ProUni), para o segundo semestre deste ano. O prazo para os estudantes comparecerem \u00e0s institui\u00e7\u00f5es de ensino termina na\u00a0sexta-feira (27). A lista com o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/enem_2020_prova_tmazs_2401214024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/enem_2020_prova_tmazs_2401214024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/enem_2020_prova_tmazs_2401214024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/enem_2020_prova_tmazs_2401214024.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/enem_2020_prova_tmazs_2401214024.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17593,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","url_meta":{"origin":4216,"position":1},"title":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda","author":"Di\u00e1rio de Ouro Preto","date":"31 de Julho de 2022","format":false,"excerpt":"Estudantes que almejam bolsas de estudo em institui\u00e7\u00f5es privadas de ensino superior poder\u00e3o, a partir de segunda (1\u00ba), fazer inscri\u00e7\u00e3o na 2\u00aa edi\u00e7\u00e3o de 2022 do Programa Universidade para Todos (ProUni). As inscri\u00e7\u00f5es v\u00e3o at\u00e9 o dia 4 de agosto e\u00a0podem ser efetuadas pelo\u00a0site\u00a0do ProUni. As bolsas oferecidas pelo programa\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24068,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/abertas-ate-sexta-feira-inscricoes-para-o-processo-seletivo-do-prouni\/","url_meta":{"origin":4216,"position":2},"title":"Abertas at\u00e9 sexta-feira inscri\u00e7\u00f5es para o processo seletivo do Prouni\u00a0","author":"Di\u00e1rio de Ouro Preto","date":"28 de Junho de 2023","format":false,"excerpt":"As inscri\u00e7\u00f5es para o processo seletivo do Programa Universidade para Todos (Prouni), referente ao segundo semestre de 2023, foram abertas nesta ter\u00e7a-feira (27) e se estender\u00e3o\u00a0at\u00e9 as 23h59 (hor\u00e1rio de Bras\u00edlia) de sexta-feira (30).\u00a0 De acordo com o Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), ser\u00e3o disponibilizadas 276.566 bolsas de estudo, sendo 215.530\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/06\/20230627_123934_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/06\/20230627_123934_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/06\/20230627_123934_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/06\/20230627_123934_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/06\/20230627_123934_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28018,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-para-o-prouni-comecam-nesta-segunda-feira\/","url_meta":{"origin":4216,"position":3},"title":"Inscri\u00e7\u00f5es para o Prouni come\u00e7am nesta segunda-feira","author":"Di\u00e1rio de Ouro Preto","date":"29 de Janeiro de 2024","format":false,"excerpt":"As inscri\u00e7\u00f5es para o Programa Universidade Para Todos (Prouni) do primeiro semestre de 2024 come\u00e7am nesta segunda-feira (29). O prazo segue at\u00e9 a pr\u00f3xima quinta-feira (1\u00ba) e elas s\u00e3o feitas exclusivamente pelo\u00a0Portal \u00danico de Acesso ao Ensino Superior. Essa edi\u00e7\u00e3o do programa vai ofertar 406.428 bolsas \u2014\u202fsendo 308.977 integrais, o\u2026","rel":"","context":"In &quot;Oportunidades&quot;","block_context":{"text":"Oportunidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/oportunidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36325,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-gratuitas-para-prouni-de-2024-terminam-nesta-sexta-feira\/","url_meta":{"origin":4216,"position":4},"title":"Inscri\u00e7\u00f5es gratuitas para Prouni de 2024 terminam nesta sexta-feira","author":"Di\u00e1rio de Ouro Preto","date":"25 de Julho de 2024","format":false,"excerpt":"Programa oferece mais de 243 mil bolsas em faculdades privadas As inscri\u00e7\u00f5es para o processo seletivo do Programa Universidade para Todos (Prouni) para o segundo semestre de 2024 terminam nesta sexta-feira (26\/07). Criado\u202fem\u202f2004, o\u202fprograma federal oferece bolsas de estudo\u202fintegrais e parciais\u202fem cursos de gradua\u00e7\u00e3o e sequenciais\u00a0de forma\u00e7\u00e3o espec\u00edfica, em institui\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41923,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-para-o-prouni-2025-terminam-nesta-terca-feira-28\/","url_meta":{"origin":4216,"position":5},"title":"Inscri\u00e7\u00f5es para o Prouni 2025 terminam nesta ter\u00e7a-feira (28)","author":"Di\u00e1rio de Ouro Preto","date":"27 de Janeiro de 2025","format":false,"excerpt":"Inscri\u00e7\u00e3o \u00e9 gratuita e deve ser feita exclusivamente pela p\u00e1gina do Prouni, no Portal \u00danico de Acesso ao Ensino Superior O prazo para inscri\u00e7\u00e3o no Programa Universidade Para Todos (Prouni) 2025 termina nesta ter\u00e7a-feira, 28 de janeiro. O Prouni oferece bolsas integrais (100%) ou parciais (50%) sobre o valor da\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4216"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4217"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}