{"id":4212,"date":"2020-07-12T11:37:29","date_gmt":"2020-07-12T14:37:29","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4212"},"modified":"2020-07-12T11:37:32","modified_gmt":"2020-07-12T14:37:32","slug":"receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/","title":{"rendered":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia"},"content":{"rendered":"<p>As empresas e os demais contribuintes devem estar atentos para o retorno de obriga\u00e7\u00f5es com o Fisco adiadas durante a pandemia do novo coronav\u00edrus. Tributos e declara\u00e7\u00f5es que haviam sido suspensos ou postergados voltam a valer em julho.<br><br>A Receita Federal emitiu um alerta para orientar o contribuinte. A contribui\u00e7\u00e3o patronal ao Instituto Nacional do Seguro Social (INSS), a Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (Cofins) e os Programas de Integra\u00e7\u00e3o Social (PIS) e de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico (Pasep) devem ser pagas neste m\u00eas. O mesmo ocorre com a contribui\u00e7\u00e3o de empresas e de empregadores dom\u00e9sticos ao Fundo de Garantia do Tempo de Servi\u00e7o (FGTS).<br><br>No caso das contribui\u00e7\u00f5es para o INSS, a Cofins e o PIS\/Pasep, a suspens\u00e3o s\u00f3 valeu para as quotas de abril e de maio, cujo pagamento foi transferido para agosto e outubro, respectivamente. As quotas de junho, com vencimento em julho, devem ser quitadas.<br><br>A contribui\u00e7\u00e3o da empresa para o INSS deve ser paga at\u00e9 o dia 20, assim como a contribui\u00e7\u00e3o da agroind\u00fastria e dos empregadores rurais para a Previd\u00eancia Social. As contribui\u00e7\u00f5es para a Cofins e o PIS\/Pasep devem ser quitadas at\u00e9 o dia 24.<br><br>No caso do FGTS, o governo adiou o pagamento das quotas de abril, maio e junho. Os valores poder\u00e3o ser divididos em seis parcelas, de julho a dezembro, sem multas e encargos. A quota deste m\u00eas deve voltar a ser paga no dia do vencimento. A contribui\u00e7\u00e3o para o empregador dom\u00e9stico venceu na \u00faltima ter\u00e7a-feira (7).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1311343&amp;o=node\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Declara\u00e7\u00f5es<\/h2>\n\n\n\n<p>Tamb\u00e9m devem ser entregues neste m\u00eas declara\u00e7\u00f5es que estavam suspensas. As declara\u00e7\u00f5es de D\u00e9bitos e Cr\u00e9ditos Tribut\u00e1rios Federais (DCTF) originalmente previstas para o 15\u00ba dia \u00fatil de abril, de maio e de junho, dever\u00e3o ser apresentadas at\u00e9 21 de julho. Segundo a Receita Federal, inclusive a declara\u00e7\u00e3o referente aos fatos geradores de maio de 2020 dever\u00e1 ser enviada.<br><br>O arquivo digital da EFD-Contribui\u00e7\u00f5es, que integra o Sistema P\u00fablico de Escritura\u00e7\u00e3o Digital (Sped) deve ser entregue at\u00e9 a pr\u00f3xima ter\u00e7a-feira (14). O envio estavas previsto para o 10\u00ba dia \u00fatil de abril, maio e junho. A escritura\u00e7\u00e3o referente a maio de 2020 tamb\u00e9m dever\u00e1 ser transmitida ao Fisco.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Edi\u00e7\u00e3o: N\u00e1dia Franco<\/p>","protected":false},"excerpt":{"rendered":"<p>As empresas e os demais contribuintes devem estar atentos para o retorno de obriga\u00e7\u00f5es com o Fisco adiadas durante a pandemia do novo coronav\u00edrus. Tributos e declara\u00e7\u00f5es que haviam sido suspensos ou postergados voltam a valer em julho. A Receita Federal emitiu um alerta para orientar o contribuinte. A contribui\u00e7\u00e3o<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-4212","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-12T14:37:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-12T14:37:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia\",\"datePublished\":\"2020-07-12T14:37:29+00:00\",\"dateModified\":\"2020-07-12T14:37:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/\"},\"wordCount\":423,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/receitafederal.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/\",\"name\":\"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/receitafederal.jpg\",\"datePublished\":\"2020-07-12T14:37:29+00:00\",\"dateModified\":\"2020-07-12T14:37:32+00:00\",\"description\":\"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/receitafederal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/receitafederal.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Superintend\u00eancia da Receita Federal, em Bras\u00edlia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto","description":"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/","og_locale":"pt_PT","og_type":"article","og_title":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto","og_description":"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-07-12T14:37:29+00:00","article_modified_time":"2020-07-12T14:37:32+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia","datePublished":"2020-07-12T14:37:29+00:00","dateModified":"2020-07-12T14:37:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/"},"wordCount":423,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/","url":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/","name":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","datePublished":"2020-07-12T14:37:29+00:00","dateModified":"2020-07-12T14:37:32+00:00","description":"Algumas contribui\u00e7\u00f5es devem ser pagas neste m\u00eas","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","width":1170,"height":700,"caption":"Superintend\u00eancia da Receita Federal, em Bras\u00edlia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/receita-alerta-para-retorno-de-obrigacoes-adiadas-na-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Receita alerta para retorno de obriga\u00e7\u00f5es adiadas na pandemia"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg","jetpack-related-posts":[{"id":27454,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/contribuicao-do-mei-tem-novo-valor-com-alta-do-salario-minimo-em-2024\/","url_meta":{"origin":4212,"position":0},"title":"Contribui\u00e7\u00e3o do MEI tem novo valor com alta do sal\u00e1rio m\u00ednimo em 2024","author":"Di\u00e1rio de Ouro Preto","date":"6 de Janeiro de 2024","format":false,"excerpt":"O reajuste do sal\u00e1rio m\u00ednimo para R$ 1.412 - a partir de 1\u00ba de janeiro de 2024 - tamb\u00e9m alterou o pagamento de impostos \u00e0 Receita Federal, incluindo a contribui\u00e7\u00e3o mensal do Microempreendedor Individual (MEI). Os novos valores come\u00e7am a valer nos boletos com vencimento em 20 de fevereiro, referentes\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/10\/economia_1609210423_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":11977,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/arrecadacao-federal-cresce-141-e-bate-recorde-em-novembro\/","url_meta":{"origin":4212,"position":1},"title":"Arrecada\u00e7\u00e3o federal cresce 1,41% e bate recorde em novembro","author":"Di\u00e1rio de Ouro Preto","date":"21 de Dezembro de 2021","format":false,"excerpt":"Bras\u00edlia - Impulsionada pela recupera\u00e7\u00e3o da economia e por receitas extras de impostos ligados ao lucro das empresas, a arrecada\u00e7\u00e3o federal bateu recorde para meses de novembro. Segundo dados divulgados hoje (21) pela Receita Federal, o governo arrecadou R$ 157,34 bilh\u00f5es no m\u00eas passado, com aumento de 1,41% acima da\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36332,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/arrecadacao-no-primeiro-semestre-teve-aumento-de-908\/","url_meta":{"origin":4212,"position":2},"title":"Arrecada\u00e7\u00e3o no primeiro semestre teve aumento de 9,08%","author":"Di\u00e1rio de Ouro Preto","date":"25 de Julho de 2024","format":false,"excerpt":"Perda com enchentes no RS foi estimada em R$ 8 bilh\u00f5es A arrecada\u00e7\u00e3o do governo federal apresentou um\u00a0aumento real, descontada a infla\u00e7\u00e3o, de 9,08%, no primeiro semestre de 2024, informou hoje (25) a Receita Federal. No per\u00edodo, a arrecada\u00e7\u00e3o alcan\u00e7ou o valor de R$ 1,289 trilh\u00e3o. Em junho, a arrecada\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/receitafederal.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":51930,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-quer-converter-receitas-extras-com-petroleo-em-desoneracoes\/","url_meta":{"origin":4212,"position":3},"title":"Governo quer converter receitas extras com petr\u00f3leo em desonera\u00e7\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"24 de Abril de 2026","format":false,"excerpt":"Projeto prev\u00ea que aumento de arrecada\u00e7\u00e3o compense corte de impostos O governo federal enviou nesta quinta-feira (23) ao Congresso o Projeto de Lei Complementar 114 de 2026, que cria um mecanismo para reduzir tributos sobre combust\u00edveis caso haja aumento de arrecada\u00e7\u00e3o com receitas do petr\u00f3leo. A proposta foi apresentada pelo\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/0g0a8739.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/0g0a8739.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/0g0a8739.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/0g0a8739.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/0g0a8739.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10384,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/receita-adia-para-30-de-setembro-prazo-de-regularizacao-do-mei\/","url_meta":{"origin":4212,"position":4},"title":"Receita adia para 30 de setembro prazo de regulariza\u00e7\u00e3o do MEI","author":"Di\u00e1rio de Ouro Preto","date":"31 de Agosto de 2021","format":false,"excerpt":"Bras\u00edlia - Cerca de 1,8 milh\u00e3o de microempreendedores individuais (MEI) com tributos e obriga\u00e7\u00f5es em atraso referentes a 2016 e a anos anteriores ganharam mais um m\u00eas para regularizar a situa\u00e7\u00e3o. A Receita Federal prorrogou o prazo para 30 de setembro.Caso n\u00e3o quitem os tributos e as obriga\u00e7\u00f5es em atraso,\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":50796,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/envio-de-declaracao-do-ir-comeca-na-proxima-semana-veja-regras\/","url_meta":{"origin":4212,"position":5},"title":"Envio de declara\u00e7\u00e3o do IR come\u00e7a na pr\u00f3xima semana; veja regras","author":"Di\u00e1rio de Ouro Preto","date":"10 de Mar\u00e7o de 2026","format":false,"excerpt":"Nova isen\u00e7\u00e3o de at\u00e9 R$ 5 mil n\u00e3o afeta declara\u00e7\u00e3o deste ano A Receita Federal divulgar\u00e1 na pr\u00f3xima segunda-feira (16) as regras da Declara\u00e7\u00e3o do Imposto de Renda Pessoa F\u00edsica (IRPF) 2026. Embora o calend\u00e1rio oficial ainda n\u00e3o tenha sido anunciado, a expectativa \u00e9 que o prazo de entrega da\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/real_moeda_020120a84t47475213.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/real_moeda_020120a84t47475213.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/real_moeda_020120a84t47475213.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/real_moeda_020120a84t47475213.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/real_moeda_020120a84t47475213.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4212"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2386"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}