{"id":4167,"date":"2020-07-05T16:02:26","date_gmt":"2020-07-05T19:02:26","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4167"},"modified":"2020-07-05T16:29:54","modified_gmt":"2020-07-05T19:29:54","slug":"covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/","title":{"rendered":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em  Lavras Novas"},"content":{"rendered":"<p>Lavras Novas &#8211; Quem n\u00e3o gostaria de aproveitar o domingo colocando o p\u00e9 na estrada, para curtir o domingo de sol? Um dos destinos tur\u00edsticos mais procurados em Ouro Preto, Lavras Novas teve cerca de 300 ve\u00edculos parados na barreira Sanit\u00e1ria at\u00e9 as 15 horas, quando mais carros chegavam.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"797\" data-attachment-id=\"4174\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470639\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639.jpg\" data-orig-size=\"1200,797\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593954019&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;9.7&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470639\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-904x600.jpg\" src=\"https:\/\/i2.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639.jpg?fit=904%2C600&amp;ssl=1\" alt=\"\" data-id=\"4174\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470639\/\" class=\"wp-image-4174\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-596x396.jpg 596w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-904x600.jpg 904w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-768x510.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470639-1536x1020.jpg 1536w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"797\" data-attachment-id=\"4175\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470645\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645.jpg\" data-orig-size=\"1200,797\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593954607&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;8.7&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470645\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-904x600.jpg\" src=\"https:\/\/i1.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645.jpg?fit=904%2C600&amp;ssl=1\" alt=\"\" data-id=\"4175\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470645\/\" class=\"wp-image-4175\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-596x396.jpg 596w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-904x600.jpg 904w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-768x510.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470645-1536x1020.jpg 1536w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"797\" data-attachment-id=\"4177\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470647\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647.jpg\" data-orig-size=\"1200,797\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593955038&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17.5&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470647\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-904x600.jpg\" src=\"https:\/\/i1.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647.jpg?fit=904%2C600&amp;ssl=1\" alt=\"\" data-id=\"4177\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470647\/\" class=\"wp-image-4177\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-596x396.jpg 596w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-904x600.jpg 904w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-768x510.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470647-1536x1020.jpg 1536w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"797\" data-attachment-id=\"4178\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470648\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648.jpg\" data-orig-size=\"1200,797\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593955225&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;23.1&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470648\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-904x600.jpg\" src=\"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648.jpg?fit=904%2C600&amp;ssl=1\" alt=\"\" data-id=\"4178\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470648\/\" class=\"wp-image-4178\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-596x396.jpg 596w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-904x600.jpg 904w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-768x510.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470648-1536x1020.jpg 1536w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4179\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470717\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593957780&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;12.9&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470717\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717.jpg\" alt=\"\" data-id=\"4179\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470717\/\" class=\"wp-image-4179\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470717-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4180\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470663\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593957075&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470663\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663.jpg\" alt=\"\" data-id=\"4180\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470663\/\" class=\"wp-image-4180\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470663-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4181\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470747\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958442&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.8&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470747\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747.jpg\" alt=\"\" data-id=\"4181\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470747\/\" class=\"wp-image-4181\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470747-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4182\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470743\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958426&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;13.5&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470743\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743.jpg\" alt=\"\" data-id=\"4182\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470743\/\" class=\"wp-image-4182\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470743-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4183\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470749\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958652&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18.2&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470749\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749.jpg\" alt=\"\" data-id=\"4183\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470749\/\" class=\"wp-image-4183\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470749-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4184\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470750\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958654&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18.2&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470750\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750.jpg\" alt=\"\" data-id=\"4184\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470750\/\" class=\"wp-image-4184\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470750-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4185\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470751\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958671&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;11.8&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470751\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751.jpg\" alt=\"\" data-id=\"4185\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470751\/\" class=\"wp-image-4185\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470751-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"424\" data-attachment-id=\"4187\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470756\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756.jpg\" data-orig-size=\"640,424\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1593958696&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.1&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1470756\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756.jpg\" src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756.jpg\" alt=\"\" data-id=\"4187\" data-full-url=\"https:\/\/i1.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756.jpg?fit=640%2C424&amp;ssl=1\" data-link=\"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/p1470756\/\" class=\"wp-image-4187\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756.jpg 640w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756-598x396.jpg 598w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470756-150x99.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>S\u00e3o 3:00 horas da tarde \u00e9 domingo,aquele movimento de pessoas caminhando nas ruas do distrito n\u00e3o foram registrados, o p\u00fablico estavam em estabelecimentos comerciais que tem mesas afastadas e ao ar livre. O Uso de m\u00e1scaras foi percebido entre moradores, gar\u00e7ons e visitantes, mas nem todos cumpriram a determina\u00e7\u00e3o da lei municipal.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Ref\u00fagio dos rec\u00e9m casados, neste domingo n\u00e3o foi diferente. Lavras Novas recebeu v\u00e1rios casais e fam\u00edlias. N\u00e3o foram registrados grupos de motociclistas. Pelo caminho, fam\u00edlias brincavam de soltar papagaio e faziam pick-nick. O Domingo foi de sol!<br><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Marcelino de Castro<\/p>","protected":false},"excerpt":{"rendered":"<p>Lavras Novas &#8211; Quem n\u00e3o gostaria de aproveitar o domingo colocando o p\u00e9 na estrada, para curtir o domingo de sol? Um dos destinos tur\u00edsticos mais procurados em Ouro Preto, Lavras Novas teve cerca de 300 ve\u00edculos parados na barreira Sanit\u00e1ria at\u00e9 as 15 horas, quando mais carros chegavam. S\u00e3o<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-4167","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-05T19:02:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-05T19:29:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas\",\"datePublished\":\"2020-07-05T19:02:26+00:00\",\"dateModified\":\"2020-07-05T19:29:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/\"},\"wordCount\":166,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/P1470649-e1593977374945.jpg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/\",\"name\":\"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/P1470649-e1593977374945.jpg\",\"datePublished\":\"2020-07-05T19:02:26+00:00\",\"dateModified\":\"2020-07-05T19:29:54+00:00\",\"description\":\"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/P1470649-e1593977374945.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/P1470649-e1593977374945.jpg\",\"width\":800,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto","description":"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/","og_locale":"pt_PT","og_type":"article","og_title":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto","og_description":"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-07-05T19:02:26+00:00","article_modified_time":"2020-07-05T19:29:54+00:00","og_image":[{"width":800,"height":531,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas","datePublished":"2020-07-05T19:02:26+00:00","dateModified":"2020-07-05T19:29:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/"},"wordCount":166,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/","url":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/","name":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","datePublished":"2020-07-05T19:02:26+00:00","dateModified":"2020-07-05T19:29:54+00:00","description":"- Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas - Ouro Preto","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","width":800,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/covid-19-barreira-sanitaria-monitorou-chegada-de-visitantes-em-lavras-novas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Covid-19: Barreira Sanit\u00e1ria monitorou chegada de visitantes em Lavras Novas"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/P1470649-e1593977374945.jpg","jetpack-related-posts":[{"id":3970,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/fim-de-semana-tem-barreira-sanitaria-em-lavras-novas-e-cachoeira-do-campo\/","url_meta":{"origin":4167,"position":0},"title":"Fim de semana tem barreira sanit\u00e1ria em Lavras Novas e Cachoeira do Campo","author":"Di\u00e1rio de Ouro Preto","date":"21 de Junho de 2020","format":false,"excerpt":"Ouro Preto - A prefeitura atendendo aos pedidos da comunidade de Lavras Novas realiza hoje, 21\/06, barreira sanit\u00e1ria na chegada do distrito. Na \u00faltima quinta-feira foram colocadas faixas de orienta\u00e7\u00e3o aos visitantes, na chegada e em frente a igreja de Nossa Senhora dos prazeres. O que relataram os moradores \u00e9\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470457.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470457.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470457.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3942,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/em-alerta-moradores-de-lavras-novas-se-preparam-para-mais-um-fim-de-semana\/","url_meta":{"origin":4167,"position":1},"title":"Em alerta moradores de Lavras Novas se preparam para mais um fim de semana","author":"Di\u00e1rio de Ouro Preto","date":"19 de Junho de 2020","format":false,"excerpt":"Lavras Novas -\u00a0 Os moradores est\u00e3o apreensivo com o n\u00famero de pessoas que tem frequentado a localidade, mesmo em tempo de pandemia. Nesta quinta-feira,18\/06, foram fixadas faixas na chegada e em frente a igreja de Nossa Senhora dos prazeres.De acordo com moradores que preferem n\u00e3o se identificar, aos s\u00e1bados e\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470478.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470478.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/P1470478.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4238,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-mais-um-fim-de-semana-com-barreira-sanitaria-em-lavras-novas\/","url_meta":{"origin":4167,"position":2},"title":"Covid-19: Mais um fim de semana com barreira sanit\u00e1ria em Lavras Novas","author":"Di\u00e1rio de Ouro Preto","date":"12 de Julho de 2020","format":false,"excerpt":"Lavras Novas - A Guarda Municipal registrou a entrada de 376 ve\u00edculos no s\u00e1bado. Neste domingo, 12\/07, at\u00e9 \u00e0s 18 horas, 413 ve\u00edculos de visitantes passaram pela barreira sanit\u00e1ria. Por diversos pontos dos distritos existem faixas orientando a obriga\u00e7\u00e3o do uso de m\u00e1scaras de acordo com lei municipal. O distrito\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-12-at-2.47.16-PM-e1594583393961.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-12-at-2.47.16-PM-e1594583393961.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-12-at-2.47.16-PM-e1594583393961.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-12-at-2.47.16-PM-e1594583393961.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3973,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/boletim-95-covid-19-136-casos-confirmados\/","url_meta":{"origin":4167,"position":3},"title":"Boletim 95 &#8211; Covid-19- 136 casos confirmados","author":"Di\u00e1rio de Ouro Preto","date":"21 de Junho de 2020","format":false,"excerpt":"Ouro Preto - O prefeito J\u00falio Pimenta gravou o boletim epidemiol\u00f3gico neste domingo do audit\u00f3rio da prefeitura. Hoje atendendo aos moradores de Lavras Novas montou barreira sanit\u00e1ria na chegada do distrito. https:\/\/youtu.be\/4eY3D1HjU-Y","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/4eY3D1HjU-Y\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3345,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-monta-barreiras-sanitarias-para-enfrentamento-ao-covid-19\/","url_meta":{"origin":4167,"position":4},"title":"Ouro Preto monta barreiras sanit\u00e1rias para enfrentamento ao Covid-19","author":"Di\u00e1rio de Ouro Preto","date":"28 de Maio de 2020","format":false,"excerpt":"A Prefeitura de Ouro Preto tem intensificado as a\u00e7\u00f5es de orienta\u00e7\u00e3o e preven\u00e7\u00e3o contra o coronav\u00edrus. Uma delas \u00e9 a estrutura\u00e7\u00e3o e implanta\u00e7\u00e3o de novas barreiras sanit\u00e1rias em pontos estrat\u00e9gicos do munic\u00edpio: a j\u00e1 instalada no terminal rodovi\u00e1rio de Cachoeira do Campo ser\u00e1 reestruturada; a que funciona na rodovi\u00e1ria de\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Ouro-Preto-_-Foto-Ane-Souz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Ouro-Preto-_-Foto-Ane-Souz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Ouro-Preto-_-Foto-Ane-Souz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Ouro-Preto-_-Foto-Ane-Souz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4300,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/turistas-encontram-bares-e-restaurantes-fechados-em-lavras-novas\/","url_meta":{"origin":4167,"position":5},"title":"Turistas encontram bares e restaurantes fechados em Lavras Novas","author":"Di\u00e1rio de Ouro Preto","date":"19 de Julho de 2020","format":false,"excerpt":"Lavras Novas - A \"Onda Verde do Minas Consciente\" permite a abertura apenas de com\u00e9rcios considerados essenciais. Assim os turistas que chegam a Lavras Novas se deparam com todos os bares fechados. A alternativa s\u00e3o as padarias e os mercados. Na sexta-feira a Policia Militar realizou patrulha para conferir o\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/carrochegando-em-lavrasnovas-e1595177845183.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/carrochegando-em-lavrasnovas-e1595177845183.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/carrochegando-em-lavrasnovas-e1595177845183.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4167"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4168"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}