{"id":4081,"date":"2020-06-26T11:56:17","date_gmt":"2020-06-26T14:56:17","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4081"},"modified":"2020-06-26T11:56:20","modified_gmt":"2020-06-26T14:56:20","slug":"campanha-ajude-hoje-quem-te-amparou-ontem","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/","title":{"rendered":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d"},"content":{"rendered":"<p>A Funda\u00e7\u00e3o GORCEIX e parceiros lan\u00e7am campanha para, durante a pandemia, cuidar dos moradores em situa\u00e7\u00e3o de vulnerabilidade em Ouro Preto e regi\u00e3o&nbsp;<\/p>\n\n\n\n<p>A Funda\u00e7\u00e3o GORCEIX, dentro de sua vertente de a\u00e7\u00e3o social, tem investido na luta contra a Covid 19 em Ouro Preto, cidade onde tem sua sede. Nessas a\u00e7\u00f5es j\u00e1 foram investidos R$ 150.000,00 na doa\u00e7\u00e3o de equipamentos de prote\u00e7\u00e3o (EPI\u00b4s) para os profissionais da sa\u00fade da Santa Casa de Miseric\u00f3rdia de Ouro Preto e na aquisi\u00e7\u00e3o de itens de alimenta\u00e7\u00e3o, higiene, material de limpeza, medicamentos, entre outros para o Lar S\u00e3o Vicente de Paula.<\/p>\n\n\n\n<p>No momento, est\u00e1 promovendo a Campanha \u201cAjude hoje, quem te amparou ontem\u201d, dirigida aos ex-alunos da Escola de Minas e da UFOP, ex-moradores da cidade e ao p\u00fablico em geral para angariar recursos financeiros, que ser\u00e3o investidos nos cuidados com a comunidade em situa\u00e7\u00e3o de risco de Ouro Preto e regi\u00e3o, em que a pandemia de COVID &#8211; 19 afeta, principalmente, as pessoas mais vulner\u00e1veis.&nbsp;<\/p>\n\n\n\n<p>Segundo, o presidente executivo da Funda\u00e7\u00e3o, prof. Cristovam Paes de Oliveira, \u201cfazemos quest\u00e3o de citar o valor do investimento acima como forma de agradecer aos nossos parceiros, empresas e \u00f3rg\u00e3os p\u00fablicos ou privados, com os quais desenvolvemos Projetos, que nos permitem realizar nosso or\u00e7amento anual, totalmente direcionado \u00e0s nossas finalidades estatut\u00e1rias, com foco na assist\u00eancia social\u201d.&nbsp;<\/p>\n\n\n\n<p>O professor observa ainda que ferramenta mais importante nessa guerra \u00e9, principalmente, a preven\u00e7\u00e3o, atrav\u00e9s de cuidados especiais com a sa\u00fade e higiene e, quando poss\u00edvel, o isolamento e o distanciamento social. S\u00f3 assim o controle da infec\u00e7\u00e3o ser\u00e1 fact\u00edvel, sem colapsar o sistema regional ou nacional de sa\u00fade, at\u00e9 que um medicamento ou uma vacina sejam encontrados.<\/p>\n\n\n\n<p>A Campanha<\/p>\n\n\n\n<p>A a\u00e7\u00e3o liderada pela Funda\u00e7\u00e3o GORCEIX conta com o apoio da Escola de Minas\/UFOP, da Associa\u00e7\u00e3o dos Antigos Alunos da Escola de Minas, da UFOP (Universidade Federal de Ouro Preto) e do Instituto Federal de Minas Gerais.<\/p>\n\n\n\n<p>Voc\u00ea pode contribuir a partir de R$ 100 reais, mas nada lhe impede de doar mais. Toda arrecada\u00e7\u00e3o ser\u00e1 convertida em bens e alimentos, que ser\u00e3o repassados para as entidades beneficentes que apoiam a popula\u00e7\u00e3o carente de Ouro Preto e regi\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Os recursos doados ser\u00e3o gerenciados pela Funda\u00e7\u00e3o Gorceix, que j\u00e1 alocou, desde o in\u00edcio da pandemia, mais de cento e cinquenta mil reais em recursos pr\u00f3prios exclusivamente para este fim, sem contar os outros recursos que a institui\u00e7\u00e3o investe em filantropia.<\/p>\n\n\n\n<p>A transpar\u00eancia na utiliza\u00e7\u00e3o das doa\u00e7\u00f5es \u00e9 ponto b\u00e1sico e ter\u00e1 ampla divulga\u00e7\u00e3o, demostrando onde foram aplicados os recursos.<\/p>\n\n\n\n<p>Podem doar pessoas f\u00edsicas e jur\u00eddicas, \u2013 SEM POSSIBILIDADE DE DESCONTO EM IR \u2013 de forma bem simples.<\/p>\n\n\n\n<p><strong>Como fazer sua doa\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Por dep\u00f3sito banc\u00e1rio:<br>BANCO DO BRASIL<br>Ag\u00eancia n\u00ba 0473-1 \u2013 Ouro Preto<br>Conta corrente n\u00ba 82.181-0 &#8211; Funda\u00e7\u00e3o Gorceix<\/p>\n\n\n\n<p>&nbsp;CAIXA ECON\u00d4MICA FEDERAL<br>Ag\u00eancia n\u00ba 0136 \u2013 Ouro Preto<br>Opera\u00e7\u00e3o: 003 (Conta corrente pessoa jur\u00eddica)<br>Conta corrente n\u00ba 3272-1 \u2013 Funda\u00e7\u00e3o Gorceix,&nbsp;<\/p>\n\n\n\n<p>SANTANDER<br>Ag\u00eancia n\u00ba 3222 \u2013 Ouro Preto<br>Conta corrente n\u00ba 130790953 \u2013 Funda\u00e7\u00e3o Gorceix<br><br>Tem ainda a op\u00e7\u00e3o de solicitar um boleto por e-mail: <a href=\"mailto:contato@gorceix.org.br\" data-wpel-link=\"internal\">contato@gorceix.org.br<\/a><\/p>\n\n\n\n<p>E o professor Cristovam Paes convida todos a participar desta a\u00e7\u00e3o solid\u00e1ria, lembrando: \u201cajude a comunidade que t\u00e3o bem te recebeu no tempo em que voc\u00ea foi aluno ou viveu em Ouro Preto.<\/p>\n\n\n\n<p><strong>Outras a\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p><strong>Doa\u00e7\u00e3o de 150 mil em EPI\u00b4s e apoio ao Lar S\u00e3o Vicente de Paula<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Santa Casa de Miseric\u00f3rdia de Ouro Preto<\/strong>, provendo recursos financeiros para aquisi\u00e7\u00e3o dos EPI\u2019s necess\u00e1rios a seu corpo cl\u00ednico e de funcion\u00e1rios, que est\u00e3o sempre na linha de frente nessa luta para controlar a COVID 19. At\u00e9 agora a institui\u00e7\u00e3o recebeu os seguintes equipamentos e itens:<\/li><\/ol>\n\n\n\n<ul class=\"wp-block-list\"><li>500 litros de \u00e1lcool et\u00edlico 70%.<\/li><li>20. 000 luvas de procedimento.<\/li><li>1.500 m\u00e1scaras cir\u00fargicas.<\/li><li>700 m\u00e1scaras PFF2, com respirador.<\/li><li>300 unidades de sondas traqueais.&nbsp;<\/li><li>5.000 Aventais.<\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li><strong>Lar S\u00e3o Vicente de Paulo<\/strong>, provendo recursos financeiros para a aquisi\u00e7\u00e3o de:<\/li><\/ol>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><ul class=\"wp-block-list\"><li>G\u00eaneros Aliment\u00edcios e Diet\u00e9ticos.<\/li><li>Materiais Farmac\u00eauticos, em geral.<\/li><li>Materiais de Limpeza\/Copa.<\/li><li>Materiais de Escrit\u00f3rio.<\/li><\/ul>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria da Funda\u00e7\u00e3o Gorceix<\/p>","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o GORCEIX e parceiros lan\u00e7am campanha para, durante a pandemia, cuidar dos moradores em situa\u00e7\u00e3o de vulnerabilidade em Ouro Preto e regi\u00e3o&nbsp; A Funda\u00e7\u00e3o GORCEIX, dentro de sua vertente de a\u00e7\u00e3o social, tem investido na luta contra a Covid 19 em Ouro Preto, cidade onde tem sua sede. Nessas<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":3998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-4081","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-26T14:56:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-26T14:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Campanha \u201cAjude hoje, quem te amparou ontem\u201d\",\"datePublished\":\"2020-06-26T14:56:17+00:00\",\"dateModified\":\"2020-06-26T14:56:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/\"},\"wordCount\":735,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/campanha-cartaz.jpg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/\",\"name\":\"Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/campanha-cartaz.jpg\",\"datePublished\":\"2020-06-26T14:56:17+00:00\",\"dateModified\":\"2020-06-26T14:56:20+00:00\",\"description\":\"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/campanha-cartaz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/campanha-cartaz.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/campanha-ajude-hoje-quem-te-amparou-ontem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campanha \u201cAjude hoje, quem te amparou ontem\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto","description":"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/","og_locale":"pt_PT","og_type":"article","og_title":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto","og_description":"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/campanha-ajude-hoje-quem-te-amparou-ontem\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-26T14:56:17+00:00","article_modified_time":"2020-06-26T14:56:20+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d","datePublished":"2020-06-26T14:56:17+00:00","dateModified":"2020-06-26T14:56:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/"},"wordCount":735,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/","url":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/","name":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","datePublished":"2020-06-26T14:56:17+00:00","dateModified":"2020-06-26T14:56:20+00:00","description":"- Campanha \u201cAjude hoje, quem te amparou ontem\u201d - Ouro Preto","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/campanha-ajude-hoje-quem-te-amparou-ontem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Campanha \u201cAjude hoje, quem te amparou ontem\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/campanha-cartaz.jpg","jetpack-related-posts":[{"id":12968,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/fundacao-gorceix-lanca-campanha-para-socorrer-os-desabrigados-pelas-chuvas-em-ouro-preto\/","url_meta":{"origin":4081,"position":0},"title":"Funda\u00e7\u00e3o Gorceix lan\u00e7a campanha para socorrer os desabrigados pelas chuvas em Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"19 de Janeiro de 2022","format":false,"excerpt":"A Funda\u00e7\u00e3o Gorceix (FG) reabriu a campanha \u201cAjude hoje quem te amparou ontem\u201d devido ao avan\u00e7o da \u00d4micron do Coronav\u00edrus e dos casos de influenza nas \u00faltimas semanas, que aumentou a demanda por atendimentos na Santa Casa de Ouro Preto. A campanha tamb\u00e9m ir\u00e1 auxiliar no socorro \u00e0s pessoas atingidas\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Captura-de-tela-2022-01-19-18.04.22.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Captura-de-tela-2022-01-19-18.04.22.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Captura-de-tela-2022-01-19-18.04.22.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Captura-de-tela-2022-01-19-18.04.22.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17142,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/coluna-fundacao-gorceix-e-a-regiao-de-ouro-preto\/","url_meta":{"origin":4081,"position":1},"title":"[Coluna]  Funda\u00e7\u00e3o Gorceix e a Regi\u00e3o de Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"8 de Julho de 2022","format":false,"excerpt":"A Funda\u00e7\u00e3o GORCEIX (FG) existe h\u00e1 62 anos. Foi fundada em 18 de abril de 1960 e, desde ent\u00e3o, est\u00e1 inserida na hist\u00f3ria de Ouro Preto e Regi\u00e3o. Seu ato de funda\u00e7\u00e3o foi presidido pelo ent\u00e3o presidente da Rep\u00fablica, Juscelino Kubistchek de Oliveira que, tr\u00eas dias depois, inauguraria Bras\u00edlia, a\u2026","rel":"","context":"In &quot;Coluna&quot;","block_context":{"text":"Coluna","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/coluna\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/cristovam-rosto.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/cristovam-rosto.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/cristovam-rosto.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/cristovam-rosto.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25266,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/fundacao-gorceix-apresenta-revisao-do-plano-diretor-em-coletiva\/","url_meta":{"origin":4081,"position":2},"title":"Funda\u00e7\u00e3o Gorceix apresenta revis\u00e3o do Plano Diretor em coletiva","author":"Di\u00e1rio de Ouro Preto","date":"4 de Setembro de 2023","format":false,"excerpt":"Ouro Preto - Em coletiva na \u00faltima sexta-feira, 01\/09, a Funda\u00e7\u00e3o Gorceix apresentou o balan\u00e7o das Oficinas do Plano Diretor que percorreram todas as regi\u00f5es do munic\u00edpio. Na ocasi\u00e3o estiveram presentes no Audit\u00f3rio da Prefeitura o prefeito Angelo Oswaldo, a vice- prefeita Regina Braga, o presidente da C\u00e2mara Jos\u00e9 Muniz,\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Imagem-do-WhatsApp-de-2023-09-04-as-14.09.03.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Imagem-do-WhatsApp-de-2023-09-04-as-14.09.03.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Imagem-do-WhatsApp-de-2023-09-04-as-14.09.03.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Imagem-do-WhatsApp-de-2023-09-04-as-14.09.03.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Imagem-do-WhatsApp-de-2023-09-04-as-14.09.03.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52167,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/camara-municipal-de-ouro-preto-lanca-a-campanha-do-agasalho-2026\/","url_meta":{"origin":4081,"position":3},"title":"C\u00e2mara Municipal de Ouro Preto lan\u00e7a a Campanha do Agasalho 2026","author":"Di\u00e1rio de Ouro Preto","date":"7 de Maio de 2026","format":false,"excerpt":"Com o inverno chegando e a temperatura j\u00e1 alterando, a C\u00e2mara Municipal de Ouro Preto lan\u00e7a hoje, dia 6 de maio, a Campanha do Agasalho 2026, que visa acalentar pessoas em situa\u00e7\u00e3o de vulnerabilidade social. Cobertores, agasalhos, meias e acess\u00f3rios, novos ou seminovos ser\u00e3o muito bem-vindos! As doa\u00e7\u00f5es ser\u00e3o destinadas\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Campanha-do-Agasalho-2026.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Campanha-do-Agasalho-2026.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Campanha-do-Agasalho-2026.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Campanha-do-Agasalho-2026.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Campanha-do-Agasalho-2026.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12537,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/entidades-reunidas-promovem-campanha-solidaria-de-apoio-aos-desabrigados\/","url_meta":{"origin":4081,"position":4},"title":"Entidades reunidas promovem campanha solid\u00e1ria de apoio aos desabrigados","author":"Di\u00e1rio de Ouro Preto","date":"9 de Janeiro de 2022","format":false,"excerpt":"A Universidade Federal de Ouro Preto (UFOP), o Instituto Federal de Minas Gerais \u2013 Campus Ouro Preto (IFMG), o Sindicato dos Trabalhadores T\u00e9cnico-administrativos da UFOP (ASSUFOP), a Associa\u00e7\u00e3o dos Docentes da UFOP \u2013 Se\u00e7\u00e3o Sindical, (ADUFOP), o Sindicato Nacional dos Servidores Federais da Educa\u00e7\u00e3o B\u00e1sica, Profissional e Tecnol\u00f3gica (SINASEFE), Funda\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8697,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/parque-das-andorinhas-sera-administrado-em-parceria-com-a-fundacao-gorceix\/","url_meta":{"origin":4081,"position":5},"title":"Parque das Andorinhas ser\u00e1 administrado em parceria com a Funda\u00e7\u00e3o Gorceix","author":"Di\u00e1rio de Ouro Preto","date":"17 de Junho de 2021","format":false,"excerpt":"Ouro Preto - Considerado uma excelente op\u00e7\u00e3o para quem quer se integrar \u00e0 natureza, aproveitar as cachoeiras e observar as paisagens de serras que cercam o munic\u00edpio de Ouro Preto, o Parque das Andorinhas foi, na \u00faltima quinta (10), objeto de parceria entre a Prefeitura e a Funda\u00e7\u00e3o Gorceix. \u00a0\u201cO\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/parceria-entre-Prefeitura-e-Fundacao-Gorceix-2-e1623955842917.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/parceria-entre-Prefeitura-e-Fundacao-Gorceix-2-e1623955842917.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/parceria-entre-Prefeitura-e-Fundacao-Gorceix-2-e1623955842917.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/parceria-entre-Prefeitura-e-Fundacao-Gorceix-2-e1623955842917.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/parceria-entre-Prefeitura-e-Fundacao-Gorceix-2-e1623955842917.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4081"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/3998"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}