{"id":4063,"date":"2020-06-25T11:59:45","date_gmt":"2020-06-25T14:59:45","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4063"},"modified":"2020-06-25T11:59:47","modified_gmt":"2020-06-25T14:59:47","slug":"artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/","title":{"rendered":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo"},"content":{"rendered":"<p>O mais antigo teatro em funcionamento em toda a Am\u00e9rica Latina e o primeiro do Brasil, a Casa da \u00d3pera volta a receber artistas no pr\u00f3ximo s\u00e1bado, dia 27 de junho. \u00c9 o projeto \u201cOuro Preto Viva\u201d, que ir\u00e1 reunir diversos artistas da cidade para arrecadar doa\u00e7\u00f5es para o Lar que abriga idosos em Ouro Preto.<\/p>\n\n\n\n<p>Com repert\u00f3rios variados, como forr\u00f3, mpb e samba, a live ter\u00e1 in\u00edcio \u00e0s 16h. Ser\u00e3o quatro horas de muita m\u00fasica, com apresenta\u00e7\u00e3o das bandas Pavio de Lamparina e Manguaceira; dos artistas Danilo Avellar, Kastora, Tiago Couto, Daniel Marcos e David Martins;<\/p>\n\n\n\n<p>Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A live ser\u00e1 transmitida no perfil oficial da Prefeitura de Ouro Preto no Facebook (<a href=\"http:\/\/www.facebook.com\/prefeituraouropreto\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">www.facebook.com\/prefeituraouropreto<\/a>).<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Ouro Preto Viva tem apoio da Prefeitura de Ouro Preto, Gerencianet, Valenet, Navalha Produtora Audiovisual e FalaF\u00e1cil.<\/p>","protected":false},"excerpt":{"rendered":"<p>O mais antigo teatro em funcionamento em toda a Am\u00e9rica Latina e o primeiro do Brasil, a Casa da \u00d3pera volta a receber artistas no pr\u00f3ximo s\u00e1bado, dia 27 de junho. \u00c9 o projeto \u201cOuro Preto Viva\u201d, que ir\u00e1 reunir diversos artistas da cidade para arrecadar doa\u00e7\u00f5es para o Lar<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["entry","author-diario","post-4063","post","type-post","status-publish","format-standard","has-post-thumbnail","category-culturaeartes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-25T14:59:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-25T14:59:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"905\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo\",\"datePublished\":\"2020-06-25T14:59:45+00:00\",\"dateModified\":\"2020-06-25T14:59:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/\"},\"wordCount\":193,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Divulga\u00e7\u00e3o-e1593097124791.jpeg\",\"articleSection\":[\"Cultura, Artes e Patrim\u00f4nio\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/\",\"name\":\"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Divulga\u00e7\u00e3o-e1593097124791.jpeg\",\"datePublished\":\"2020-06-25T14:59:45+00:00\",\"dateModified\":\"2020-06-25T14:59:47+00:00\",\"description\":\"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Divulga\u00e7\u00e3o-e1593097124791.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Divulga\u00e7\u00e3o-e1593097124791.jpeg\",\"width\":905,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto","description":"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/","og_locale":"pt_PT","og_type":"article","og_title":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto","og_description":"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-25T14:59:45+00:00","article_modified_time":"2020-06-25T14:59:47+00:00","og_image":[{"width":905,"height":438,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo","datePublished":"2020-06-25T14:59:45+00:00","dateModified":"2020-06-25T14:59:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/"},"wordCount":193,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","articleSection":["Cultura, Artes e Patrim\u00f4nio"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/","url":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/","name":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","datePublished":"2020-06-25T14:59:45+00:00","dateModified":"2020-06-25T14:59:47+00:00","description":"Haver\u00e1 tamb\u00e9m participa\u00e7\u00e3o especial de Tadeu Franco, Chico Lobo, Luiza Gai\u00e3o, Galanga, Nando Santos, Tianast\u00e1cia e Orquestra Ouro Preto com Alceu Valen\u00e7a, com a exibi\u00e7\u00e3o dos v\u00eddeos enviados por esses artistas.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","width":905,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/artistas-de-ouro-preto-realizam-live-em-prol-do-lar-sao-vicente-de-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Artistas de Ouro Preto realizam live em prol do Lar S\u00e3o Vicente de Paulo"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Divulga\u00e7\u00e3o-e1593097124791.jpeg","jetpack-related-posts":[{"id":14712,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ia-instituto-de-arte-contemporanea-de-ouro-preto-realiza-lives-para-o-publico-com-debates-propostos-no-programa-de-residencia-extincao\/","url_meta":{"origin":4063,"position":0},"title":"\u201cIA &#8211; Instituto de Arte Contempor\u00e2nea de Ouro Preto\u201d realiza lives para o p\u00fablico com debates propostos no programa de resid\u00eancia \u201cextin\u00e7\u00e3o\u201d","author":"Di\u00e1rio de Ouro Preto","date":"1 de Abril de 2022","format":false,"excerpt":"P\u00fablico pode conferir as Lives com convidados especiais nos dias 4 e 18 de abril o Canal de Youtube do IA O primeiro programa de resid\u00eancia 2022 do IA - Instituto de Arte Contempor\u00e2nea de Ouro Preto tem a tem\u00e1tica \u201cEXTIN\u00c7\u00c3O\u201d e j\u00e1 est\u00e1 em andamento com os artistas selecionados.\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/Frederico-Filippi-Divulgacao-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/Frederico-Filippi-Divulgacao-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/Frederico-Filippi-Divulgacao-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/04\/Frederico-Filippi-Divulgacao-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7521,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comecou-o-festival-musica-no-largo-de-marilia\/","url_meta":{"origin":4063,"position":1},"title":"Come\u00e7ou o Festival M\u00fasica no Largo de Mar\u00edlia","author":"Di\u00e1rio de Ouro Preto","date":"8 de Abril de 2021","format":false,"excerpt":"Ouro Preto \u2013\u00a0 O Festival\u00a0 \u201cM\u00fasica no Largo de Mar\u00edlia\u201d, come\u00e7ou hoje, 08\/04,e segue at\u00e9 domingo 11\/04, com a programa\u00e7\u00e3o on-line, as apresenta\u00e7\u00f5es ser\u00e3o transmitidas duas lives di\u00e1rias, a primeira ao meio-dia e segunda\u00a0 \u00e0s 16 horas.Foram selecionados 8 grupos\/artistas de Ouro Preto e regi\u00e3o para se apresentarem no formato\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-08-at-12.25.30.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-08-at-12.25.30.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-08-at-12.25.30.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-08-at-12.25.30.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-08-at-12.25.30.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8782,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/sesc-cine-live-show-exibira-shows-com-grandes-artistas-durante-a-16a-cineop\/","url_meta":{"origin":4063,"position":2},"title":"Sesc Cine Live Show exibir\u00e1 shows com grandes artistas durante a 16\u00aa CineOP","author":"Di\u00e1rio de Ouro Preto","date":"22 de Junho de 2021","format":false,"excerpt":"A tradicional Mostra de Cinema de Ouro Preto \u2013 CineOP, que marca o calend\u00e1rio audiovisual brasileiro com uma vasta programa\u00e7\u00e3o cultural, chega em sua 16\u00aa edi\u00e7\u00e3o, de 23 a 28 de junho. Mais uma vez, o Sesc em Minas ser\u00e1 parceiro do evento, com o Sesc Cine Live Show.\u00a0Toda a\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/ZeliaDuncan_credito-Roberto-Setton-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/ZeliaDuncan_credito-Roberto-Setton-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/ZeliaDuncan_credito-Roberto-Setton-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/ZeliaDuncan_credito-Roberto-Setton-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/ZeliaDuncan_credito-Roberto-Setton-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8691,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/coletivo-minas-da-voz-realiza-a-2a-mostra-de-mulheres-compositoras-minas-da-voz\/","url_meta":{"origin":4063,"position":3},"title":"Coletivo Minas da Voz realiza a \u201c2\u00aa Mostra de Mulheres Compositoras Minas da Voz\u201d","author":"Di\u00e1rio de Ouro Preto","date":"17 de Junho de 2021","format":false,"excerpt":"A II Mostra de Mulheres Compositoras Minas da Voz ser\u00e1 realizada entre os dias 24 e 27 de junho no Youtube e Instagram (@minas.da.voz) e conta com 12 shows musicais, lives e rodas de conversas.\u00a0 Adaptando-se ao formato virtual, a segunda edi\u00e7\u00e3o da mostra, que \u00e9 realizada e produzida pelo\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/CAPA-PROGRAMACAO-COMPLETA-1-e1623955090201.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/CAPA-PROGRAMACAO-COMPLETA-1-e1623955090201.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/CAPA-PROGRAMACAO-COMPLETA-1-e1623955090201.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/06\/CAPA-PROGRAMACAO-COMPLETA-1-e1623955090201.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2919,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/orquestra-ouro-preto-lanca-apresentacao-inedita-de-concerto-de-mendelssohn\/","url_meta":{"origin":4063,"position":4},"title":"Orquestra Ouro Preto lan\u00e7a apresenta\u00e7\u00e3o IN\u00c9DITA de concerto de Mendelssohn","author":"Di\u00e1rio de Ouro Preto","date":"4 de Maio de 2020","format":false,"excerpt":"A Orquestra Ouro Preto resgata mais um concerto in\u00e9dito para o p\u00fablico nessa quarentena. Dessa vez, a arte do compositor e regente alem\u00e3o Felix Mendelssohn (1809 - 1847) ser\u00e1 apresentada no Concerto para Violino e Orquestra em R\u00e9 Menor, com participa\u00e7\u00e3o do solista Carmelo de Los Santos, ao violino. Gravado\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/2019.06.29_SalaMinasGerais_Academia_OOP_IrisZanetti-120-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/2019.06.29_SalaMinasGerais_Academia_OOP_IrisZanetti-120-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/2019.06.29_SalaMinasGerais_Academia_OOP_IrisZanetti-120-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/2019.06.29_SalaMinasGerais_Academia_OOP_IrisZanetti-120-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/2019.06.29_SalaMinasGerais_Academia_OOP_IrisZanetti-120-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7439,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/musica-no-largo-de-marilia-ganha-edicao-on-line-em-abril-de-2021\/","url_meta":{"origin":4063,"position":5},"title":"\u201cM\u00fasica no Largo de Mar\u00edlia\u201d ganha edi\u00e7\u00e3o on-line em abril de 2021","author":"Di\u00e1rio de Ouro Preto","date":"4 de Abril de 2021","format":false,"excerpt":"Ouro Preto -\u00a0 A semana de p\u00e1scoa tem em sua grade de programa\u00e7\u00e3o o \u201cM\u00fasica no Largo de Mar\u00edlia\u201d, de quinta 8\/04 a domingo 11\/04 ser\u00e3o transmitidas duas lives, ao meio-dia e \u00e0s 16 horas. Foram selecionados 8 grupos\/artistas de Ouro Preto e regi\u00e3o para se apresentarem no formato audiovisual\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/1200x300-Live-Festival-Musica-no-Largo-Site-Marcelino_LOGO_MAIOR.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/1200x300-Live-Festival-Musica-no-Largo-Site-Marcelino_LOGO_MAIOR.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/1200x300-Live-Festival-Musica-no-Largo-Site-Marcelino_LOGO_MAIOR.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/1200x300-Live-Festival-Musica-no-Largo-Site-Marcelino_LOGO_MAIOR.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/1200x300-Live-Festival-Musica-no-Largo-Site-Marcelino_LOGO_MAIOR.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4063"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4064"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}