{"id":4045,"date":"2020-06-24T14:49:29","date_gmt":"2020-06-24T17:49:29","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4045"},"modified":"2020-06-24T14:49:31","modified_gmt":"2020-06-24T17:49:31","slug":"asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/","title":{"rendered":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o"},"content":{"rendered":"<p>Ouro Preto &#8211; Conhecida principalmente pela festa em honra \u00e0 padroeira Santa Quit\u00e9ria, realizada no m\u00eas de maio, a localidade de Catarina Mendes \u00e9 uma das mais pr\u00f3ximas \u00e0 sede Ouro Preto. Mas esta proximidade n\u00e3o lhe garantia facilidade de acesso, j\u00e1 que a estrada, n\u00e3o pavimentada, dificultava a passagem de moradores e visitantes, principalmente em dias de chuva. Essa \u00e9 mais uma realidade que come\u00e7a a ser transformada pela Prefeitura.<\/p>\n\n\n\n<p>O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores. Dono de um bar bastante conhecido na localidade, Ricardo Lopes j\u00e1 comemora. \u201cO asfalto vai ser \u00f3timo. Quando chove aqui fica intransit\u00e1vel. Essa era a principal reivindica\u00e7\u00e3o dos moradores aqui de Catarina Mendes. Vai ajudar na sa\u00fade e na educa\u00e7\u00e3o, por causa do transporte escolar. Vai ser um sonho realizado mesmo\u201d, comenta.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Com a pavimenta\u00e7\u00e3o de estradas, o Munic\u00edpio tira distritos e localidades do isolamento, construindo o caminho do progresso.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p><em>Foto: Obras j\u00e1 come\u00e7aram na estrada que liga Catarina Mendes a Ouro Preto. Ane Souz<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Ouro Preto &#8211; Conhecida principalmente pela festa em honra \u00e0 padroeira Santa Quit\u00e9ria, realizada no m\u00eas de maio, a localidade de Catarina Mendes \u00e9 uma das mais pr\u00f3ximas \u00e0 sede Ouro Preto. Mas esta proximidade n\u00e3o lhe garantia facilidade de acesso, j\u00e1 que a estrada, n\u00e3o pavimentada, dificultava a passagem<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":4046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-4045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-24T17:49:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-24T17:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o\",\"datePublished\":\"2020-06-24T17:49:29+00:00\",\"dateModified\":\"2020-06-24T17:49:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/\",\"name\":\"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg\",\"datePublished\":\"2020-06-24T17:49:29+00:00\",\"dateModified\":\"2020-06-24T17:49:31+00:00\",\"description\":\"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto","description":"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/","og_locale":"pt_PT","og_type":"article","og_title":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto","og_description":"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-24T17:49:29+00:00","article_modified_time":"2020-06-24T17:49:31+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o","datePublished":"2020-06-24T17:49:29+00:00","dateModified":"2020-06-24T17:49:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/"},"wordCount":196,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/","url":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/","name":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","datePublished":"2020-06-24T17:49:29+00:00","dateModified":"2020-06-24T17:49:31+00:00","description":"O asfalto que vai ligar Catarina Mendes ao bairro Morro S\u00e3o Sebasti\u00e3o vai levar mais comodidade aos moradores.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/asfalto-vai-ligar-catarina-mendes-ao-morro-sao-sebastiao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Asfalto vai ligar Catarina Mendes ao Morro S\u00e3o Sebasti\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/M\u00e1quina-trabalhando-na-estrada-de-Catarina-Mendes.jpeg","jetpack-related-posts":[{"id":47070,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/pavimentacao-asfaltica-entre-catarina-mendes-e-ouro-preto-esta-em-fase-de-conclusao\/","url_meta":{"origin":4045,"position":0},"title":"Pavimenta\u00e7\u00e3o asf\u00e1ltica entre Catarina Mendes e Ouro Preto est\u00e1 em fase de conclus\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"21 de Agosto de 2025","format":false,"excerpt":"A Prefeitura de Ouro Preto est\u00e1 executando a fase final das obras de pavimenta\u00e7\u00e3o asf\u00e1ltica na localidade de Catarina Mendes. Nesta etapa, a equipe da Secretaria de Obras realiza a constru\u00e7\u00e3o de meio-fio para acabamento e conserva\u00e7\u00e3o do trabalho realizado. \u201cO trabalho em Catarina Mendes \u00e9 fundamental para assegurar mais\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-16-at-07.38.40.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-16-at-07.38.40.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-16-at-07.38.40.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-16-at-07.38.40.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-16-at-07.38.40.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24235,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/auto-parque-da-bauxita-deve-ser-entregue-em-setembro\/","url_meta":{"origin":4045,"position":1},"title":"Auto Parque da Bauxita deve ser entregue em Setembro","author":"Di\u00e1rio de Ouro Preto","date":"7 de Julho de 2023","format":false,"excerpt":"Ouro Preto - Os engarrafamentos na Rua Jo\u00e3o Pedro da Silva, (Rua do Mar\u00e7al) devem ser solucionados com a conclus\u00e3o das obras do Auto Parque da Bauxita, com previs\u00e3o de entrega das obras para setembro, as obras come\u00e7aram ano passado e est\u00e3o em fase de finaliza\u00e7\u00e3o. O empreendimento busca aliviar\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/07\/auto-parq.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/07\/auto-parq.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/07\/auto-parq.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/07\/auto-parq.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/07\/auto-parq.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":27271,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/365-dias-por-ano-a-prefeitura-nao-para-de-cuidar-da-cidade\/","url_meta":{"origin":4045,"position":2},"title":"365 dias por ano. A Prefeitura n\u00e3o para de cuidar da cidade","author":"Di\u00e1rio de Ouro Preto","date":"20 de Dezembro de 2023","format":false,"excerpt":"No in\u00edcio do ano, o prefeito Angelo Oswaldo anunciou o pacote de obras, descrevendo 2023 como o ano da colheita, relembrando as dificuldades or\u00e7ament\u00e1rias herdadas, a pandemia e os intensos per\u00edodos chuvosos em 2021 e 2022. Apesar de todo o apelo hist\u00f3rico da cidade, que completou 312 anos, o governo\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/IMG_4700.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":37258,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/associacao-de-moradores-do-morro-sao-sebastiao-convoca-candidatos-a-prefeito-de-ouro-preto-para-apresentarem-seus-planos-de-governo-no-bairro\/","url_meta":{"origin":4045,"position":3},"title":"Associa\u00e7\u00e3o de Moradores do Morro S\u00e3o Sebasti\u00e3o convoca candidatos a prefeito de Ouro Preto para apresentarem seus planos de Governo no Bairro","author":"Di\u00e1rio de Ouro Preto","date":"22 de Agosto de 2024","format":false,"excerpt":"A Associa\u00e7\u00e3o Comunit\u00e1ria de Moradores do Morro S\u00e3o Sebasti\u00e3o (ACOMOSS) quer ouvir todos os planos de governo dos candidatos a prefeito de Ouro Preto. O primeiro a participar do convite foi o candidato Du Evangelista , da Federa\u00e7\u00e3o PSOl - Rede. O encontro se realizou, ontem 21\/08, \u00e0 noite, no\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2024-08-22-as-13.03.36_f82ff37d.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2024-08-22-as-13.03.36_f82ff37d.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2024-08-22-as-13.03.36_f82ff37d.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2024-08-22-as-13.03.36_f82ff37d.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2024-08-22-as-13.03.36_f82ff37d.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4054,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/obras-do-asfalto-do-distrito-de-santo-antonio-do-salto-ja-comecaram\/","url_meta":{"origin":4045,"position":4},"title":"Obras do asfalto do distrito de Santo Ant\u00f4nio do Salto j\u00e1 come\u00e7aram","author":"Di\u00e1rio de Ouro Preto","date":"25 de Junho de 2020","format":false,"excerpt":"Ouro Preto - Santo Ant\u00f4nio do Salto \u00e9 um distrito que impressiona pela beleza de sua paisagem. Por\u00e9m, as m\u00e1s condi\u00e7\u00f5es da estrada que liga a sede ao distrito, principalmente no per\u00edodo chuvoso, impedem que esta maravilha esteja ao alcance de todos. Esta realidade j\u00e1 est\u00e1 sendo transformada. A Prefeitura\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Asfalto-na-estrada-que-liga-ao-Salto-e1593090011541.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1562,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/camara-de-ouro-preto-aprova-orcamento-do-municipio-para-2020camara-de-ouro-preto-aprova-orcamento-do-municipio-para-2020-e-vereadores-entram-em-recesso\/","url_meta":{"origin":4045,"position":5},"title":"C\u00e2mara de Ouro Preto aprova or\u00e7amento do munic\u00edpio para 2020 e vereadores entram em recesso","author":"Di\u00e1rio de Ouro Preto","date":"18 de Dezembro de 2019","format":false,"excerpt":"Ouro Preto -Nesta ter\u00e7a-feira (17), a C\u00e2mara Municipal de Ouro Preto realizou a 78\u00aa Reuni\u00e3o Ordin\u00e1ria de 2019, \u00faltimo encontro antes do recesso legislativo. Na Ordem do Dia, os vereadores aprovaram o projeto 201\/2019, que disp\u00f5em sobre a estimativa da Receita e a fixa\u00e7\u00e3o da Despesa do munic\u00edpio para o\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/78-Reuni%C3%A3o-Ordin%C3%A1ria.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/78-Reuni%C3%A3o-Ordin%C3%A1ria.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/78-Reuni%C3%A3o-Ordin%C3%A1ria.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4045"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/4046"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}