{"id":4028,"date":"2020-06-23T19:56:56","date_gmt":"2020-06-23T22:56:56","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=4028"},"modified":"2020-06-23T19:57:04","modified_gmt":"2020-06-23T22:57:04","slug":"senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/","title":{"rendered":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro"},"content":{"rendered":"<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><strong>Bras\u00edlia- <\/strong> O Plen\u00e1rio aprovou h\u00e1 pouco, em sess\u00e3o remota, proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC n\u00ba 18\/2020) que adia as elei\u00e7\u00f5es municipais de outubro para novembro (dias 15 e 29). Os senadores agora analisam destaques \u00e0 proposta.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Ag\u00eancia Senado<\/p>","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia- O Plen\u00e1rio aprovou h\u00e1 pouco, em sess\u00e3o remota, proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC n\u00ba 18\/2020) que adia as elei\u00e7\u00f5es municipais de outubro para novembro (dias 15 e 29). Os senadores agora analisam destaques \u00e0 proposta. Fonte: Ag\u00eancia Senado<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":3778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[46],"tags":[],"class_list":["entry","author-diario","post-4028","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-23T22:56:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T22:57:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro\",\"datePublished\":\"2020-06-23T22:56:56+00:00\",\"dateModified\":\"2020-06-23T22:57:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/\"},\"wordCount\":52,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Senado_Federal_do_Brasil_Flag.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/\",\"name\":\"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Senado_Federal_do_Brasil_Flag.jpg\",\"datePublished\":\"2020-06-23T22:56:56+00:00\",\"dateModified\":\"2020-06-23T22:57:04+00:00\",\"description\":\"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Senado_Federal_do_Brasil_Flag.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Senado_Federal_do_Brasil_Flag.jpg\",\"width\":1200,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto","description":"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/","og_locale":"pt_PT","og_type":"article","og_title":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto","og_description":"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-23T22:56:56+00:00","article_modified_time":"2020-06-23T22:57:04+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro","datePublished":"2020-06-23T22:56:56+00:00","dateModified":"2020-06-23T22:57:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/"},"wordCount":52,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/","name":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","datePublished":"2020-06-23T22:56:56+00:00","dateModified":"2020-06-23T22:57:04+00:00","description":"- Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro - Pol\u00edtica","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","width":1200,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-da-aval-para-o-adiamento-das-eleicoes-para-novembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Senado d\u00e1 aval para o adiamento das elei\u00e7\u00f5es para novembro"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Senado_Federal_do_Brasil_Flag.jpg","jetpack-related-posts":[{"id":4142,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/promulgada-emenda-que-adia-eleicoes-municipais-para-novembro\/","url_meta":{"origin":4028,"position":0},"title":"Promulgada emenda que adia elei\u00e7\u00f5es municipais para novembro","author":"Di\u00e1rio de Ouro Preto","date":"2 de Julho de 2020","format":false,"excerpt":"Bras\u00edlia - As Mesas da C\u00e2mara e do Senado promulgaram nesta quinta-feira a proposta que adia as elei\u00e7\u00f5es municipais para novembro por conta da pandemia do novo coronav\u00edrus. Os prazos do calend\u00e1rio eleitoral tamb\u00e9m s\u00e3o adiados. De acordo com a Emenda Constitucional 107, os dois turnos das elei\u00e7\u00f5es ser\u00e3o realizados\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200702111627426-768x512-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200702111627426-768x512-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200702111627426-768x512-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200702111627426-768x512-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4070,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/maia-afirma-que-ainda-nao-ha-votos-na-camara-para-aprovar-adiamento-das-eleicoes\/","url_meta":{"origin":4028,"position":1},"title":"Maia afirma que ainda n\u00e3o h\u00e1 votos na C\u00e2mara para aprovar adiamento das elei\u00e7\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"25 de Junho de 2020","format":false,"excerpt":"O presidente da C\u00e2mara, Rodrigo Maia (DEM-RJ), voltou a defender o adiamento das elei\u00e7\u00f5es municipais deste ano, previstas para outubro, em raz\u00e3o da pandemia de Covid-19, mas afirmou que ainda n\u00e3o h\u00e1 votos na C\u00e2mara para aprovar a mat\u00e9ria. O Senado aprovou a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC 18\/20)\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200625183644728-768x499-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200625183644728-768x499-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200625183644728-768x499-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200625183644728-768x499-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4135,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/camara-aprova-em-segundo-turno-pec-que-adia-eleicoes-municipais-para-novembro\/","url_meta":{"origin":4028,"position":2},"title":"C\u00e2mara aprova em segundo turno PEC que adia elei\u00e7\u00f5es municipais para novembro","author":"Di\u00e1rio de Ouro Preto","date":"1 de Julho de 2020","format":false,"excerpt":"A C\u00e2mara dos Deputados aprovou h\u00e1 pouco, em segundo turno, a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 18\/20, que adia as elei\u00e7\u00f5es municipais deste ano devido \u00e0 pandemia causada pelo novo coronav\u00edrus. O placar de vota\u00e7\u00e3o no segundo turno foi de 407 votos a 70. Segundo o presidente da C\u00e2mara,\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200701191243441-768x512-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200701191243441-768x512-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/07\/img20200701191243441-768x512-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4002,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/senado-vota-nesta-terca-adiamento-de-eleicoes\/","url_meta":{"origin":4028,"position":3},"title":"Senado vota nesta ter\u00e7a adiamento de elei\u00e7\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"23 de Junho de 2020","format":false,"excerpt":"O Senado analisa em sess\u00e3o remota nesta ter\u00e7a-feira (23) a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 18\/2020, que adia as elei\u00e7\u00f5es municipais, inicialmente previstas para outubro, em decorr\u00eancia da pandemia de coronav\u00edrus. O relator da proposta, senador Weverton (PDT-MA), deve apresentar seu relat\u00f3rio at\u00e9 a manh\u00e3 desta ter\u00e7a-feira. Ele quer\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/imagem_materia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/imagem_materia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/imagem_materia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/imagem_materia-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":47906,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/isencao-do-ir-senado-deve-aprovar-projeto-rapidamente-avaliam-senadores\/","url_meta":{"origin":4028,"position":4},"title":"Isen\u00e7\u00e3o do IR: Senado deve aprovar projeto rapidamente, avaliam senadores","author":"Di\u00e1rio de Ouro Preto","date":"3 de Outubro de 2025","format":false,"excerpt":"Depois de mais de seis meses de tramita\u00e7\u00e3o, a C\u00e2mara dos Deputados aprovou na quarta-feira (1\u00ba) o projeto de lei que prev\u00ea a isen\u00e7\u00e3o do Imposto de Renda (IR) para quem recebe at\u00e9 R$ 5 mil mensais, al\u00e9m de descontos para quem ganha at\u00e9 R$ 7.350. Esse projeto (PL 1.087\/25)\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/imagem_materia.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/imagem_materia.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/imagem_materia.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/imagem_materia.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4115,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/maia-diz-que-acordo-para-votar-adiamento-das-eleicoes-ainda-esta-longe\/","url_meta":{"origin":4028,"position":5},"title":"Maia diz que acordo para votar adiamento das elei\u00e7\u00f5es ainda est\u00e1 longe","author":"Di\u00e1rio de Ouro Preto","date":"29 de Junho de 2020","format":false,"excerpt":"Bras\u00edlia - O presidente da C\u00e2mara dos Deputados, Rodrigo Maia (DEM-RJ), disse hoje (29) que ainda est\u00e1 longe de um acordo para votar na Casa a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 18\/20, que adia as elei\u00e7\u00f5es municipais deste ano, previstas para outubro, em raz\u00e3o da pandemia do novo coronav\u00edrus\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200610144430739.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200610144430739.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200610144430739.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200610144430739.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/img20200610144430739.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=4028"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/4028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/3778"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=4028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=4028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=4028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}