{"id":3726,"date":"2020-06-11T12:15:41","date_gmt":"2020-06-11T15:15:41","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=3726"},"modified":"2020-06-11T12:15:44","modified_gmt":"2020-06-11T15:15:44","slug":"padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/","title":{"rendered":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco"},"content":{"rendered":"<p>O deputado federal Padre Jo\u00e3o destinou mais 135 mil reais para o munic\u00edpio de Ouro Branco. Desta vez, foram contemplados o Instituto Federal, que receber\u00e1 100 mil, o Lar Comunit\u00e1rio Frederico Ozanam receber\u00e1 35 mil, por meio&nbsp; do Fundo Estadual de Assist\u00eancia Social e a Comunidade Terap\u00eautica Bom Pastor receber\u00e1 100 mil. Estas emendas s\u00e3o do or\u00e7amento de 2020 e s\u00e3o impositivas, ou seja, o governo \u00e9 obrigado a pagar.&nbsp;<\/p>\n\n\n\n<p>O deputado atende aos pedidos das lideran\u00e7as da comunidade e do diret\u00f3rio do Partido dos Trabalhadores. Segundo o parlamentar, os recursos para o Instituto Federal representa o compromisso com a educa\u00e7\u00e3o e com o desenvolvimento da regi\u00e3o. Desde a inaugura\u00e7\u00e3o do Instituto em Ouro Branco, em 2011 e, tamb\u00e9m, do Campus da Universidade Federal de S\u00e3o Del Rei em Ouro Branco, em 2007. Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais.&nbsp;<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Por outro lado, o deputado tamb\u00e9m destina recursos para investimento em sa\u00fade em hospitais filantr\u00f3picos e p\u00fablicos, para as prefeituras e tamb\u00e9m para Assist\u00eancia Social. E a Regi\u00e3o do Alto Paraopeba tem recebido todos os anos aportes financeiros para estas \u00e1reas.&nbsp;<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Padre Jo\u00e3o lembra que o recursos p\u00fablicos para Educa\u00e7\u00e3o, Sa\u00fade e Assist\u00eancia Social tiveram perdas bilion\u00e1rias com a aprova\u00e7\u00e3o de PEC 245, em 2016, que congelou os investimentos por 20 anos nestas tr\u00eas \u00e1reas. \u201cEu votei contra esta PEC, atual Emenda Constitucional 95. Estamos sentido na pele o sucateamento do SUS \u2013 Sistema \u00danico de Sa\u00fade. E n\u00e3o fosse o SUS neste momento de pandemia, as mortes seriam muito maiores, atingindo, sobretudo os mais pobres. Precisamos revogar esta emenda e fortalecer cada vez mais o nosso SUS\u201d, afirma Padre Jo\u00e3o.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>O deputado federal Padre Jo\u00e3o destinou mais 135 mil reais para o munic\u00edpio de Ouro Branco. Desta vez, foram contemplados o Instituto Federal, que receber\u00e1 100 mil, o Lar Comunit\u00e1rio Frederico Ozanam receber\u00e1 35 mil, por meio&nbsp; do Fundo Estadual de Assist\u00eancia Social e a Comunidade Terap\u00eautica Bom Pastor receber\u00e1<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":3727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["entry","author-diario","post-3726","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cidades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-11T15:15:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-11T15:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco\",\"datePublished\":\"2020-06-11T15:15:41+00:00\",\"dateModified\":\"2020-06-11T15:15:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg\",\"articleSection\":[\"Cidades\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/\",\"name\":\"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg\",\"datePublished\":\"2020-06-11T15:15:41+00:00\",\"dateModified\":\"2020-06-11T15:15:44+00:00\",\"description\":\"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto","description":"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/","og_locale":"pt_PT","og_type":"article","og_title":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto","og_description":"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-11T15:15:41+00:00","article_modified_time":"2020-06-11T15:15:44+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco","datePublished":"2020-06-11T15:15:41+00:00","dateModified":"2020-06-11T15:15:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/"},"wordCount":329,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","articleSection":["Cidades"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/","name":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","datePublished":"2020-06-11T15:15:41+00:00","dateModified":"2020-06-11T15:15:44+00:00","description":"Todos os anos o parlamentar destina recursos, via emenda parlamentar, para as institui\u00e7\u00f5es de ensino t\u00e9cnico e superior em todo Estado de Minas Gerais","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-destina-mais-de-r-235-mil-em-emendas-impositivas-para-ouro-branco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Padre Jo\u00e3o destina mais de R$ 235 mil em emendas impositivas para Ouro Branco"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-10-at-19.52.27-1.jpeg","jetpack-related-posts":[{"id":31131,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/leleco-em-padre-joao-visitaram-ouro-preto-nesta-sexta-feira\/","url_meta":{"origin":3726,"position":0},"title":"Leleco e Padre Jo\u00e3o visitaram Ouro Preto nesta sexta-feira","author":"Di\u00e1rio de Ouro Preto","date":"24 de Mar\u00e7o de 2024","format":false,"excerpt":"Ouro Preto - O prefeito Angelo Oswaldo recebeu ontem em seu gabinete os deputados Leleco Pimentel e Padre Jo\u00e3o, que desenvolvem o mandato \u201cJuntos para servir\u201d, a reuni\u00e3o serviu tamb\u00e9m para reafirmar os investimentos do governo Federal em Ouro Preto.Para o Instituto Cultural Samba Preto foram destinados R$ 30 mil\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/Imagem-do-WhatsApp-de-2024-03-22-as-18.52.56_3f8c3c80.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/Imagem-do-WhatsApp-de-2024-03-22-as-18.52.56_3f8c3c80.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/Imagem-do-WhatsApp-de-2024-03-22-as-18.52.56_3f8c3c80.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/Imagem-do-WhatsApp-de-2024-03-22-as-18.52.56_3f8c3c80.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/03\/Imagem-do-WhatsApp-de-2024-03-22-as-18.52.56_3f8c3c80.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1264,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-anuncia-descontingenciamento-de-emenda-para-a-a-santa-casa-de-ouro-preto\/","url_meta":{"origin":3726,"position":1},"title":"Padre Jo\u00e3o anuncia descontingenciamento  de emenda para a Santa Casa de Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"7 de Novembro de 2019","format":false,"excerpt":"Ouro Preto - O deputado federal Padre Jo\u00e3o (PT) participou do 3\u00ba Semin\u00e1rio Gest\u00e3o Hospitalar e Sustentabilidade na Sa\u00fade realizado nesta quinta-feira (05\/11), pela Santa Casa de Ouro Preto. O deputado destacou que foram descontingenciados R$ 66 mil de emenda parlamentar, destinados ao custeio das atividades da Santa Casa.\u00a0 \u201cEstamos\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/11\/P1380704.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/11\/P1380704.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/11\/P1380704.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":10259,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/padre-joao-visita-ouro-preto-em-cumprimento-de-diversas-agendas\/","url_meta":{"origin":3726,"position":2},"title":"Padre Jo\u00e3o visitou Ouro Preto em cumprimento de diversas agendas","author":"Di\u00e1rio de Ouro Preto","date":"26 de Agosto de 2021","format":false,"excerpt":"Ouro Preto - Na \u00faltima sexta-feira (20), o Deputado Federal Padre Jo\u00e3o iniciou, no Distrito de Amarantina, uma extensa agenda em Ouro Preto\/MG, acompanhado do Assessor Regional (Tiago Fernandes) e do Leleco Pimentel - Presidente do PT de Ouro Preto\/Deputado Estadual Suplente. Durante a visita, participaram de reuni\u00e3o com moradores\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/240536822_1929572473891013_1941027488440692698_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/240536822_1929572473891013_1941027488440692698_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/08\/240536822_1929572473891013_1941027488440692698_n.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":38333,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/leleco-e-padre-joao-destinam-emenda-de-r-225-mil-para-a-santa-casa\/","url_meta":{"origin":3726,"position":3},"title":"Leleco e Padre Jo\u00e3o destinam emenda de R$ 225 mil para a Santa Casa","author":"Di\u00e1rio de Ouro Preto","date":"20 de Setembro de 2024","format":false,"excerpt":"Ouro Preto -\u00a0 O deputado estadual, Leleco Pimentel e o deputado Federal Padre Jo\u00e3o estiveram ontem na Santa Casa de Miseric\u00f3rdia para oficializar a entrega dos recursos de R$ 225 mil destinados \u00e0 entidade por meio de emenda parlamentar. Os recursos devem ser aplicados em tratamento especializado como a nefrologia.\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-19-as-16.37.19_0eceba89.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-19-as-16.37.19_0eceba89.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-19-as-16.37.19_0eceba89.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-19-as-16.37.19_0eceba89.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-19-as-16.37.19_0eceba89.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9105,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tiquinho-de-politica-o-8-de-julho-o-aniversario-da-camara-e-o-fora-saneouro\/","url_meta":{"origin":3726,"position":4},"title":"Tiquinho de Pol\u00edtica:  O 8 de julho! O Anivers\u00e1rio da C\u00e2mara e o \u201cFora Saneouro\u201d","author":"Di\u00e1rio de Ouro Preto","date":"8 de Julho de 2021","format":false,"excerpt":"Ouro Preto - A quinta-feira foi agitada. Apesar do feriado de anivers\u00e1rio, a manh\u00e3 foi iniciada com a manifesta\u00e7\u00e3o do movimento\u00a0 \u201cFora Saneouro\u201d. Enquanto os manifestantes ocupavam a pra\u00e7a Tiradentes, na igreja do Pilar, o prefeito Angelo Oswaldo, a vice-prefeita Regina Braga e os vereadores Z\u00e9 do Binga, Renato Zoroastro,\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-15.39.13.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-15.39.13.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-15.39.13.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-15.39.13.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-15.39.13.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46794,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/veiculos-abandonados-pelo-governo-de-minas-serao-finalmente-entregues-a-instituicoes-de-apoio-ao-idoso\/","url_meta":{"origin":3726,"position":5},"title":"Ve\u00edculos abandonados pelo Governo de Minas ser\u00e3o finalmente entregues a institui\u00e7\u00f5es de apoio ao idoso","author":"Di\u00e1rio de Ouro Preto","date":"6 de Agosto de 2025","format":false,"excerpt":"Ap\u00f3s meses de descaso, dois carros adquiridos com emenda do deputado Padre Jo\u00e3o ser\u00e3o repassados a entidades em Vi\u00e7osa e Uruc\u00e2nia para refor\u00e7ar atendimento do SUAS Nesta quinta-feira, 7 de agosto, dois ve\u00edculos novos ser\u00e3o entregues a institui\u00e7\u00f5es de apoio ao idoso nos munic\u00edpios de Vi\u00e7osa e Uruc\u00e2nia, na Zona\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/0608_Entrega_Vicosa_atual.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/0608_Entrega_Vicosa_atual.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/0608_Entrega_Vicosa_atual.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/0608_Entrega_Vicosa_atual.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/0608_Entrega_Vicosa_atual.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=3726"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/3727"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=3726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=3726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=3726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}