{"id":3612,"date":"2020-06-09T11:27:53","date_gmt":"2020-06-09T14:27:53","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=3612"},"modified":"2020-06-09T11:27:57","modified_gmt":"2020-06-09T14:27:57","slug":"covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/","title":{"rendered":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a?"},"content":{"rendered":"<p>Nota da Prefeitura <br>Desde o in\u00edcio da pandemia em Minas Gerais, a Prefeitura de Ouro Preto vem adotando diversas medidas para conter o avan\u00e7o da doen\u00e7a. O munic\u00edpio foi um dos primeiros do Estado a tomar iniciativa para a constru\u00e7\u00e3o do\u00a0<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1626\" target=\"_blank\" data-wpel-link=\"external\"><strong>hospital de campanha<\/strong><\/a>, o qual foi entregue no dia 13 de abril, sendo o segundo de Minas Gerais a entrar em funcionamento. S\u00e3o 50 leitos, consult\u00f3rios, salas de triagem e paramenta\u00e7\u00e3o, banheiros, posto m\u00e9dico e enfermarias, \u00e1rea de expurgos e descarte de res\u00edduos e estacionamento. Tamb\u00e9m nesta quest\u00e3o da amplia\u00e7\u00e3o de atendimento, est\u00e1 sendo finalizada a constru\u00e7\u00e3o da\u00a0<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1572\" target=\"_blank\" data-wpel-link=\"external\"><strong>nova UPA Municipal<\/strong><\/a>, prevista para ser entregue nas pr\u00f3ximas semanas, e foi intermediado junto ao Minist\u00e9rio P\u00fablico do Trabalho e Justi\u00e7a Federal do Trabalho a utiliza\u00e7\u00e3o de recursos advindos de acordos com a Samarco para a Regi\u00e3o dos Inconfidentes e munic\u00edpios da Bacia do Rio Doce para\u00a0<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1630\" target=\"_blank\" data-wpel-link=\"external\"><strong>amplia\u00e7\u00e3o do n\u00famero de leitos na Santa Casa de Miseric\u00f3rdia<\/strong><\/a>, que passou de 10 para 20 leitos de UTI e ganhou mais 15 leitos cl\u00ednicos de isolamento para atendimento aos pacientes da COVID-19.<\/p>\n\n\n\n<p>Tamb\u00e9m em mar\u00e7o foi institu\u00eddo o&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1582\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>Comit\u00ea T\u00e9cnico Coronavirus<\/strong><\/a>&nbsp;\u2013 COVID 19 para deliberar sobre quest\u00f5es relativas \u00e0 atua\u00e7\u00e3o municipal perante a pandemia; foi decretado o&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1616\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>fechamento do com\u00e9rcio local<\/strong><\/a>, exceto as atividades fundamentais; iniciou-se o trabalho de&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1598\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>desinfec\u00e7\u00e3o das ruas<\/strong>&nbsp;<\/a>da cidade e distritos; foram implantadas&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1596\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>barreiras sanit\u00e1rias<\/strong>&nbsp;<\/a>nos terminais rodovi\u00e1rios para orienta\u00e7\u00e3o dos passageiros e na entrada da cidade; e a&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1659\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>vacina\u00e7\u00e3o contra a gripe para os idosos foi realizada de casa em casa<\/strong><\/a>, evitando aglomera\u00e7\u00f5es nos postos de sa\u00fade.<\/p>\n\n\n\n<p>Com aux\u00edlio de moradores e comerciantes locais, a Prefeitura tamb\u00e9m ampliou o n\u00famero de&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1599\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>cestas b\u00e1sicas<\/strong><\/a>&nbsp;para serem distribu\u00eddas para a popula\u00e7\u00e3o, inclusive comprando produtos da agricultura familiar de produtores locais.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1605\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>turismo<\/strong><\/a>, tamb\u00e9m foram adotadas medidas para minimizar o impacto ap\u00f3s a pandemia: articula\u00e7\u00e3o entre as cidades do Circuito Tur\u00edstico para interceder junto ao governo federal na busca de&nbsp;<strong>minimizar os impactos<\/strong>&nbsp;na atividade tur\u00edstica e desenvolvimento da campanha \u201c<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1601\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>Visitem Ouro Preto depois<\/strong><\/a>\u201d, para que os turistas apenas adiem a visita \u00e0 cidade, e n\u00e3o cancelem. Em<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1603\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">&nbsp;Lavras Novas<\/a>&nbsp;tamb\u00e9m houve articula\u00e7\u00e3o entre os comerciantes locais com promo\u00e7\u00f5es de vouchers para estadia ap\u00f3s a finaliza\u00e7\u00e3o do isolamento social.<\/p>\n\n\n\n<p>Por fim, a Prefeitura criou diversos canais para&nbsp;<strong>atendimento online da popula\u00e7\u00e3o<\/strong>: call center 24h (9 8431-5603), site com todas as informa\u00e7\u00f5es sobre a situa\u00e7\u00e3o do coronav\u00edrus na cidade, disponibiliza\u00e7\u00e3o de diversos&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1634\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">servi\u00e7os online<\/a>&nbsp;para continuar atendendo \u00e0 popula\u00e7\u00e3o mesmo sem atendimento presencial e publica\u00e7\u00e3o de&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/coronavirus\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\"><strong>boletins di\u00e1rios<\/strong><\/a>&nbsp;informando sobre os casos da COVID-19 no Munic\u00edpio.<\/p>\n\n\n\n<p><strong>Como os testes est\u00e3o sendo feitos?<\/strong><\/p>\n\n\n\n<p>O Munic\u00edpio segue a orienta\u00e7\u00e3o da Secretaria Estadual de Sa\u00fade e do Minist\u00e9rio da Sa\u00fade, com teste na rede de profissionais em sa\u00fade, sintom\u00e1ticos, e nos casos de contatos com contatos positivos, efetuando monitoramento. Nos territ\u00f3rios mapeados com maiores incid\u00eancias de ocorr\u00eancias, as testagens est\u00e3o sendo mais abrangentes, sempre rastreando os casos com maior risco de infec\u00e7\u00e3o, mais pr\u00f3ximos dos j\u00e1 infectados. Todos os casos internados s\u00e3o testados por teste r\u00e1pido. Caso o resultado d\u00ea negativo, \u00e9 feita a contra-prova com o teste PCR, da FUNED.<\/p>\n\n\n\n<p><strong>Aumento do n\u00famero de casos confirmados<\/strong><\/p>\n\n\n\n<p>Ouro Preto tem tr\u00eas vertentes econ\u00f4micas relevantes:<\/p>\n\n\n\n<p>1 &#8211; A educa\u00e7\u00e3o, atrav\u00e9s da Universidade Federal de Ouro Preto (UFOP), o Instituto Federal de Minas Gerais (IFMG), a Rede municipal e estadual de ensino;<\/p>\n\n\n\n<p>2 &#8211; O turismo;<\/p>\n\n\n\n<p>3 \u2013 A minera\u00e7\u00e3o.<\/p>\n\n\n\n<p>As duas primeiras, educa\u00e7\u00e3o e turismo,&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1592\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">foram paralisadas quase que completamente<\/a>. A maioria dos estudantes que n\u00e3o s\u00e3o ouro-pretanos retornaram \u00e0s suas cidades, e os atrativos tur\u00edsticos est\u00e3o fechados, evitando a circula\u00e7\u00e3o de turistas.<\/p>\n\n\n\n<p>O quadro de contamina\u00e7\u00e3o se mostra ascendente muito em fun\u00e7\u00e3o da atividade mineradora, que responde por mais de 80% dos casos confirmados. As mineradoras e suas empreiteiras foram orientadas a testarem seus funcion\u00e1rios em massa, possibilitando diagnosticar tamb\u00e9m os casos assintom\u00e1ticos, que, assim, passaram a ficar em isolamento domiciliar, com monitoramento pelas equipes dos Programas de Sa\u00fade Familiar (PSF) e da Vigil\u00e2ncia em Sa\u00fade, bem como tamb\u00e9m s\u00e3o monitorados os familiares e os contatos mais recentes.<\/p>\n\n\n\n<p><strong>Programa Minas Consciente<\/strong><\/p>\n\n\n\n<p>Ouro Preto aderiu ao programa Minas Consciente, do Governo do Estado, para que haja um&nbsp;<a href=\"https:\/\/www.ouropreto.mg.gov.br\/index.php?page=noticia&amp;id=1653\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">retorno programado e respons\u00e1vel<\/a>&nbsp;das atividades comerciais, uma vez que o isolamento social tem agravado a crise econ\u00f4mica.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><em>Fonte: Assessoria de Imprensa PMOP<\/em><br><em>Texto: colabora\u00e7\u00e3o Gilson Martins<\/em><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p><em>Fotos: Ane Souz<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Nota da Prefeitura Desde o in\u00edcio da pandemia em Minas Gerais, a Prefeitura de Ouro Preto vem adotando diversas medidas para conter o avan\u00e7o da doen\u00e7a. O munic\u00edpio foi um dos primeiros do Estado a tomar iniciativa para a constru\u00e7\u00e3o do\u00a0hospital de campanha, o qual foi entregue no dia 13<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":3613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,61],"tags":[],"class_list":["entry","author-diario","post-3612","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T14:27:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T14:27:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a?\",\"datePublished\":\"2020-06-09T14:27:53+00:00\",\"dateModified\":\"2020-06-09T14:27:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/\"},\"wordCount\":858,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg\",\"articleSection\":[\"Ouro Preto\",\"Sa\u00fade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/\",\"name\":\"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg\",\"datePublished\":\"2020-06-09T14:27:53+00:00\",\"dateModified\":\"2020-06-09T14:27:57+00:00\",\"description\":\"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto","description":"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/","og_locale":"pt_PT","og_type":"article","og_title":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto","og_description":"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-06-09T14:27:53+00:00","article_modified_time":"2020-06-09T14:27:57+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a?","datePublished":"2020-06-09T14:27:53+00:00","dateModified":"2020-06-09T14:27:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/"},"wordCount":858,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","articleSection":["Ouro Preto","Sa\u00fade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/","name":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","datePublished":"2020-06-09T14:27:53+00:00","dateModified":"2020-06-09T14:27:57+00:00","description":"- COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a? - Sa\u00fade","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/covid-19-em-ouro-preto-o-que-esta-sendo-feito-na-cidade-para-controlar-a-disseminacao-da-doenca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"COVID-19 em Ouro Preto: O que est\u00e1 sendo feito na cidade para controlar a dissemina\u00e7\u00e3o da doen\u00e7a?"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/Barreira-sanit\u00e1ria-Antonio-Pereira-2.jpeg","jetpack-related-posts":[{"id":13622,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-doa-10-mil-testes-de-covid-19-para-a-prefeitura-de-ouro-preto\/","url_meta":{"origin":3612,"position":0},"title":"Vale doa 10 mil testes de Covid-19 para a Prefeitura de Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"14 de Fevereiro de 2022","format":false,"excerpt":"Ouro Preto - A Vale entregou na \u00faltima sexta-feira, 11\/02, ao Munic\u00edpio 10 mil testes de Covid-19. A contribui\u00e7\u00e3o ajuda a administra\u00e7\u00e3o p\u00fablica a monitorar a situa\u00e7\u00e3o epidemiol\u00f3gica da doen\u00e7a e dar continuidade \u00e0s a\u00e7\u00f5es de conten\u00e7\u00e3o da pandemia. No in\u00edcio do ano, devido ao aumento do n\u00famero de casos,\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/Ane-Souz-6.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/Ane-Souz-6.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/Ane-Souz-6.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/Ane-Souz-6.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/Ane-Souz-6.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31916,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-de-ouro-preto-realiza-cerimonia-de-recebimento-dos-despojos-da-heroina-da-inconfidencia-mineira-barbara-heliodora\/","url_meta":{"origin":3612,"position":1},"title":"Prefeitura de Ouro Preto realiza cerim\u00f4nia de recebimento dos despojos da hero\u00edna da Inconfid\u00eancia Mineira, B\u00e1rbara Heliodora","author":"Di\u00e1rio de Ouro Preto","date":"19 de Abril de 2024","format":false,"excerpt":"Na ter\u00e7a-feira, 16\/04, foi recebida na Igreja do Carmo, uma com a terra da sepultura os restos mortais da poetisa.\u00a0 O evento contou com a presen\u00e7a de v\u00e1rias autoridades, entre elas o prefeito de Ouro Preto, Angelo Oswaldo, a vice-prefeita Regina Braga; a vereadora L\u00edlian Fran\u00e7a; o diretor do Museu\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/DSC09386.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/DSC09386.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/DSC09386.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/DSC09386.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/DSC09386.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25552,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/gerdau-entrega-primeira-etapa-do-patrimonio-vivo-em-miguel-burnier\/","url_meta":{"origin":3612,"position":2},"title":"Gerdau entrega primeira etapa do Patrim\u00f4nio Vivo, em Miguel Burnier","author":"Di\u00e1rio de Ouro Preto","date":"18 de Setembro de 2023","format":false,"excerpt":"Com investimento de R$ 15 milh\u00f5es, iniciativa valoriza a mem\u00f3ria e incentiva a cultura local. Projeto foi constru\u00eddo junto com a comunidade A Gerdau, maior empresa brasileira produtora de a\u00e7o, entrega, na manh\u00e3 desta segunda-feira (18\/09), a primeira fase do projeto Patrim\u00f4nio Vivo, em Miguel Burnier, distrito de Ouro Preto.\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Patrimonio-Vivo.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Patrimonio-Vivo.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Patrimonio-Vivo.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Patrimonio-Vivo.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/09\/Patrimonio-Vivo.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2989,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/estado-entrega-mais-368-leitos-de-uti\/","url_meta":{"origin":3612,"position":3},"title":"Estado entrega mais 368 leitos de UTI","author":"Di\u00e1rio de Ouro Preto","date":"7 de Maio de 2020","format":false,"excerpt":"O governador Romeu Zema anunciou nesta quinta-feira (7\/5) a libera\u00e7\u00e3o de mais 368 leitos de Unidade de Tratamento Intensivo (UTI), da rede SUS, em hospitais de todas as regi\u00f5es do estado. O aporte de unidades de sa\u00fade intensiva \u00e9 fruto de um esfor\u00e7o conjunto, organizado pela\u00a0Secretaria Estadual de Sa\u00fade (SES),\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/UTI.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/UTI.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/UTI.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/UTI.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/UTI.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41972,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ubs-saramenha-sera-referencia-para-3-mil-cidadaos-ouro-pretanos\/","url_meta":{"origin":3612,"position":4},"title":"UBS Saramenha ser\u00e1 refer\u00eancia para 3 mil cidad\u00e3os ouro-pretanos","author":"Di\u00e1rio de Ouro Preto","date":"29 de Janeiro de 2025","format":false,"excerpt":"Com um investimento de R$ 2 milh\u00f5es, a unidade est\u00e1 em constru\u00e7\u00e3o; a previs\u00e3o de entrega para a comunidade \u00e9 em 2026 Est\u00e1 em processo de constru\u00e7\u00e3o uma Unidade B\u00e1sica de Sa\u00fade (UBS), no bairro Saramenha. A obra faz parte do planejamento de expans\u00e3o e melhorias no sistema de sa\u00fade\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/7f6a326263c06e211e26f7632715a4cb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/7f6a326263c06e211e26f7632715a4cb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/7f6a326263c06e211e26f7632715a4cb.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/7f6a326263c06e211e26f7632715a4cb.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/7f6a326263c06e211e26f7632715a4cb.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":44841,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-entregara-reassentamentos-em-julho\/","url_meta":{"origin":3612,"position":5},"title":"Samarco entregar\u00e1 reassentamentos em Julho","author":"Di\u00e1rio de Ouro Preto","date":"30 de Maio de 2025","format":false,"excerpt":"Novo Bento Rodrigues - A Samarco promoveu uma visita orientada nesta quarta-feira, 28\/05, com a imprensa da regi\u00e3o, para apresentar o balan\u00e7o dos primeiros 6 meses do novo acordo da Bacia do Rio Doce e a entrega do distrito para a municipalidade.\u00a0 A diretora de Sustentabilidade Rosane Santos apresentou os\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-19.34.53_c3f82898.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-19.34.53_c3f82898.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-19.34.53_c3f82898.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-19.34.53_c3f82898.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-19.34.53_c3f82898.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=3612"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/3613"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=3612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=3612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=3612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}