{"id":3037,"date":"2020-05-12T01:03:36","date_gmt":"2020-05-12T04:03:36","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=3037"},"modified":"2020-05-12T01:03:39","modified_gmt":"2020-05-12T04:03:39","slug":"samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/","title":{"rendered":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos"},"content":{"rendered":"<p>A Samarco recebeu do Ibama, nesta segunda-feira (11), a licen\u00e7a de opera\u00e7\u00e3o dos tr\u00eas minerodutos, &nbsp;para o futuro transporte &nbsp;da polpa de min\u00e9rio de ferro entre os complexos de Germano (MG) e de Ubu (ES), de forma gradual, quando a empresa retomar suas opera\u00e7\u00f5es.<\/p>\n\n\n\n<p>Concedida pelo Ibama, a LO tem validade de dez anos e unifica as licen\u00e7as dos tr\u00eas minerodutos da empresa, al\u00e9m de incorporar as torres de transmiss\u00e3o e as esta\u00e7\u00f5es de bombas existentes ao longo do trajeto, anteriormente licenciados pelo \u00f3rg\u00e3o estadual.<\/p>\n\n\n\n<p>A Licen\u00e7a de Opera\u00e7\u00e3o (LO) dos minerodutos relembra um marco na hist\u00f3ria da empresa. H\u00e1 exatamente 43 anos, em 11\/05\/1977, a Samarco iniciava efetivamente suas opera\u00e7\u00f5es com a realiza\u00e7\u00e3o do primeiro batch transportado pelo mineroduto, de Ouro Preto at\u00e9 Anchieta, e realizava, posteriormente, o primeiro embarque no Porto de Ubu.<\/p>\n\n\n\n<p>A analista de Meio Ambiente da Samarco, Alessandra de Jesus, explica que as licen\u00e7as anteriores dos minerodutos eram independentes e estavam vigentes. \u201cCom a unifica\u00e7\u00e3o das licen\u00e7as, incorporando tamb\u00e9m as esta\u00e7\u00f5es de bombas, \u00e9 poss\u00edvel fortalecer a &nbsp;gest\u00e3o e implementar novos programas ambientais que reflitam a nova fase da Samarco\u201d, afirma.<\/p>\n\n\n\n<p>Em outubro de 2019, a Samarco recebeu a Licen\u00e7a Operacional Corretiva (LOC) para o retorno das opera\u00e7\u00f5es em Germano e, atualmente, concentra seus esfor\u00e7os na implanta\u00e7\u00e3o de um novo sistema de disposi\u00e7\u00e3o de rejeitos, com sistema de filtragem para empilhamento a seco de 80% do rejeito a ser gerado.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"http:\/\/www.samarco.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-11-at-17.27.59-300x277.jpeg\" alt=\"imagem da constru\u00e7\u00e3o do mineroduto 1\" class=\"wp-image-96584\" width=\"474\" height=\"438\"\/><figcaption>Foto Arquivo Samarco<\/figcaption><\/figure>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Samarco.com<\/p>","protected":false},"excerpt":{"rendered":"<p>A Samarco recebeu do Ibama, nesta segunda-feira (11), a licen\u00e7a de opera\u00e7\u00e3o dos tr\u00eas minerodutos, &nbsp;para o futuro transporte &nbsp;da polpa de min\u00e9rio de ferro entre os complexos de Germano (MG) e de Ubu (ES), de forma gradual, quando a empresa retomar suas opera\u00e7\u00f5es. Concedida pelo Ibama, a LO tem<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":1605,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,4,6,1],"tags":[],"class_list":["entry","author-diario","post-3037","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-mariana","category-minas-gerais","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-12T04:03:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-12T04:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos\",\"datePublished\":\"2020-05-12T04:03:36+00:00\",\"dateModified\":\"2020-05-12T04:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trabalhe-conosco-samarco.png\",\"articleSection\":[\"Brasil\",\"Mariana\",\"Minas Gerais\",\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/\",\"name\":\"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trabalhe-conosco-samarco.png\",\"datePublished\":\"2020-05-12T04:03:36+00:00\",\"dateModified\":\"2020-05-12T04:03:39+00:00\",\"description\":\"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trabalhe-conosco-samarco.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trabalhe-conosco-samarco.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto","description":"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/","og_locale":"pt_PT","og_type":"article","og_title":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto","og_description":"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-05-12T04:03:36+00:00","article_modified_time":"2020-05-12T04:03:39+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","type":"image\/png"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos","datePublished":"2020-05-12T04:03:36+00:00","dateModified":"2020-05-12T04:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/"},"wordCount":276,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","articleSection":["Brasil","Mariana","Minas Gerais","Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/","name":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","datePublished":"2020-05-12T04:03:36+00:00","dateModified":"2020-05-12T04:03:39+00:00","description":"- Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos - Brasil","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-recebe-licenca-unificada-para-reativacao-dos-minerodutos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Samarco recebe licen\u00e7a unificada para reativa\u00e7\u00e3o dos minerodutos"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/trabalhe-conosco-samarco.png","jetpack-related-posts":[{"id":6164,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-de-volta-primeiro-embarque-de-pelotas-apos-20-dias-do-inicio-das-operacoes\/","url_meta":{"origin":3037,"position":0},"title":"Samarco de volta: primeiro embarque de pelotas  ap\u00f3s 20 dias do in\u00edcio das opera\u00e7\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"19 de Janeiro de 2021","format":false,"excerpt":"Espirito Santo - A Samarco realizou seu primeiro embarque dia 11\/01, apenas 20 dias ap\u00f3s o rein\u00edcio das opera\u00e7\u00f5es no complexo Germano, no dia 23\/12. A retomada da empresa era aguardada pelas comunidades em que sua opera\u00e7\u00e3o \u00e9 base da economia. Representando cerca de 50% da arrecada\u00e7\u00e3o de Mariana, 35%\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/DJI_0392-scaled-e1611066089686.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/DJI_0392-scaled-e1611066089686.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/DJI_0392-scaled-e1611066089686.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/DJI_0392-scaled-e1611066089686.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19202,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-retomou-operacoes-sem-quitar-multas-com-ibama\/","url_meta":{"origin":3037,"position":1},"title":"Samarco retomou opera\u00e7\u00f5es sem quitar multas com Ibama","author":"Di\u00e1rio de Ouro Preto","date":"5 de Novembro de 2022","format":false,"excerpt":"Enquanto a trag\u00e9dia\u00a0em Mariana (MG) chega ao seu s\u00e9timo anivers\u00e1rio, a Samarco est\u00e1 prestes a completar dois anos da retomada de suas opera\u00e7\u00f5es. A mineradora n\u00e3o quitou nenhuma das multas ambientais impostas pelo Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis (Ibama) em decorr\u00eancia do rompimento de sua\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/1096521-jfcrzabr031117001670_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/1096521-jfcrzabr031117001670_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/1096521-jfcrzabr031117001670_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/1096521-jfcrzabr031117001670_1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/11\/1096521-jfcrzabr031117001670_1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4662,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-completa-43-anos-com-foco-na-retomada-das-operacoes\/","url_meta":{"origin":3037,"position":2},"title":"Samarco completa 43 anos  com foco na retomada das opera\u00e7\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"24 de Agosto de 2020","format":false,"excerpt":"Ouro Preto - A Samarco comemora 43 anos hoje, 24\/08. A mina da empresa est\u00e1 localizada na unidade de Germano, entre Mariana e Ouro Preto, que ter\u00e1 suas opera\u00e7\u00f5es utilizando novas tecnologias para o empilhamento de rejeitos a seco. Dessa forma, o retorno das atividades relacionadas \u00e0 extra\u00e7\u00e3o de min\u00e9rio\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/reduzida_Foto-Complexo-de-Germano_Samarco-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":18130,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-completa-45-anos-com-producao-de-cerca-de-12-milhoes-de-pelotas-e-finos-de-minerio\/","url_meta":{"origin":3037,"position":3},"title":"Samarco completa 45 anos com produ\u00e7\u00e3o de cerca de 12 milh\u00f5es de pelotas e finos de min\u00e9rio","author":"Di\u00e1rio de Ouro Preto","date":"24 de Agosto de 2022","format":false,"excerpt":"A Samarco completa 45 anos, nesta quarta-feira (24\/08), com dados que mostram que a retomada gradual das opera\u00e7\u00f5es permitiu a continuidade de sua contribui\u00e7\u00e3o para o desenvolvimento socioecon\u00f4mico dos territ\u00f3rios onde atua em Minas Gerais e no Esp\u00edrito Santo. Desde sua retomada at\u00e9 junho deste ano, a empresa alcan\u00e7ou a\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/24.08.22-Complexo-de-Germano-Pixel-Studio.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/24.08.22-Complexo-de-Germano-Pixel-Studio.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/24.08.22-Complexo-de-Germano-Pixel-Studio.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/24.08.22-Complexo-de-Germano-Pixel-Studio.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/24.08.22-Complexo-de-Germano-Pixel-Studio.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":47117,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/samarco-48-anos-uma-historia-de-inovacao-desafios-e-transformacao\/","url_meta":{"origin":3037,"position":4},"title":"\u201cSamarco 48 anos: uma hist\u00f3ria de inova\u00e7\u00e3o, desafios e transforma\u00e7\u00e3o\u201d","author":"Di\u00e1rio de Ouro Preto","date":"24 de Agosto de 2025","format":false,"excerpt":"Por Rodrigo Vilela, presidente da Samarco Hoje a Samarco celebra 48 anos de exist\u00eancia. Para compreender nossa trajet\u00f3ria at\u00e9 aqui, \u00e9 importante revisitar nossas origens e a hist\u00f3ria de seus fundadores. A Samarco foi constitu\u00edda em\u00a01973, como um projeto de\u00a0US$ 272 milh\u00f5es\u00a0\u2013 por muito tempo conhecido simplesmente como \u201cprojeto Samarco\u201d\u2026","rel":"","context":"In &quot;Coluna&quot;","block_context":{"text":"Coluna","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/coluna\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/Imagem-do-WhatsApp-de-2025-08-22-as-18.53.30_b5862929.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/Imagem-do-WhatsApp-de-2025-08-22-as-18.53.30_b5862929.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/Imagem-do-WhatsApp-de-2025-08-22-as-18.53.30_b5862929.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/Imagem-do-WhatsApp-de-2025-08-22-as-18.53.30_b5862929.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/Imagem-do-WhatsApp-de-2025-08-22-as-18.53.30_b5862929.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18238,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mg-129-tera-interdicao-na-manha-de-domingo-4-09-por-obras-da-samarco\/","url_meta":{"origin":3037,"position":5},"title":"MG 129 ter\u00e1 interdi\u00e7\u00e3o na manh\u00e3 de domingo, 4\/09, por obras da Samarco","author":"Di\u00e1rio de Ouro Preto","date":"1 de Setembro de 2022","format":false,"excerpt":"O tr\u00e2nsito da MG-129 ser\u00e1 interrompido pela manha deste domingo 4\/09, para conclus\u00e3o das obras realizadas pela Samarco, ser\u00e1 montada uma estrutura sobre a estrada para a opera\u00e7\u00e3o. A empresa n\u00e3o informou se ser\u00e1 um aqueduto ou mineroduto. A rodovia MG-129 ser\u00e1 interditada temporariamente na altura do quil\u00f4metro 113, pr\u00f3ximo\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-01-at-10.12.20.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-01-at-10.12.20.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-01-at-10.12.20.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-01-at-10.12.20.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-01-at-10.12.20.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=3037"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/3037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/1605"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=3037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=3037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=3037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}