{"id":2914,"date":"2020-05-04T19:12:22","date_gmt":"2020-05-04T22:12:22","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2914"},"modified":"2020-05-04T19:12:25","modified_gmt":"2020-05-04T22:12:25","slug":"catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/","title":{"rendered":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19"},"content":{"rendered":"<p>Catas Altas &#8211; A cidade viu sua arrecada\u00e7\u00e3o municipal despencar. A CFEM (Compensa\u00e7\u00e3o Financeira pela Explora\u00e7\u00e3o de Recursos Minerais) que garantia a maior fonte de receita, caiu R$ 2.702.486,55, se comparado abril com janeiro, a queda m\u00eas a m\u00eas encontrou em abril seu menor valor sendo auferidos R$619.385,10. \u00a0<\/p>\n\n\n\n<p>A cidade \u00e9 dependente da minera\u00e7\u00e3o e, ao mesmo tempo est\u00e1 em embate com a mineradora em processo referente ao licenciamento do Projeto Amplia\u00e7\u00e3o Fazend\u00e3o (PA COPAM n\u00ba 00312\/1996\/045\/2015), que teve audi\u00eancia tensa no dia 5 de mar\u00e7o, o conv\u00edvio entre a comunidade e a opera\u00e7\u00e3o industrial foi o foco das manifesta\u00e7\u00f5es da comunidade. Diante deste contexto, Catas Altas perdeu 61,08% entre janeiro e abril de sua arrecada\u00e7\u00e3o, sendo dependente da CFEM.<\/p>\n\n\n\n<p>A redu\u00e7\u00e3o aconteceu nas tr\u00eas principais fontes de receita devido \u00e0 paralisa\u00e7\u00e3o das atividades econ\u00f4micas nas esferas municipal, estadual e federal.<\/p>\n\n\n\n<p>Em <strong>janeiro<\/strong>, o munic\u00edpio arrecadou R$ 5.649.107,86 com:<\/p>\n\n\n\n<p>Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM) R$ 771.898,97 <\/p>\n\n\n\n<p>ICMS ESTADUAL- R$ 1.555.337,24<\/p>\n\n\n\n<p>CFEM &#8211; R$ 3.321.871,65<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Em <strong>fevereiro<\/strong>, foram R$ 5.160.068,09, uma queda de 8,66%.<\/p>\n\n\n\n<p>R$ 1.115.359,58- Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM)<\/p>\n\n\n\n<p>R$ 1.721.140,22 &#8211; ICMS ESTADUAL<\/p>\n\n\n\n<p>R$ 2.323.568,29 &#8211; CFEM<\/p>\n\n\n\n<p class=\"has-medium-font-size\">J\u00e1 em <strong>mar\u00e7o<\/strong>, esse valor caiu 30,66% em compara\u00e7\u00e3o com fevereiro, arrecadando R$ 3.577.859,57 com:<\/p>\n\n\n\n<p>R$ 652.181,60 &#8211; Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM)<\/p>\n\n\n\n<p>R$ 1.953.835,13 &#8211; ICMS ESTADUAL<\/p>\n\n\n\n<p>R$ 971.842,84 \u2013 CFEM<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Por fim, o m\u00eas de <strong>abril<\/strong> est\u00e1 fechando com 2.198.353,87 (38,55%) a menos nos cofres p\u00fablicos em rela\u00e7\u00e3o a mar\u00e7o, sendo:<\/p>\n\n\n\n<p>R$ 639.282,36 &#8211; Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM)<\/p>\n\n\n\n<p>R$ 939.686,41- ICMS ESTADUAL<\/p>\n\n\n\n<p>R$ 619.385,10\u2013 CFEM<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A preocupa\u00e7\u00e3o do prefeito \u00e9 a perman\u00eancia da queda da arrecada\u00e7\u00e3o, o que inviabilizaria inclusive o socorro \u00e0 popula\u00e7\u00e3o durante a Pandemia. \u201cEssa queda \u00e9 muito preocupante, pois o munic\u00edpio precisa desses recursos para continuar ofertando os servi\u00e7os aos mun\u00edcipes. At\u00e9 agora, estamos mantendo todas as pol\u00edticas p\u00fablicas e ainda tentando minimizar o sofrimento da popula\u00e7\u00e3o com algumas a\u00e7\u00f5es emergenciais, mas a cada dia ficar\u00e1 mais dif\u00edcil e n\u00e3o sabemos como e quando tudo isso vai terminar\u201d, destaca o prefeito Jos\u00e9 Alves Parreira.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Para o vice-prefeito Fernando Rodrigues Guimar\u00e3es, o munic\u00edpio sabe da necessidade da flexibiliza\u00e7\u00e3o e da retomada das atividades econ\u00f4micas. \u201cPor\u00e9m, precisamos ter cautela e aguardar estudos mais conclusivos e protocolos oficiais que nos orientem de como fazer esse retorno de forma segura. Uma volta precipitada pode trazer impactos negativos maiores tanto para a popula\u00e7\u00e3o quanto para a economia da cidade\u201d, justifica.<\/p>","protected":false},"excerpt":{"rendered":"<p>Catas Altas &#8211; A cidade viu sua arrecada\u00e7\u00e3o municipal despencar. A CFEM (Compensa\u00e7\u00e3o Financeira pela Explora\u00e7\u00e3o de Recursos Minerais) que garantia a maior fonte de receita, caiu R$ 2.702.486,55, se comparado abril com janeiro, a queda m\u00eas a m\u00eas encontrou em abril seu menor valor sendo auferidos R$619.385,10. \u00a0 A<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["entry","author-diario","post-2914","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cidades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T22:12:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-04T22:12:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19\",\"datePublished\":\"2020-05-04T22:12:22+00:00\",\"dateModified\":\"2020-05-04T22:12:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg\",\"articleSection\":[\"Cidades\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/\",\"name\":\"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg\",\"datePublished\":\"2020-05-04T22:12:22+00:00\",\"dateModified\":\"2020-05-04T22:12:25+00:00\",\"description\":\"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg\",\"width\":1131,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto","description":"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/","og_locale":"pt_PT","og_type":"article","og_title":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto","og_description":"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-05-04T22:12:22+00:00","article_modified_time":"2020-05-04T22:12:25+00:00","og_image":[{"width":1131,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19","datePublished":"2020-05-04T22:12:22+00:00","dateModified":"2020-05-04T22:12:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/"},"wordCount":444,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","articleSection":["Cidades"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/","url":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/","name":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","datePublished":"2020-05-04T22:12:22+00:00","dateModified":"2020-05-04T22:12:25+00:00","description":"- Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19 - Cidades","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","width":1131,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/catas-altas-registra-queda-de-61-na-arrecadacao-em-abril-por-conta-da-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Catas Altas registra queda de 61% na arrecada\u00e7\u00e3o em abril por conta da COVID 19"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/queda-arrecada\u00e7ao-de-catas-altas-scaled.jpg","jetpack-related-posts":[{"id":27901,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/anm-arrecada-mais-de-r-68-bilhoes-de-royalties-da-mineracao-em-2023\/","url_meta":{"origin":2914,"position":0},"title":"ANM arrecada mais de R$ 6,8 bilh\u00f5es de royalties da minera\u00e7\u00e3o em 2023","author":"Di\u00e1rio de Ouro Preto","date":"22 de Janeiro de 2024","format":false,"excerpt":"Redu\u00e7\u00e3o de R$160 milh\u00f5es em compara\u00e7\u00e3o com 2022 \u00e9 devido \u00e0 queda do d\u00f3lar A Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM) arrecadou o montante de R$ 6.853.077.808,28 referente a Compensa\u00e7\u00e3o Financeira pela Explora\u00e7\u00e3o Mineral (CFEM). O valor representa uma queda de 2,3% em rela\u00e7\u00e3o ao ano anterior. Segundo o superintendente de\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Area-IX-da-Mina-Fabrica-Vale.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Area-IX-da-Mina-Fabrica-Vale.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Area-IX-da-Mina-Fabrica-Vale.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/01\/Area-IX-da-Mina-Fabrica-Vale.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9621,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-lucra-r-11-bilhoes-no-2o-trimestre-minerio-e-pelotas-seguraram-as-vendas\/","url_meta":{"origin":2914,"position":1},"title":"Vale lucra US$ 11 Bilh\u00f5es no 2\u00ba trimestre min\u00e9rio e pelotas seguraram as vendas","author":"Di\u00e1rio de Ouro Preto","date":"28 de Julho de 2021","format":false,"excerpt":"Ouro Preto - A produ\u00e7\u00e3o de min\u00e9rio de ferro da Vale e as pelotas foram o destaque das vendas da empresa, e que garantiram mais retorno para a companhia. O relat\u00f3rio financeiro foi divulgado pela empresa. A vale \u00e9 respons\u00e1vel por boa parte do caixa das cidades da regi\u00e3o sendo\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":31464,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/moradores-e-visitantes-de-catas-altas-poderao-treinar-acoes-de-seguranca-em-caso-de-emergencia-envolvendo-barragens\/","url_meta":{"origin":2914,"position":2},"title":"Moradores e visitantes de Catas Altas poder\u00e3o treinar a\u00e7\u00f5es de seguran\u00e7a em caso de emerg\u00eancia envolvendo barragens","author":"Di\u00e1rio de Ouro Preto","date":"2 de Abril de 2024","format":false,"excerpt":"A comunidade do munic\u00edpio de Catas Altas poder\u00e1 participar de um treinamento sobre os procedimentos de seguran\u00e7a, em caso de emerg\u00eancia envolvendo barragens. No dia 3 de abril, quarta-feira, \u00e0s 9h30, a Defesa Civil Municipal realizar\u00e1, com apoio da Vale, o simulado pr\u00e1tico de emerg\u00eancia com a popula\u00e7\u00e3o que reside\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/unnamed-15.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/unnamed-15.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/unnamed-15.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/unnamed-15.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/04\/unnamed-15.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":44840,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/lei-de-diretrizes-orcamentarias-chega-hoje-a-camara-com-previsao-de-r-890-milhoes-para-2026\/","url_meta":{"origin":2914,"position":3},"title":"Lei de Diretrizes Or\u00e7ament\u00e1rias Chega Hoje \u00e0 C\u00e2mara com previs\u00e3o de R$ 890 milh\u00f5es para 2026","author":"Di\u00e1rio de Ouro Preto","date":"30 de Maio de 2025","format":false,"excerpt":"De acordo com os dados apresentados, a receita corrente l\u00edquida tem crescido nos \u00faltimos anos. O Projeto de Lei deve ser distribu\u00eddo \u00e0s Comiss\u00f5es na pr\u00f3xima reuni\u00e3o da C\u00e2mara, ter\u00e7a-feira, 3\/06 Ouro Preto - O diretor de Or\u00e7amento, Luiz Barbosa ontem apresentou o valor de R$ 890.688.339,00 como perspectiva de\u2026","rel":"","context":"In &quot;Manchete do dia&quot;","block_context":{"text":"Manchete do dia","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/manchete-do-dia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-18.19.24_948ed818.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-18.19.24_948ed818.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-18.19.24_948ed818.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-18.19.24_948ed818.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2025-05-29-as-18.19.24_948ed818.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":26043,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/anm-distribui-quase-r-900-milhoes-de-royalties-da-mineracao-a-estados-e-municipios-produtores\/","url_meta":{"origin":2914,"position":4},"title":"ANM distribui quase R$ 900 milh\u00f5es de royalties da minera\u00e7\u00e3o a estados e munic\u00edpios produtores","author":"Di\u00e1rio de Ouro Preto","date":"9 de Outubro de 2023","format":false,"excerpt":"A Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM) distribuiu nesta quinta-feira (5\/10) o montante de R$ 887.746.138,33 a estados e munic\u00edpios produtores minerais. O valor \u00e9 referente \u00e0 cota-parte da Compensa\u00e7\u00e3o Financeira pela Explora\u00e7\u00e3o Mineral (CFEM) arrecadada nos meses de julho e agosto de 2023.Do total distribu\u00eddo, R$ 176.038.493,55 foram para os\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/capa-noticia-geral-e1617738740372.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/capa-noticia-geral-e1617738740372.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/09\/capa-noticia-geral-e1617738740372.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":18142,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/r-22-bilhoes-prefeitos-das-cidades-mineradoras-exigem-o-pagamento-imediato-da-divida-da-vale\/","url_meta":{"origin":2914,"position":5},"title":"R$ 2,2 bilh\u00f5es \u2013 Prefeitos das cidades mineradoras exigem o pagamento imediato da d\u00edvida da Vale","author":"Di\u00e1rio de Ouro Preto","date":"26 de Agosto de 2022","format":false,"excerpt":"Ouro Preto- Uma grande manifesta\u00e7\u00e3o paralisou a Pra\u00e7a Tiradentes nesta quarta-feira, 24\/08. O ato foi promovido pela Associa\u00e7\u00e3o dos Munic\u00edpios Mineradores de Minas Gerais e do Brasil, AMIG, que reivindica o pagamento da d\u00edvida da Vale com os munic\u00edpios onde a empresa atua.Na hist\u00f3rica cidade, foi apresentada uma carta aberta\u2026","rel":"","context":"In &quot;Manchete do dia&quot;","block_context":{"text":"Manchete do dia","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/manchete-do-dia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-19.05.21.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-19.05.21.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-19.05.21.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-19.05.21.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-19.05.21.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2914"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2916"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}