{"id":2835,"date":"2020-04-23T18:56:24","date_gmt":"2020-04-23T21:56:24","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2835"},"modified":"2020-04-23T18:56:27","modified_gmt":"2020-04-23T21:56:27","slug":"auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/","title":{"rendered":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso"},"content":{"rendered":"<p><br>Bras\u00edlia &#8211; A Caixa j\u00e1 creditou mais de R$ 16 bilh\u00f5es do aux\u00edlio emergencial para mais de 24 milh\u00f5es de brasileiros. Mais de 44 milh\u00f5es de cadastros j\u00e1 foram realizados e mais de 10 milh\u00f5es de contas abertas. Ainda assim, restam algumas d\u00favidas sobre como se cadastrar, como receber, como utilizar o aplicativo, como movimentar a Poupan\u00e7a Digital CAIXA e como sacar os valores.<\/p>\n\n\n\n<p>Este texto vai responder algumas dessas quest\u00f5es.<\/p>\n\n\n\n<p><strong>Como utilizar a conta poupan\u00e7a digital?<\/strong><\/p>\n\n\n\n<p>A movimenta\u00e7\u00e3o da Poupan\u00e7a Digital CAIXA \u00e9 realizada pelo aplicativo CAIXA Tem, dispon\u00edvel nas lojas de aplicativos Play Store e App Store. Os benefici\u00e1rios que receberem o cr\u00e9dito por meio dessa conta podem, pelo aplicativo, realizar pagamento de boletos e contas de \u00e1gua, luz, telefone, dentre outras, e tamb\u00e9m efetuar transfer\u00eancias ilimitadas entre contas da CAIXA ou realizar gratuitamente at\u00e9 tr\u00eas transfer\u00eancias para outros bancos a cada m\u00eas, pelos pr\u00f3ximos 90 dias.<\/p>\n\n\n\n<p>Os benefici\u00e1rios ter\u00e3o cart\u00e3o de d\u00e9bito virtual que poder\u00e1 ser usado em lojas habilitadas. Atualmente, j\u00e1 s\u00e3o 700 empresas habilitadas ou que est\u00e3o em fase de implementa\u00e7\u00e3o, como supermercados, farm\u00e1cias, empresas do ramo aliment\u00edcio e de transporte. Para que o com\u00e9rcio possa aceitar o d\u00e9bito virtual da CAIXA, basta que ele entre em contato com a adquirente que o atende solicitando a habilita\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para utilizar o aplicativo, que tem f\u00e1cil navega\u00e7\u00e3o e baixo consumo da mem\u00f3ria do celular, basta que o usu\u00e1rio se cadastre utilizando o CPF. Al\u00e9m de movimentar a poupan\u00e7a digital, ser\u00e1 poss\u00edvel consultar FGTS, PIS, Bolsa Fam\u00edlia, entre outros servi\u00e7os. Mas tamb\u00e9m \u00e9 poss\u00edvel realizar saques em esp\u00e9cie, de acordo com o cronograma divulgado.<\/p>\n\n\n\n<p><strong>Como proceder para sacar em esp\u00e9cie?<\/strong><\/p>\n\n\n\n<p>N\u00e3o \u00e9 necess\u00e1ria corrida \u00e0s ag\u00eancias ou \u00e0s lot\u00e9ricas para realizar os saques em esp\u00e9cie. Na data prevista para in\u00edcio do saque em esp\u00e9cie, o cliente ter\u00e1 esta op\u00e7\u00e3o habilitada no aplicativo CAIXA Tem. Bastar\u00e1 informar o valor a ser retirado e ser\u00e1 gerado um c\u00f3digo autorizador para saque nos caixas eletr\u00f4nicos e casas lot\u00e9ricas.<\/p>\n\n\n\n<p>Com o objetivo de evitar aglomera\u00e7\u00f5es nas ag\u00eancias e unidades lot\u00e9ricas, expondo empregados, parceiros e clientes ao risco de cont\u00e1gio, a CAIXA escalonou o calend\u00e1rio de saque. Lembramos que os recursos creditados na Poupan\u00e7a digital podem ser utilizados atrav\u00e9s do app CAIXA Tem para pagamentos e transfer\u00eancias, entre outros servi\u00e7os.<\/p>\n\n\n\n<p>Segue o calend\u00e1rio de saque em esp\u00e9cie da poupan\u00e7a digital sem cart\u00e3o nos canais de autoatendimento e lot\u00e9ricas:<\/p>\n\n\n\n<p>\u2022 27 de abril \u2013 nascidos em janeiro e fevereiro<\/p>\n\n\n\n<p>\u2022 28 de abril \u2013 nascidos em mar\u00e7o e abril<\/p>\n\n\n\n<p>\u2022 29 de abril \u2013 nascidos em maio e junho<\/p>\n\n\n\n<p>\u2022 30 de abril \u2013 nascidos julho e agosto<\/p>\n\n\n\n<p>\u2022 04 de maio \u2013 nascidos em setembro e outubro<\/p>\n\n\n\n<p>\u2022 05 de maio \u2013 nascidos em novembro e dezembro<\/p>\n\n\n\n<p><strong>Como quem n\u00e3o tem internet pode utilizar os aplicativos?<\/strong><\/p>\n\n\n\n<p>As operadoras de telefonia m\u00f3vel est\u00e3o disponibilizando os aplicativos CAIXA | Aux\u00edlio Emergencial e CAIXA Tem com navega\u00e7\u00e3o gratuita, assim todo brasileiro pode navegar no seu telefone gratuitamente nestes aplicativos at\u00e9 o fim de maio.<\/p>\n\n\n\n<p><strong>Se o pedido do aux\u00edlio for negado \u00e9 poss\u00edvel recorrer?<\/strong><\/p>\n\n\n\n<p>Sim. O aplicativo CAIXA | Aux\u00edlio Emergencial passou a disponibilizar possibilidade de nova solicita\u00e7\u00e3o ou contesta\u00e7\u00e3o do resultado da an\u00e1lise efetuada pela Dataprev.<\/p>\n\n\n\n<p><strong>Para solicita\u00e7\u00e3o do aux\u00edlio emergencial feita depois do prazo de pagamento da parcela de abril: quantas parcelas o cidad\u00e3o ter\u00e1 direito?<\/strong><\/p>\n\n\n\n<p>Ter\u00e1 direito a tr\u00eas parcelas do aux\u00edlio emergencial, mesmo que fa\u00e7a a solicita\u00e7\u00e3o depois do pagamento da parcela de abril.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><strong>\u00c9 poss\u00edvel fazer solicita\u00e7\u00e3o presencial do aux\u00edlio nas ag\u00eancias ou unidades lot\u00e9ricas?<\/strong><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>N\u00e3o. Quem atende \u00e0s regras do aux\u00edlio e j\u00e1 est\u00e1 no Cadastro \u00danico ou recebe o benef\u00edcio Bolsa Fam\u00edlia, receber\u00e1 o aux\u00edlio emergencial automaticamente, sem precisar solicitar. Se n\u00e3o estiver inscrito no Cadastro \u00danico, deve solicitar o aux\u00edlio no site&nbsp;<a href=\"http:\/\/auxilio.caixa.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">auxilio.caixa.gov.br<\/a>&nbsp;ou no aplicativo CAIXA | Aux\u00edlio Emergencial.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; A Caixa j\u00e1 creditou mais de R$ 16 bilh\u00f5es do aux\u00edlio emergencial para mais de 24 milh\u00f5es de brasileiros. Mais de 44 milh\u00f5es de cadastros j\u00e1 foram realizados e mais de 10 milh\u00f5es de contas abertas. Ainda assim, restam algumas d\u00favidas sobre como se cadastrar, como receber, como<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-2835","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-23T21:56:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-23T21:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"194\" \/>\n\t<meta property=\"og:image:height\" content=\"111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso\",\"datePublished\":\"2020-04-23T21:56:24+00:00\",\"dateModified\":\"2020-04-23T21:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/\"},\"wordCount\":719,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image001-e1586470537987.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/\",\"name\":\"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image001-e1586470537987.jpg\",\"datePublished\":\"2020-04-23T21:56:24+00:00\",\"dateModified\":\"2020-04-23T21:56:27+00:00\",\"description\":\"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image001-e1586470537987.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image001-e1586470537987.jpg\",\"width\":194,\"height\":111},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto","description":"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/","og_locale":"pt_PT","og_type":"article","og_title":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto","og_description":"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-04-23T21:56:24+00:00","article_modified_time":"2020-04-23T21:56:27+00:00","og_image":[{"width":194,"height":111,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso","datePublished":"2020-04-23T21:56:24+00:00","dateModified":"2020-04-23T21:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/"},"wordCount":719,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/","name":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","datePublished":"2020-04-23T21:56:24+00:00","dateModified":"2020-04-23T21:56:27+00:00","description":"- AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso - Brasil","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","width":194,"height":111},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-explica-principais-duvidas-sobre-o-recurso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"AUX\u00cdLIO EMERGENCIAL: Caixa explica principais d\u00favidas sobre o recurso"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/image001-e1586470537987.jpg","jetpack-related-posts":[{"id":2709,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/caixa-inicia-pagamento-do-auxilio-emergencial\/","url_meta":{"origin":2835,"position":0},"title":"Caixa inicia pagamento do aux\u00edlio emergencial","author":"Di\u00e1rio de Ouro Preto","date":"9 de Abril de 2020","format":false,"excerpt":"Bras\u00edlia - A CAIXA creditou, nesta quinta-feira (9), os primeiros pagamentos do aux\u00edlio emergencial do governo federal. O benef\u00edcio foi creditado na conta poupan\u00e7a de 2.150.497 clientes do banco. Outros 436.078 lan\u00e7amentos ser\u00e3o realizados pelo Banco do Brasil ainda nesta quinta-feira. Mais de 2,5 milh\u00f5es de cidad\u00e3os j\u00e1 foram beneficiados,\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2812,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/caixa-antecipa-creditos-da-2a-parcela-do-auxilio-emergencial-e-libera-o-beneficio-para-mais-de-26-milhoes-nesta-semana\/","url_meta":{"origin":2835,"position":1},"title":"Caixa antecipa cr\u00e9ditos da 2\u00aa  parcela do aux\u00edlio emergencial e libera o benef\u00edcio para mais de 26 milh\u00f5es nesta semana","author":"Di\u00e1rio de Ouro Preto","date":"20 de Abril de 2020","format":false,"excerpt":"Bras\u00edlia - Desde o dia 9 de abril, quando teve in\u00edcio o pagamento do Aux\u00edlio Emergencial do governo federal, a CAIXA j\u00e1 creditou mais de R$\u00a016,3\u00a0bilh\u00f5es para\u00a024,2\u00a0milh\u00f5es de brasileiros.\u00a0O banco, agente pagador do aux\u00edlio, est\u00e1 realizando a maior opera\u00e7\u00e3o de\u00a0bancariza\u00e7\u00e3o\u00a0da hist\u00f3ria do\u00a0Brasil, tendo aberto at\u00e9 esta data\u00a0(20)\u00a0mais de\u00a010\u00a0milh\u00f5es de contas\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2726,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/caixa-tira-duvidas-sobre-auxilio-emergencial\/","url_meta":{"origin":2835,"position":2},"title":"CAIXA TIRA D\u00daVIDAS SOBRE AUX\u00cdLIO EMERGENCIAL","author":"Di\u00e1rio de Ouro Preto","date":"9 de Abril de 2020","format":false,"excerpt":"Ouro Preto - A Caixa respondeu \u00e0s perguntas dos leitores do di\u00e1rio sobre o pagamento dos aux\u00edlios emergenciais. Mais cedo, ap\u00f3s ser veiculada nota oficial, os leitores nos informaram sobre a efetiva\u00e7\u00e3o do cr\u00e9dito, outros deixaram suas d\u00edvidas, as quais encaminhamos e obtivemos as seguintes respostas: Quem est\u00e1 regular no\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2840,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/caixa-abrira-799-agencias-amanha-para-atendimento-de-servicos-essenciais\/","url_meta":{"origin":2835,"position":3},"title":"Caixa abrir\u00e1 799 agencias amanh\u00e3 para atendimento de servi\u00e7os essenciais","author":"Di\u00e1rio de Ouro Preto","date":"24 de Abril de 2020","format":false,"excerpt":"A CAIXA abrir\u00e1 799 ag\u00eancias neste s\u00e1bado (25), de 8h \u00e0s 12h, para atendimento de servi\u00e7os essenciais \u00e0 popula\u00e7\u00e3o. Poder\u00e3o ser realizados saque INSS sem cart\u00e3o; saque de Seguro Desemprego\/Defeso sem cart\u00e3o e senha; saque Bolsa Fam\u00edlia e outros benef\u00edcios sociais sem cart\u00e3o e senha; pagamento de Abono Salarial e\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3347,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/caixa-abre-sabado-as-agencias-de-ouro-preto-mariana-e-itabirito-para-pagamento-do-auxilio-emergencial\/","url_meta":{"origin":2835,"position":4},"title":"Caixa abre s\u00e1bado as ag\u00eancias de Ouro Preto, Mariana e Itabirito  para pagamento do aux\u00edlio emergencial","author":"Di\u00e1rio de Ouro Preto","date":"28 de Maio de 2020","format":false,"excerpt":"A CAIXA vai abrir, neste s\u00e1bado (30), de 8h \u00e0s 12h, 217 ag\u00eancias em Minas Gerais\u00a0para atendimento aos benefici\u00e1rios do Aux\u00edlio Emergencial que receberam a primeira parcela at\u00e9 30 de abril, nascidos\u00a0em janeiro e que queiram fazer o saque em esp\u00e9cie do benef\u00edcio. A partir desta data, tamb\u00e9m ser\u00e1\u00a0 poss\u00edvel\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/image003.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5820,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/auxilio-emergencial-caixa-credita-hoje-r-11-bi-para-32-milhoes-de-beneficiarios-do-ciclo-6-nascidos-em-abril\/","url_meta":{"origin":2835,"position":5},"title":"Aux\u00edlio Emergencial: caixa credita hoje R$ 1,1 bi para 3,2 milh\u00f5es de benefici\u00e1rios do ciclo 6 nascidos em Abril","author":"Di\u00e1rio de Ouro Preto","date":"16 de Dezembro de 2020","format":false,"excerpt":"Ciclo 6 contempla parcelas do Aux\u00edlio Emergencial e do Aux\u00edlio Emergencial Extens\u00e3o A CAIXA realiza, nesta quarta-feira (16\/12), mais uma etapa de pagamento do Aux\u00edlio Emergencial e do Aux\u00edlio Emergencial Extens\u00e3o para 3,2 milh\u00f5es de brasileiros do ciclo 6 nascidos em abril. Os benefici\u00e1rios receber\u00e3o R$ 1,1 bilh\u00e3o em suas\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/lancamento_do_aplicativo_caixa_auxilio_emergencial_0407201851.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2835"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2727"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}