{"id":2713,"date":"2020-04-09T12:51:09","date_gmt":"2020-04-09T15:51:09","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2713"},"modified":"2020-04-09T13:41:40","modified_gmt":"2020-04-09T16:41:40","slug":"comunicado-saneouro-antonio-pereira","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/","title":{"rendered":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA"},"content":{"rendered":"<p>COMUNICADO<br><\/p>\n\n\n\n<p><strong>Qualidade da \u00e1gua do Distrito de Ant\u00f4nio Pereira<\/strong><br><\/p>\n\n\n\n<p><strong>OURO PRETO SERVI\u00c7OS DE SANEAMENTO S.A. \u2013 SANEOURO<\/strong>, concession\u00e1ria dos servi\u00e7os p\u00fablicos de \u00e1gua e esgoto, com sede administrativa na Cidade de Ouro Preto, Estado de Minas Gerais, na Av. Juscelino Kubitscheck, 717 \u2013 loja 03, Vila Itacolomi, inscrita no CNPJ sob n\u00ba 35.198.517\/0001-11 (\u201cSANEOURO\u201d ou \u201cConcession\u00e1ria\u201d), vem por meio deste esclarecer o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.<br><\/p>\n\n\n\n<p><strong>Hist\u00f3rico<\/strong><br><\/p>\n\n\n\n<p>A SANEOURO, antes do in\u00edcio de suas opera\u00e7\u00f5es, para ter seguran\u00e7a de processo, realizou a coleta da \u00e1gua bruta em todas as capta\u00e7\u00f5es do Munic\u00edpio, incluindo a capta\u00e7\u00e3o do c\u00f3rrego \u00c1gua Suja, que \u00e9 a fonte de capta\u00e7\u00e3o da \u00e1gua que \u00e9 tratada na ETA Ant\u00f4nio Pereira. Em 29 de novembro de 2019, a concentra\u00e7\u00e3o de Mangan\u00eas na amostra de \u00e1gua bruta analisada era de 0,0359 mg\/L.&nbsp;<\/p>\n\n\n\n<p>Iniciamos a opera\u00e7\u00e3o no Munic\u00edpio de Ouro Preto no dia 02 de janeiro de 2020 e no in\u00edcio de mar\u00e7o come\u00e7amos a ter notifica\u00e7\u00f5es de que a \u00e1gua do Distrito, nas resid\u00eancias abastecidas pela rede proveniente da ETA Ant\u00f4nio Pereira, estava chegando com colora\u00e7\u00e3o marrom avermelhada.&nbsp;<\/p>\n\n\n\n<p>O Distrito de Ant\u00f4nio Pereira possui um po\u00e7o que foi perfurado, mas que nunca chegou a ser ligado na rede. Por ocasi\u00e3o do nosso in\u00edcio de opera\u00e7\u00e3o, contratamos empresa especializada para avalia\u00e7\u00e3o do po\u00e7o e para podermos avaliar sua real capacidade de produ\u00e7\u00e3o e qualidade de \u00e1gua, colocamos o po\u00e7o em funcionamento, bombeando \u00e1gua para a ETA no per\u00edodo de 09 de mar\u00e7o \u00e0 25 de mar\u00e7o \u00faltimo, dia em que a bomba do po\u00e7o sofreu avaria tendo em vista a elevada carga de s\u00f3lidos (areia) que a \u00e1gua do po\u00e7o traz consigo, impossibilitando a utiliza\u00e7\u00e3o do mesmo, portanto a possibilidade de utilizarmos a \u00e1gua deste po\u00e7o para o abastecimento do distrito foi descartada. A Saneouro j\u00e1 elaborou projeto de um novo po\u00e7o e o processo de contrata\u00e7\u00e3o da perfura\u00e7\u00e3o encontra-se em andamento.<\/p>\n\n\n\n<p>Com a volta da capta\u00e7\u00e3o para o C\u00f3rrego \u00c1gua Suja, a popula\u00e7\u00e3o voltou a ter problemas com a colora\u00e7\u00e3o da \u00e1gua das redes, neste sentido, realizamos novamente a coleta e an\u00e1lise da \u00e1gua bruta e o n\u00edvel de Mangan\u00eas presente na amostra testada subiu para 0,268 mg\/L, ou seja a concentra\u00e7\u00e3o subiu quase 7,5 vezes. \u00c9 importante salientar que essa colora\u00e7\u00e3o n\u00e3o prejudica a qualidade da \u00e1gua no seu aspecto sanit\u00e1rio.&nbsp;<\/p>\n\n\n\n<p>O tratamento completo em uma esta\u00e7\u00e3o prev\u00ea a desinfec\u00e7\u00e3o da \u00e1gua tratada com cloro e o cloro em contato com mangan\u00eas reage causando precipita\u00e7\u00e3o e, portanto, tornando a colora\u00e7\u00e3o da \u00e1gua marrom. Esta rea\u00e7\u00e3o n\u00e3o \u00e9 imediata, por isso, na sa\u00edda da ETA a colora\u00e7\u00e3o da \u00e1gua n\u00e3o apresenta altera\u00e7\u00f5es e \u00e0 medida que esta \u00e1gua percorre as tubula\u00e7\u00f5es e fica nos reservat\u00f3rios das resid\u00eancias a rea\u00e7\u00e3o vai acontecendo e a precipita\u00e7\u00e3o e consequentemente a colora\u00e7\u00e3o da \u00e1gua vai se alterando.<br><\/p>\n\n\n\n<p><strong>A\u00e7\u00f5es da SANEOURO<\/strong><br><\/p>\n\n\n\n<p>Com base nestas informa\u00e7\u00f5es, e para chegarmos neste resultado foi necess\u00e1rio fazermos v\u00e1rios outros testes para descartarmos outras poss\u00edveis causas, estamos alterando o processo de tratamento de \u00e1gua da ETA Ant\u00f4nio Pereira e instalando um tanque de pr\u00e9-oxida\u00e7\u00e3o (clora\u00e7\u00e3o) para que a rea\u00e7\u00e3o do cloro com o mangan\u00eas aconte\u00e7a antes do tratamento propriamente dito e, desta forma por meio de decanta\u00e7\u00e3o e filtra\u00e7\u00e3o as part\u00edculas sejam removidas no processo de tratamento e n\u00e3o se formem ap\u00f3s a desinfec\u00e7\u00e3o por clora\u00e7\u00e3o na sa\u00edda da ETA.<\/p>\n\n\n\n<p>Estas altera\u00e7\u00f5es j\u00e1 foram iniciadas e toda a instala\u00e7\u00e3o deve estar pronta at\u00e9 o final da pr\u00f3xima semana.<\/p>\n\n\n\n<p>Como medida emergencial, estamos realizando continuamente descargas de rede para a limpeza das tubula\u00e7\u00f5es e na data de hoje (07\/04\/2020) realizamos a lavagem da caixa de contato da ETA.<br><\/p>\n\n\n\n<p>Sem mais para o momento,<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><strong>Elisa Ribeiro<\/strong><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Superintendente &#8211; SANEOURO<br><\/p>","protected":false},"excerpt":{"rendered":"<p>COMUNICADO Qualidade da \u00e1gua do Distrito de Ant\u00f4nio Pereira OURO PRETO SERVI\u00c7OS DE SANEAMENTO S.A. \u2013 SANEOURO, concession\u00e1ria dos servi\u00e7os p\u00fablicos de \u00e1gua e esgoto, com sede administrativa na Cidade de Ouro Preto, Estado de Minas Gerais, na Av. Juscelino Kubitscheck, 717 \u2013 loja 03, Vila Itacolomi, inscrita no CNPJ<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-2713","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T15:51:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T16:41:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA\",\"datePublished\":\"2020-04-09T15:51:09+00:00\",\"dateModified\":\"2020-04-09T16:41:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/redes-sociais-2-semana-saneouro-APROVADO.png\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/\",\"name\":\"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/redes-sociais-2-semana-saneouro-APROVADO.png\",\"datePublished\":\"2020-04-09T15:51:09+00:00\",\"dateModified\":\"2020-04-09T16:41:40+00:00\",\"description\":\"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/redes-sociais-2-semana-saneouro-APROVADO.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/redes-sociais-2-semana-saneouro-APROVADO.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/comunicado-saneouro-antonio-pereira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto","description":"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/","og_locale":"pt_PT","og_type":"article","og_title":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto","og_description":"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-04-09T15:51:09+00:00","article_modified_time":"2020-04-09T16:41:40+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","type":"image\/png"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA","datePublished":"2020-04-09T15:51:09+00:00","dateModified":"2020-04-09T16:41:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/"},"wordCount":720,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/","name":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","datePublished":"2020-04-09T15:51:09+00:00","dateModified":"2020-04-09T16:41:40+00:00","description":"A SANEOURO esclarece o motivo da eventual colora\u00e7\u00e3o da \u00e1gua proveniente da ETA Ant\u00f4nio Pereira e expor as a\u00e7\u00f5es para a corre\u00e7\u00e3o de tal problema.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/comunicado-saneouro-antonio-pereira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"COMUNICADO SANEOURO: ANT\u00d4NIO PEREIRA"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/redes-sociais-2-semana-saneouro-APROVADO.png","jetpack-related-posts":[{"id":49835,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/saneouro-investiu-r15-milhao-em-antonio-pereira\/","url_meta":{"origin":2713,"position":0},"title":"Saneouro investiu R$1,5 Milh\u00e3o em Ant\u00f4nio Pereira","author":"Di\u00e1rio de Ouro Preto","date":"19 de Janeiro de 2026","format":false,"excerpt":"Distrito foi o primeiro a receber um po\u00e7o profundo perfurado pela empresa Ao contr\u00e1rio do que afirma o vereador Wemerson Tit\u00e3o em v\u00eddeos divulgados no \u00faltimo final de semana, o distrito de Ant\u00f4nio Pereira foi o primeiro de Ouro Preto a receber investimentos da Saneouro para melhoria da qualidade da\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/Poco_Antonio_Pereira_01.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/Poco_Antonio_Pereira_01.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/Poco_Antonio_Pereira_01.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/Poco_Antonio_Pereira_01.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49790,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/saneouro-informa-instalacao-de-hidrometros\/","url_meta":{"origin":2713,"position":1},"title":"Saneouro informa instala\u00e7\u00e3o de hidr\u00f4metros","author":"Di\u00e1rio de Ouro Preto","date":"15 de Janeiro de 2026","format":false,"excerpt":"A Saneouro informa que, cumprindo uma recomenda\u00e7\u00e3o do Minist\u00e9rio P\u00fablico do Estado de Minas Gerais, conforme Procedimento Administrativo de Acompanhamento de Pol\u00edticas P\u00fablicas de 17 de novembro de 2025, iniciar\u00e1 neste m\u00eas de janeiro de 2026 a instala\u00e7\u00e3o de hidr\u00f4metros em Ouro Preto, nas liga\u00e7\u00f5es de \u00e1gua que ainda n\u00e3o\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/Nova-ETA-Itacolomi-Divulgacao-Saneouro-5-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/Nova-ETA-Itacolomi-Divulgacao-Saneouro-5-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/Nova-ETA-Itacolomi-Divulgacao-Saneouro-5-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/Nova-ETA-Itacolomi-Divulgacao-Saneouro-5-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/Nova-ETA-Itacolomi-Divulgacao-Saneouro-5-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":26748,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/onda-de-calor-saneouro-esta-com-a-capacidade-de-fornecimento-em-100\/","url_meta":{"origin":2713,"position":2},"title":"Onda de Calor: Saneouro est\u00e1 com a capacidade de fornecimento em 100%","author":"Di\u00e1rio de Ouro Preto","date":"16 de Novembro de 2023","format":false,"excerpt":"Ouro Preto -\u00a0 \u00c1gua! Essa semana foi necess\u00e1rio beber muita \u00e1gua! Visitamos ontem a esta\u00e7\u00e3o de tratamento do Itacolomi, que coloca no sistema de abastecimento 50 litros por segundo, ou 210 M\u00b3 por hora. A produ\u00e7\u00e3o de \u00e1gua pot\u00e1vel pela empresa concession\u00e1ria est\u00e1 em sua plena capacidade.\u00a0 A demanda por\u2026","rel":"","context":"In &quot;Caderno Verde&quot;","block_context":{"text":"Caderno Verde","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/caderno-verde\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/11\/IMG_4868.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/11\/IMG_4868.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/11\/IMG_4868.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/11\/IMG_4868.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/11\/IMG_4868.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8065,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/foco-da-semana-8-perguntas-para-a-saneouro\/","url_meta":{"origin":2713,"position":3},"title":"Foco da Semana: 8 Perguntas para a Saneouro","author":"Di\u00e1rio de Ouro Preto","date":"8 de Maio de 2021","format":false,"excerpt":"Ouro Preto - A semana teve o foco nos debates que andam acalourados em rela\u00e7\u00e3o a atua\u00e7\u00e3o da concession\u00e1ria dos servi\u00e7os de \u00e1gua e esgoto, a Saneouro.\u00a0 Nesta semana, durante as duas reuni\u00f5es da C\u00e2mara, os vereadores discursaram sobre a presta\u00e7\u00e3o de servi\u00e7os, especialmente sobre a possibilidade de uma conta\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7378,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/saneouro-implanta-sistema-de-telemetria-para-diminuir-as-perdas-de-agua-nos-reservatorios\/","url_meta":{"origin":2713,"position":4},"title":"SANEOURO implanta sistema de telemetria para diminuir as perdas de \u00e1gua nos reservat\u00f3rios","author":"Di\u00e1rio de Ouro Preto","date":"31 de Mar\u00e7o de 2021","format":false,"excerpt":"A SANEOURO continua com os investimentos e o trabalho de melhorias cont\u00ednuas em Ouro Preto. J\u00e1 foram realizadas v\u00e1rias melhorias na cidade, como as obras e servi\u00e7os para diminui\u00e7\u00e3o das perdas no sistema de abastecimento de \u00e1gua. Entre elas est\u00e1 a instala\u00e7\u00e3o da telemetria, uma tecnologia que funciona como uma\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Com-o-objetivo-de-diminuir-as-perdas-de-agua-nos-reservatorios-SANEOURO-implanta-sistema-de-telemetria.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Com-o-objetivo-de-diminuir-as-perdas-de-agua-nos-reservatorios-SANEOURO-implanta-sistema-de-telemetria.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/Com-o-objetivo-de-diminuir-as-perdas-de-agua-nos-reservatorios-SANEOURO-implanta-sistema-de-telemetria.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":10707,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/saneouro-divulga-comunicado-sobre-escassez-hidrica\/","url_meta":{"origin":2713,"position":5},"title":"Saneouro divulga comunicado sobre escassez h\u00eddrica","author":"Di\u00e1rio de Ouro Preto","date":"28 de Setembro de 2021","format":false,"excerpt":"A SANEOURO informa que Ouro Preto est\u00e1 enfrentando um rigoroso per\u00edodo de escassez h\u00eddrica, ocasionado pela falta de chuva. O impacto da estiagem j\u00e1 pode ser sentido na sede do Munic\u00edpio. Em fun\u00e7\u00e3o desta estiagem, a capta\u00e7\u00e3o superficial que abastece a Esta\u00e7\u00e3o de Tratamento de \u00c1gua \u2013 ETA do Itacolomi\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-e1617738740372.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2713"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2720"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}