{"id":2705,"date":"2020-04-08T21:44:31","date_gmt":"2020-04-09T00:44:31","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2705"},"modified":"2020-04-08T21:44:34","modified_gmt":"2020-04-09T00:44:34","slug":"zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","title":{"rendered":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19"},"content":{"rendered":"<p>Belo Horizonte &#8211; Diante do contexto socioecon\u00f4mico desafiador gerado pela Covid-19, o\u00a0<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"http:\/\/www.bdmg.mg.gov.br\/\" target=\"_blank\" data-wpel-link=\"external\">Banco de Desenvolvimento de Minas gerais (BDMG)<\/a>\u00a0estruturou um plano de a\u00e7\u00e3o que vai oferecer cr\u00e9dito e tornar as condi\u00e7\u00f5es ainda mais acess\u00edveis para as empresas, especialmente as micro e pequenas (MPEs). A meta \u00e9 disponibilizar cr\u00e9dito de at\u00e9 R$ 1,1 bilh\u00e3o para empresas, tendo em vista a crise provocada pelo coronav\u00edrus.<br><br>O plano foi lan\u00e7ado hoje pelo governador Romeu Zema e pelo presidente do Banco, Sergio Gusm\u00e3o Suchodolski. Ele agrega \u00e0s duas a\u00e7\u00f5es preventivas implantadas nos \u00faltimos dias para os setores da Sa\u00fade e do Turismo, quatro novas a\u00e7\u00f5es com foco reparat\u00f3rio: 1) possibilidade de renegocia\u00e7\u00e3o de d\u00edvidas de empresas com o banco; 2) redu\u00e7\u00e3o das taxas de juros, com prazo de car\u00eancia dobrado, para as MPE de todos os setores econ\u00f4micos e em todos os munic\u00edpios mineiros (programa BDMG Solid\u00e1rio);\u00a03) agiliza\u00e7\u00e3o de processos (dispensa de documentos) para MPE do setor da Sa\u00fade; 4) amplia\u00e7\u00e3o em R$ 100 milh\u00f5es do limite de cr\u00e9dito dispon\u00edvel via Fundo Garantidor para Investimentos (FGI), do BNDES. Al\u00e9m disso, o BDMG estima que, em 2020, o total de desembolsos para as MPE seja de aproximadamente R$ 1,1 bilh\u00e3o.<br><br>De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira. \u201cO que n\u00f3s queremos, via BDMG, \u00e9 disponibilizar linhas de cr\u00e9dito competitivas e desburocratizar processos. Caso sejam necess\u00e1rias, outras medidas ser\u00e3o anunciadas para ajudar essas empresas que empregam a maior parte da m\u00e3o de obra do pa\u00eds\u201d, explicou.\u00a0\u00a0 \u00a0<br><br>As novas a\u00e7\u00f5es ser\u00e3o disponibilizadas a partir de hoje (8\/4). \u201cEstamos tornando ainda mais acess\u00edvel e \u00e1gil a disponibiliza\u00e7\u00e3o de recursos neste momento de desafios. O BDMG, como banco de desenvolvimento, tem atuado na frente antic\u00edclica deste cen\u00e1rio com um conjunto de a\u00e7\u00f5es efetivas para minimizar os impactos econ\u00f4micos e sociais desta pandemia\u201d, afirma Sergio Gusm\u00e3o, presidente do banco.<br><br>A fim de reduzir a burocracia e dar maior celeridade ao processo, a grande maioria das solicita\u00e7\u00f5es de cr\u00e9dito e pedidos de renegocia\u00e7\u00e3o poder\u00e1 ser feita on-line, pela plataforma digital do banco (<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"http:\/\/www.bdmg.mg.gov.br\/\" target=\"_blank\" data-wpel-link=\"external\">www.bdmg.mg.gov.br<\/a>). \u201cO BDMG foi o primeiro banco de desenvolvimento brasileiro a implantar um sistema digital para requisi\u00e7\u00e3o de cr\u00e9dito. Hoje, no cen\u00e1rio deflagrado pela pandemia, termos esta tecnologia a servi\u00e7o dos nossos clientes ser\u00e1 especialmente importante para dar maior celeridade \u00e0s an\u00e1lises\u201d, complementou Sergio Gusm\u00e3o.<br><br>S\u00edntese do Plano<\/p>\n\n\n\n<p><br><strong>A\u00e7\u00f5es j\u00e1 efetivadas<\/strong><br><br>O BDMG iniciou a execu\u00e7\u00e3o de plano para enfrentamento das consequ\u00eancias econ\u00f4micas da Covid-19 nas duas \u00faltimas semanas com a ado\u00e7\u00e3o de duas medidas espec\u00edficas destinadas a cadeias econ\u00f4micas estrat\u00e9gicas para o Estado. Confira:<\/p>\n\n\n\n<p><br><strong>1. Abertura de tr\u00eas linhas de cr\u00e9dito espec\u00edficas para empresas de todos os portes do setor de Sa\u00fade<\/strong><br><br>A primeira a\u00e7\u00e3o do planejamento do BDMG, anunciada no dia 16\/3, foi a abertura de tr\u00eas linhas de cr\u00e9dito com condi\u00e7\u00f5es especiais para auxiliar empresas do setor de Sa\u00fade, que somam mais de 35 mil estabelecimentos em Minas Gerais. S\u00e3o recursos para capital de giro e investimentos para compra de mat\u00e9ria-prima para fabrica\u00e7\u00e3o de produtos de alta demanda (m\u00e1scaras, \u00e1lcool em gel, len\u00e7os, etc.), refor\u00e7o de estoque, prepara\u00e7\u00e3o de leitos, contrata\u00e7\u00e3o de m\u00e3o de obra tempor\u00e1ria, entre outros.<br><br>Podem acessar os recursos empresas de todos os portes, desde farm\u00e1cias, distribuidores e fabricantes de materiais de higiene at\u00e9 laborat\u00f3rios, ind\u00fastrias do ramo e hospitais. As condi\u00e7\u00f5es especiais variam para cada faixa. Para as MPE com faturamento anual de at\u00e9 R$ 4,8 milh\u00f5es, por exemplo, o BDMG est\u00e1 oferecendo juros prefixados a partir de 0,83% ao m\u00eas, prazo de pagamento de at\u00e9 48 meses e at\u00e9 6 meses de car\u00eancia.<\/p>\n\n\n\n<p><strong>2. Redu\u00e7\u00e3o das taxas e melhoria de prazos para as MPE do setor de Turismo (inclui bares e restaurantes)<\/strong><\/p>\n\n\n\n<p>No dia 24\/3, o BDMG anunciou condi\u00e7\u00f5es de financiamento facilitadas para as MPE da cadeia do Turismo, que re\u00fane mais de 60 mil estabelecimentos no estado, entre bares, restaurantes, pousadas, empresas de transporte, de infraestrutura de eventos, de produ\u00e7\u00f5es art\u00edsticas e muitas outras.&nbsp; Operada com recursos do Fundo Geral do Turismo (Fungetur), a linha abaixou os juros de 0,57% ao m\u00eas (+ INPC) para 0,41% ao m\u00eas (+ INPC). O prazo de car\u00eancia dobrou de 6 para 12 meses, com pagamento em at\u00e9 48 meses.<br><br><strong>Novas a\u00e7\u00f5es<\/strong><br><br>Nesta quarta-feira, (8\/4), est\u00e3o sendo anunciadas mais quatro medidas:<br><br><strong>3. Possibilidade de renegocia\u00e7\u00e3o de d\u00edvidas com o Banco<\/strong><\/p>\n\n\n\n<p>Oferecimento \u00e0s MPE adimplentes da possibilidade de renegociar suas d\u00edvidas com o BDMG, solicitando o adiamento do pagamento das parcelas por at\u00e9 90 dias e mantendo a taxa de juros do contrato original.<\/p>\n\n\n\n<p><br><strong>4. Redu\u00e7\u00e3o das taxas de juros e prazo de car\u00eancia dobrado para as MPE com faturamento anual de at\u00e9 R$ 4,8 milh\u00f5es de todos os setores econ\u00f4micos e em todos os munic\u00edpios mineiros (programa BDMG Solid\u00e1rio)<\/strong><\/p>\n\n\n\n<p>Os juros para as micro e pequenas empresas de qualquer setor de atua\u00e7\u00e3o obterem capital de giro cair\u00e3o para a partir de 0,83% ao m\u00eas, com 6 meses de car\u00eancia e pagamento em at\u00e9 48 meses. Como refer\u00eancia, a taxa inicial classicamente praticada pelo BDMG era 0,98% ao m\u00eas e a car\u00eancia de 3 meses.<\/p>\n\n\n\n<p><br><strong>5.&nbsp; Agiliza\u00e7\u00e3o de processo para MPE do setor da Sa\u00fade<\/strong><\/p>\n\n\n\n<p>A fim de proporcionar ganhos de agilidade, as micro e pequenas empresas do setor da Sa\u00fade \u2013 que s\u00e3o aquelas que atuam mais diretamente na mitiga\u00e7\u00e3o da Covid-19 \u2013 est\u00e3o dispensadas de apresentar comprova\u00e7\u00e3o patrimonial com certid\u00f5es de cart\u00f3rio, IPTU e documento de autom\u00f3vel para requisi\u00e7\u00e3o de cr\u00e9dito, mantendo o cadastro eletr\u00f4nico na Receita Federal (e-CAC).<br><br><strong>6.&nbsp; Amplia\u00e7\u00e3o em R$ 100 milh\u00f5es do limite de cr\u00e9dito dispon\u00edvel via Fundo Garantidor para Investimentos (FGI), do BNDES.<\/strong><\/p>\n\n\n\n<p>O BDMG decidiu ampliar em R$ 100 milh\u00f5es o limite de cr\u00e9dito dispon\u00edvel via Fundo Garantidor para Investimentos (FGI), do BNDES. Isso significa mais recursos para oferecer a empreendimentos de todos os portes (com limite de faturamento anual de R$ 300 milh\u00f5es) e de todos os setores no estado. O montante estar\u00e1 dispon\u00edvel nos pr\u00f3ximos dias.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Central de Imprensa<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p> Foto:  Gil Leonardi <\/p>","protected":false},"excerpt":{"rendered":"<p>Belo Horizonte &#8211; Diante do contexto socioecon\u00f4mico desafiador gerado pela Covid-19, o\u00a0Banco de Desenvolvimento de Minas gerais (BDMG)\u00a0estruturou um plano de a\u00e7\u00e3o que vai oferecer cr\u00e9dito e tornar as condi\u00e7\u00f5es ainda mais acess\u00edveis para as empresas, especialmente as micro e pequenas (MPEs). A meta \u00e9 disponibilizar cr\u00e9dito de at\u00e9 R$<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-2705","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T00:44:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T00:44:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19\",\"datePublished\":\"2020-04-09T00:44:31+00:00\",\"dateModified\":\"2020-04-09T00:44:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/\"},\"wordCount\":1114,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Gil_Leonardi__MG_3955-scaled.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/\",\"name\":\"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Gil_Leonardi__MG_3955-scaled.jpg\",\"datePublished\":\"2020-04-09T00:44:31+00:00\",\"dateModified\":\"2020-04-09T00:44:34+00:00\",\"description\":\"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Gil_Leonardi__MG_3955-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Gil_Leonardi__MG_3955-scaled.jpg\",\"width\":1200,\"height\":794},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto","description":"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","og_locale":"pt_PT","og_type":"article","og_title":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto","og_description":"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-04-09T00:44:31+00:00","article_modified_time":"2020-04-09T00:44:34+00:00","og_image":[{"width":1200,"height":794,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19","datePublished":"2020-04-09T00:44:31+00:00","dateModified":"2020-04-09T00:44:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/"},"wordCount":1114,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","url":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/","name":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19 - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","datePublished":"2020-04-09T00:44:31+00:00","dateModified":"2020-04-09T00:44:34+00:00","description":"De acordo com o governador Romeu Zema, s\u00e3o medidas que ajudar\u00e3o a minimizar os impactos causados pela desacelera\u00e7\u00e3o da economia brasileira.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","width":1200,"height":794},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/zema-anuncia-plano-de-r-11-bilhao-para-empresas-mineiras-ganharem-maior-liquidez-diante-da-pandemia-de-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Zema anuncia plano de R$ 1,1 bilh\u00e3o para empresas mineiras ganharem maior liquidez diante da pandemia de Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/Gil_Leonardi__MG_3955-scaled.jpg","jetpack-related-posts":[{"id":2828,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-prorroga-condicoes-de-credito-para-empreendedoras\/","url_meta":{"origin":2705,"position":0},"title":"BDMG prorroga condi\u00e7\u00f5es de cr\u00e9dito para empreendedoras","author":"Di\u00e1rio de Ouro Preto","date":"23 de Abril de 2020","format":false,"excerpt":"Belo Horizonte - O\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0anuncia a prorroga\u00e7\u00e3o das condi\u00e7\u00f5es especiais de financiamento em sua linha de cr\u00e9dito Empreendedoras de Minas, voltada para micro e pequenas empresas lideradas por mulheres. As taxas de juros iniciais, reduzidas a 0,80%, passam a vigorar at\u00e9 30 de junho. O\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/bdmg-e1592345576846.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3061,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/governo-de-minas-destina-r-274-mi-em-credito-para-as-prefeituras\/","url_meta":{"origin":2705,"position":1},"title":"Governo de Minas destina R$ 274 mi em cr\u00e9dito para as prefeituras","author":"Di\u00e1rio de Ouro Preto","date":"12 de Maio de 2020","format":false,"excerpt":"O governador Romeu Zema anunciou nesta ter\u00e7a-feira\u00a0(12\/5), na Cidade Administrativa, que o\u00a0Banco de Desenvolvimento de Minas Gerais (BDMG)\u00a0alcan\u00e7ou a marca de R$ 274 milh\u00f5es em cr\u00e9dito contratado via Edital de Munic\u00edpios do bi\u00eanio 2019\/2020, montante 37% maior que a previs\u00e3o inicial de desembolso, que era de R$ 200 milh\u00f5es. Ao\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/MG_6292-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":48334,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/estado-tera-deficit-de-r-52-bilhoes-em-2026\/","url_meta":{"origin":2705,"position":2},"title":"Estado ter\u00e1 d\u00e9ficit de R$ 5,2 bilh\u00f5es em 2026","author":"Di\u00e1rio de Ouro Preto","date":"22 de Outubro de 2025","format":false,"excerpt":"Proposta or\u00e7ament\u00e1ria elaborada pelo governo leva em considera\u00e7\u00e3o a ades\u00e3o de Minas Gerais ao Propag O d\u00e9ficit or\u00e7ament\u00e1rio do Estado em 2026 ser\u00e1 de R$ 5,2 bilh\u00f5es. \u00c9 o que prev\u00ea a proposta de\u00a0or\u00e7amento\u00a0para o pr\u00f3ximo ano, contido no Projeto de Lei (PL) 4.527\/25, do governador Romeu Zema,\u00a0recebido na Reuni\u00e3o\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/2457424.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/2457424.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/2457424.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/2457424.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/10\/2457424.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2837,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bndes-libera-r-11-bi-para-empresas-afetadas-por-pandemia\/","url_meta":{"origin":2705,"position":3},"title":"BNDES libera R$ 1,1 bi para empresas afetadas por pandemia","author":"Di\u00e1rio de Ouro Preto","date":"23 de Abril de 2020","format":false,"excerpt":"A libera\u00e7\u00e3o de linhas de capital de giro para empresas afetadas pela pandemia de coronav\u00edrus somou R$ 1,1 bilh\u00e3o, informou\u00a0hoje\u00a0(23) o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES). O montante equivale a 22% da linha de cr\u00e9dito de R$ 5 bilh\u00f5es anunciada no m\u00eas passado para ajudar micro, pequenas\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/bndes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/bndes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/bndes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/bndes.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/bndes.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3883,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/bdmg-anuncia-novos-recursos-para-o-setor-do-turismo\/","url_meta":{"origin":2705,"position":4},"title":"BDMG anuncia novos recursos para o setor do turismo","author":"Di\u00e1rio de Ouro Preto","date":"18 de Junho de 2020","format":false,"excerpt":"O BDMG \u2013 Banco de Desenvolvimento de Minas Gerais desembolsou R$ 62,0 milh\u00f5es em cr\u00e9dito para micro e pequenas empresas (MPE) em maio, recorde mensal para o segmento desde que o banco foi fundado h\u00e1 58 anos. O desempenho reflete o plano de minimiza\u00e7\u00e3o dos impactos da pandemia de Covid-19,\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/03_Sergio-Gusm%C3%A3o-3_Cr%C3%A9dito-Marcus-Desimoni-NITRO_BAIXA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/03_Sergio-Gusm%C3%A3o-3_Cr%C3%A9dito-Marcus-Desimoni-NITRO_BAIXA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/03_Sergio-Gusm%C3%A3o-3_Cr%C3%A9dito-Marcus-Desimoni-NITRO_BAIXA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/03_Sergio-Gusm%C3%A3o-3_Cr%C3%A9dito-Marcus-Desimoni-NITRO_BAIXA.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/03_Sergio-Gusm%C3%A3o-3_Cr%C3%A9dito-Marcus-Desimoni-NITRO_BAIXA.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3028,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/atuacao-integrada-marca-estrategia-do-governo-de-minas-contra-a-covid-19\/","url_meta":{"origin":2705,"position":5},"title":"Atua\u00e7\u00e3o integrada marca estrat\u00e9gia do Governo de Minas contra a covid-19","author":"Di\u00e1rio de Ouro Preto","date":"9 de Maio de 2020","format":false,"excerpt":"Belo Horizonte - A r\u00e1pida resposta do\u00a0Governo de Minas\u00a0para as a\u00e7\u00f5es de preven\u00e7\u00e3o e combate ao coronav\u00edrus \u00e9 resultado de uma s\u00e9rie de esfor\u00e7os coordenados de gest\u00e3o e planejamento. Prova disso \u00e9 que, antes mesmo de a situa\u00e7\u00e3o pand\u00eamica ser confirmada pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS), o Estado j\u00e1\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/1-hospital-de-campanha-expominas-cr%C3%A9dito-Pedro-Gontijo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/1-hospital-de-campanha-expominas-cr%C3%A9dito-Pedro-Gontijo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/1-hospital-de-campanha-expominas-cr%C3%A9dito-Pedro-Gontijo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/1-hospital-de-campanha-expominas-cr%C3%A9dito-Pedro-Gontijo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/1-hospital-de-campanha-expominas-cr%C3%A9dito-Pedro-Gontijo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2705"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2706"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}