{"id":2489,"date":"2020-03-26T11:38:02","date_gmt":"2020-03-26T14:38:02","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2489"},"modified":"2020-03-26T11:38:02","modified_gmt":"2020-03-26T14:38:02","slug":"deputados-avaliam-que-momento-e-de-uniao-de-forcas","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/","title":{"rendered":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as"},"content":{"rendered":"<p>Belo Horizonte &#8211; <strong>Atender \u00e0s medidas de conten\u00e7\u00e3o recomendadas\u00a0<\/strong>pelas autoridades de sa\u00fade<strong>\u00a0e estabelecer uni\u00e3o irrestrita de for\u00e7as \u2013 dos tr\u00eas poderes<\/strong>, nas esferas federal, estadual e municipal &#8211;<strong>\u00a0para conter o avan\u00e7o do coronav\u00edrus no Pa\u00eds.<\/strong>\u00a0Essa vis\u00e3o permeou pronunciamentos da maioria dos deputados presentes \u00e0 reuni\u00e3o on-line do Plen\u00e1rio da Assembleia Legislativa de Minas Gerais (ALMG), realizada nesta quarta-feira (25\/3\/20).<\/p>\n\n\n\n<p>Na reuni\u00e3o, na qual foi aprovado por unanimidade o&nbsp;<a href=\"https:\/\/www.almg.gov.br\/atividade_parlamentar\/tramitacao_projetos\/interna.html?a=2020&amp;n=20&amp;t=PRE\" data-wpel-link=\"external\" target=\"_blank\" rel=\"follow external noopener noreferrer sponsored ugc\">Projeto de Resolu\u00e7\u00e3o (PRE) 20\/20<\/a>, que&nbsp;<strong>reconhece&nbsp;estado de calamidade em raz\u00e3o da propaga\u00e7\u00e3o da Covid-19<\/strong>, quase todos os parlamentares fizeram declara\u00e7\u00e3o de voto, nas quais ressaltaram o valoroso trabalho prestado pelos profissionais da \u00e1rea de sa\u00fade.<\/p>\n\n\n\n<p>Tamb\u00e9m n\u00e3o faltaram agradecimentos aos produtores rurais, caminhoneiros e trabalhadores das for\u00e7as de Seguran\u00e7a P\u00fablica, entre outros profissionais.<\/p>\n\n\n\n<p>\u201cDeclaro meu voto sim, muito preocupado em coordenar todas as a\u00e7\u00f5es no sentido de preservar a vida de todos, inclusive daqueles que est\u00e3o trabalhando por n\u00f3s. A\u00ed tem um aspecto todo especial o pessoal da seguran\u00e7a, da sa\u00fade e da agropecu\u00e1ria&#8221;, ressaltou o presidente da Comiss\u00e3o de Agropecu\u00e1ria e Agroind\u00fastria, deputado Coronel Henrique (PSL).<\/p>\n\n\n\n<p>Os pronunciamentos ainda destacaram os&nbsp;<strong>riscos socioecon\u00f4micos da pandemia, assim como o impacto sobre a popula\u00e7\u00e3o mais vulner\u00e1vel<\/strong>, como moradores em situa\u00e7\u00e3o de rua, microempres\u00e1rios e trabalhadores informais.<\/p>\n\n\n\n<p>Nesse sentido, houve apelo para que&nbsp;<strong>a ALMG acelere a vota\u00e7\u00e3o de mat\u00e9rias que favore\u00e7am essa parcela da sociedade, como a proposi\u00e7\u00e3o que estabelece o Fundo de Erradica\u00e7\u00e3o da Mis\u00e9ria.<\/strong><strong>Saiba mais<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.almg.gov.br\/acompanhe\/noticias\/arquivos\/2020\/03\/25_plenario_aprovacao_estado_calamidade.html\" data-wpel-link=\"external\" target=\"_blank\" rel=\"follow external noopener noreferrer sponsored ugc\">Assembleia reconhece estado de calamidade p\u00fablica em Minas<\/a><\/li><li><a href=\"https:\/\/www.almg.gov.br\/acompanhe\/noticias\/arquivos\/2020\/03\/25_coletiva_presidente_coronavirus.html\" data-wpel-link=\"external\" target=\"_blank\" rel=\"follow external noopener noreferrer sponsored ugc\">Verbas parlamentares podem ser usadas no combate \u00e0 Covid-19<\/a><\/li><\/ul>\n\n\n\n<p><strong>Impactos econ\u00f4micos &#8211;<\/strong>&nbsp;Tamb\u00e9m foi abordada a&nbsp;<strong>possibilidade de o confinamento causar um colapso na economia<\/strong>&nbsp;do Brasil e de Minas, levando muitas fam\u00edlias a situa\u00e7\u00f5es miser\u00e1veis. Muitos dos parlamentares que falaram sobre o assunto, destacaram a necessidade de a ALMG tamb\u00e9m apresentar e votar medidas que ajudem a reduzir esse tipo de dano.<\/p>\n\n\n\n<p>\u201cNas pr\u00f3ximas reuni\u00f5es, votaremos mat\u00e9rias tamb\u00e9m importantes, complementares, sempre com a preocupa\u00e7\u00e3o do impacto na sa\u00fade p\u00fablica, mas tamb\u00e9m o econ\u00f4mico e social para a popula\u00e7\u00e3o de Minas e do Brasil. \u00c9 importante que o Fundo de Erradica\u00e7\u00e3o da Mis\u00e9ria seja estritamente utilizado para este momento t\u00e3o delicado que estamos passando\u201d, ponderou o l\u00edder do Bloco Democracia e Luta, deputado Andr\u00e9 Quint\u00e3o (PT).<\/p>\n\n\n\n<p>\u201cPrecisamos de equil\u00edbrio, temos que buscar um caminho, trabalhar em duas frentes para conciliar a preven\u00e7\u00e3o, adotando todos os cuidados poss\u00edveis para evitar a contamina\u00e7\u00e3o, mas ao mesmo tempo pensando no emprego, nos pais de fam\u00edlia, num colapso de nossa economia, pois suas consequ\u00eancias ser\u00e3o devastadoras\u201d, avaliou Sargento Rodrigues (PTB).<\/p>\n\n\n\n<p>Ainda houve declara\u00e7\u00f5es abordando o conte\u00fado do texto aprovado, assim&nbsp;<strong>como cobran\u00e7as de que o governador Romeu Zema (Novo) apresente um plano de a\u00e7\u00f5es para conter a pandemia no Estado.<\/strong><\/p>\n\n\n\n<p>Tamb\u00e9m foram feitas reivindica\u00e7\u00f5es de hospitais de campanha em diversas regi\u00f5es do Estado ainda n\u00e3o contempladas nas propostas do governo, assim como solicita\u00e7\u00f5es de empenho para suprir os hospitais e \u00f3rg\u00e3os de sa\u00fade p\u00fablica, sobretudo no interior.<\/p>\n\n\n\n<p>O deputado Thiago Cota,que levanta a bandeira da sa\u00fade desde o primeiro mandato e, mais vez, defendeu essa causa em plen\u00e1rio. Como relator, o parlamentar foi ferrenho na defesa de recursos para a popula\u00e7\u00e3o e conseguiu o apoio dos pares. At\u00e9 31 de dezembro, Minas Gerais est\u00e1 em situa\u00e7\u00e3o de calamidade p\u00fablica. <br><\/p>\n\n\n\n<p>\u201cA aprova\u00e7\u00e3o desse projeto \u00e9 de grande valia para a popula\u00e7\u00e3o e por isso coloquei esfor\u00e7os para que ele fosse aprovado. Neste momento, \u00e9 primordial valorizar a sa\u00fade e essa ser\u00e1 a minha bandeira\u201d, frisa o deputado Thiago Cota. Com o respaldo da ALMG, a compra de insumos b\u00e1sicos para combater a doen\u00e7a e a contrata\u00e7\u00e3o de profissionais da sa\u00fade acontecer\u00e1 em um processo mais simples e eficiente.<br><\/p>\n\n\n\n<p>Homenagem<br><\/p>\n\n\n\n<p>H\u00e1 um m\u00eas dos primeiros registros de infec\u00e7\u00e3o no Brasil, Minas Gerais j\u00e1 registra mais de 14 mil casos suspeitos de coronav\u00edrus e outros 133 j\u00e1 foram confirmados pela Secretaria Estadual de Sa\u00fade. Postos e hospitais n\u00e3o param de receber pacientes. \u00c9 por isso, que em plen\u00e1rio, o parlamentar ainda homenageou m\u00e9dicos e enfermeiros que n\u00e3o tem medido esfor\u00e7os para salvar vidas. \u201cMerecem todo o nosso aplauso e gratid\u00e3o, s\u00e3o in\u00fameros exemplos de profissionais que t\u00eam se dedicado muito\u201d, concluiu Thiago Cota.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1198\" height=\"800\" data-attachment-id=\"2491\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/reuniao-ordinaria-remota-3\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-scaled.jpg\" data-orig-size=\"1198,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;Guilherme Bergamini&quot;,&quot;camera&quot;:&quot;NIKON D610&quot;,&quot;caption&quot;:&quot;Thiago Cota (deputado estadual MDB\/MG),&quot;,&quot;created_timestamp&quot;:&quot;1585145710&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;185&quot;,&quot;iso&quot;:&quot;1600&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;Reuni\\u00e3o Ordin\\u00e1ria Remota&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Reuni\u00e3o Ordin\u00e1ria Remota\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Thiago Cota (deputado estadual MDB\/MG),&lt;\/p&gt;\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-899x600.jpg\" src=\"https:\/\/i1.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-scaled.jpg?fit=899%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-2491\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-scaled.jpg 1198w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-593x396.jpg 593w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-899x600.jpg 899w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-150x100.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-768x513.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-1536x1025.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510511-2048x1367.jpg 2048w\" sizes=\"(max-width: 1198px) 100vw, 1198px\" \/><figcaption>Deputado Estadual Thiago Cota durante reuni\u00e3o desta quarta-feira, 25\/03\/2020 Foto: ALMG<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Parlamentares repercutem pronunciamento do presidente&nbsp;<\/strong><\/p>\n\n\n\n<p>Destaque, ainda, para o pronunciamento feito pelo presidente Jair Messias Bolsonaro, na noite dessa ter\u00e7a (24), no qual ele criticou medidas de confinamento impostas nos Estados, disse que o Pa\u00eds precisa \u201cretomar a rotina\u201d e voltou a chamar a Covid-19 de \u201cgripezinha\u201d.<\/p>\n\n\n\n<p><strong>Bolsonaro defendeu<\/strong>&nbsp;o chamado \u201cisolamento vertical\u201d, que prop\u00f5e manter em&nbsp;<strong>isolamento apenas aqueles que forem do grupo de risco<\/strong>&nbsp;&#8211; como idosos e doentes cr\u00f4nicos &#8211;&nbsp;<strong>e que os demais circulem livremente<\/strong>. Combina\u00e7\u00e3o que, segundo os \u00f3rg\u00e3os de sa\u00fade, favoreceria a prolifera\u00e7\u00e3o do v\u00edrus, uma vez que os n\u00e3o-confinados teriam contato com os isolados.<\/p>\n\n\n\n<p>Os&nbsp;<strong>deputados da oposi\u00e7\u00e3o, e alguns de outros blocos, criticaram o posicionamento<\/strong>, ressaltando que as medidas de conten\u00e7\u00e3o t\u00eam sido aplicadas em todos os pa\u00edses vitimados pela pandemia, al\u00e9m de serem indicadas por todas as autoridades de sa\u00fade. Houve, inclusive, parlamentares que declaram ser favor\u00e1veis a Bolsonaro, mas contr\u00e1rios ao que ele expressou neste caso.<\/p>\n\n\n\n<p>\u201cSe n\u00e3o fosse grave, n\u00f3s n\u00e3o estar\u00edamos fazendo essa vota\u00e7\u00e3o remota. N\u00e3o \u00e9 uma gripezinha. A contamina\u00e7\u00e3o est\u00e1 ascendente. Ent\u00e3o, \u00e9 uma irresponsabilidade, \u00e9 uma postura mesmo genocida o que o presidente da Rep\u00fablica fez em seu pronunciamento\u201d, criticou a deputada Betriz Cerqueira (PT).<\/p>\n\n\n\n<p>\u201cO falido pode se recuperar, o falecido n\u00e3o\u201d citou Delegado Heli Grilo (PSL), ao avaliar que<strong>&nbsp;o mais importante, agora, \u00e9 salvar vidas.<\/strong><\/p>\n\n\n\n<p>\u201cBolsonaro tem o meu apoio, mas acho que a declara\u00e7\u00e3o dele vem na contram\u00e3o de tudo o que vem sendo pregado. Trata-se de uma doen\u00e7a cujo grande risco \u00e9 a escalada exponencial. Ent\u00e3o, um dia faz muita diferen\u00e7a\u201d, disse o deputado Bart\u00f4 (Novo).<\/p>\n\n\n\n<p>Em contrapartida, os deputados Coronel Sandro e Bruno Engler (ambos do PSL) elogiaram a postura do presidente e sua cr\u00edtica a medidas de conten\u00e7\u00e3o aplicadas por governadores e prefeitos.<\/p>\n\n\n\n<p>\u201cO presidente Jair Bolsonaro defende, sim, o isolamento vertical de idosos e de pessoas com doen\u00e7as, a popula\u00e7\u00e3o de risco. Mas n\u00f3s precisamos manter o Pa\u00eds funcionando. Eu fico muito feliz que tenhamos, neste momento, um verdadeiro l\u00edder na figura do presidente\u201d, declarou Bruno Engler.<\/p>\n\n\n\n<p>\u201cAinda bem que, na maior crise da nossa gera\u00e7\u00e3o, temos um l\u00edder que tem coragem de tomar a melhor decis\u00e3o e que n\u00e3o est\u00e1 preocupado com a quest\u00e3o eleitoral. A op\u00e7\u00e3o pelo isolamento vertical \u00e9 uma necessidade. Se n\u00e3o fizermos isso, mataremos as pessoas e mataremos a economia\u201d, afirmou Coronel Sandro.<\/p>\n\n\n\n<p>Al\u00e9m dos parlamentares j\u00e1 citados, tamb\u00e9m fizeram declara\u00e7\u00f5es de votos as deputadas Ana Paula Siqueira (Rede), Andr\u00e9ia de Jesus (Psol), Laura Serrano (Novo), Leninha e Mar\u00edlia Campos (ambas do PT).<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>E ainda os deputados Alencar da Silveira j\u00fanior (PDT), Antonio Carlos Arantes (PSDB), Arlen Santiago (PTB), Bet\u00e3o (PT), Bosco (Avante), Carlos Henrique (Republicanos), Carlos Pimenta (PDT), Celinho Sintrocel (PCdoB), Cristiano Silveira (PT), Doutor Jean Freire (PT), Doutor Paulo (Patri), Duarte Bechir (PSD), Elismar Prado (Pros), Gil Pereira (PP), Glaycon Franco (PV), Guilherme da Cunha (Novo), Gustavo Santana (PL), Hely Tarq\u00fc\u00ednio (PV), L\u00e9o Portela (PL), Noraldino J\u00fanior (PSC), Professor Irineu (PSL), Professor Wendel Mesquita (Solidariedade), Raul Bel\u00e9m (PSC), Tadeu Martins Leite (MDB), Thiago Cota (MDB), Ulysses Gomes (PT), Virg\u00edlio Guimar\u00e3es (PT) e Z\u00e9 Reis (PSD).<br><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: Assessoria de Imprensa ALMG<br><strong>Fot\u00f3grafo:<\/strong>\u00a0Guilherme Bergamini<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Belo Horizonte &#8211; Atender \u00e0s medidas de conten\u00e7\u00e3o recomendadas\u00a0pelas autoridades de sa\u00fade\u00a0e estabelecer uni\u00e3o irrestrita de for\u00e7as \u2013 dos tr\u00eas poderes, nas esferas federal, estadual e municipal &#8211;\u00a0para conter o avan\u00e7o do coronav\u00edrus no Pa\u00eds.\u00a0Essa vis\u00e3o permeou pronunciamentos da maioria dos deputados presentes \u00e0 reuni\u00e3o on-line do Plen\u00e1rio da Assembleia<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-2489","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T14:38:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1198\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as\",\"datePublished\":\"2020-03-26T14:38:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/\"},\"wordCount\":1409,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1510544-scaled.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/\",\"name\":\"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1510544-scaled.jpg\",\"datePublished\":\"2020-03-26T14:38:02+00:00\",\"description\":\"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1510544-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/1510544-scaled.jpg\",\"width\":1198,\"height\":800,\"caption\":\"Tadeu Martins Leite (1\u00ba- secret\u00e1rio da ALMG - MDB\\\/MG), Agostinho Patrus (presidente da ALMG \u2013 PV\\\/MG), Thiago Cota (deputado estadual MDB\\\/MG),\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto","description":"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/","og_locale":"pt_PT","og_type":"article","og_title":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto","og_description":"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-03-26T14:38:02+00:00","og_image":[{"width":1198,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as","datePublished":"2020-03-26T14:38:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/"},"wordCount":1409,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/","url":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/","name":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","datePublished":"2020-03-26T14:38:02+00:00","description":"- Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as - Minas Gerais","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","width":1198,"height":800,"caption":"Tadeu Martins Leite (1\u00ba- secret\u00e1rio da ALMG - MDB\/MG), Agostinho Patrus (presidente da ALMG \u2013 PV\/MG), Thiago Cota (deputado estadual MDB\/MG),"},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/deputados-avaliam-que-momento-e-de-uniao-de-forcas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Deputados avaliam que momento \u00e9 de uni\u00e3o de for\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/1510544-scaled.jpg","jetpack-related-posts":[{"id":27092,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/federalizacao-de-estatais-mineiras-nao-tem-consenso-entre-deputados\/","url_meta":{"origin":2489,"position":0},"title":"Federaliza\u00e7\u00e3o de estatais mineiras n\u00e3o tem consenso entre deputados","author":"Di\u00e1rio de Ouro Preto","date":"9 de Dezembro de 2023","format":false,"excerpt":"A proposta de federaliza\u00e7\u00e3o das estatais mineiras n\u00e3o tem consenso na Assembleia Legislativa de Minas Gerais, disseram nesta sexta-feira (8) deputados estaduais de oposi\u00e7\u00e3o ao governador Romeu Zema. Eles se reuniram por cerca de 1h30 com o ministro da Fazenda, Fernando Haddad, para discutirem alternativas \u00e0s propostas sobre o pagamento\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/haddad_e_deputados.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/haddad_e_deputados.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/haddad_e_deputados.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/haddad_e_deputados.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2023\/12\/haddad_e_deputados.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35760,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/adesao-de-minas-gerais-ao-rrf-e-aprovada-em-1o-turno-na-almg\/","url_meta":{"origin":2489,"position":1},"title":"Ades\u00e3o de Minas Gerais ao RRF \u00e9 aprovada em 1\u00ba turno na ALMG","author":"Di\u00e1rio de Ouro Preto","date":"15 de Julho de 2024","format":false,"excerpt":"PL 1.202\/19 recebe aval do Plen\u00e1rio e aguarda parecer de 2\u00ba turno da Comiss\u00e3o de Fiscaliza\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria A ades\u00e3o de Minas Gerais ao\u00a0Regime de Recupera\u00e7\u00e3o Fiscal (RRF)\u00a0foi aprovada em 1\u00ba turno\u00a0pela Assembleia Legislativa de Minas Gerais (ALMG) nesta segunda-feira (15\/07). O Projeto de Lei 1.202\/19, que trata desse\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/2153915.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/2153915.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/2153915.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":45741,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/transferencia-da-uemg-a-uniao-pauta-audiencia\/","url_meta":{"origin":2489,"position":2},"title":"Transfer\u00eancia da Uemg \u00e0 Uni\u00e3o pauta audi\u00eancia","author":"Di\u00e1rio de Ouro Preto","date":"30 de Junho de 2025","format":false,"excerpt":"Objetivo \u00e9 que secret\u00e1rios de Estado expliquem projeto do governador que repassa gest\u00e3o e im\u00f3veis da universidade para abater d\u00edvida no \u00e2mbito do Propag A\u00a0inten\u00e7\u00e3o do governo estadual de incluir a\u00a0Uemg, a Universidade do Estado de Minas Gerais, entre os ativos oferecidos para abater sua\u00a0d\u00edvida com a Uni\u00e3o\u00a0ser\u00e1 discutida em\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/2329688.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/2329688.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/2329688.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/2329688.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/06\/2329688.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4850,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/com-aprovacao-de-plc-assembleia-conclui-votacao-da-reforma\/","url_meta":{"origin":2489,"position":3},"title":"Com aprova\u00e7\u00e3o de PLC, Assembleia conclui vota\u00e7\u00e3o da reforma","author":"Di\u00e1rio de Ouro Preto","date":"4 de Setembro de 2020","format":false,"excerpt":"O\u00a0Projeto de Lei Complementar (PLC) 46\/20, do governador Romeu Zema, que integra a\u00a0reforma da previd\u00eancia\u00a0dos servidores p\u00fablicos estaduais\u00a0juntamente com a\u00a0Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 55\/20,\u00a0foi aprovado em definitivo\u00a0(2\u00ba turno) pela Assembleia Legislativa de Minas Gerais (ALMG) durante Reuni\u00e3o Extraordin\u00e1ria de Plen\u00e1rio, nesta sexta-feira (4\/9\/20). O texto recebeu 52 votos\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1525325-scaled-e1599253340962.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1525325-scaled-e1599253340962.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1525325-scaled-e1599253340962.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1525325-scaled-e1599253340962.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/09\/1525325-scaled-e1599253340962.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":45836,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/plenario-aprova-em-definitivo-federalizacao-da-codemig-e-da-codemge\/","url_meta":{"origin":2489,"position":4},"title":"Plen\u00e1rio aprova em definitivo federaliza\u00e7\u00e3o da Codemig e da Codemge","author":"Di\u00e1rio de Ouro Preto","date":"4 de Julho de 2025","format":false,"excerpt":"Parlamentares analisam proposi\u00e7\u00f5es na Reuni\u00e3o Extraordin\u00e1ria de Plen\u00e1rio da manh\u00e3 desta quarta-feira O objetivo \u00e9 repassar as duas empresas \u00e0 Uni\u00e3o como forma de amortizar 20% da d\u00edvida do EstadOs Projetos de Lei (PLs) 3.734\/25 e 3.735\/25, que autorizam a federaliza\u00e7\u00e3o da Codemig e da Codemge, respectivamente, foram aprovados em\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/2359097.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/2359097.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/2359097.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/2359097.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/07\/2359097.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4703,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/comissao-do-trabalho-rejeita-plc-da-reforma-da-previdencia\/","url_meta":{"origin":2489,"position":5},"title":"Comiss\u00e3o do Trabalho rejeita PLC da reforma da previd\u00eancia","author":"Di\u00e1rio de Ouro Preto","date":"26 de Agosto de 2020","format":false,"excerpt":"A Comiss\u00e3o do Trabalho, da Previd\u00eancia Social e da Assist\u00eancia Social da Assembleia Legislativa de Minas Gerais (ALMG) aprovou\u00a0parecer\u00a0de 1\u00ba turno\u00a0contr\u00e1rio ao\u00a0Projeto de Lei Complementar (PLC) 46\/20, de autoria do governador do Estado, em reuni\u00e3o na manh\u00e3 desta quarta-feira (26\/8\/20). A proposi\u00e7\u00e3o altera legisla\u00e7\u00f5es anteriores, cria nova autarquia e fundos\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/luiz_santanaalmg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/luiz_santanaalmg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/08\/luiz_santanaalmg.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2489"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2490"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}