{"id":2376,"date":"2020-03-21T19:07:47","date_gmt":"2020-03-21T22:07:47","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2376"},"modified":"2020-03-21T19:07:53","modified_gmt":"2020-03-21T22:07:53","slug":"vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/","title":{"rendered":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria"},"content":{"rendered":"<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>\n\nA Vale S.A. (\u201cVale\u201d) informa sobre primeiros casos de infec\u00e7\u00e3o entre seus empregados, a ajuda humanit\u00e1ria oferecida ao governo brasileiro e as medidas que est\u00e3o sendo tomadas em resposta \u00e0 epidemia COVID-19.<br><br>Foram confirmados nesta sexta-feira, 20 de mar\u00e7o, os primeiros dois casos de empregados da Vale com coronav\u00edrus, em Minas Gerais e no Rio de Janeiro. A Vale comunicou os dois casos \u00e0s autoridades e presta toda a assist\u00eancia necess\u00e1ria aos empregados, que passam bem e est\u00e3o em isolamento domiciliar.<br><br>Como maior exportadora de min\u00e9rio de ferro brasileiro para a \u00c1sia, a Vale ofereceu ao governo brasileiro ajuda humanit\u00e1ria, utilizando a sua infraestrutura na regi\u00e3o para trazer insumos m\u00e9dicos, como respiradores mec\u00e2nicos e kits para teste, para atender pacientes infectados pelo novo coronav\u00edrus. A opera\u00e7\u00e3o est\u00e1 em andamento, com permanente contato com as autoridades de sa\u00fade do governo federal.<br><br>Adicionalmente, a companhia est\u00e1 implementando em suas opera\u00e7\u00f5es em todo o mundo diversas medidas de apoio \u00e0 preven\u00e7\u00e3o ao COVID-19 e de continuidade de neg\u00f3cio:<br>\u2022&nbsp; Criou em janeiro de 2020 a estrutura e a governan\u00e7a para Gest\u00e3o de Crise com o objetivo de gerir e implementar as a\u00e7\u00f5es definidas no Plano Global de Prepara\u00e7\u00e3o e Resposta para Pandemia do COVID-19 de acordo com as classifica\u00e7\u00f5es de risco locais;<br>\u2022&nbsp; Organizou, em times fisicamente isolados, as lideran\u00e7as e equipes operacionais cr\u00edticas, com a ado\u00e7\u00e3o de contingentes m\u00ednimos para a opera\u00e7\u00e3o com seguran\u00e7a, equipes de backup e restri\u00e7\u00e3o de mobilidade;<br>\u2022&nbsp; Est\u00e1 implementando pontos de triagem nas opera\u00e7\u00f5es, limitando acesso a visitantes e fornecedores essenciais e a\u00e7\u00f5es preventivas nos refeit\u00f3rios para reduzir a exposi\u00e7\u00e3o e fontes de contamina\u00e7\u00e3o;<br>\u2022&nbsp; Est\u00e1 planejando o fornecimento de suprimentos essenciais, continuidade de neg\u00f3cio e blindagem de opera\u00e7\u00f5es cr\u00edticas;<br>\u2022&nbsp; Cancelou ou postergou todas as viagens e eventos de neg\u00f3cios;<br>\u2022&nbsp; Instruiu a todos os empregados retornando de viagens internacionais que entrem em contato com o departamento m\u00e9dico da companhia por telefone antes de retornar \u00e0s suas atividades, mesmo n\u00e3o apresentando qualquer sintoma de contamina\u00e7\u00e3o;<br>\u2022&nbsp; Implementou o regime de home-office para as fun\u00e7\u00f5es nas quais o contato social n\u00e3o \u00e9 mandat\u00f3rio;<br>\u2022&nbsp; Est\u00e1 se comunicando com todos os empregados atrav\u00e9s de webcasts e canais internos sobre o Plano Global de Prepara\u00e7\u00e3o e Resposta para Pandemia do COVID-19 e as medidas de preven\u00e7\u00e3o necess\u00e1rias; e<br>\u2022&nbsp; Est\u00e1 apoiando e monitorando os empregados que apresentam sintomas de contamina\u00e7\u00e3o.<br><br>A companhia informa ainda que est\u00e1 em conformidade com os protocolos de sa\u00fade e seguran\u00e7a estabelecidos pelas autoridades e ag\u00eancias de cada um dos pa\u00edses em que opera e est\u00e1 monitorando o desenvolvimento da situa\u00e7\u00e3o.<br><br>A Vale reafirma seu comprometimento com a seguran\u00e7a de seus empregados e das comunidades em que opera e manter\u00e1 os investidores e o mercado informados de futuros desenvolvimentos.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Fonte: VALE.COM<\/p>","protected":false},"excerpt":{"rendered":"<p>A Vale S.A. (\u201cVale\u201d) informa sobre primeiros casos de infec\u00e7\u00e3o entre seus empregados, a ajuda humanit\u00e1ria oferecida ao governo brasileiro e as medidas que est\u00e3o sendo tomadas em resposta \u00e0 epidemia COVID-19. Foram confirmados nesta sexta-feira, 20 de mar\u00e7o, os primeiros dois casos de empregados da Vale com coronav\u00edrus, em<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["entry","author-diario","post-2376","post","type-post","status-publish","format-standard","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-21T22:07:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-21T22:07:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-1-e1617740501646.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria\",\"datePublished\":\"2020-03-21T22:07:47+00:00\",\"dateModified\":\"2020-03-21T22:07:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/\",\"name\":\"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"datePublished\":\"2020-03-21T22:07:47+00:00\",\"dateModified\":\"2020-03-21T22:07:53+00:00\",\"description\":\"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto","description":"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/","og_locale":"pt_PT","og_type":"article","og_title":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto","og_description":"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-03-21T22:07:47+00:00","article_modified_time":"2020-03-21T22:07:53+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/capa-noticia-geral-1-e1617740501646.png","type":"image\/png"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria","datePublished":"2020-03-21T22:07:47+00:00","dateModified":"2020-03-21T22:07:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/"},"wordCount":524,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"articleSection":["Brasil"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/","url":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/","name":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"datePublished":"2020-03-21T22:07:47+00:00","dateModified":"2020-03-21T22:07:53+00:00","description":"- Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria - Brasil","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/vale-atualiza-informacoes-sobre-a-epidemia-de-coronavirus-e-ajuda-humanitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Vale atualiza informa\u00e7\u00f5es sobre a epidemia de coronav\u00edrus e ajuda humanit\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":6633,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-anuncia-doacao-de-50-milhoes-de-seringas-para-combate-a-covid-19\/","url_meta":{"origin":2376,"position":0},"title":"Vale anuncia doa\u00e7\u00e3o de 50 milh\u00f5es de seringas para combate \u00e0 Covid-19","author":"Di\u00e1rio de Ouro Preto","date":"25 de Fevereiro de 2021","format":false,"excerpt":"A Vale vai doar 50 milh\u00f5es de seringas ao Minist\u00e9rio da Sa\u00fade para apoiar os esfor\u00e7os de imuniza\u00e7\u00e3o contra a Covid-19 no pa\u00eds. Os primeiros lotes, com um total de dois milh\u00f5es de seringas, est\u00e3o previstos para chegar ao Brasil em mar\u00e7o e abril e os 48 milh\u00f5es restantes, at\u00e9\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/vale-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/vale-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/10\/vale-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7526,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/municipios-mineiros-recebem-apoio-da-vale-no-enfrentamento-da-covid-19\/","url_meta":{"origin":2376,"position":1},"title":"Munic\u00edpios mineiros recebem apoio da Vale no enfrentamento da COVID-19","author":"Di\u00e1rio de Ouro Preto","date":"9 de Abril de 2021","format":false,"excerpt":"Belo Horizonte, 9 de abril de 2021 -\u00a0A Vale refor\u00e7ou seu apoio aos munic\u00edpios onde mant\u00e9m suas opera\u00e7\u00f5es no enfrentamento da COVID-19. Neste momento mais cr\u00edtico da pandemia, a empresa cedeu, \u00e0 Prefeitura de Ouro Preto, dois cont\u00eaineres para a amplia\u00e7\u00e3o da Unidade de Pronto Atendimento (UPA) do bairro Saramenha.\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/04\/unnamed-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3074,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-conclui-doacao-de-5-milhoes-de-kits-de-teste-rapido-e-de-quase-16-milhoes-de-epis-para-governo-federal\/","url_meta":{"origin":2376,"position":2},"title":"Vale conclui doa\u00e7\u00e3o de 5 milh\u00f5es de kits de teste r\u00e1pido e de quase 16 milh\u00f5es de EPIs para governo federal","author":"Di\u00e1rio de Ouro Preto","date":"13 de Maio de 2020","format":false,"excerpt":"Guarulhos - O d\u00e9cimo-primeiro avi\u00e3o com insumos comprados pela Vale na China para combater a dissemina\u00e7\u00e3o do novo coronav\u00edrus (Sars-CoV-2), que provoca a Covid-19, pousou na noite de s\u00e1bado (9\/5) no Aeroporto Internacional de Guarulhos (SP). A aeronave trouxe a \u00faltima carga - 250 mil aventais cir\u00fargicos - doada ao\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6822,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-anuncia-chegada-do-primeiro-lote-de-2-milhoes-de-seringas-para-combate-a-covid-19\/","url_meta":{"origin":2376,"position":3},"title":"Vale anuncia chegada do primeiro lote de 2 milh\u00f5es de seringas para combate \u00e0 Covid-19","author":"Di\u00e1rio de Ouro Preto","date":"11 de Mar\u00e7o de 2021","format":false,"excerpt":"Guarulhos - Como parte de um novo pacote de ajuda humanit\u00e1ria no combate \u00e0 pandemia no pa\u00eds, a Vale informa que o primeiro lote com dois milh\u00f5es de seringas para combate \u00e0 Covid-19 chegou na noite desta ter\u00e7a-feira (9\/3) no aeroporto de Guarulhos, S\u00e3o Paulo. Os insumos, que ser\u00e3o doados\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/unnamed-1-1-scaled-e1615483654436.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/unnamed-1-1-scaled-e1615483654436.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/unnamed-1-1-scaled-e1615483654436.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/unnamed-1-1-scaled-e1615483654436.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/03\/unnamed-1-1-scaled-e1615483654436.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12005,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/acao-humanitaria-realizada-pela-vale-e-parceiros-entrega-mais-de-1-milhao-de-cestas-basicas-em-todo-o-brasil\/","url_meta":{"origin":2376,"position":4},"title":"A\u00e7\u00e3o humanit\u00e1ria realizada pela Vale e parceiros entrega mais de 1 milh\u00e3o de cestas b\u00e1sicas em todo o Brasil","author":"Di\u00e1rio de Ouro Preto","date":"21 de Dezembro de 2021","format":false,"excerpt":"A Vale alcan\u00e7ou a marca de mais de 1 milh\u00e3o de cestas b\u00e1sicas\/cart\u00f5es-alimenta\u00e7\u00e3o entregues para\u00a0mais de\u00a0220\u00a0mil fam\u00edlias em todo o Brasil. A meta foi alcan\u00e7ada gra\u00e7as \u00e0 uni\u00e3o de for\u00e7as entre a mineradora e organiza\u00e7\u00f5es como o Movimento Panela Cheia (formado por Cufa, Gerando Falc\u00f5es e Frente Nacional Antirracista), o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/unnamed.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/unnamed.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/unnamed.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/unnamed.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/unnamed.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2414,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/vale-anuncia-pacote-de-ajuda-temporaria-para-fornecedores\/","url_meta":{"origin":2376,"position":5},"title":"Vale anuncia pacote de ajuda tempor\u00e1ria para fornecedores","author":"Di\u00e1rio de Ouro Preto","date":"24 de Mar\u00e7o de 2020","format":false,"excerpt":"Rio de Janeiro - A Vale anunciou hoje (24\/03) uma s\u00e9rie de medidas de suporte para seus fornecedores durante a crise provocada pela epidemia do coronav\u00edrus. A estimativa \u00e9 que a empresa injete cerca de R$ 160 milh\u00f5es na economia nos pr\u00f3ximos dias somente com a antecipa\u00e7\u00e3o de pagamentos para\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2376"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2376\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}