{"id":2328,"date":"2020-03-19T18:24:55","date_gmt":"2020-03-19T21:24:55","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2328"},"modified":"2020-03-19T18:25:02","modified_gmt":"2020-03-19T21:25:02","slug":"tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/","title":{"rendered":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril"},"content":{"rendered":"<p>O TRE-MG suspendeu o expediente presencial em todos os cart\u00f3rios eleitorais, postos e centrais de atendimento ao eleitor e unidades da Secretaria no per\u00edodo compreendido entre 19 de mar\u00e7o e 07 de abril de 2020, podendo haver prorroga\u00e7\u00e3o. Com a decis\u00e3o, os servi\u00e7os ao eleitor que dependam de atendimento presencial ficam suspensos at\u00e9 07 de abril.<\/p>\n\n\n\n<p>A medida foi tomada para preservar a sa\u00fade e seguran\u00e7a dos servidores e do p\u00fablico que frequenta a institui\u00e7\u00e3o, em fun\u00e7\u00e3o da preocupa\u00e7\u00e3o com a propaga\u00e7\u00e3o do novo coronav\u00edrus. A suspens\u00e3o de expediente foi determinada por meio da&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/portaria-suspende-expediente-no-tre-mg\/rybena_pdf?file=http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/portaria-suspende-expediente-no-tre-mg\/at_download\/file\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Portaria Conjunta n\u00ba 30\/2020<\/a>&nbsp;(formato PDF), assinada pelos desembargadores Rog\u00e9rio Medeiros e Alexandre Carvalho, presidente e corregedor do Tribunal, respectivamente.<\/p>\n\n\n\n<p>As portas de acesso ao p\u00fablico externo permanecer\u00e3o fechadas e os servidores atuar\u00e3o em regime de trabalho remoto. As sess\u00f5es da Corte ser\u00e3o mantidas e acontecer\u00e3o nos dias 23, 24 e 30 de mar\u00e7o e 1\u00ba e 06 de abril. Os prazos dos processos f\u00edsicos ficar\u00e3o suspensos a partir de 19 de mar\u00e7o at\u00e9 nova medida em contr\u00e1rio. Os prazos dos processos que tramitam no PJe continuam correndo normalmente, j\u00e1 que dispensam a necessidade de ju\u00edzes, servidores e advogados estarem fisicamente na institui\u00e7\u00e3o.&nbsp;&nbsp;<\/p>\n\n\n\n<p>As medidas poder\u00e3o ser revistas, prorrogadas ou revogadas a qualquer momento, em virtude de novas orienta\u00e7\u00f5es das autoridades sanit\u00e1rias e determina\u00e7\u00e3o das autoridades governamentais. Neste momento, o Disque-Eleitor (telefone 148) continuar\u00e1 funcionando de segunda a sexta-feira, das 13h \u00e0s 18h, para esclarecer eventuais d\u00favidas dos eleitores.<\/p>\n\n\n\n<p><strong>Servi\u00e7os on-line<\/strong><\/p>\n\n\n\n<p>Alguns servi\u00e7os da Justi\u00e7a Eleitoral podem ser encontrados no site do TRE-MG e permanecer\u00e3o dispon\u00edveis. Confira:<\/p>\n\n\n\n<p>&#8211;&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/eleitor\/certidoes\/certidoes\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Certid\u00f5es<\/a>: emiss\u00e3o de certid\u00f5es de quita\u00e7\u00e3o eleitoral, filia\u00e7\u00e3o partid\u00e1ria, composi\u00e7\u00e3o partid\u00e1ria, crimes eleitorais e negativa de alistamento<\/p>\n\n\n\n<p>&#8211;&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/eleitor\/debitos-do-eleitor\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">D\u00e9bitos do eleitor<\/a>: possibilita a emiss\u00e3o de guia para pagamento de multas eleitorais decorrentes de aus\u00eancia \u00e0s urnas e\/ou aos trabalhos eleitorais<\/p>\n\n\n\n<p>&#8211;&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/eleitor\/situacao-eleitoral\/situacao-eleitoral\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Situa\u00e7\u00e3o eleitoral<\/a>: consulta para verificar a exist\u00eancia de pend\u00eancias no cadastro<\/p>\n\n\n\n<p>&#8211;\u00a0<a rel=\"noreferrer noopener follow external sponsored ugc\" href=\"http:\/\/www.tre-mg.jus.br\/eleitor\/titulo-e-local-de-votacao\/titulo-e-local-de-votacao\" target=\"_blank\" data-wpel-link=\"external\">T\u00edtulo e local de vota\u00e7\u00e3o<\/a>: consulta sobre os dados do t\u00edtulo de eleitor e local de vota\u00e7\u00e3o<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TRE-MG vai realizar sess\u00f5es de julgamento virtuais<\/strong><\/p>\n\n\n\n<p>A nova modalidade ser\u00e1 utilizada a partir de 30 de mar\u00e7o<\/p>\n\n\n\n<p>O Tribunal Regional Eleitoral de Minas Gerais regulamentou a realiza\u00e7\u00e3o de sess\u00f5es de julgamento virtuais para o trabalho da Corte. Elas ser\u00e3o operacionalizadas por meio de funcionalidade dispon\u00edvel no sistema do Processo Judicial Eletr\u00f4nico (PJe). A&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/resolucao-sessoes-virtuais\/rybena_pdf?file=http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/resolucao-sessoes-virtuais\/at_download\/file\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Resolu\u00e7\u00e3o 1.134\/2020<\/a>&nbsp;(formato PDF), que trata do assunto, foi publicada no DJE desta quarta-feira.<\/p>\n\n\n\n<p>O Tribunal j\u00e1 vinha planejando a implanta\u00e7\u00e3o dessa modalidade de julgamentos e agilizou a elabora\u00e7\u00e3o da norma para reduzir a necessidade da presen\u00e7a de magistrados, servidores e p\u00fablico externo em sua sede durante o per\u00edodo de precau\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 propaga\u00e7\u00e3o do novo coronav\u00edrus. Para preservar a sa\u00fade de todos, o&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/2020\/Marco\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">expediente presencial foi suspenso<\/a>&nbsp;de 19 de mar\u00e7o a 07 de abril, com possibilidade de prorroga\u00e7\u00e3o.<\/p>\n\n\n\n<p>As sess\u00f5es da Corte marcadas para esse per\u00edodo foram mantidas nas datas anteriormente divulgadas. Nos dias 23 (17h) e 24 de mar\u00e7o (9h), elas ainda ser\u00e3o presenciais. Nos dias 30 de mar\u00e7o, 1\u00ba e 06 de abril, as sess\u00f5es ser\u00e3o virtuais, todas \u00e0s 17h. Essa defini\u00e7\u00e3o est\u00e1 na&nbsp;<a href=\"http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/portaria-suspende-expediente-no-tre-mg\/rybena_pdf?file=http:\/\/www.tre-mg.jus.br\/imprensa\/noticias-tre-mg\/arquivos\/portaria-suspende-expediente-no-tre-mg\/at_download\/file\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Portaria Conjunta n\u00ba 30\/2020<\/a>&nbsp;(formato PDF). Caso haja prorroga\u00e7\u00e3o da suspens\u00e3o de expediente, ser\u00e1 avaliado de que forma ser\u00e3o realizadas as sess\u00f5es j\u00e1 previstas no calend\u00e1rio da Corte Eleitoral.<\/p>\n\n\n\n<p>Quando o expediente no TRE-MG for normalizado, caber\u00e1 aos membros da Corte definir, a cada m\u00eas, a forma de realiza\u00e7\u00e3o de cada sess\u00e3o de julgamentos. As que forem realizadas no meio virtual dever\u00e3o seguir todas as normas previstas na Resolu\u00e7\u00e3o 1.134.<\/p>\n\n\n\n<p>S\u00f3 poder\u00e3o ser inclu\u00eddos nas pautas de sess\u00f5es virtuais os processos (judiciais ou administrativos) que tramitam no PJe e nos quais n\u00e3o \u00e9 permitida sustenta\u00e7\u00e3o oral. As sess\u00f5es virtuais ter\u00e3o in\u00edcio no dia e hor\u00e1rio previamente estabelecidos e se encerrar\u00e3o \u00e0s 23h59 do dia seguinte. Nesse intervalo de tempo, os membros da Corte dever\u00e3o se pronunciar nos processos pautados.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><strong>Suspens\u00e3o de prazos<\/strong><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A Resolu\u00e7\u00e3o tamb\u00e9m definiu que os prazos de processos que tramitam em meio f\u00edsico, no primeiro e segundo graus da Justi\u00e7a Eleitoral mineira, ficam suspensos a partir de 19 de mar\u00e7o at\u00e9 nova medida em contr\u00e1rio. Os prazos dos processos que tramitam no PJe continuam correndo normalmente.<\/p>","protected":false},"excerpt":{"rendered":"<p>O TRE-MG suspendeu o expediente presencial em todos os cart\u00f3rios eleitorais, postos e centrais de atendimento ao eleitor e unidades da Secretaria no per\u00edodo compreendido entre 19 de mar\u00e7o e 07 de abril de 2020, podendo haver prorroga\u00e7\u00e3o. Com a decis\u00e3o, os servi\u00e7os ao eleitor que dependam de atendimento presencial<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["entry","author-diario","post-2328","post","type-post","status-publish","format-standard","has-post-thumbnail","category-minas-gerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-19T21:24:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-19T21:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"314\" \/>\n\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril\",\"datePublished\":\"2020-03-19T21:24:55+00:00\",\"dateModified\":\"2020-03-19T21:25:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/\"},\"wordCount\":807,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_cor-e1591743213355.jpg\",\"articleSection\":[\"Minas Gerais\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/\",\"name\":\"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_cor-e1591743213355.jpg\",\"datePublished\":\"2020-03-19T21:24:55+00:00\",\"dateModified\":\"2020-03-19T21:25:02+00:00\",\"description\":\"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_cor-e1591743213355.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_cor-e1591743213355.jpg\",\"width\":314,\"height\":265},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto","description":"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/","og_locale":"pt_PT","og_type":"article","og_title":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto","og_description":"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-03-19T21:24:55+00:00","article_modified_time":"2020-03-19T21:25:02+00:00","og_image":[{"width":314,"height":265,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril","datePublished":"2020-03-19T21:24:55+00:00","dateModified":"2020-03-19T21:25:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/"},"wordCount":807,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","articleSection":["Minas Gerais"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/","url":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/","name":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","datePublished":"2020-03-19T21:24:55+00:00","dateModified":"2020-03-19T21:25:02+00:00","description":"- TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril - Minas Gerais","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","width":314,"height":265},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/tre-suspende-o-expediente-presencial-de-19-de-marco-a-07-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"TRE suspende o expediente presencial de 19 de mar\u00e7o a 07 de abril"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg","jetpack-related-posts":[{"id":2446,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-viabiliza-atendimento-por-meio-eletronico-aos-pretensos-candidatos-a-eleicao-municipal\/","url_meta":{"origin":2328,"position":0},"title":"TRE viabiliza atendimento por meio eletr\u00f4nico aos pretensos candidatos \u00e0 elei\u00e7\u00e3o municipal","author":"Di\u00e1rio de Ouro Preto","date":"24 de Mar\u00e7o de 2020","format":false,"excerpt":"Belo Horizonte - O TRE de Minas Gerais regulamentou a presta\u00e7\u00e3o de servi\u00e7os para garantir que aqueles que pretendem se candidatar \u00e0s elei\u00e7\u00f5es 2020 possam cumprir os prazos previstos no calend\u00e1rio eleitoral relativos ao domic\u00edlio eleitoral e \u00e0 filia\u00e7\u00e3o partid\u00e1ria, que vencem no dia 4 de abril. O atendimento presencial\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":41315,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-retoma-expediente-regular-hoje\/","url_meta":{"origin":2328,"position":1},"title":"TRE retoma expediente regular hoje","author":"Di\u00e1rio de Ouro Preto","date":"7 de Janeiro de 2025","format":false,"excerpt":"Atendimento ao eleitor volta a ser das 12h \u00e0s 17h a partir de hoje 07 de Janeiro Os cart\u00f3rios eleitorais e a Secretaria do TRE-MG retornam ao expediente normal nesta ter\u00e7a-feira, ap\u00f3s o recesso forense, que foi de 20 de dezembro a 6 de janeiro. Nos cart\u00f3rios eleitorais e centrais\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/09\/IMG_1547.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2885,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/eleitores-tem-ate-06-de-maio-para-fazerem-o-primeiro-titulo-transferencia-e-regularizacao\/","url_meta":{"origin":2328,"position":2},"title":"Eleitores t\u00eam at\u00e9 06 de maio para fazerem o primeiro t\u00edtulo, transfer\u00eancia e regulariza\u00e7\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"30 de Abril de 2020","format":false,"excerpt":"O dia 06 de maio marca o fechamento do cadastro eleitoral. Nessa data, termina o prazo para quem quer votar nas Elei\u00e7\u00f5es 2020 fazer a primeira via do t\u00edtulo, transfer\u00eancia de munic\u00edpio, atualiza\u00e7\u00e3o ou regulariza\u00e7\u00e3o do cadastro.\u00a0 Os atendimentos para esses servi\u00e7os podem ser solicitados no site do TRE, por\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/logo_cor-e1591743213355.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5052,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tre-antecipa-atendimento-presencial-aos-partidos-politicos-para-registro-de-candidaturas\/","url_meta":{"origin":2328,"position":3},"title":"TRE antecipa atendimento presencial aos partidos pol\u00edticos para registro de candidaturas","author":"Di\u00e1rio de Ouro Preto","date":"21 de Setembro de 2020","format":false,"excerpt":"O TRE decidiu antecipar para esta segunda-feira (21) o atendimento presencial aos partidos pol\u00edticos e candidatos nos cart\u00f3rios eleitorais para os procedimentos de registro de candidaturas. A previs\u00e3o anterior era somente para o dia 26 de setembro. A decis\u00e3o ocorreu em raz\u00e3o da instabilidade do sistema CANDex, de uso obrigat\u00f3rio\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/antcrz_abr_1909185135df.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4873,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/atendimento-presencial-para-registro-de-candidaturas-e-regulamentado\/","url_meta":{"origin":2328,"position":4},"title":"Atendimento presencial para registro de candidaturas \u00e9 regulamentado","author":"Di\u00e1rio de Ouro Preto","date":"8 de Setembro de 2020","format":false,"excerpt":"Os partidos pol\u00edticos podem solicitar os registros de seus candidatos assim que a conven\u00e7\u00e3o partid\u00e1ria for realizada. O prazo para o registro de candidaturas\u00a0\u00e9 at\u00e9 26 de setembro, mas o TRE recomenda que os pedidos sejam enviados o quanto antes pelo\u00a0sistema CANDex, evitando-se, assim, eventuais dificuldades de acesso \u00e0 plataforma\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/urna_menor.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/urna_menor.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/urna_menor.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/urna_menor.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/06\/urna_menor.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31603,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prazo-para-tirar-transferir-e-regularizar-o-titulo-eleitoral-termina-em-um-mes\/","url_meta":{"origin":2328,"position":5},"title":"Prazo para tirar, transferir e regularizar o t\u00edtulo eleitoral termina em um m\u00eas","author":"Di\u00e1rio de Ouro Preto","date":"9 de Abril de 2024","format":false,"excerpt":"Cadastro eleitoral fecha no dia 8 de maio Eleitoras e eleitores t\u00eam apenas mais um m\u00eas para regularizar a situa\u00e7\u00e3o eleitoral, solicitar a transfer\u00eancia de domic\u00edlio eleitoral, atualizar dados cadastrais e colher a biometria para quem ainda n\u00e3o realizou esse procedimento. Ap\u00f3s o dia 8 de maio, o cadastro do\u2026","rel":"","context":"In &quot;Elei\u00e7\u00f5es&quot;","block_context":{"text":"Elei\u00e7\u00f5es","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/eleicoes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/etitulo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/etitulo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/etitulo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/etitulo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/05\/etitulo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2328"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2329"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}