{"id":2279,"date":"2020-03-17T13:54:48","date_gmt":"2020-03-17T16:54:48","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2279"},"modified":"2020-03-17T13:54:54","modified_gmt":"2020-03-17T16:54:54","slug":"mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/","title":{"rendered":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores"},"content":{"rendered":"<p>Em mais uma medida tomada para beneficiar o servidor, a Prefeitura de Mariana anunciou uma revis\u00e3o anual de 6% nos rendimentos dos seus funcion\u00e1rios. Com a revis\u00e3o, o Executivo garante mais um ganho para os trabalhadores do servi\u00e7o p\u00fablico. O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.<\/p>\n\n\n\n<p>Al\u00e9m do aumento, a Secretaria de Administra\u00e7\u00e3o prop\u00f4s um novo valor para o vale-alimenta\u00e7\u00e3o dos funcion\u00e1rios, que ir\u00e1 beneficiar mais pessoas. Agora, todos os servidores do munic\u00edpio que tem vencimentos b\u00e1sicos de at\u00e9 R$3.000 ter\u00e3o direito ao aux\u00edlio. A nova medida prev\u00ea tamb\u00e9m uma paridade para todos os que recebem, com o valor do aux\u00edlio sendo o mesmo para profissionais efetivos, contratados e nomeados.&nbsp;<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Segundo a secret\u00e1ria de Administra\u00e7\u00e3o, Arlinda Gon\u00e7alves, a revis\u00e3o anual foi s\u00f3 poss\u00edvel por conta de um trabalho s\u00e9rio feito por uma gest\u00e3o comprometida com a valoriza\u00e7\u00e3o dos servidores e o desenvolvimento de munic\u00edpio. \u201cPassamos por uma grande crise em momentos anteriores, mas fizemos todos os esfor\u00e7os para diminuir e qualificar os gastos, o que nos possibilitou a concess\u00e3o de revis\u00e3o geral anual nos anos de 2019 e 2020 e tamb\u00e9m permitiu a implementa\u00e7\u00e3o in\u00e9dita de Plano de Cargos, Carreiras e Vencimentos aos Servidores no final do ano passado\u201d, afirmou a secret\u00e1ria.&nbsp;<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A implementa\u00e7\u00e3o do PCCV garante ganhos reais para todas as categorias a m\u00e9dio e longo prazo, al\u00e9m de corrigir pontualmente distor\u00e7\u00f5es salariais, fazendo adequa\u00e7\u00e3o de algumas carreiras que nunca foram valorizadas antes.<br>Fonte: Assessoria de Imprensa<br>Foto: Marcelino de Castro<\/p>","protected":false},"excerpt":{"rendered":"<p>Em mais uma medida tomada para beneficiar o servidor, a Prefeitura de Mariana anunciou uma revis\u00e3o anual de 6% nos rendimentos dos seus funcion\u00e1rios. Com a revis\u00e3o, o Executivo garante mais um ganho para os trabalhadores do servi\u00e7o p\u00fablico. O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019,<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["entry","author-diario","post-2279","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mariana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T16:54:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T16:54:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Mariana assegura aumento real de sal\u00e1rios para todos os servidores\",\"datePublished\":\"2020-03-17T16:54:48+00:00\",\"dateModified\":\"2020-03-17T16:54:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/P1430812.jpg\",\"articleSection\":[\"Mariana\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/\",\"name\":\"Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/P1430812.jpg\",\"datePublished\":\"2020-03-17T16:54:48+00:00\",\"dateModified\":\"2020-03-17T16:54:54+00:00\",\"description\":\"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/P1430812.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/P1430812.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mariana assegura aumento real de sal\u00e1rios para todos os servidores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto","description":"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/","og_locale":"pt_PT","og_type":"article","og_title":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto","og_description":"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-03-17T16:54:48+00:00","article_modified_time":"2020-03-17T16:54:54+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores","datePublished":"2020-03-17T16:54:48+00:00","dateModified":"2020-03-17T16:54:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/"},"wordCount":324,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","articleSection":["Mariana"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/","url":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/","name":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","datePublished":"2020-03-17T16:54:48+00:00","dateModified":"2020-03-17T16:54:54+00:00","description":"O acr\u00e9scimo \u00e9 maior do que a infla\u00e7\u00e3o oficial de 2019, que fechou em 4,48%, resultando de fato em um aumento real do sal\u00e1rio dos servidores, uma vez que ele cresceu mais do que aumento dos pre\u00e7os de produtos e servi\u00e7os.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/mariana-assegura-aumento-real-de-salarios-para-todos-os-servidores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Mariana assegura aumento real de sal\u00e1rios para todos os servidores"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/03\/P1430812.jpg","jetpack-related-posts":[{"id":51642,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeito-assina-acordo-coletivo-com-reajuste-salarial-acima-da-inflacao\/","url_meta":{"origin":2279,"position":0},"title":"Prefeito assina Acordo Coletivo com reajuste salarial acima da infla\u00e7\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"10 de Abril de 2026","format":false,"excerpt":"Valoriza\u00e7\u00e3o, conquistas e respeito com os servidores p\u00fablicos municipais. Este \u00e9 o resumo da importante a\u00e7\u00e3o de assinatura do Acordo Coletivo firmado entre o Munic\u00edpio de Ouro Preto e o Sindicato dos Servidores e Funcion\u00e1rios P\u00fablicos (Sindsfop), na \u00faltima segunda-feira, 6. Entre as conquistas alcan\u00e7adas, destaca-se o reajuste de 8%\u2026","rel":"","context":"In &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/c4d0b9b8fafeabc5383a8fb291d2d856.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/c4d0b9b8fafeabc5383a8fb291d2d856.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/c4d0b9b8fafeabc5383a8fb291d2d856.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/04\/c4d0b9b8fafeabc5383a8fb291d2d856.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13073,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeito-duarte-anuncia-aumento-historico-para-os-servidores-municipais-e-inicio-da-gratuidade-no-transporte-publico-em-mariana\/","url_meta":{"origin":2279,"position":1},"title":"Prefeito Juliano Duarte anuncia aumento hist\u00f3rico para os servidores municipais e in\u00edcio da gratuidade no transporte p\u00fablico em Mariana","author":"Di\u00e1rio de Ouro Preto","date":"25 de Janeiro de 2022","format":false,"excerpt":"O prefeito de Mariana, Juliano Duarte, encaminhou hoje, ter\u00e7a-feira, 25, dois projetos de Lei para serem votados na C\u00e2mara, em reuni\u00e3o extraordin\u00e1ria. Um desses projeto prop\u00f5e aumento de 16,34% para todos os servidores do munic\u00edpio, um valor que representa, de acordo com o prefeito, \u201co maior reajuste da hist\u00f3ria de\u2026","rel":"","context":"In &quot;Mariana&quot;","block_context":{"text":"Mariana","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/mariana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ativo-29logo.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13321,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/propostas-apresentadas-na-assembleia-do-sindsfop-sao-aprovadas-por-unanimidade\/","url_meta":{"origin":2279,"position":2},"title":"Propostas apresentadas na Assembleia do SINDSFOP s\u00e3o aprovadas por unanimidade","author":"Di\u00e1rio de Ouro Preto","date":"3 de Fevereiro de 2022","format":false,"excerpt":"Hoje, 03 de fevereiro de 2022, foi realizada a Assembleia Geral Extraordin\u00e1ria do Sindicato dos Servidores e Funcion\u00e1rios P\u00fablicos Municipais de Ouro Preto, SINDSFOP. Em pauta, a delibera\u00e7\u00e3o sobre as propostas para reajuste salarial e a elei\u00e7\u00e3o da Comiss\u00e3o de Negocia\u00e7\u00e3o da data-base para 2022. O presidente do Sindicato Leandro\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-03-at-22.04.32.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-03-at-22.04.32.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-03-at-22.04.32.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-03-at-22.04.32.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15155,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/nova-manobra-do-governo-zema-contra-os-servidores-da-educacao-saude-e-seguranca\/","url_meta":{"origin":2279,"position":3},"title":"Nova manobra do governo Zema contra os servidores da Educa\u00e7\u00e3o, Sa\u00fade e Seguran\u00e7a","author":"Di\u00e1rio de Ouro Preto","date":"20 de Abril de 2022","format":false,"excerpt":"O governador de Minas Gerais, Romeu Zema (Novo) continua empenhado em fazer de tudo para n\u00e3o precisar pagar reajustes salariais acima do \u00edndice geral de 10,06% concedido ao funcionalismo p\u00fablico de Minas Gerais. Zema vetou os valores adicionais concedidos para servidores da seguran\u00e7a, da educa\u00e7\u00e3o e da sa\u00fade, mas seu\u2026","rel":"","context":"In &quot;Minas Gerais&quot;","block_context":{"text":"Minas Gerais","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/minas-gerais\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/PG__Zema_ALMG___6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/PG__Zema_ALMG___6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/PG__Zema_ALMG___6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/PG__Zema_ALMG___6.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/PG__Zema_ALMG___6.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13260,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/servidores-publicos-municipais-sao-contemplados-com-vale-alimentacao-de-r50000\/","url_meta":{"origin":2279,"position":4},"title":"Servidores p\u00fablicos municipais de Mariana s\u00e3o contemplados com Vale Alimenta\u00e7\u00e3o de R$500,00","author":"Di\u00e1rio de Ouro Preto","date":"3 de Fevereiro de 2022","format":false,"excerpt":"Uma boa not\u00edcia para os servidores p\u00fablicos municipais, foi aprovado na c\u00e2mara, na \u00faltima quarta-feira (29), o projeto de lei que disp\u00f5e sobre o aux\u00edlio alimenta\u00e7\u00e3o para todos os servidores p\u00fablicos contratados, efetivos e nomeados. Uma demanda antiga, j\u00e1 que antes, nem todos os servidores recebiam o aux\u00edlio. A partir\u2026","rel":"","context":"In &quot;Cidades&quot;","block_context":{"text":"Cidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/cidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/marianavaleali.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/marianavaleali.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/marianavaleali.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/marianavaleali.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34107,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/recomposicao-de-462-para-servidores-ja-pode-ser-votada-em-definitivo-na-almg\/","url_meta":{"origin":2279,"position":5},"title":"Recomposi\u00e7\u00e3o de 4,62% para servidores j\u00e1 pode ser votada em definitivo na ALMG","author":"Di\u00e1rio de Ouro Preto","date":"5 de Junho de 2024","format":false,"excerpt":"Parecer da Fiscaliza\u00e7\u00e3o Financeira incorpora o novo \u00edndice, proposto por todos os deputados e pelo governador, equivalente \u00e0 infla\u00e7\u00e3o de 2023 Com a aprova\u00e7\u00e3o do parecer de 2\u00ba turno da Comiss\u00e3o de Fiscaliza\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria (FFO), nesta quarta-feira (5\/6\/24), o\u00a0Projeto de Lei (PL) 2.309\/24, do governador, que trata da\u00a0revis\u00e3o\u2026","rel":"","context":"In &quot;Pol\u00edtica&quot;","block_context":{"text":"Pol\u00edtica","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/2115803.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/2115803.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/06\/2115803.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2279"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2280"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}