{"id":2084,"date":"2020-02-18T23:30:00","date_gmt":"2020-02-19T02:30:00","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=2084"},"modified":"2020-02-19T08:18:04","modified_gmt":"2020-02-19T11:18:04","slug":"mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/","title":{"rendered":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos"},"content":{"rendered":"<p class=\"has-medium-font-size\">Ant\u00f4nio Pereira &#8211; A reuni\u00e3o entre a comunidade e os Promotores de Justi\u00e7a do Minist\u00e9rio P\u00fablico, realizada hoje (18), tirou como encaminhamento o esclarecimentos das d\u00favidas sobre a <a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/antonio-pereira-tera-157-familias-evacuadas-pela-vale\/\" data-wpel-link=\"external\" target=\"_blank\" rel=\"follow external noopener noreferrer sponsored ugc\">remo\u00e7\u00e3o<\/a>. A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros, que explicou \u00e0 comunidade que ir\u00e1 oficiar a Vale e Defesa Civil para prestar esclarecimentos.&nbsp;<br><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Marcada para  \u00e0s 18 horas, a reuni\u00e3o teve ades\u00e3o e pontualidade. Quem abriu a fala foi Dr. Domingos, explicou que falaria depois do Dr. Andr\u00e9, que contou as experi\u00eancias vividas pelas comunidades atingidas em Macacos, Bar\u00e3o de Cocais e Brumadinho.&nbsp;<br><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Andr\u00e9 Sperling orientou que n\u00e3o sejam feitos acordos individuais, que a comunidade deve se unir e se fortalecer, s\u00f3 negociar coletivamente. \u201cCom rela\u00e7\u00e3o a sa\u00edda de casa, \u00e9 importante explicar para voc\u00eas que n\u00f3s do Minist\u00e9rio P\u00fablico n\u00e3o sabemos o n\u00edvel de risco. Outra coisa \u00e9 um processo de descomissionamento, antes dela resolver o problema dela, ela tem que resolver o problema de voc\u00eas. Se a defesa civil disser que tem que sair correndo,&nbsp; a\u00ed tem que sair correndo mesmo\u201d. Ele perguntou aos presentes se houve oferta de algum aux\u00edlio financeiro. \u201cEm Macacos(<em>distrito de Brumadinho<\/em>) que \u00e9 uma situa\u00e7\u00e3o parecida com a de voc\u00eas, eles recebem um vale de mil reais ao m\u00eas por pessoa, isso foi oferecido isso para voc\u00eas?&#8221;.&nbsp;Questionou o promotor da for\u00e7a tarefa.<br><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Em seguida Dra. Aline Silva Barros explicou que a falta de informa\u00e7\u00e3o tamb\u00e9m \u00e9 viola\u00e7\u00e3o de direitos. Ela explicou que todos os cuidados ser\u00e3o tomados, inclusive com os animais. Para assegurar o direito \u00e0 informa\u00e7\u00e3o ir\u00e1 oficiar a Vale e a Defesa Civil a prestarem esclarecimentos \u00e0 comunidade em reuni\u00e3o a ser marcada na Escola Estadual Daura de Carvalho.<br><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Dr. Domingos Ventura explicou que a Matriz da Tuv S\u00fcd, na Alemanha, ao revisar seus procedimentos enviou informa\u00e7\u00f5es ao Minist\u00e9rio P\u00fablico e entre as informa\u00e7\u00f5es estava sobre a barragem de Doutor, em Ant\u00f4nio Pereira. \u201cRecebemos esse documento da Tuv S\u00fcd revendo a modelagem de c\u00e1lculo, nessa revis\u00e3o tem algumas estruturas e dentre essas barragens estava a barragem do Doutor\u201d<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img decoding=\"async\" data-attachment-id=\"2090\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/p1410382\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382.jpg\" data-orig-size=\"1067,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1582052454&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;7.8&quot;,&quot;iso&quot;:&quot;1600&quot;,&quot;shutter_speed&quot;:&quot;0.16666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1410382\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-800x600.jpg\" src=\"https:\/\/i1.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382.jpg?fit=800%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-2090\" width=\"355\" height=\"266\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382.jpg 1067w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-528x396.jpg 528w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-800x600.jpg 800w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-150x113.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-768x576.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-1536x1152.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410382-160x120.jpg 160w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/><\/figure><\/div>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p class=\"has-medium-font-size\">De acordo com Dr. Domingos, a Ag\u00eancia Nacional de Minera\u00e7\u00e3o descobriu anomalias nas ombreiras da barragem. \u201cDevido \u00e0s chuvas a empresa est\u00e1 corrigindo a anomalia, com o acompanhamento da ANM\u201d, explicou.<br>O vereador Vander Leitoa (PV), acompanhou toda reuni\u00e3o com os promotores, mas n\u00e3o se manifestou. <br><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Texto e Fotos: Marcelino de Castro<\/p>","protected":false},"excerpt":{"rendered":"<p>Ant\u00f4nio Pereira &#8211; A reuni\u00e3o entre a comunidade e os Promotores de Justi\u00e7a do Minist\u00e9rio P\u00fablico, realizada hoje (18), tirou como encaminhamento o esclarecimentos das d\u00favidas sobre a remo\u00e7\u00e3o. A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr.<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":2089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-2084","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T02:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-19T11:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos\",\"datePublished\":\"2020-02-19T02:30:00+00:00\",\"dateModified\":\"2020-02-19T11:18:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/\"},\"wordCount\":475,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/P1410309-e1582083028672.jpg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/\",\"name\":\"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/P1410309-e1582083028672.jpg\",\"datePublished\":\"2020-02-19T02:30:00+00:00\",\"dateModified\":\"2020-02-19T11:18:04+00:00\",\"description\":\"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/P1410309-e1582083028672.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/P1410309-e1582083028672.jpg\",\"width\":952,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto","description":"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/","og_locale":"pt_PT","og_type":"article","og_title":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto","og_description":"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-02-19T02:30:00+00:00","article_modified_time":"2020-02-19T11:18:04+00:00","og_image":[{"width":952,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos","datePublished":"2020-02-19T02:30:00+00:00","dateModified":"2020-02-19T11:18:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/"},"wordCount":475,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/","url":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/","name":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","datePublished":"2020-02-19T02:30:00+00:00","dateModified":"2020-02-19T11:18:04+00:00","description":"A comunidade recebeu 3 promotores de Justi\u00e7a, Andr\u00e9 Sperling, da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico, refor\u00e7ou a equipe formada pelo Dr. Domingos Ventura, da 4\u00aa Promotoria e a respons\u00e1vel pela 2\u00aa Promotoria de Justi\u00e7a, Dra. Aline Silva Barros","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","width":952,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/mp-esclarece-moradores-de-antonio-pereira-sobre-seus-direitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"MP esclarece moradores de Ant\u00f4nio Pereira sobre seus direitos"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410309-e1582083028672.jpg","jetpack-related-posts":[{"id":2214,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ministerio-publico-realizou-audiencia-entre-a-comunidade-de-antonio-pereira-e-a-vale\/","url_meta":{"origin":2084,"position":0},"title":"Minist\u00e9rio P\u00fablico realizou audi\u00eancia entre a comunidade de Ant\u00f4nio Pereira e a Vale","author":"Di\u00e1rio de Ouro Preto","date":"28 de Fevereiro de 2020","format":false,"excerpt":"Ant\u00f4nio Pereira - Atendendo ao of\u00edcio da 2\u00aa Promotoria de Justi\u00e7a de Ouro Preto ocorreu na noite de ontem (27) mais uma reuni\u00e3o com a comunidade do distrito. Estiveram presentes funcion\u00e1rios da Vale e a equipe da Defesa Civil prestando esclarecimentos \u00e0 comunidade e aos promotores Aline Silva Barros,\u00a0 Dr.\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1430442-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1430442-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1430442-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2131,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/moradores-de-antonio-pereira-fecham-a-mg-129-e-pressionam-vale\/","url_meta":{"origin":2084,"position":1},"title":"Moradores de Ant\u00f4nio Pereira fecham a MG 129  e pressionam Vale","author":"Di\u00e1rio de Ouro Preto","date":"21 de Fevereiro de 2020","format":false,"excerpt":"Ant\u00f4nio Pereira - Cansados de informa\u00e7\u00f5es desencontradas e de n\u00e3o conseguirem se reunir com representantes da Vale, cerca de 150 moradores se reuniram em frente ao Cras, por volta das 5h30 da manh\u00e3 fecharam a pista da MG 129. O fluxo de \u00f4nibus dos funcion\u00e1rios das Vale, da Samarco e\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0040.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0040.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0040.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0040.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0040.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2044,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/tecnica-do-mp-esteve-com-moradores-de-antonio-pereira-neste-domingo\/","url_meta":{"origin":2084,"position":2},"title":"T\u00e9cnica do MP esteve com moradores de Ant\u00f4nio Pereira neste domingo","author":"Di\u00e1rio de Ouro Preto","date":"16 de Fevereiro de 2020","format":false,"excerpt":"Ouro Preto -\u00a0 O reconhecimento do territ\u00f3rio e o di\u00e1logo com os moradores em \u00e1reas de mancha prestando esclarecimentos e tirando d\u00favidas foi a tarefa da Assessora da For\u00e7a Tarefa do Minist\u00e9rio P\u00fablico Estadual, Liziane Vasconcelos, que neste domingo (16), esteve em Ant\u00f4nio Pereira. O encontro sem alarde foi na\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0046.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0046.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0046.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0046.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1943,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/antonio-pereira-tera-157-familias-evacuadas-pela-vale\/","url_meta":{"origin":2084,"position":3},"title":"ANT\u00d4NIO PEREIRA TER\u00c1 232 PESSOAS EVACUADAS PELA VALE","author":"Di\u00e1rio de Ouro Preto","date":"12 de Fevereiro de 2020","format":false,"excerpt":"Ouro Preto - Em reuni\u00e3o tensa na noite desta quarta-feira, (12), a comunidade de Ant\u00f4nio Pereira foi informada pelo prefeito J\u00falio Pimenta, que 232 pessoas, em 98 edifica\u00e7\u00f5es ser\u00e3o removidas de suas casas, localizadas pr\u00f3ximas ao rio, e que os trabalhos de remo\u00e7\u00e3o come\u00e7am amanh\u00e3.\u00a0\u00a0A medida preventiva se deve ao\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410122b.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410122b.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410122b.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410122b.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1410122b.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1972,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/moradores-de-antonio-pereira-ficam-indignados-com-ausencia-da-vale-em-reuniao-sobre-remocao\/","url_meta":{"origin":2084,"position":4},"title":"Moradores de Ant\u00f4nio Pereira ficam indignados com aus\u00eancia da Vale em reuni\u00e3o sobre remo\u00e7\u00e3o","author":"Di\u00e1rio de Ouro Preto","date":"15 de Fevereiro de 2020","format":false,"excerpt":"Ant\u00f4nio Pereira - Solicitada para ser realizada hoje, \u00e0s 10 horas, a reuni\u00e3o entre a Vale e as fam\u00edlias a serem removidas n\u00e3o ocorreu. As fam\u00edlias esperavam esclarecimentos sobre como ser\u00e3o realocadas. Indignados apenas em encontrar os servidores da Defesa Civil no Cras (Centro de Refer\u00eancia da Assist\u00eancia Social), um\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/20200215_105845-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/20200215_105845-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/20200215_105845-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/20200215_105845-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/20200215_105845-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2199,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/promotora-convocou-vale-prefeitura-e-defesa-civil-a-prestarem-esclarecimentos-aos-moradores-de-antonio-pereira-hoje\/","url_meta":{"origin":2084,"position":5},"title":"Promotora convocou Vale, Prefeitura e Defesa Civil a prestarem esclarecimentos aos moradores de Ant\u00f4nio Pereira hoje","author":"Di\u00e1rio de Ouro Preto","date":"27 de Fevereiro de 2020","format":false,"excerpt":"Ouro Preto - A comunidade de Ant\u00f4nio Pereira se reunir\u00e1 hoje, \u00e0s 18 horas, com representantes da Vale, da Prefeitura e da Defesa Civil que dever\u00e3o prestar esclarecimentos sobre a real situa\u00e7\u00e3o da barragem de Doutor e sobre a necessidade de remo\u00e7\u00e3o preventiva ou evacua\u00e7\u00e3o emergencial. Na sexta-feira, 21, a\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0036-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0036-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0036-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0036-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG-20200221-WA0036-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=2084"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/2084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/2089"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=2084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=2084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=2084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}