{"id":1936,"date":"2020-02-10T15:57:16","date_gmt":"2020-02-10T18:57:16","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=1936"},"modified":"2020-02-10T15:57:23","modified_gmt":"2020-02-10T18:57:23","slug":"carnaval-patrimonio-2020-tem-programacao-divulgada","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/","title":{"rendered":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada"},"content":{"rendered":"<p>\n\nOuro Preto segue apostando na tradi\u00e7\u00e3o hist\u00f3rica para fazer um dos melhores carnavais de rua do pa\u00eds. Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.<br>Jacubas e os Mocot\u00f3s eram chamados os habitantes de Ouro Preto de acordo com a regi\u00e3o em que residiam. De um lado, o bairro de Ant\u00f4nio Dias, com sua imponente Matriz de Nossa Senhora da Concei\u00e7\u00e3o, e os jacubas, como eram chamados seus moradores. De outro, o bairro do Pilar, ostentando sua Matriz de Nossa Senhora do Pilar, uma das mais ricas do pa\u00eds, e os mocot\u00f3s, apelido dado pelos jacubas aos que ali viviam.<br>A historiadora e moradora de Ouro Preto, Deolinda dos Santos, explica a origem dos nomes dos grupos. \u201cJacuba \u00e9 um tipo de farinha misturado com um pouco de gordura ou sal que \u00e9 para o sustento do garimpeiro. Do outro lado, o mocot\u00f3 \u00e9 o caldo e representa as pessoas ricas\u201d, diz.&nbsp;<br>E, no meio, a hoje Pra\u00e7a Tiradentes, palco de um dos mais tradicionais carnavais de rua do pa\u00eds, que atrai gente de todas as idades e dos quatro cantos do Brasil. Tudo organizado e mantido pelos moradores, que fazem quest\u00e3o de manter a tradi\u00e7\u00e3o tamb\u00e9m no carnaval, mostrando que jacubas e mocot\u00f3s, hoje em dia, n\u00e3o apenas se misturam, mas organizam juntos um dos melhores carnavais de rua do pa\u00eds.<br>A op\u00e7\u00e3o por um carnaval de rua inclusivo, gratuito e que valoriza a tradi\u00e7\u00e3o \u00e9 receita de sucesso h\u00e1 gera\u00e7\u00f5es. Tanto que o Z\u00e9 Pereira dos Lacaios \u00e9 o mais antigo bloco de sua modalidade no pa\u00eds. E segue arrastando crian\u00e7as, adultos e at\u00e9 a terceira idade at\u00e9 hoje. \u201cO bloco \u00e9 uma das atividades do Clube dos Lacaios, que surgiu em Ouro Preto h\u00e1 152 anos\u201d, explica o presidente do Clube dos Lacaios, Arthur Nogueira.&nbsp;<br>E n\u00e3o s\u00f3 de Z\u00e9 Pereira vive o carnaval de Ouro Preto. Outros, como a Bandalheira, o Vermelho e Branco, o Balan\u00e7o da Cobra e o Sanat\u00f3rio Geral n\u00e3o deixam ningu\u00e9m ficar parado nos cinco dias de folia momesca. Umas das organizadoras do Bloco Balan\u00e7o da Cobra, Cida Zurlo, fala das expectativas para o carnaval deste ano. \u201cO nosso bloco j\u00e1 soma 45 anos de hist\u00f3ria. Neste ano iremos para as ruas com nossa camiseta tem\u00e1tica, com desenho e arte do artista pl\u00e1stico Carlos Bracher. A nossa expectativa \u00e9 de que o movimento na cidade seja grande j\u00e1 que esse ano os blocos est\u00e3o tendo mais espa\u00e7o pelas ruas da cidade, o que deixa o carnaval muito mais animado\u201d, revela Cida.<\/p>\n\n\n\n<p>&#8220;O carnaval de Ouro Preto \u00e9 o melhor carnaval de rua do pa\u00eds. \u00c9 uma festa bonita, alegre, da qual podem participar todos, inclusive fam\u00edlias e idosos&#8221;, diz o engenheiro Geraldo Malta, que apesar de morar em Vit\u00f3ria (ES), frequenta o carnaval ouropretano h\u00e1 mais de 50 anos.<br><strong>Confira a programa\u00e7\u00e3o:&nbsp;<\/strong><br><strong>Dia 20 de fevereiro (quinta-feira)<\/strong><br>Bloco \u201cOs Conspirados\u201d<br>Hor\u00e1rio: 17h \u2013 Local: Pra\u00e7a Tiradentes (Centro)<br>Descri\u00e7\u00e3o: Bloco do CAPS (Centro de Aten\u00e7\u00e3o Psicossocial) da Prefeitura Municipal de Ouro Preto. Em 2020, o bloco comemora seus 20 anos.<\/p>\n\n\n\n<p><strong>Dia 20 de fevereiro (quinta-feira)<\/strong><br>Bloco \u201cVermelho i Branco\u201d<br>Hor\u00e1rio: 20h \\ Local: Bairro Ros\u00e1rio<br>Descri\u00e7\u00e3o: Bloco conhecido por sua hist\u00f3ria no bairro Ros\u00e1rio. Atualmente, re\u00fane cerca de 5 mil foli\u00f5es vestidos de vermelho e branco. O bloco sai pelas ruas ouro-pretanas ao som de marchinhas.<\/p>\n\n\n\n<p><strong>Dia 20 de fevereiro (quinta-feira)<\/strong><br>Baile de M\u00e1scaras \u2013 Show Baianas Ozadas<br>Local: Largo do Cinema \\ Hor\u00e1rio: 23h<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<p><strong>Dias 20, 22 e 25 de fevereiro (quinta, s\u00e1bado e ter\u00e7a)<\/strong><br>Bloco \u201cZ\u00e9 Pereira do Club dos Lacaios\u201d<br>Hor\u00e1rio: 21h \u2013 Local: Pra\u00e7a Tiradentes (Centro)<br>Descri\u00e7\u00e3o: Agremia\u00e7\u00e3o carnavalesca em funcionamento mais antiga do pa\u00eds. Em 2020, o bloco completa seus 153 anos de hist\u00f3ria.<\/p>\n\n\n\n<p><strong>Dia 21 de fevereiro (sexta-feira)<\/strong><br>Abertura Oficial do Carnaval 2020 \u2013 Show Banda Mikareteiros<br>Local: Pra\u00e7a Tiradentes \\ Hor\u00e1rio: 23h<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<p><strong>Dia 21 de fevereiro (sexta-feira)<\/strong><br>Show do Grupo JPG \u2013 Formado pelo filho de Z\u00e9 Ramalho e Amelinha.<br>Local: Largo da Alegria<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<p><strong>Dia 22 de fevereiro (s\u00e1bado)<\/strong><br>Bloco \u201cSanat\u00f3rio Geral\u201d<br>Hor\u00e1rio: 15h<br>Descri\u00e7\u00e3o: O bloco presta uma homenagem aos ilustres ouro-pretanos. Cidad\u00e3os que com suas ideias e posi\u00e7\u00f5es marcaram a vida na cidade e passaram a fazer parte do imagin\u00e1rio de seus habitantes.<\/p>\n\n\n\n<p><strong>Dia 22 de fevereiro (s\u00e1bado)<\/strong><br>Show Banda Tianast\u00e1cia e Cabrobloco<br>Local: Pra\u00e7a Tiradentes \\ Hor\u00e1rio: 18h<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<p><strong>Dias 23 e 24 de fevereiro (domingo e segunda)<\/strong><br>Desfiles das Escolas De Samba<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<p><strong>Dia 24 de fevereiro (segunda)<\/strong><br>Bloco \u201cBalan\u00e7o da Cobra\u201d<br>Hor\u00e1rio: 17h<br>Descri\u00e7\u00e3o: Com s\u00e1tiras bem humoradas alusivas aos fatos ocorridos durante o ano, o bloco sai \u00e0s ruas com muita criatividade. Os acess\u00f3rios incluem cartazes, faixas e fantasias.<\/p>\n\n\n\n<p><strong>Dia 25 de fevereiro (ter\u00e7a)<\/strong><br>Show Bartucada<br>Classifica\u00e7\u00e3o: Livre para todos os p\u00fablicos \\ Entrada: Gratuita.<\/p>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p><strong>Como chegar a Ouro Preto<\/strong><br>H\u00e1 voos di\u00e1rios das capitais e principais cidades para Belo Horizonte (Aeroporto de Confins). De l\u00e1, pode-se optar por um servi\u00e7o de transfer at\u00e9 Ouro Preto (t\u00e1xi, uber, etc.) ou ir at\u00e9 o Terminal Rodovi\u00e1rio de Belo Horizonte e tomar um \u00f4nibus para Ouro Preto, que sai de hora em hora, a partir das 6h.<br>Do Rio, de S\u00e3o Paulo, de Bras\u00edlia e de Vit\u00f3ria, h\u00e1 \u00f4nibus direto para Ouro Preto <\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Foto: Ane Souz<\/p>","protected":false},"excerpt":{"rendered":"<p>Ouro Preto segue apostando na tradi\u00e7\u00e3o hist\u00f3rica para fazer um dos melhores carnavais de rua do pa\u00eds. Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.Jacubas e os<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":1937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[42,41,43],"class_list":["entry","author-diario","post-1936","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carnaval","tag-carnaval-jacubas-e-mocotos","tag-carnaval-ouro-preto-2020","tag-ouro-preto-folia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-10T18:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-10T18:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada\",\"datePublished\":\"2020-02-10T18:57:16+00:00\",\"dateModified\":\"2020-02-10T18:57:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/\"},\"wordCount\":979,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg\",\"keywords\":[\"Carnaval Jacubas e Mocot\u00f3s\",\"carnaval Ouro Preto 2020\",\"Ouro Preto folia\"],\"articleSection\":[\"Carnaval\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/\",\"name\":\"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg\",\"datePublished\":\"2020-02-10T18:57:16+00:00\",\"dateModified\":\"2020-02-10T18:57:23+00:00\",\"description\":\"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg\",\"width\":799,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/carnaval-patrimonio-2020-tem-programacao-divulgada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto","description":"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/","og_locale":"pt_PT","og_type":"article","og_title":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto","og_description":"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/carnaval-patrimonio-2020-tem-programacao-divulgada\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-02-10T18:57:16+00:00","article_modified_time":"2020-02-10T18:57:23+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada","datePublished":"2020-02-10T18:57:16+00:00","dateModified":"2020-02-10T18:57:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/"},"wordCount":979,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","keywords":["Carnaval Jacubas e Mocot\u00f3s","carnaval Ouro Preto 2020","Ouro Preto folia"],"articleSection":["Carnaval"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/","url":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/","name":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","datePublished":"2020-02-10T18:57:16+00:00","dateModified":"2020-02-10T18:57:23+00:00","description":"Em 2020, o carnaval homenageia os 40 anos do t\u00edtulo de Patrim\u00f4nio Mundial da cidade, relembrando a antiga e divertida disputa centen\u00e1ria dos moradores, com o tema \u201cEntre Jacubas e Mocot\u00f3s\u201d.","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","width":799,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/carnaval-patrimonio-2020-tem-programacao-divulgada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Carnaval Patrim\u00f4nio 2020 tem programa\u00e7\u00e3o divulgada"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/Bloco-Bandalheira-_Credito-Ane-Souz.jpg","jetpack-related-posts":[{"id":11957,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/sem-diferencas-nem-distincao-ouro-pretanos-celebram-o-fim-de-ano-unidos-pela-religiosidade\/","url_meta":{"origin":1936,"position":0},"title":"Sem diferen\u00e7as nem distin\u00e7\u00e3o, ouro-pretanos celebram o fim de ano unidos pela religiosidade","author":"Di\u00e1rio de Ouro Preto","date":"21 de Dezembro de 2021","format":false,"excerpt":"Victor Stutz, para o Di\u00e1rio de Ouro Preto Foi no S\u00e9culo XVIII, quando o arraial do Ant\u00f4nio Dias se uniu ao arraial do Ouro Preto, uma disputa foi iniciada entre os dois lados da nova Vila Rica. De um lado, os moradores do Bairro Ant\u00f4nio Dias, os chamados Jacubas. Do\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-21-at-12.45.46.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-21-at-12.45.46.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-21-at-12.45.46.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-21-at-12.45.46.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-21-at-12.45.46.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1849,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/atracoes-do-carnaval-de-ouro-preto-2020\/","url_meta":{"origin":1936,"position":1},"title":"Confira a programa\u00e7\u00e3o do Carnaval de Ouro Preto 2020","author":"Di\u00e1rio de Ouro Preto","date":"20 de Fevereiro de 2020","format":false,"excerpt":"Para animar a cidade no per\u00edodo do carnaval diversos shows, desfiles de escolas de samba e blocos est\u00e3o programados. Confira a pr\u00e9via da programa\u00e7\u00e3o: Blocos 20 de fevereiro - Quinta-feira BLOCO \u201cOs Conspirados\u201d Bloco do CAPS (Centro de Aten\u00e7\u00e3o Psicossocial) da Prefeitura Municipal de Ouro Preto. Em 2020, o bloco\u2026","rel":"","context":"In &quot;Carnaval&quot;","block_context":{"text":"Carnaval","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/carnaval\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/carnaval.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13429,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/familiares-do-mestre-vandico-fazem-campanha-de-doacao-de-sangue-em-nome-do-grande-artista-ouro-pretano\/","url_meta":{"origin":1936,"position":2},"title":"Familiares do Mestre Vandico fazem campanha de doa\u00e7\u00e3o de sangue em nome do grande artista ouro-pretano","author":"Di\u00e1rio de Ouro Preto","date":"7 de Fevereiro de 2022","format":false,"excerpt":"Vandico, um dos mais respeitados criadores de Arte de Ouro Preto est\u00e1 precisando de todos n\u00f3s. Ele est\u00e1 internado em Belo Horizonte em estado bastante grave, passou por um longo per\u00edodo de tratamento e, agora, precisa repor o banco de sangue. Para isso, os familiares pedem ajuda a todos que\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/vandico-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/vandico-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/02\/vandico-2.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1636,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ze-pereira-inicia-ensaios-com-cortejo-no-proximo-domingo\/","url_meta":{"origin":1936,"position":3},"title":"Z\u00e9 Pereira inicia ensaios com cortejo no pr\u00f3ximo domingo","author":"Di\u00e1rio de Ouro Preto","date":"16 de Janeiro de 2020","format":false,"excerpt":"Os ensaios do bloco Z\u00e9 Pereira come\u00e7am a deixar Ouro Preto no clima de carnaval. No pr\u00f3ximo domingo, 19\/01, \u00e0s 20 horas, o bloco realiza cortejo seguindo todo o trajeto costumeiro que do carnaval: Sa\u00edda da sede (Rua Santa Efig\u00eania), passando pelo Largo do Mar\u00edlia, Rua Bernardo Vasconcelos, Rua Cl\u00e1udio\u2026","rel":"","context":"In &quot;Carnaval&quot;","block_context":{"text":"Carnaval","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/carnaval\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/20190305_212846-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/20190305_212846-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/20190305_212846-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/20190305_212846-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/01\/20190305_212846-scaled.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":355,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/escola-de-samba-sao-clemente-leva-ouro-preto-para-o-carnaval-carioca\/","url_meta":{"origin":1936,"position":4},"title":"Escola de samba S\u00e3o Clemente leva Ouro Preto para o carnaval Carioca","author":"Di\u00e1rio de Ouro Preto","date":"18 de Junho de 2019","format":false,"excerpt":"Com o enredo \u201cO Conto do Vig\u00e1rio\u201d, a cidade e a hist\u00f3ria de Minas Gerais ser\u00e3o homenageadas na Marqu\u00eas de Sapuca\u00ed Ouro Preto e Minas Gerais ser\u00e3o tema da Escola de Samba carioca, S\u00e3o Clemente, no Carnaval de 2020. A informa\u00e7\u00e3o foi confirmada na \u00faltima quinta-feira, dia 13, no lan\u00e7amento\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ouro-Preto-ser%C3%A1-tema-da-Escola-de-Samba-S%C3%A3o-Clemente-800x600.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ouro-Preto-ser%C3%A1-tema-da-Escola-de-Samba-S%C3%A3o-Clemente-800x600.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ouro-Preto-ser%C3%A1-tema-da-Escola-de-Samba-S%C3%A3o-Clemente-800x600.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/Ouro-Preto-ser%C3%A1-tema-da-Escola-de-Samba-S%C3%A3o-Clemente-800x600.jpeg?resize=700%2C400 2x"},"classes":[]},{"id":39326,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/deslizamento-de-terra-na-rua-pandia-calogeras-altera-circulacao-de-linhas-de-onibus\/","url_meta":{"origin":1936,"position":5},"title":"Deslizamento de terra na Rua Pandi\u00e1 Cal\u00f3geras altera circula\u00e7\u00e3o de linhas de \u00f4nibus","author":"Di\u00e1rio de Ouro Preto","date":"30 de Outubro de 2024","format":false,"excerpt":"Nesta madrugada, 30\/10, ocorreu um deslizamento na Rua Pandi\u00e1 Cal\u00f3geras, popularmente conhecida como \u201cMorro do Gamb\u00e1\u201d. O incidente provocou a queda de um poste, causando falta de energia em toda a regi\u00e3o. Equipes coordenadas pela Defesa Civil isolaram a \u00e1rea e interditaram a via para garantir a seguran\u00e7a de pedestres\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-30-as-10.06.20_efeebe20.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-30-as-10.06.20_efeebe20.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-30-as-10.06.20_efeebe20.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/1936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=1936"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/1936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/1937"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=1936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=1936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=1936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}