{"id":1912,"date":"2020-02-07T15:37:42","date_gmt":"2020-02-07T18:37:42","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=1912"},"modified":"2020-02-07T16:00:23","modified_gmt":"2020-02-07T19:00:23","slug":"empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/","title":{"rendered":"Empres\u00e1rios lan\u00e7am &#8220;Movimento Viva Ouro Preto Efici\u00eancia &#8211; Compet\u00eancia -Honestidade&#8221;"},"content":{"rendered":"<p>Ouro Preto &#8211; Planejar o futuro com sustentabilidade dos neg\u00f3cios para os pr\u00f3ximos 30 anos \u00e9 a proposta do MOV-OP, Movimento Viva Ouro Preto, lan\u00e7ado nesta quinta-feira, 06\/02, no anexo do Museu da Inconfid\u00eancia, tendo como palestrantes o secret\u00e1rio-adjunto da Secretaria de Desenvolvimento Econ\u00f4mico (Sede), Fernando Passalio, do ex-presidente da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais e Empresariais de Minas Gerais (Federaminas), Em\u00edlio Parolini.&nbsp;<br><\/p>\n\n\n\n<p>Com a participa\u00e7\u00e3o das principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, foi lan\u00e7ado o MOV-OP com o lema \u201cUnir para desenvolver e crescer\u201d. O MOV- OP objetiva sensibilizar e unir todos da comunidade, para diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, consequentemente criar projetos de desenvolvimento e cidadania para Ouro Preto.<br><\/p>\n\n\n\n<p>O debate teve contribui\u00e7\u00e3o do ex-presidente da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es Comerciais e Empresariais de Minas Gerais (Federaminas), Em\u00edlio Parolini. A condu\u00e7\u00e3o das diretrizes do f\u00f3rum foi apresentada por um dos representantes do Movimento Viva Ouro Preto, M\u00e1rcio Homem Cotta de Faria. \u201cQueremos ir al\u00e9m dos horizontes e tra\u00e7ar novos caminhos para nossa regi\u00e3o. A contribui\u00e7\u00e3o do Governo de Minas Gerais ser\u00e1 muito positiva\u201d, destacou Cotta. O movimento \u00e9 difundido e coordenado por diversas lideran\u00e7as do munic\u00edpio.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1067\" height=\"800\" data-attachment-id=\"1914\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/p1400933\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933.jpg\" data-orig-size=\"1067,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1581020005&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17.9&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.2&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1400933\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-800x600.jpg\" src=\"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933.jpg?fit=800%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-1914\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933.jpg 1067w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-528x396.jpg 528w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-800x600.jpg 800w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-150x113.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-768x576.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-1536x1152.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400933-160x120.jpg 160w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><figcaption>Secret\u00e1rio Adjunto, Fernando Passalio tamb\u00e9m falou sobre a import\u00e2ncia de se chancelar os arranjos produtivos locais de Ouro Preto<\/figcaption><\/figure>\n\n\n\n<p>O secret\u00e1rio-adjunto, Fernando Passalio, apresentou os eixos estrat\u00e9gicos de atua\u00e7\u00e3o do Desenvolvimento Econ\u00f4mico: Minas Livre Para Crescer, Atra\u00e7\u00e3o de Investimentos e Desestatiza\u00e7\u00e3o e Privatiza\u00e7\u00e3o. \u201cEstamos com uma estrat\u00e9gia voltada para melhorar a vida dos mineiros. Por meio das a\u00e7\u00f5es de desenvolvimento econ\u00f4mico j\u00e1 estamos conquistando resultados no social, com frutos para gera\u00e7\u00e3o de emprego e renda\u201d, destacou Passalio.<\/p>\n\n\n\n<p>O Minas Livre Para Crescer, programa do governo estadual, foi o eixo principal da discuss\u00e3o no semin\u00e1rio. As atividades de liberdade econ\u00f4mica e a facilita\u00e7\u00e3o da vida do empreendedor foram as principais pautas debatidas entre os convidados. \u201cO programa Minas Livre Para Crescer est\u00e1 facilitando a vida do empreendedor. O Governo quer ouvir os empres\u00e1rios, quer desburocratizar as a\u00e7\u00f5es. O resultado ser\u00e1 refletido em toda a sociedade. Todos est\u00e3o convidados a participar\u201d, reafirmou os secret\u00e1rio-adjunto.<\/p>\n\n\n\n<p>O semin\u00e1rio \u00e9 o in\u00edcio da constru\u00e7\u00e3o para um planejamento de desenvolvimento econ\u00f4mico e social de Ouro Preto e regi\u00e3o. As a\u00e7\u00f5es do documento estar\u00e3o divididas em cinco pilares: turismo, cultura e esporte; com\u00e9rcio, servi\u00e7os; ind\u00fastria; educa\u00e7\u00e3o e tecnologia. Durante o evento, os convidados puderam tirar d\u00favidas e fazer perguntas para os palestrantes. A constru\u00e7\u00e3o do plano ser\u00e1 realizada por meio de novas rodadas de palestras.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1067\" height=\"800\" data-attachment-id=\"1915\" data-permalink=\"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/p1400935\/\" data-orig-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935.jpg\" data-orig-size=\"1067,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-FZ47&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1581020025&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;500&quot;,&quot;shutter_speed&quot;:&quot;0.25&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"P1400935\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-800x600.jpg\" src=\"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935.jpg?fit=800%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-1915\" srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935.jpg 1067w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-528x396.jpg 528w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-800x600.jpg 800w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-150x113.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-768x576.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-1536x1152.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/P1400935-160x120.jpg 160w\" sizes=\"(max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Al\u00e9m de empres\u00e1rios participaram l\u00edderes comunit\u00e1rios como Cor-J\u00e9sus do Esp\u00edrito Santo, do Grupo Nata, Alu\u00edsio Drummond, da Funda\u00e7\u00e3o Sorria, o professor Rog\u00e9rio Fernandes, pr\u00e9-candidato a prefeito de Ouro Preto tamb\u00e9m estavam presentes.\u00a0<br><\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Foto destaque:  Matheus Fonseca\/Sede e Marcelino de Castro\/di\u00e1rioop<\/p>","protected":false},"excerpt":{"rendered":"<p>Ouro Preto &#8211; Planejar o futuro com sustentabilidade dos neg\u00f3cios para os pr\u00f3ximos 30 anos \u00e9 a proposta do MOV-OP, Movimento Viva Ouro Preto, lan\u00e7ado nesta quinta-feira, 06\/02, no anexo do Museu da Inconfid\u00eancia, tendo como palestrantes o secret\u00e1rio-adjunto da Secretaria de Desenvolvimento Econ\u00f4mico (Sede), Fernando Passalio, do ex-presidente da<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":1913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-1912","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empres\u00e1rios lan\u00e7am &quot;Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade&quot; - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empres\u00e1rios lan\u00e7am &quot;Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade&quot; - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-07T18:37:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-07T19:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"Empres\u00e1rios lan\u00e7am &#8220;Movimento Viva Ouro Preto Efici\u00eancia &#8211; Compet\u00eancia -Honestidade&#8221;\",\"datePublished\":\"2020-02-07T18:37:42+00:00\",\"dateModified\":\"2020-02-07T19:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_1423_07-02-2020-scaled.jpg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/\",\"name\":\"Empres\u00e1rios lan\u00e7am \\\"Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade\\\" - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_1423_07-02-2020-scaled.jpg\",\"datePublished\":\"2020-02-07T18:37:42+00:00\",\"dateModified\":\"2020-02-07T19:00:23+00:00\",\"description\":\"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_1423_07-02-2020-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_1423_07-02-2020-scaled.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empres\u00e1rios lan\u00e7am &#8220;Movimento Viva Ouro Preto Efici\u00eancia &#8211; Compet\u00eancia -Honestidade&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empres\u00e1rios lan\u00e7am \"Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade\" - Di\u00e1rio de Ouro Preto","description":"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Empres\u00e1rios lan\u00e7am \"Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade\" - Di\u00e1rio de Ouro Preto","og_description":"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2020-02-07T18:37:42+00:00","article_modified_time":"2020-02-07T19:00:23+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"Empres\u00e1rios lan\u00e7am &#8220;Movimento Viva Ouro Preto Efici\u00eancia &#8211; Compet\u00eancia -Honestidade&#8221;","datePublished":"2020-02-07T18:37:42+00:00","dateModified":"2020-02-07T19:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/"},"wordCount":551,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/","url":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/","name":"Empres\u00e1rios lan\u00e7am \"Movimento Viva Ouro Preto Efici\u00eancia - Compet\u00eancia -Honestidade\" - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","datePublished":"2020-02-07T18:37:42+00:00","dateModified":"2020-02-07T19:00:23+00:00","description":"Com as principais lideran\u00e7as empresariais e comunit\u00e1rias de Ouro Preto, com o lema \u201cUnir para desenvolver e crescer\u201d. A Miss\u00e3o do MOV- OP \u00e9 sensibilizar e unir todos da comunidade; para depois diagnosticar as potencialidades e prioridades, formando n\u00facleos setoriais com especialistas competentes em cada \u00e1rea e assim fazer o planejamento estrat\u00e9gico, criar projetos de desenvolvimento e cidadania para Ouro Preto.\ufeff","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/empresarios-lancam-movimento-viva-ouro-preto-eficiencia-competencia-honestidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"Empres\u00e1rios lan\u00e7am &#8220;Movimento Viva Ouro Preto Efici\u00eancia &#8211; Compet\u00eancia -Honestidade&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/02\/IMG_1423_07-02-2020-scaled.jpg","jetpack-related-posts":[{"id":42027,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-lanca-candidatura-como-cidade-criativa-da-unesco\/","url_meta":{"origin":1912,"position":0},"title":"Ouro Preto lan\u00e7a candidatura como Cidade Criativa da UNESCO","author":"Di\u00e1rio de Ouro Preto","date":"31 de Janeiro de 2025","format":false,"excerpt":"Ontem 30\/01, a Casa da \u00d3pera recebeu o evento de lan\u00e7amento oficial da candidatura de Ouro Preto ao t\u00edtulo de Cidade Criativa da UNESCO, no campo das Artes Populares e Artesanato. A iniciativa \u00e9 fruto de uma parceria entre a Prefeitura de Ouro Preto, por meio da Secretaria de Desenvolvimento\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/IMG_20250130_195555.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/IMG_20250130_195555.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/IMG_20250130_195555.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/IMG_20250130_195555.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/IMG_20250130_195555.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41747,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-ira-lancar-candidatura-como-cidade-criativa-da-unesco-em-evento-na-casa-da-opera\/","url_meta":{"origin":1912,"position":1},"title":"Ouro Preto ir\u00e1 lan\u00e7ar candidatura como Cidade Criativa da UNESCO em evento na Casa da \u00d3pera","author":"Di\u00e1rio de Ouro Preto","date":"22 de Janeiro de 2025","format":false,"excerpt":"O Teatro Municipal ser\u00e1 palco do lan\u00e7amento oficial da candidatura de Ouro Preto ao t\u00edtulo de Cidade Criativa da UNESCO, no campo das Artes Populares e Artesanato No dia 30 de janeiro, \u00e0s 18h, a Casa da \u00d3pera receber\u00e1 o evento de lan\u00e7amento oficial da candidatura de Ouro Preto ao\u2026","rel":"","context":"In &quot;Cultura, Artes e Patrim\u00f4nio&quot;","block_context":{"text":"Cultura, Artes e Patrim\u00f4nio","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/culturaeartes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/c2a137d4e35285e11683f9a459fe7f86.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/c2a137d4e35285e11683f9a459fe7f86.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/c2a137d4e35285e11683f9a459fe7f86.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/c2a137d4e35285e11683f9a459fe7f86.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2815,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/universidade-federal-de-ouro-preto-e-instituto-federal-reforcam-necessidade-do-isolamento\/","url_meta":{"origin":1912,"position":2},"title":"Universidade Federal de Ouro Preto e Instituto Federal refor\u00e7am necessidade do isolamento","author":"Di\u00e1rio de Ouro Preto","date":"20 de Abril de 2020","format":false,"excerpt":"\"Neste momento em que o mundo e o Brasil vivem num cen\u00e1rio de enfrentamento contra a pandemia da COVID19, o Instituto Federal Minas Gerais \u0374 Campus Ouro Preto (IFMG-OP) e a Universidade Federal de Ouro Preto(UFOP) \u0374 campi Ouro Preto, Mariana e Jo\u00e3o Monlevade, entendendo o compromisso social com os\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/slide_-_1177x432_px_-_coronaaaaa_2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/slide_-_1177x432_px_-_coronaaaaa_2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/slide_-_1177x432_px_-_coronaaaaa_2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2020\/04\/slide_-_1177x432_px_-_coronaaaaa_2.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6112,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/angelo-oswaldo-e-aceop-se-reunem-para-discutir-a-situacao-do-comercio-de-ouro-preto\/","url_meta":{"origin":1912,"position":3},"title":"Angelo Oswaldo e ACEOP se re\u00fanem para discutir a situa\u00e7\u00e3o do com\u00e9rcio de Ouro Preto","author":"Di\u00e1rio de Ouro Preto","date":"13 de Janeiro de 2021","format":false,"excerpt":"Ouro Preto - O prefeito Angelo Oswaldo recebeu o presidente da Associa\u00e7\u00e3o Comercial e Empresarial de Ouro Preto (ACEOP), Paulo Ferreira e o vice, Walmir Maximiano, nesta segunda-feira, 11 de janeiro,na Prefeitura de Ouro Preto para tratar das demandas dos empres\u00e1rios do Munic\u00edpio. A proposta \u00e9 realizar um plano de\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/Credito-Neno-Vianna.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/Credito-Neno-Vianna.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/Credito-Neno-Vianna.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/Credito-Neno-Vianna.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/01\/Credito-Neno-Vianna.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1581,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prefeitura-aciona-o-judiciario-para-garantir-emprestimo-de-r-50-milhoes\/","url_meta":{"origin":1912,"position":4},"title":"Prefeitura aciona o Judici\u00e1rio para garantir empr\u00e9stimo de R$ 50 Milh\u00f5es","author":"Di\u00e1rio de Ouro Preto","date":"10 de Janeiro de 2020","format":false,"excerpt":"Ouro Preto- A prefeitura move uma A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) referente ao empr\u00e9stimo de R$ 50 milh\u00f5es, o projeto de Lei 206\/2019, de autoria do executivo que disp\u00f5es sobre contrata\u00e7\u00e3o de cr\u00e9dito foi rejeitado. De acordo com o regimento interno da C\u00e2mara, por 9 votos a 6, mesmo com\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/P1390694.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/P1390694.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/12\/P1390694.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":46737,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/ouro-preto-lanca-edital-para-impulsionar-negocios-criativos-com-apoio-do-condes-e-pade\/","url_meta":{"origin":1912,"position":5},"title":"Ouro Preto lan\u00e7a edital para impulsionar neg\u00f3cios criativos com apoio do CONDES e PADE","author":"Di\u00e1rio de Ouro Preto","date":"5 de Agosto de 2025","format":false,"excerpt":"Est\u00e1 oficialmente aberto o Edital da Incubadora Criativa do C.criA \u2013 Centro de Neg\u00f3cios Criativos | Hub Ouro Preto, iniciativa que promete transformar ideias culturais e criativas em neg\u00f3cios estruturados e sustent\u00e1veis. A chamada p\u00fablica, voltada para empreendedores(as), coletivos, produtoras culturais e Microempreendedores Individuais (MEIs), \u00e9 gratuita e contempla apenas\u2026","rel":"","context":"In &quot;Oportunidades&quot;","block_context":{"text":"Oportunidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/oportunidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/negocio-criativo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/negocio-criativo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/negocio-criativo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/negocio-criativo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/08\/negocio-criativo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}