{"id":17593,"date":"2022-07-31T15:33:05","date_gmt":"2022-07-31T18:33:05","guid":{"rendered":"https:\/\/www.diariodeouropreto.com.br\/?p=17593"},"modified":"2022-07-31T15:33:07","modified_gmt":"2022-07-31T18:33:07","slug":"prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda","status":"publish","type":"post","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","title":{"rendered":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda"},"content":{"rendered":"<p>Estudantes que almejam bolsas de estudo em institui\u00e7\u00f5es privadas de ensino superior poder\u00e3o, a partir de segunda (1\u00ba), fazer inscri\u00e7\u00e3o na 2\u00aa edi\u00e7\u00e3o de 2022 do Programa Universidade para Todos (ProUni).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1473182&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1473182&amp;o=node\"><\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es v\u00e3o at\u00e9 o dia 4 de agosto e&nbsp;<a href=\"https:\/\/acessounico.mec.gov.br\/prouni\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">podem ser efetuadas pelo&nbsp;<em>site<\/em>&nbsp;do ProUni<\/a>. As bolsas oferecidas pelo programa s\u00e3o parciais (50%) ou integrais (100%). Dentre os requisitos, o estudante deve ter atingido m\u00e9dia de 450 pontos em cada mat\u00e9ria do Exame Nacional do Ensino M\u00e9dio (Enem) e ter tido nota superior a zero na prova de reda\u00e7\u00e3o. Inscritos como treineiros no exame n\u00e3o poder\u00e3o concorrer a bolsas do ProUni.<\/p>\n\n\n\n<p>Os resultados ser\u00e3o divulgados em duas chamadas: a primeira ser\u00e1 realizada em 8 de agosto; a segunda, em 22 de agosto.&nbsp;<a href=\"https:\/\/acessounico.mec.gov.br\/prouni\" target=\"_blank\" rel=\"noreferrer noopener follow external sponsored ugc\" data-wpel-link=\"external\">Os resultados estar\u00e3o dispon\u00edveis&nbsp;<em>online<\/em><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Novidades<\/h2>\n\n\n\n<p>Esta edi\u00e7\u00e3o do ProUni trar\u00e1 algumas inova\u00e7\u00f5es. Dentre elas, inscri\u00e7\u00f5es que ser\u00e3o categorizadas como ampla concorr\u00eancia ou a\u00e7\u00f5es afirmativas. A ordem de prioridade na chamada varia de acordo com a categoria da inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outra mudan\u00e7a \u00e9 a prioriza\u00e7\u00e3o de inscritos que cumpram os seguintes crit\u00e9rios (em ordem decrescente de relev\u00e2ncia para a classifica\u00e7\u00e3o):<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>\u00bb Sejam professores da rede p\u00fablica de ensino (exclusivamente para os cursos de licenciatura e pedagogia destinados \u00e0 forma\u00e7\u00e3o do magist\u00e9rio da educa\u00e7\u00e3o b\u00e1sica, se for o caso e se houver inscritos nessa situa\u00e7\u00e3o);<\/td><\/tr><tr><td>\u00bb Estudantes que tenham cursado o ensino m\u00e9dio integralmente em escola da rede p\u00fablica;<\/td><\/tr><tr><td>\u00bb Estudantes que tenham cursado o ensino m\u00e9dio parcialmente em escola da rede p\u00fablica e parcialmente em institui\u00e7\u00e3o privada (com bolsa integral);<\/td><\/tr><tr><td>\u00bb Estudantes que tenham cursado o ensino m\u00e9dio parcialmente em escola da rede p\u00fablica e parcialmente em institui\u00e7\u00e3o privada (com bolsa parcial ou sem bolsa);<\/td><\/tr><tr><td>\u00bb Estudantes que tenham cursado o ensino m\u00e9dio integralmente em institui\u00e7\u00e3o privada (com bolsa integral);<\/td><\/tr><tr><td>\u00bb Estudantes que tenham cursado o ensino m\u00e9dio completo em institui\u00e7\u00e3o privada (com bolsa parcial ou sem bolsa de estudos).<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Renda<\/h2>\n\n\n\n<p>Para participar do processo o candidato deve preencher certos crit\u00e9rios, como as exig\u00eancias de faixas de renda&nbsp;<em>per capita<\/em>. Veja na tabela:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Bolsa integral (100%)<\/td><td>At\u00e9 1,5 sal\u00e1rio m\u00ednimo<\/td><\/tr><tr><td>Bolsa parcial (50%)<\/td><td>At\u00e9 3 sal\u00e1rios m\u00ednimos<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div id=\"110753\" class=\"advads-saneouro advads-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.saneouro.com.br\/noticias\/de-olho-na-saude-publica-lixo-descartado-incorretamente-pode-entupir-redes-de-esgoto\/\" target=\"_blank\" aria-label=\"Diario_Ouro_Preto_Site\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site.jpg 300w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-180x150.jpg 180w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/05\/Diario_Ouro_Preto_Site-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Segundo o Minist\u00e9rio da Educa\u00e7\u00e3o, a classifica\u00e7\u00e3o dos estudantes inscritos nos processos seletivos do ProUni considerar\u00e1 as notas obtidas nas duas \u00faltimas edi\u00e7\u00f5es do Enem, imediatamente anteriores ao processo seletivo do ProUni para ingresso em curso de gradua\u00e7\u00e3o ou sequencial de forma\u00e7\u00e3o espec\u00edfica.<\/p>\n\n\n\n<div id=\"50321\" class=\"advads-plantao advads-entity-placement\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/\" target=\"_blank\" aria-label=\"site &#8211; noticia\" data-wpel-link=\"external\" rel=\"follow external noopener noreferrer sponsored ugc\"><img src=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg\" alt=\"\"  srcset=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755.jpg 1200w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-150x38.jpg 150w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-660x167.jpg 660w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-768x194.jpg 768w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1000x252.jpg 1000w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-1536x388.jpg 1536w, https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/09\/titulosite2-e1616373489755-2048x517.jpg 2048w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"303\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Publicado em 30\/07\/2022 &#8211; 19:33 Por Ag\u00eancia Brasil &#8211; Bras\u00edlia<br>Edi\u00e7\u00e3o: Pedro Ivo de Oliveira<br>Foto: Walter Campanato\/Ag\u00eancia Brasil<\/p>","protected":false},"excerpt":{"rendered":"<p>Estudantes que almejam bolsas de estudo em institui\u00e7\u00f5es privadas de ensino superior poder\u00e3o, a partir de segunda (1\u00ba), fazer inscri\u00e7\u00e3o na 2\u00aa edi\u00e7\u00e3o de 2022 do Programa Universidade para Todos (ProUni). As inscri\u00e7\u00f5es v\u00e3o at\u00e9 o dia 4 de agosto e&nbsp;podem ser efetuadas pelo&nbsp;site&nbsp;do ProUni. As bolsas oferecidas pelo programa<span class=\"more-link\"><a href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/\" data-wpel-link=\"internal\">Continue Lendo<\/a><\/span><\/p>","protected":false},"author":1,"featured_media":17594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["entry","author-diario","post-17593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ouro-preto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto<\/title>\n<meta name=\"description\" content=\"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"og:description\" content=\"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diariodeouropreto\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T18:33:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-31T18:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Di\u00e1rio de Ouro Preto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/\"},\"author\":{\"name\":\"Di\u00e1rio de Ouro Preto\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\"},\"headline\":\"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda\",\"datePublished\":\"2022-07-31T18:33:05+00:00\",\"dateModified\":\"2022-07-31T18:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/\"},\"wordCount\":470,\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/enem_vac_abr_2811214307.jpg\",\"articleSection\":[\"Ouro Preto\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/\",\"name\":\"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/enem_vac_abr_2811214307.jpg\",\"datePublished\":\"2022-07-31T18:33:05+00:00\",\"dateModified\":\"2022-07-31T18:33:07+00:00\",\"description\":\"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/enem_vac_abr_2811214307.jpg\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/enem_vac_abr_2811214307.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Participantes do Exame Nacional do Ensino M\u00e9dio (Enem) 2021 fazem, neste domingo (28), segundo dia de avalia\u00e7\u00e3o, provas de matem\u00e1tica e de ci\u00eancia da natureza.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"description\":\"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\"},\"alternateName\":\"Jornal di\u00e1rio de Ouro Preto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#organization\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"alternateName\":\"Jornal di\u00e1rio Ouro Preto\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"contentUrl\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-logotransp-2.png\",\"width\":1323,\"height\":251,\"caption\":\"Di\u00e1rio de Ouro Preto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/diariodeouropreto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/#\\\/schema\\\/person\\\/7654e7b471204a6dab6dc0ce6e140c99\",\"name\":\"Di\u00e1rio de Ouro Preto\",\"sameAs\":[\"http:\\\/\\\/www.diariodeouropreto.com.br\"],\"url\":\"https:\\\/\\\/www.diariodeouropreto.com.br\\\/pt\\\/author\\\/diario\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto","description":"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","og_locale":"pt_PT","og_type":"article","og_title":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto","og_description":"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas","og_url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","og_site_name":"Di\u00e1rio de Ouro Preto","article_publisher":"https:\/\/www.facebook.com\/diariodeouropreto\/","article_published_time":"2022-07-31T18:33:05+00:00","article_modified_time":"2022-07-31T18:33:07+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","type":"image\/jpeg"}],"author":"Di\u00e1rio de Ouro Preto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Di\u00e1rio de Ouro Preto","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#article","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/"},"author":{"name":"Di\u00e1rio de Ouro Preto","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99"},"headline":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda","datePublished":"2022-07-31T18:33:05+00:00","dateModified":"2022-07-31T18:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/"},"wordCount":470,"publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","articleSection":["Ouro Preto"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/","name":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda - Di\u00e1rio de Ouro Preto","isPartOf":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#primaryimage"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","datePublished":"2022-07-31T18:33:05+00:00","dateModified":"2022-07-31T18:33:07+00:00","description":"Programa priorizar\u00e1 bolsas para estudantes de escolas p\u00fablicas","breadcrumb":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#primaryimage","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","width":1170,"height":700,"caption":"Participantes do Exame Nacional do Ensino M\u00e9dio (Enem) 2021 fazem, neste domingo (28), segundo dia de avalia\u00e7\u00e3o, provas de matem\u00e1tica e de ci\u00eancia da natureza."},{"@type":"BreadcrumbList","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-inscricoes-para-segunda-edicao-de-2022-comecam-na-segunda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.diariodeouropreto.com.br\/pt\/"},{"@type":"ListItem","position":2,"name":"ProUni: inscri\u00e7\u00f5es para segunda edi\u00e7\u00e3o de 2022 come\u00e7am na segunda"}]},{"@type":"WebSite","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#website","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","name":"Di\u00e1rio de Ouro Preto","description":"Not\u00edcias Ouro Preto; Mariana;Minas Gerais;Jornal;Jornalismo;Not\u00edcias;","publisher":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization"},"alternateName":"Jornal di\u00e1rio de Ouro Preto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diariodeouropreto.com.br\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#organization","name":"Di\u00e1rio de Ouro Preto","alternateName":"Jornal di\u00e1rio Ouro Preto","url":"https:\/\/www.diariodeouropreto.com.br\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","contentUrl":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2019\/06\/cropped-logotransp-2.png","width":1323,"height":251,"caption":"Di\u00e1rio de Ouro Preto"},"image":{"@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/diariodeouropreto\/"]},{"@type":"Person","@id":"https:\/\/www.diariodeouropreto.com.br\/pt\/#\/schema\/person\/7654e7b471204a6dab6dc0ce6e140c99","name":"Di\u00e1rio de Ouro Preto","sameAs":["http:\/\/www.diariodeouropreto.com.br"],"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/author\/diario\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2022\/07\/enem_vac_abr_2811214307.jpg","jetpack-related-posts":[{"id":28018,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-para-o-prouni-comecam-nesta-segunda-feira\/","url_meta":{"origin":17593,"position":0},"title":"Inscri\u00e7\u00f5es para o Prouni come\u00e7am nesta segunda-feira","author":"Di\u00e1rio de Ouro Preto","date":"29 de Janeiro de 2024","format":false,"excerpt":"As inscri\u00e7\u00f5es para o Programa Universidade Para Todos (Prouni) do primeiro semestre de 2024 come\u00e7am nesta segunda-feira (29). O prazo segue at\u00e9 a pr\u00f3xima quinta-feira (1\u00ba) e elas s\u00e3o feitas exclusivamente pelo\u00a0Portal \u00danico de Acesso ao Ensino Superior. Essa edi\u00e7\u00e3o do programa vai ofertar 406.428 bolsas \u2014\u202fsendo 308.977 integrais, o\u2026","rel":"","context":"In &quot;Oportunidades&quot;","block_context":{"text":"Oportunidades","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/oportunidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/01\/vestibular_marco_santos.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7939,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/termina-hoje-prazo-para-inscricoes-de-bolsas-remanescentes-do-prouni\/","url_meta":{"origin":17593,"position":1},"title":"Termina hoje prazo para inscri\u00e7\u00f5es de bolsas remanescentes do Prouni","author":"Di\u00e1rio de Ouro Preto","date":"4 de Maio de 2021","format":false,"excerpt":"Bras\u00edlia - Termina hoje (4) o prazo para as inscri\u00e7\u00f5es no processo seletivo de bolsas remanescentes do Programa Universidade para Todos (Prouni), relativo ao primeiro semestre deste ano. As inscri\u00e7\u00f5es devem ser realizadas, exclusivamente, na\u00a0p\u00e1gina do Prouni\u00a0at\u00e9 as 23h59. O resultado ser\u00e1 divulgado nesta sexta-feira (7). As bolsas remanescentes s\u00e3o\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/dsc_3563.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/dsc_3563.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/dsc_3563.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/dsc_3563.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/dsc_3563.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17738,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/mec-prorroga-ate-amanha-inscricao-para-o-prouni\/","url_meta":{"origin":17593,"position":2},"title":"MEC prorroga at\u00e9 amanh\u00e3 inscri\u00e7\u00e3o para o Prouni","author":"Di\u00e1rio de Ouro Preto","date":"4 de Agosto de 2022","format":false,"excerpt":"O Minist\u00e9rio da Educa\u00e7\u00e3o prorrogou por mais um dia as inscri\u00e7\u00f5es para o Programa Universidade para Todos (Prouni) deste segundo semestre, previstas para serem finalizadas hoje (4). Com isso, os estudantes interessados em bolsas de estudos em institui\u00e7\u00f5es privadas de ensino superior t\u00eam at\u00e9 amanh\u00e3 (5) para acessar o site\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/10_07_2020_ministerio_educacao-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/10_07_2020_ministerio_educacao-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/10_07_2020_ministerio_educacao-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/10_07_2020_ministerio_educacao-3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2021\/05\/10_07_2020_ministerio_educacao-3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41923,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-para-o-prouni-2025-terminam-nesta-terca-feira-28\/","url_meta":{"origin":17593,"position":3},"title":"Inscri\u00e7\u00f5es para o Prouni 2025 terminam nesta ter\u00e7a-feira (28)","author":"Di\u00e1rio de Ouro Preto","date":"27 de Janeiro de 2025","format":false,"excerpt":"Inscri\u00e7\u00e3o \u00e9 gratuita e deve ser feita exclusivamente pela p\u00e1gina do Prouni, no Portal \u00danico de Acesso ao Ensino Superior O prazo para inscri\u00e7\u00e3o no Programa Universidade Para Todos (Prouni) 2025 termina nesta ter\u00e7a-feira, 28 de janeiro. O Prouni oferece bolsas integrais (100%) ou parciais (50%) sobre o valor da\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2025\/01\/unnamed-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":36325,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/inscricoes-gratuitas-para-prouni-de-2024-terminam-nesta-sexta-feira\/","url_meta":{"origin":17593,"position":4},"title":"Inscri\u00e7\u00f5es gratuitas para Prouni de 2024 terminam nesta sexta-feira","author":"Di\u00e1rio de Ouro Preto","date":"25 de Julho de 2024","format":false,"excerpt":"Programa oferece mais de 243 mil bolsas em faculdades privadas As inscri\u00e7\u00f5es para o processo seletivo do Programa Universidade para Todos (Prouni) para o segundo semestre de 2024 terminam nesta sexta-feira (26\/07). Criado\u202fem\u202f2004, o\u202fprograma federal oferece bolsas de estudo\u202fintegrais e parciais\u202fem cursos de gradua\u00e7\u00e3o e sequenciais\u00a0de forma\u00e7\u00e3o espec\u00edfica, em institui\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Ouro Preto&quot;","block_context":{"text":"Ouro Preto","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/ouro-preto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2024\/07\/20230627_123947_0.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":49959,"url":"https:\/\/www.diariodeouropreto.com.br\/pt\/prouni-2026-inscricoes-para-o-1o-semestre-comecam-nesta-segunda\/","url_meta":{"origin":17593,"position":5},"title":"Prouni 2026: inscri\u00e7\u00f5es para o 1\u00ba semestre come\u00e7am nesta segunda","author":"Di\u00e1rio de Ouro Preto","date":"26 de Janeiro de 2026","format":false,"excerpt":"Processo \u00e9 gratuito e deve ser feito exclusivamente pela internet Come\u00e7am nesta segunda-feira (26) as inscri\u00e7\u00f5es do processo seletivo para o primeiro semestre de 2026 do Programa Universidade para Todos (Prouni).\u00a0O processo \u00e9 gratuito e deve ser feito exclusivamente pela internet, por meio do\u00a0Portal \u00danico\u00a0de Acesso ao Ensino Superior, at\u00e9\u2026","rel":"","context":"In &quot;Brasil&quot;","block_context":{"text":"Brasil","link":"https:\/\/www.diariodeouropreto.com.br\/pt\/Editoria\/brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/20230627_123947_0.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/20230627_123947_0.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/20230627_123947_0.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/20230627_123947_0.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.diariodeouropreto.com.br\/wp-content\/uploads\/2026\/01\/20230627_123947_0.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/17593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/comments?post=17593"}],"version-history":[{"count":0,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/posts\/17593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media\/17594"}],"wp:attachment":[{"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/media?parent=17593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/categories?post=17593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diariodeouropreto.com.br\/pt\/wp-json\/wp\/v2\/tags?post=17593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}